{"id":285684,"date":"2023-09-10T12:27:06","date_gmt":"2023-09-10T11:27:06","guid":{"rendered":"https:\/\/perlagesuite.com\/?page_id=285684"},"modified":"2024-06-17T08:54:23","modified_gmt":"2024-06-17T07:54:23","slug":"chiara-bassi","status":"publish","type":"page","link":"http:\/\/perlagesuite.com\/en\/","title":{"rendered":"Chiara Bassi"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Best Selling Book Section&#8221; _builder_version=&#8221;4.16&#8243; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_direction=&#8221;90deg&#8221; background_color_gradient_stops=&#8221;rgba(148,166,191,0.34) 40%|#f4f4f4 40%&#8221; background_color_gradient_start=&#8221;rgba(148,166,191,0.34)&#8221; background_color_gradient_start_position=&#8221;40%&#8221; background_color_gradient_end=&#8221;#f4f4f4&#8243; background_color_gradient_end_position=&#8221;0%&#8221; background_image=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2023\/09\/paper.jpg&#8221; background_blend=&#8221;multiply&#8221; custom_padding=&#8221;70px|0|70px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.16&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2023\/09\/copertina-edizione-speciale-ISBN.jpg&#8221; alt=&#8221;Libro sommelier&#8221; title_text=&#8221;copertina edizione speciale ISBN&#8221; align_tablet=&#8221;center&#8221; align_phone=&#8221;center&#8221; align_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.22.1&#8243; animation_style=&#8221;slide&#8221; animation_direction=&#8221;left&#8221; animation_intensity_slide=&#8221;5%&#8221; animation_starting_opacity=&#8221;100%&#8221; border_radii=&#8221;on|6px|6px|6px|6px&#8221; box_shadow_style=&#8221;preset3&#8243; box_shadow_vertical=&#8221;35px&#8221; box_shadow_blur=&#8221;70px&#8221; box_shadow_spread=&#8221;-35px&#8221; box_shadow_color=&#8221;rgba(0,0,0,0.6)&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;70px|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Title&#8221; _builder_version=&#8221;4.22.1&#8243; text_font=&#8221;Nunito|600|||||||&#8221; text_font_size=&#8221;15px&#8221; header_font=&#8221;Crushed|700|||||||&#8221; header_font_size=&#8221;68px&#8221; header_line_height=&#8221;1.2em&#8221; header_4_font=&#8221;Crushed|700||on|||||&#8221; header_4_text_color=&#8221;gcid-21fbec71-877e-4169-81a6-b6b5df6aa348&#8243; header_4_font_size=&#8221;20px&#8221; header_4_letter_spacing=&#8221;2px&#8221; header_4_line_height=&#8221;1.8em&#8221; header_5_font=&#8221;Gloria Hallelujah||||||||&#8221; header_5_font_size=&#8221;17px&#8221; custom_margin=&#8221;||40px|&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;right&#8221; animation_intensity_slide=&#8221;5%&#8221; animation_starting_opacity=&#8221;100%&#8221; header_font_size_tablet=&#8221;40px&#8221; header_font_size_phone=&#8221;&#8221; header_font_size_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{%22gcid-21fbec71-877e-4169-81a6-b6b5df6aa348%22:%91%22header_4_text_color%22%93}&#8221;]<\/p>\n<h4>By Chiara Bassi<\/h4>\n<h1>Sommelier:<\/h1>\n<h1>il manuale illustrato<\/h1>\n<h5>Tutti i miei appunti sul vino e sul cibo in un solo libro<\/h5>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.22.1&#8243; text_font=&#8221;Nunito||||||||&#8221; text_font_size=&#8221;18px&#8221; text_line_height=&#8221;1.8em&#8221; header_font=&#8221;||||||||&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;right&#8221; animation_intensity_slide=&#8221;5%&#8221; animation_starting_opacity=&#8221;100%&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Il manuale \u00e8 pensato per tutti gli aspiranti sommelier, ma \u00e8 utilissimo anche per i &#8220;gi\u00e0 sommelier&#8221; che vogliono ripassare, per i winelover che vogliono cominciare a dare basi concrete alla loro passione e per gli operatori di settore che vogliono guadagnare di pi\u00f9 imparando sia a gestire la cantina del loro ristorante sia a vendere la bottiglia giusta ai loro clienti.<\/p>\n<p>[\/et_pb_text][et_pb_button button_url=&#8221;https:\/\/perlagesuite.com\/prodotto\/come-diventare-sommelier-esame-ais-corso-sommelier\/&#8221; button_text=&#8221;Compra questo libro &#8211;  \u20ac 38&#8243; _builder_version=&#8221;4.22.1&#8243; custom_button=&#8221;on&#8221; button_text_size=&#8221;14px&#8221; button_text_color=&#8221;#ffffff&#8221; button_bg_color=&#8221;gcid-21fbec71-877e-4169-81a6-b6b5df6aa348&#8243; button_border_width=&#8221;8px&#8221; button_border_color=&#8221;gcid-21fbec71-877e-4169-81a6-b6b5df6aa348&#8243; button_letter_spacing=&#8221;2px&#8221; button_font=&#8221;Crushed|700||on|||||&#8221; button_use_icon=&#8221;off&#8221; custom_margin=&#8221;30px|||&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;right&#8221; animation_intensity_slide=&#8221;5%&#8221; animation_starting_opacity=&#8221;100%&#8221; box_shadow_style=&#8221;preset2&#8243; box_shadow_horizontal=&#8221;0px&#8221; box_shadow_vertical=&#8221;25px&#8221; box_shadow_blur=&#8221;45px&#8221; box_shadow_color=&#8221;rgba(148,166,191,0.25)&#8221; global_colors_info=&#8221;{%22gcid-21fbec71-877e-4169-81a6-b6b5df6aa348%22:%91%22button_bg_color%22,%22button_border_color%22%93}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|desktop&#8221; admin_label=&#8221;Author Section&#8221; _builder_version=&#8221;4.16&#8243; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_direction=&#8221;90deg&#8221; background_color_gradient_stops=&#8221;#ffffff 70%|#f4f4f4 70%&#8221; background_color_gradient_start=&#8221;#ffffff&#8221; background_color_gradient_start_position=&#8221;70%&#8221; background_color_gradient_end=&#8221;#f4f4f4&#8243; background_color_gradient_end_position=&#8221;0%&#8221; parallax=&#8221;on&#8221; custom_margin=&#8221;|||&#8221; custom_margin_tablet=&#8221;0px|||&#8221; custom_margin_last_edited=&#8221;off|desktop&#8221; custom_padding=&#8221;69px|0|30px|||&#8221; custom_padding_tablet=&#8221;70px||120px|&#8221; custom_padding_phone=&#8221;&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;70px||70px|&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Title&#8221; _builder_version=&#8221;4.22.1&#8243; text_font=&#8221;Nunito|600|||||||&#8221; text_font_size=&#8221;15px&#8221; header_font=&#8221;Crushed||||||||&#8221; header_2_font=&#8221;Crushed|700|||||||&#8221; header_2_font_size=&#8221;60px&#8221; header_2_line_height=&#8221;1.2em&#8221; header_4_font=&#8221;Crushed|700||on|||||&#8221; header_4_text_color=&#8221;gcid-21fbec71-877e-4169-81a6-b6b5df6aa348&#8243; header_4_font_size=&#8221;20px&#8221; header_4_letter_spacing=&#8221;2px&#8221; header_4_line_height=&#8221;1.8em&#8221; custom_margin=&#8221;||40px|&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;right&#8221; animation_intensity_slide=&#8221;5%&#8221; animation_starting_opacity=&#8221;100%&#8221; header_font_size_tablet=&#8221;40px&#8221; header_font_size_last_edited=&#8221;off|desktop&#8221; header_2_font_size_tablet=&#8221;40px&#8221; header_2_font_size_phone=&#8221;&#8221; header_2_font_size_last_edited=&#8221;on|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22gcid-21fbec71-877e-4169-81a6-b6b5df6aa348%22:%91%22header_4_text_color%22%93}&#8221;]<\/p>\n<h4>Best Selling Author<\/h4>\n<h2>Chiara Bassi<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.22.1&#8243; text_font=&#8221;Nunito||||||||&#8221; text_font_size=&#8221;18px&#8221; text_line_height=&#8221;1.8em&#8221; header_font=&#8221;||||||||&#8221; custom_margin=&#8221;|||&#8221; custom_padding=&#8221;||10px|&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;right&#8221; animation_intensity_slide=&#8221;5%&#8221; animation_starting_opacity=&#8221;100%&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Sono nata l&#8217;8 maggio 1985 a Faenza (RA), citt\u00e0 famosa per le ceramiche artistiche, il vino Sangiovese e la piadina romagnola. Maturit\u00e0 artistica a Ravenna e poi un primo percorso di studio (all&#8217;Alma Mater Studiorum di Bologna) e lavoro (in un famoso studio di architettura di Ravenna) nell&#8217;Ingegneria Edile, durato oltre 10 anni. Gi\u00e0 Sommelier AIS, in &#8220;et\u00e0 adulta&#8221; mi sono laureata con lode in Scienze, culture e politiche dell&#8217; Enogastronomia e mi sono perfezionata in giornalismo enogastronomico alla Luiss Guido Carli di Roma.<\/p>\n<p>[\/et_pb_text][et_pb_button button_url=&#8221;https:\/\/perlagesuite.com\/chiara-bassi-sommelier-wine-blogger-4\/&#8221; button_text=&#8221;La mia storia&#8221; _builder_version=&#8221;4.22.1&#8243; custom_button=&#8221;on&#8221; button_text_size=&#8221;14px&#8221; button_text_color=&#8221;#ffffff&#8221; button_bg_color=&#8221;gcid-21fbec71-877e-4169-81a6-b6b5df6aa348&#8243; button_border_width=&#8221;8px&#8221; button_border_color=&#8221;gcid-21fbec71-877e-4169-81a6-b6b5df6aa348&#8243; button_letter_spacing=&#8221;2px&#8221; button_font=&#8221;Crushed|700||on|||||&#8221; button_use_icon=&#8221;off&#8221; custom_margin=&#8221;30px|||&#8221; custom_margin_tablet=&#8221;|||&#8221; custom_margin_phone=&#8221;&#8221; custom_margin_last_edited=&#8221;on|tablet&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;right&#8221; animation_intensity_slide=&#8221;5%&#8221; animation_starting_opacity=&#8221;100%&#8221; box_shadow_style=&#8221;preset2&#8243; box_shadow_horizontal=&#8221;0px&#8221; box_shadow_vertical=&#8221;25px&#8221; box_shadow_blur=&#8221;45px&#8221; box_shadow_color=&#8221;rgba(148,166,191,0.25)&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22gcid-21fbec71-877e-4169-81a6-b6b5df6aa348%22:%91%22button_bg_color%22,%22button_border_color%22%93}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_button][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2018\/07\/chiara-bassi-sommelier-millesima-blog-awards.jpg&#8221; alt=&#8221;chiara bassi wine blogger&#8221; title_text=&#8221;chiara-bassi-sommelier-millesima-blog-awards&#8221; align_tablet=&#8221;center&#8221; align_phone=&#8221;center&#8221; align_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.22.1&#8243; animation_style=&#8221;slide&#8221; animation_direction=&#8221;left&#8221; animation_intensity_slide=&#8221;5%&#8221; animation_starting_opacity=&#8221;100%&#8221; border_radii=&#8221;on|6px|6px|6px|6px&#8221; box_shadow_style=&#8221;preset3&#8243; box_shadow_vertical=&#8221;35px&#8221; box_shadow_blur=&#8221;70px&#8221; box_shadow_spread=&#8221;-35px&#8221; box_shadow_color=&#8221;rgba(0,0,0,0.6)&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Fun Fact Section&#8221; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;50px||50px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_number_counter title=&#8221;Libri pubblicati&#8221; number=&#8221;4&#8243; percent_sign=&#8221;off&#8221; _builder_version=&#8221;4.22.1&#8243; title_font=&#8221;Crushed|700||on|||||&#8221; title_text_color=&#8221;#666666&#8243; title_font_size=&#8221;22px&#8221; number_font=&#8221;Crushed|700|||||||&#8221; number_text_color=&#8221;gcid-21fbec71-877e-4169-81a6-b6b5df6aa348&#8243; number_font_size=&#8221;80px&#8221; number_line_height=&#8221;100px&#8221; global_colors_info=&#8221;{%22gcid-21fbec71-877e-4169-81a6-b6b5df6aa348%22:%91%22number_text_color%22%93}&#8221;][\/et_pb_number_counter][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_number_counter title=&#8221;Best Sellers&#8221; number=&#8221;1&#8243; percent_sign=&#8221;off&#8221; _builder_version=&#8221;4.22.1&#8243; title_font=&#8221;Crushed|700||on|||||&#8221; title_text_color=&#8221;#666666&#8243; title_font_size=&#8221;22px&#8221; number_font=&#8221;Crushed|700|||||||&#8221; number_text_color=&#8221;gcid-21fbec71-877e-4169-81a6-b6b5df6aa348&#8243; number_font_size=&#8221;80px&#8221; number_line_height=&#8221;100px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22gcid-21fbec71-877e-4169-81a6-b6b5df6aa348%22:%91%22number_text_color%22%93}&#8221;][\/et_pb_number_counter][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_number_counter title=&#8221;Libri venduti&#8221; number=&#8221;24.320&#8243; percent_sign=&#8221;off&#8221; _builder_version=&#8221;4.22.1&#8243; title_font=&#8221;Crushed|700||on|||||&#8221; title_text_color=&#8221;#666666&#8243; title_font_size=&#8221;22px&#8221; number_font=&#8221;Crushed|700|||||||&#8221; number_text_color=&#8221;gcid-21fbec71-877e-4169-81a6-b6b5df6aa348&#8243; number_font_size=&#8221;80px&#8221; number_line_height=&#8221;100px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22gcid-21fbec71-877e-4169-81a6-b6b5df6aa348%22:%91%22number_text_color%22%93}&#8221;][\/et_pb_number_counter][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Quote Section&#8221; _builder_version=&#8221;4.22.1&#8243; background_color=&#8221;gcid-21fbec71-877e-4169-81a6-b6b5df6aa348&#8243; background_image=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2023\/09\/pages-divider.png&#8221; background_size=&#8221;contain&#8221; background_position=&#8221;top_center&#8221; custom_padding=&#8221;57px||31px|||&#8221; top_divider_color=&#8221;rgba(255,255,255,0.3)&#8221; global_colors_info=&#8221;{%22gcid-21fbec71-877e-4169-81a6-b6b5df6aa348%22:%91%22background_color%22%93}&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_blurb use_icon=&#8221;on&#8221; font_icon=&#8221;&#x7b;||divi||400&#8243; icon_color=&#8221;#ffffff&#8221; content_max_width=&#8221;800px&#8221; _builder_version=&#8221;4.25.2&#8243; header_font=&#8221;Gloria Hallelujah||||||||&#8221; body_font=&#8221;Raleway|500|||||||&#8221; body_font_size=&#8221;20px&#8221; body_line_height=&#8221;1.4em&#8221; text_orientation=&#8221;center&#8221; background_layout=&#8221;dark&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span>Ricorda: i risultati che si raggiungono nella vita non sono una questione di fortuna. Insinuare questo significa credere di essere in mano della sorte. La fortuna esiste, ma \u00e8 solo quella che ha determinato le nostre condizioni di partenza, il vantaggio o lo svantaggio prima ancora di cominciare la nostra partita. Ovunque tu sia oggi, ne sei il principale responsabile. Pensaci: ogni tua azione \u00e8 causa ed effetto di ci\u00f2 che sei e di ci\u00f2 che sarai. Questo non solo \u00e8 straordinario, ma \u00e8 anche una grande consolazione. Con una metafora, la tua vita \u00e8 un\u2019auto che guidi tu e sempre tu ne decidi il percorso. L\u2019auto che guidi &#8211; tipologia, modello, optional\u2026 &#8211; e la strada &#8211; autostrada, strada secondaria, mulattiera\u2026 &#8211; possono sempre cambiare. Ad ogni istante di tempo c\u2019\u00e8 sempre un\u2019altra scelta che puoi fare. A meno che non ritieni il posto in cui sei adesso il pi\u00f9 soddisfacente dei luoghi possibili\u2026 non fermarti!<\/span><\/p>\n<p>[\/et_pb_blurb][et_pb_text admin_label=&#8221;Text&#8221; _builder_version=&#8221;4.22.1&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_4_font=&#8221;Gloria Hallelujah|700||on|||||&#8221; header_4_letter_spacing=&#8221;2px&#8221; text_orientation=&#8221;center&#8221; background_layout=&#8221;dark&#8221; custom_padding=&#8221;45px|||&#8221; animation_style=&#8221;fade&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4>&#8211; Chiara Bassi<\/h4>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|desktop&#8221; admin_label=&#8221;Upcoming Book Section&#8221; _builder_version=&#8221;4.16&#8243; background_color_gradient_direction=&#8221;0deg&#8221; background_image=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2023\/09\/paper.jpg&#8221; background_size=&#8221;contain&#8221; background_position=&#8221;top_center&#8221; background_blend=&#8221;multiply&#8221; custom_margin=&#8221;|||&#8221; custom_margin_tablet=&#8221;0px|||&#8221; custom_margin_last_edited=&#8221;off|desktop&#8221; custom_padding=&#8221;50px||50px|||&#8221; custom_padding_tablet=&#8221;70px||120px|&#8221; custom_padding_phone=&#8221;&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.22.1&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Crushed|700|||||||&#8221; header_2_font_size=&#8221;60px&#8221; header_2_line_height=&#8221;1.2em&#8221; text_orientation=&#8221;center&#8221; custom_margin=&#8221;|||&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;top&#8221; animation_intensity_slide=&#8221;5%&#8221; animation_starting_opacity=&#8221;100%&#8221; header_2_font_size_tablet=&#8221;40px&#8221; header_2_font_size_phone=&#8221;&#8221; header_2_font_size_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Prossima uscita<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;70px||70px|&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Title&#8221; _builder_version=&#8221;4.22.1&#8243; text_font=&#8221;Nunito|600|||||||&#8221; text_font_size=&#8221;15px&#8221; header_font=&#8221;||||||||&#8221; header_font_size=&#8221;80px&#8221; header_2_font=&#8221;Crushed|700|||||||&#8221; header_2_font_size=&#8221;60px&#8221; header_2_line_height=&#8221;1.2em&#8221; header_4_font=&#8221;Crushed|700||on|||||&#8221; header_4_text_color=&#8221;gcid-21fbec71-877e-4169-81a6-b6b5df6aa348&#8243; header_4_font_size=&#8221;22px&#8221; header_4_letter_spacing=&#8221;2px&#8221; header_4_line_height=&#8221;1.8em&#8221; header_5_font=&#8221;Gloria Hallelujah||||||||&#8221; header_5_font_size=&#8221;17px&#8221; header_6_font=&#8221;Nunito|600|||||||&#8221; header_6_text_color=&#8221;#666666&#8243; header_6_font_size=&#8221;18px&#8221; header_6_line_height=&#8221;1.4em&#8221; custom_margin=&#8221;||40px|&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;right&#8221; animation_intensity_slide=&#8221;5%&#8221; animation_starting_opacity=&#8221;100%&#8221; header_font_size_tablet=&#8221;40px&#8221; header_font_size_phone=&#8221;&#8221; header_font_size_last_edited=&#8221;on|tablet&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22gcid-21fbec71-877e-4169-81a6-b6b5df6aa348%22:%91%22header_4_text_color%22%93}&#8221;]<\/p>\n<h4>A partire dal 1 ottobre 2023<\/h4>\n<h2>Sommelier: an illustrated handbook<\/h2>\n<h5>All my notes on wine and food in a only book.<\/h5>\n<p>English version<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.22.1&#8243; text_font=&#8221;Nunito||||||||&#8221; text_font_size=&#8221;18px&#8221; text_line_height=&#8221;1.8em&#8221; header_font=&#8221;||||||||&#8221; custom_margin=&#8221;|||&#8221; custom_padding=&#8221;||10px|&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;right&#8221; animation_intensity_slide=&#8221;5%&#8221; animation_starting_opacity=&#8221;100%&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>The manual is designed for all aspiring sommeliers, but it is also very useful for &#8220;already sommeliers&#8221; who want to brush up, for wine lovers who want to start giving concrete foundations to their passion and for sector operators who want to earn more by learning both to manage the cellar of their restaurant and to sell the right bottle to their customers.<\/p>\n<p>[\/et_pb_text][et_pb_button button_text=&#8221;Preorder the Book &#8211; $ 38&#8243; _builder_version=&#8221;4.22.1&#8243; custom_button=&#8221;on&#8221; button_text_size=&#8221;14px&#8221; button_text_color=&#8221;#ffffff&#8221; button_bg_color=&#8221;gcid-21fbec71-877e-4169-81a6-b6b5df6aa348&#8243; button_border_width=&#8221;8px&#8221; button_border_color=&#8221;gcid-21fbec71-877e-4169-81a6-b6b5df6aa348&#8243; button_letter_spacing=&#8221;2px&#8221; button_font=&#8221;Nunito|700||on|||||&#8221; button_use_icon=&#8221;off&#8221; custom_margin=&#8221;30px|||&#8221; custom_margin_tablet=&#8221;|||&#8221; custom_margin_phone=&#8221;&#8221; custom_margin_last_edited=&#8221;on|tablet&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;right&#8221; animation_intensity_slide=&#8221;5%&#8221; animation_starting_opacity=&#8221;100%&#8221; box_shadow_style=&#8221;preset2&#8243; box_shadow_horizontal=&#8221;0px&#8221; box_shadow_vertical=&#8221;25px&#8221; box_shadow_blur=&#8221;45px&#8221; box_shadow_color=&#8221;rgba(148,166,191,0.25)&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22gcid-21fbec71-877e-4169-81a6-b6b5df6aa348%22:%91%22button_bg_color%22,%22button_border_color%22%93}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_button][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2023\/09\/Libro-sommelier-inglese-copertina.jpeg&#8221; alt=&#8221;Libro sommelier inglese copertina&#8221; title_text=&#8221;Libro sommelier inglese copertina&#8221; align_tablet=&#8221;center&#8221; align_phone=&#8221;center&#8221; align_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.22.1&#8243; animation_style=&#8221;slide&#8221; animation_direction=&#8221;left&#8221; animation_intensity_slide=&#8221;5%&#8221; animation_starting_opacity=&#8221;100%&#8221; border_radii=&#8221;on|6px|6px|6px|6px&#8221; box_shadow_style=&#8221;preset3&#8243; box_shadow_vertical=&#8221;35px&#8221; box_shadow_blur=&#8221;70px&#8221; box_shadow_spread=&#8221;-35px&#8221; box_shadow_color=&#8221;rgba(0,0,0,0.6)&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Blog Section&#8221; _builder_version=&#8221;4.16&#8243; background_color=&#8221;#f4f4f4&#8243; background_image=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2023\/09\/pages-divider.png&#8221; background_size=&#8221;contain&#8221; background_position=&#8221;top_center&#8221; custom_padding=&#8221;60px||3.6%|||&#8221; top_divider_color=&#8221;rgba(255,255,255,0.3)&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Title&#8221; _builder_version=&#8221;4.22.1&#8243; text_font=&#8221;Nunito|600|||||||&#8221; text_font_size=&#8221;15px&#8221; header_font=&#8221;||||||||&#8221; header_font_size=&#8221;80px&#8221; header_2_font=&#8221;Crushed|700|||||||&#8221; header_2_font_size=&#8221;60px&#8221; header_2_line_height=&#8221;1.2em&#8221; header_4_font=&#8221;Nunito|700||on|||||&#8221; header_4_text_color=&#8221;gcid-21fbec71-877e-4169-81a6-b6b5df6aa348&#8243; header_4_font_size=&#8221;22px&#8221; header_4_letter_spacing=&#8221;2px&#8221; header_4_line_height=&#8221;1.8em&#8221; header_6_font=&#8221;Nunito|600|||||||&#8221; header_6_text_color=&#8221;#666666&#8243; header_6_font_size=&#8221;18px&#8221; header_6_line_height=&#8221;1.4em&#8221; text_orientation=&#8221;center&#8221; custom_margin=&#8221;||40px|&#8221; animation_direction=&#8221;left&#8221; header_font_size_tablet=&#8221;40px&#8221; header_font_size_phone=&#8221;&#8221; header_font_size_last_edited=&#8221;on|tablet&#8221; header_2_font_size_tablet=&#8221;40px&#8221; header_2_font_size_phone=&#8221;&#8221; header_2_font_size_last_edited=&#8221;on|tablet&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22gcid-21fbec71-877e-4169-81a6-b6b5df6aa348%22:%91%22header_4_text_color%22%93}&#8221;]<\/p>\n<h4>Sommelier Suite: la mia testata giornalistica<\/h4>\n<h2>Leggi tutti i miei articoli<\/h2>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2023\/09\/Apple-Mock-up-SommelierSuite.png&#8221; alt=&#8221;Libro sommelier suite&#8221; title_text=&#8221;Apple Mock-up SommelierSuite&#8221; _builder_version=&#8221;4.22.1&#8243; _module_preset=&#8221;default&#8221; width=&#8221;70%&#8221; module_alignment=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_button button_url=&#8221;https:\/\/sommeliersuite.com\/&#8221; url_new_window=&#8221;on&#8221; button_text=&#8221;Leggi i miei articoli&#8221; button_alignment=&#8221;center&#8221; _builder_version=&#8221;4.22.1&#8243; custom_button=&#8221;on&#8221; button_text_size=&#8221;14px&#8221; button_text_color=&#8221;#ffffff&#8221; button_bg_color=&#8221;gcid-21fbec71-877e-4169-81a6-b6b5df6aa348&#8243; button_border_width=&#8221;8px&#8221; button_border_color=&#8221;gcid-21fbec71-877e-4169-81a6-b6b5df6aa348&#8243; button_letter_spacing=&#8221;2px&#8221; button_font=&#8221;Nunito|700||on|||||&#8221; button_use_icon=&#8221;off&#8221; custom_margin=&#8221;30px|||&#8221; custom_margin_tablet=&#8221;|||&#8221; custom_margin_phone=&#8221;&#8221; custom_margin_last_edited=&#8221;on|tablet&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;right&#8221; animation_intensity_slide=&#8221;5%&#8221; animation_starting_opacity=&#8221;100%&#8221; box_shadow_style=&#8221;preset2&#8243; box_shadow_horizontal=&#8221;0px&#8221; box_shadow_vertical=&#8221;25px&#8221; box_shadow_blur=&#8221;45px&#8221; box_shadow_color=&#8221;rgba(148,166,191,0.25)&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22gcid-21fbec71-877e-4169-81a6-b6b5df6aa348%22:%91%22button_bg_color%22,%22button_border_color%22%93}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Footer Section&#8221; _builder_version=&#8221;4.22.1&#8243; background_color=&#8221;#FFFFFF&#8221; custom_padding=&#8221;100px||53px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; custom_padding_last_edited=&#8221;on|phone&#8221; _builder_version=&#8221;4.22.1&#8243; background_color=&#8221;gcid-21fbec71-877e-4169-81a6-b6b5df6aa348&#8243; custom_margin=&#8221;-10%|||&#8221; custom_padding=&#8221;70px|3%|70px|3%&#8221; custom_padding_tablet=&#8221;&#8221; custom_padding_phone=&#8221;&#8221; border_radii=&#8221;on|10px|10px|10px|10px&#8221; box_shadow_style=&#8221;preset2&#8243; box_shadow_horizontal=&#8221;0px&#8221; box_shadow_vertical=&#8221;35px&#8221; box_shadow_blur=&#8221;65px&#8221; box_shadow_color=&#8221;rgba(188,163,146,0.1)&#8221; global_colors_info=&#8221;{%22gcid-21fbec71-877e-4169-81a6-b6b5df6aa348%22:%91%22background_color%22%93}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_blurb title=&#8221;Customer Care&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xf4fd;||fa||900&#8243; icon_color=&#8221;#ffffff&#8221; image_icon_background_color=&#8221;rgba(189,173,160,0)&#8221; image_icon_width=&#8221;32px&#8221; admin_label=&#8221;Where To Buy&#8221; _builder_version=&#8221;4.22.1&#8243; header_font=&#8221;Crushed|700|||||||&#8221; header_text_color=&#8221;#ffffff&#8221; header_font_size=&#8221;24px&#8221; header_line_height=&#8221;1.2em&#8221; body_font=&#8221;Nunito||||||||&#8221; body_text_color=&#8221;#ffffff&#8221; body_font_size=&#8221;18px&#8221; image_icon_custom_padding=&#8221;25px|25px|25px|25px|false|false&#8221; text_orientation=&#8221;center&#8221; border_radii_image=&#8221;on|100%|100%|100%|100%&#8221; border_width_all_image=&#8221;3px&#8221; border_color_all_image=&#8221;#ffffff&#8221; icon_font_size=&#8221;32px&#8221; use_circle=&#8221;on&#8221; use_circle_border=&#8221;on&#8221; circle_border_color=&#8221;#ffffff&#8221; circle_color=&#8221;rgba(189,173,160,0)&#8221; global_colors_info=&#8221;{}&#8221; image_icon_background_color__sticky_enabled=&#8221;#86a293&#8243; image_icon_background_color__sticky=&#8221;#86a293&#8243;]<\/p>\n<p>info@perlagesuite.com<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_blurb title=&#8221;Contatto Agente&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xf507;||fa||900&#8243; icon_color=&#8221;#ffffff&#8221; image_icon_background_color=&#8221;rgba(189,173,160,0)&#8221; image_icon_width=&#8221;32px&#8221; admin_label=&#8221;Contact Manager&#8221; _builder_version=&#8221;4.22.1&#8243; header_font=&#8221;Crushed|700|||||||&#8221; header_text_color=&#8221;#ffffff&#8221; header_font_size=&#8221;24px&#8221; header_line_height=&#8221;1.2em&#8221; body_font=&#8221;Nunito||||||||&#8221; body_text_color=&#8221;#ffffff&#8221; body_font_size=&#8221;18px&#8221; image_icon_custom_padding=&#8221;25px|25px|25px|25px|false|false&#8221; text_orientation=&#8221;center&#8221; border_radii_image=&#8221;on|100%|100%|100%|100%&#8221; border_width_all_image=&#8221;3px&#8221; border_color_all_image=&#8221;#ffffff&#8221; icon_font_size=&#8221;32px&#8221; use_circle=&#8221;on&#8221; use_circle_border=&#8221;on&#8221; circle_border_color=&#8221;#ffffff&#8221; circle_color=&#8221;rgba(189,173,160,0)&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; image_icon_background_color__sticky_enabled=&#8221;#86a293&#8243; image_icon_background_color__sticky=&#8221;#86a293&#8243;]<\/p>\n<p>valentina@perlagesuite.com<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_blurb title=&#8221;Contatto Autore&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xf4ff;||fa||900&#8243; icon_color=&#8221;#ffffff&#8221; image_icon_background_color=&#8221;rgba(189,173,160,0)&#8221; image_icon_width=&#8221;32px&#8221; admin_label=&#8221;Contact Author&#8221; _builder_version=&#8221;4.22.1&#8243; header_font=&#8221;Crushed|700|||||||&#8221; header_text_color=&#8221;#ffffff&#8221; header_font_size=&#8221;24px&#8221; header_line_height=&#8221;1.2em&#8221; body_font=&#8221;Nunito||||||||&#8221; body_text_color=&#8221;#ffffff&#8221; body_font_size=&#8221;18px&#8221; image_icon_custom_padding=&#8221;25px|25px|25px|25px|false|false&#8221; text_orientation=&#8221;center&#8221; border_radii_image=&#8221;on|100%|100%|100%|100%&#8221; border_width_all_image=&#8221;3px&#8221; border_color_all_image=&#8221;#ffffff&#8221; icon_font_size=&#8221;32px&#8221; use_circle=&#8221;on&#8221; use_circle_border=&#8221;on&#8221; circle_border_color=&#8221;#ffffff&#8221; circle_color=&#8221;rgba(189,173,160,0)&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; image_icon_background_color__sticky_enabled=&#8221;#86a293&#8243; image_icon_background_color__sticky=&#8221;#86a293&#8243;]<\/p>\n<p>chiara@perlagesuite.com<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>By Chiara Bassi Sommelier: il manuale illustrato Tutti i miei appunti sul vino e sul cibo in un solo libroIl manuale \u00e8 pensato per tutti gli aspiranti sommelier, ma \u00e8 utilissimo anche per i &#8220;gi\u00e0 sommelier&#8221; che vogliono ripassare, per i winelover che vogliono cominciare a dare basi concrete alla loro passione e per gli [&hellip;]<\/p>\n","protected":false},"author":49,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-285684","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.0 (Yoast SEO v27.7) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Chiara Bassi: scrittrice, sommelier e gastronoma | Perlage Suite<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/perlagesuite.com\/en\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chiara Bassi\" \/>\n<meta property=\"og:description\" content=\"By Chiara Bassi Sommelier: il manuale illustrato Tutti i miei appunti sul vino e sul cibo in un solo libroIl manuale \u00e8 pensato per tutti gli aspiranti sommelier, ma \u00e8 utilissimo anche per i &quot;gi\u00e0 sommelier&quot; che vogliono ripassare, per i winelover che vogliono cominciare a dare basi concrete alla loro passione e per gli [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/perlagesuite.com\/en\/\" \/>\n<meta property=\"og:site_name\" content=\"Perlage Suite\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/chiarabassiperlagesuite\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-17T07:54:23+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@perlagesuite\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/\",\"name\":\"Chiara Bassi: scrittrice, sommelier e gastronoma | Perlage Suite\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#website\"},\"datePublished\":\"2023-09-10T11:27:06+00:00\",\"dateModified\":\"2024-06-17T07:54:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/perlagesuite.com\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/perlagesuite.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chiara Bassi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#website\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/\",\"name\":\"Perlage Suite\",\"description\":\"Il Wine Blog di Chiara Bassi\",\"publisher\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/perlagesuite.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#organization\",\"name\":\"Chiara Bassi\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Chiara-Bassi-sommelier-wine-blogger-logo.png\",\"contentUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Chiara-Bassi-sommelier-wine-blogger-logo.png\",\"width\":512,\"height\":512,\"caption\":\"Chiara Bassi\"},\"image\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/chiarabassiperlagesuite\",\"https:\\\/\\\/x.com\\\/perlagesuite\",\"https:\\\/\\\/www.instagram.com\\\/perlagesuite\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Chiara Bassi: writer, sommelier and gastronome | Perlage Suite","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/perlagesuite.com\/en\/","og_locale":"en_GB","og_type":"article","og_title":"Chiara Bassi","og_description":"By Chiara Bassi Sommelier: il manuale illustrato Tutti i miei appunti sul vino e sul cibo in un solo libroIl manuale \u00e8 pensato per tutti gli aspiranti sommelier, ma \u00e8 utilissimo anche per i \"gi\u00e0 sommelier\" che vogliono ripassare, per i winelover che vogliono cominciare a dare basi concrete alla loro passione e per gli [&hellip;]","og_url":"https:\/\/perlagesuite.com\/en\/","og_site_name":"Perlage Suite","article_publisher":"https:\/\/www.facebook.com\/chiarabassiperlagesuite","article_modified_time":"2024-06-17T07:54:23+00:00","twitter_card":"summary_large_image","twitter_site":"@perlagesuite","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/perlagesuite.com\/","url":"https:\/\/perlagesuite.com\/","name":"Chiara Bassi: writer, sommelier and gastronome | Perlage Suite","isPartOf":{"@id":"https:\/\/perlagesuite.com\/#website"},"datePublished":"2023-09-10T11:27:06+00:00","dateModified":"2024-06-17T07:54:23+00:00","breadcrumb":{"@id":"https:\/\/perlagesuite.com\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/perlagesuite.com\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/perlagesuite.com\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/perlagesuite.com\/"},{"@type":"ListItem","position":2,"name":"Chiara Bassi"}]},{"@type":"WebSite","@id":"https:\/\/perlagesuite.com\/#website","url":"https:\/\/perlagesuite.com\/","name":"Perlage Suite","description":"Chiara Bassi's Wine Blog","publisher":{"@id":"https:\/\/perlagesuite.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/perlagesuite.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/perlagesuite.com\/#organization","name":"Chiara Bassi","url":"https:\/\/perlagesuite.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/perlagesuite.com\/#\/schema\/logo\/image\/","url":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2022\/03\/Chiara-Bassi-sommelier-wine-blogger-logo.png","contentUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2022\/03\/Chiara-Bassi-sommelier-wine-blogger-logo.png","width":512,"height":512,"caption":"Chiara Bassi"},"image":{"@id":"https:\/\/perlagesuite.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/chiarabassiperlagesuite","https:\/\/x.com\/perlagesuite","https:\/\/www.instagram.com\/perlagesuite\/"]}]}},"_links":{"self":[{"href":"http:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/pages\/285684","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"http:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/comments?post=285684"}],"version-history":[{"count":0,"href":"http:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/pages\/285684\/revisions"}],"wp:attachment":[{"href":"http:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/media?parent=285684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}