{"id":1597,"date":"2015-03-08T23:19:13","date_gmt":"2015-03-08T22:19:13","guid":{"rendered":"http:\/\/cavatappi.org\/?post_type=project&#038;p=1597"},"modified":"2018-05-26T17:06:57","modified_gmt":"2018-05-26T16:06:57","slug":"vinificazione-in-rosso","status":"publish","type":"project","link":"http:\/\/perlagesuite.com\/en\/project\/vinificazione-in-rosso\/","title":{"rendered":"Red vinification"},"content":{"rendered":"<p>[et_pb_section admin_label=&#8221;section&#8221; fullwidth=&#8221;on&#8221; specialty=&#8221;off&#8221; transparent_background=&#8221;off&#8221; background_color=&#8221;#955251&#8243; allow_player_pause=&#8221;off&#8221; inner_shadow=&#8221;off&#8221; parallax=&#8221;off&#8221; parallax_method=&#8221;off&#8221;][et_pb_fullwidth_slider admin_label=&#8221;Slider a Larghezza Piena&#8221; show_arrows=&#8221;on&#8221; show_pagination=&#8221;on&#8221; auto=&#8221;off&#8221; parallax=&#8221;off&#8221; parallax_method=&#8221;off&#8221; auto_ignore_hover=&#8221;off&#8221; remove_inner_shadow=&#8221;off&#8221; background_position=&#8221;default&#8221; background_size=&#8221;default&#8221; hide_content_on_mobile=&#8221;off&#8221; hide_cta_on_mobile=&#8221;off&#8221; show_image_video_mobile=&#8221;off&#8221; custom_button=&#8221;off&#8221; button_letter_spacing=&#8221;0&#8243; button_use_icon=&#8221;default&#8221; button_icon_placement=&#8221;right&#8221; button_on_hover=&#8221;on&#8221; button_letter_spacing_hover=&#8221;0&#8243;] [et_pb_slide background_image=&#8221;http:\/\/perlagesuite.com\/wp-content\/uploads\/2015\/03\/vino-rosso-uva.jpg&#8221; background_color=&#8221;#ffffff&#8221; alignment=&#8221;center&#8221; background_layout=&#8221;dark&#8221; allow_player_pause=&#8221;off&#8221; background_position=&#8221;default&#8221; background_size=&#8221;default&#8221; header_font_select=&#8221;default&#8221; body_font_select=&#8221;default&#8221; custom_button=&#8221;off&#8221; button_font_select=&#8221;default&#8221; button_use_icon=&#8221;default&#8221; button_icon_placement=&#8221;right&#8221; button_on_hover=&#8221;on&#8221;] [\/et_pb_slide] [\/et_pb_fullwidth_slider][et_pb_fullwidth_header admin_label=&#8221;Intestazione a Larghezza Piena&#8221; title=&#8221;Vinificazione in Rosso&#8221; background_layout=&#8221;dark&#8221; text_orientation=&#8221;center&#8221;] [\/et_pb_fullwidth_header][\/et_pb_section][et_pb_section admin_label=&#8221;section&#8221; fullwidth=&#8221;off&#8221; specialty=&#8221;off&#8221;][et_pb_row admin_label=&#8221;row&#8221;][et_pb_column type=&#8221;4_4&#8243;][et_pb_text admin_label=&#8221;fasi vinificazione&#8221; background_layout=&#8221;light&#8221; text_orientation=&#8221;left&#8221;]<\/p>\n<ol>\n<li style=\"text-align: justify;\"><span style=\"color: #955251;\"><strong>PIGIATURA \/ DIRASPAPIGIATURA<\/strong><\/span> = deve essere sempre soffice per evitare un&#8217;eccessiva estrazione dei tannini, per questo sempre pi\u00f9 spesso la diraspatura \u00e8 realizzata contemporaneamente o prima della pigiatura. L&#8217;eliminazione dei raspi riduce la quantit\u00e0 di aromi erbacei e di alcol etilico assorbito durante la fermentazione.<\/li>\n<li style=\"text-align: justify;\"><strong><span style=\"color: #955251;\">MOSTO CON VINACCE<\/span> =\u00a0<\/strong>la macerazione \u00e8 il contatto delle bucce con il mosto liquido, che a poco a poco si trasforma in vino. Il tempo di macerazione \u00e8 un fattore fondamentale per permettere la dissoluzione dei pigmenti colorati e delle altre sostanze presenti nelle bucce.<\/li>\n<li style=\"text-align: justify;\"><strong><span style=\"color: #955251;\">TRATTAMENTI DEL MOSTO ED AGGIUNTA DI LIEVITI SELEZIONATI<\/span> =\u00a0<\/strong>dopo trattamenti ed eventuali correzioni, il mosto \u00e8 posto nei fermentatori in acciaio inossidabile.\u00a0Dopo l&#8217;addizione con i lieviti il mosto inizia a fermentare a contatto con le vinacce (bucce e vinaccioli).<\/li>\n<li style=\"text-align: justify;\"><strong><span style=\"color: #955251;\">FERMENTAZIONE CON MACERAZIONE<\/span> =\u00a0<\/strong>gestendo il tempo di macerazione si pu\u00f2 intervenire in modo diverso sull&#8217;estrazione, salvaguardando l&#8217;eleganza del prodotto finale. Nei primi giorni di contatto sono estratti soprattutto gli antociani che danno in pochi giorni colori molto intensi con spiccate tonalit\u00e0 di rosso rubino, viola o blu scuro. Nei giorni successivi parte dei pigmenti sono riassorbiti dalle bucce ed il colore si indebolisce un po&#8217; a vantaggio di una migliore <strong>estrazione dei polifenoli<\/strong> (influenzata da: tempo di contatto del mosto con le bucce, temperatura, rimontaggi, follature, presenza di anidride solforosa ed enzimi) totali e quindi di una maggiore struttura e gusto del vino. La fermentazione di alcuni vini rossi pu\u00f2 concludersi in barrique, dove il vino che si sta formando \u00e8 arricchito delle componenti aromatiche del legno. Molti vini rossi sono prodotti con una macerazione di 10-15 giorni, per quelli pi\u00f9 leggeri e da consumare giovani \u00e8 ridotta a 4-5 giorni, mentre solo pochi mosti sono lasciati macerare fino a 4 settimane (Langhe, Barolo). La temperatura elevata di fermentazione \u00e8 un altro fattore che aumenta la dissoluzione delle sostanze presenti nelle bucce ma non sempre mantiene la qualit\u00e0 del vino. Il compromesso si raggiunge intorno ai 25\u00b0C per i vini da bere giovani nei quali \u00e8 importante preservare gli aromi fruttati, 30 \u00b0C per i vini da invecchiamento, al fine di\u00a0non danneggiare i lieviti e non alterare le caratteristiche organolettiche del vino. Durante la fermentazione le vinacce formano in superficie uno strato compatto chiamato CAPPELLO che impedisce un buon contatto con la parte liquida. Per ovviare a questo inconveniente e favorire l&#8217;estrazione, il mosto \u00e8 rimescolato con la follatura o il rimontaggio. Alla met\u00e0 od alla fine della macerazione si toglie dal serbatoio tutta la parte liquida del mosto lasciando all&#8217;interno solo quella solida. Successivamente il liquido \u00e8 reinserito dall&#8217;alto o dal basso e rompe in modo completo il cappello formato dalle bucce. In questo modo si raggiunge il duplice obiettivo di ossigenare molto bene il mosto e di rimescolare le sostanze che possono essersi stratificate favorendo i processi di fermentazione e di estrazione. Mentre il mosto continua a fermentare i lieviti trasformano gli zuccheri in alcol etilico ed anidride carbonica, formano sostanze secondarie, il colore diventa pi\u00f9 intenso e molte componenti sono estratte e passano dalle bucce alla parte liquida. Dato che l&#8217;anidride carbonica fa ribollire il mosto, questo passaggio si chiama FERMENTAZIONE TUMULTUOSA.<\/li>\n<li style=\"text-align: justify;\"><strong><span style=\"color: #955251;\">SVINATURA<\/span> =\u00a0<\/strong>eliminazione di bucce e fecce di fermentazione, cellule morte di lievito, sostanze coagulate, sali e piccole particelle solide.<\/li>\n<li style=\"text-align: justify;\"><strong><span style=\"color: #955251;\">TORCHIATURA<\/span>\u00a0= <\/strong>procedimento delicato per l&#8217;asciugatura delle\u00a0vinacce, ancora imbibite di mosto-vino con presse orizzontali a membrana o torchi continui. Il processo deve essere delicato a discapito della resa per evitare un prodotto astringente ed acido.<\/li>\n<li style=\"text-align: justify;\"><span style=\"color: #955251;\"><strong>EVENTUALE FERMENTAZIONE MALOLATTICA<\/strong><\/span><\/li>\n<li style=\"text-align: justify;\"><strong><span style=\"color: #955251;\">MATURAZIONE IN ACCIAIO E\/O BOTTE<\/span> = <\/strong>serve per perfezionare l&#8217;equilibrio del vino<\/li>\n<li style=\"text-align: justify;\"><span style=\"color: #955251;\"><strong>TRAVASI<\/strong><\/span><\/li>\n<li style=\"text-align: justify;\"><span style=\"color: #955251;\"><strong>CORREZIONI \/ STABILIZZAZIONE<\/strong><\/span><\/li>\n<li style=\"text-align: justify;\"><span style=\"color: #955251;\"><strong>IMBOTTIGLIAMENTO<\/strong><\/span><\/li>\n<li style=\"text-align: justify;\"><span style=\"color: #955251;\"><strong>AFFINAMENTO<\/strong><\/span><\/li>\n<\/ol>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section admin_label=&#8221;section&#8221; fullwidth=&#8221;off&#8221; specialty=&#8221;off&#8221; transparent_background=&#8221;off&#8221; background_color=&#8221;#9dc6d8&#8243; allow_player_pause=&#8221;off&#8221; inner_shadow=&#8221;off&#8221; parallax=&#8221;off&#8221; parallax_method=&#8221;off&#8221;][et_pb_row admin_label=&#8221;row&#8221;][et_pb_column type=&#8221;4_4&#8243;][et_pb_text admin_label=&#8221;Testo&#8221; background_layout=&#8221;dark&#8221; text_orientation=&#8221;center&#8221;]<\/p>\n<h2 style=\"text-align: center;\">Ma perch\u00e9 \u00e8 cos\u00ec importante raffreddare il mosto?<\/h2>\n<p style=\"text-align: justify;\">La temperatura ottimale alla quale i lieviti svolgono la fermentazione oscilla tra i 15 e i 30 \u00b0C, con la produzione di composti secondari di buona qualit\u00e0. Se la temperatura \u00e8 pi\u00f9 bassa la loro azione \u00e8 inibita, mentre se \u00e8 troppo alta la fermentazione diventa incontrollabile e si penalizza l&#8217;eleganza del prodotto finale.<\/p>\n<p style=\"text-align: justify;\">La fermentazione alcolica produce energia che si libera sotto forma di calore che aumenta la temperatura fino a valori che danneggerebbero i profumi e la qualit\u00e0 del vino. Inoltre oltre i 37 \u00b0C l&#8217;azione dei lieviti \u00e8 bloccata e per questo \u00e8 fondamentale refrigerare il mosto, soprattutto nelle zone pi\u00f9 calde. L&#8217;alcol etilico non \u00e8 amico dei lieviti perch\u00e9 sopra il 15-16 % inibisce la loro attivit\u00e0 fermentativa, come pu\u00f2 accadere nei vini ottenuti da mosti molto ricchi in zucchero, ricavati da uve appassite od attaccate dalla muffa nobile. Ci sono diversi sistemi di raffreddamento:<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row admin_label=&#8221;row&#8221;][et_pb_column type=&#8221;1_3&#8243;][et_pb_blurb admin_label=&#8221;refrigerante&#8221; title=&#8221;LIQUIDO REFRIGERANTE&#8221; url_new_window=&#8221;off&#8221; use_icon=&#8221;off&#8221; icon_color=&#8221;#9dc6d8&#8243; use_circle=&#8221;off&#8221; circle_color=&#8221;#9dc6d8&#8243; use_circle_border=&#8221;off&#8221; circle_border_color=&#8221;#9dc6d8&#8243; icon_placement=&#8221;top&#8221; animation=&#8221;top&#8221; background_layout=&#8221;dark&#8221; text_orientation=&#8221;center&#8221; use_icon_font_size=&#8221;off&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<p style=\"text-align: justify;\">I\u00a0fermentatori in acciaio sono dotati di una doppia parete all&#8217;interno della quale circola una soluzione refrigerante che mantiene fredda la superficie delle pareti, mentre l&#8217;agitazione meccanica rompe il cappello delle vinacce e favorisce l&#8217;abbassamento della temperatura del mosto.<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243;][et_pb_blurb admin_label=&#8221;cappello sommerso&#8221; title=&#8221;CAPPELLO SOMMERSO&#8221; url_new_window=&#8221;off&#8221; use_icon=&#8221;off&#8221; icon_color=&#8221;#9dc6d8&#8243; use_circle=&#8221;off&#8221; circle_color=&#8221;#9dc6d8&#8243; use_circle_border=&#8221;off&#8221; circle_border_color=&#8221;#9dc6d8&#8243; icon_placement=&#8221;top&#8221; animation=&#8221;top&#8221; background_layout=&#8221;dark&#8221; text_orientation=&#8221;center&#8221;]<\/p>\n<p style=\"text-align: justify;\">La fermentazione \u00e8 svolta a CAPPELLO SOMMERSO con un diagramma forato che tiene il cappello delle vinacce sotto il livello del liquido in modo da favorirne il contatto con il vino che sta nascendo incentivando l&#8217;estrazione dei polifenoli e delle altre sostanze.<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243;][et_pb_blurb admin_label=&#8221;rimontaggio&#8221; title=&#8221;RIMONTAGGIO&#8221; url_new_window=&#8221;off&#8221; use_icon=&#8221;off&#8221; icon_color=&#8221;#9dc6d8&#8243; use_circle=&#8221;off&#8221; circle_color=&#8221;#9dc6d8&#8243; use_circle_border=&#8221;off&#8221; circle_border_color=&#8221;#9dc6d8&#8243; icon_placement=&#8221;top&#8221; animation=&#8221;top&#8221; background_layout=&#8221;dark&#8221; text_orientation=&#8221;center&#8221;]<\/p>\n<p style=\"text-align: justify;\">Parte del prodotto \u00e8 spillato dalla parte inferiore del fermentatore attraverso un tubo esterno, fatto ricircolare e spruzzato sullo strato solido. Si favorisce il ricambio del liquido a contatto con le bucce e si rende omogenea e si ossigena la massa e si ridistribuiscono i lieviti.<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section admin_label=&#8221;section&#8221; transparent_background=&#8221;off&#8221; background_color=&#8221;#ffffff&#8221; allow_player_pause=&#8221;off&#8221; inner_shadow=&#8221;off&#8221; parallax=&#8221;off&#8221; parallax_method=&#8221;off&#8221;][et_pb_row admin_label=&#8221;row&#8221;][et_pb_column type=&#8221;1_2&#8243;][et_pb_blurb admin_label=&#8221;macerazione carbonica&#8221; title=&#8221;Macerazione Carbonica&#8221; url_new_window=&#8221;off&#8221; use_icon=&#8221;off&#8221; icon_color=&#8221;#9dc6d8&#8243; use_circle=&#8221;off&#8221; circle_color=&#8221;#9dc6d8&#8243; use_circle_border=&#8221;off&#8221; circle_border_color=&#8221;#9dc6d8&#8243; icon_placement=&#8221;top&#8221; animation=&#8221;top&#8221; background_layout=&#8221;light&#8221; text_orientation=&#8221;center&#8221; image=&#8221;http:\/\/perlagesuite.com\/wp-content\/uploads\/2015\/03\/vino-novello.jpg&#8221; use_icon_font_size=&#8221;off&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<p style=\"text-align: justify;\">La macerazione carbonica si applica prima della vinificazione vera e propria. I grappoli interi sono posti in vasche sature di CO2, dove sono lasciati per periodi compresi tra 5-10 giorni a circa 30 \u00b0C per favorire la produzione di sostanze profumate e di glicerina, la migrazione di pigmenti ed altri componenti dalla buccia alla polpa e la demolizione di parte dell&#8217;acido malico. Per evitare pericolose ossidazioni si aggiunge anidride solforosa. Queste condizioni favoriscono una parziale fermentazione intracellulare, senza l&#8217;intervento dei lieviti che saranno aggiunti solo dopo. La fermentazione alcolica sar\u00e0 poi veloce, da 2 a 4 giorni e i vini avranno colori intensi e molto vivaci, profumi floreali, fruttati e vinosi, saranno freschi ma gi\u00e0 equilibrati, con tannini delicati ed inadatti all&#8217;invecchiamento. Per questo i novelli sono gli unici vini ad essere messi in commercio cos\u00ec presto, a partire dal 6 novembre dello stesso anno della vendemmia che deve essere riportato sull&#8217;etichetta.<\/p>\n<p style=\"text-align: justify;\">Il <em><strong>Beaujolais Nouveau<\/strong><\/em> \u00e8 il vino novello francese che prende il nome dalla zona di produzione, Beaujolais. I francesi inventarono questa tipologia di vino nel 1934 durante un esperimento che prevedeva la conservazione dei grappoli in anidride carbonica. Dopo un paio di mesi si accorsero che i grappoli erano diventati gassosi e frizzanti, con un sapore molto particolare. Dato che questi grappoli non erano pi\u00f9 adatti per la commercializzazione decisero di vinificarli ed ottennero un vino &#8220;diverso&#8221; ma molto interessante.<\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243;][et_pb_blurb admin_label=&#8221;rosati&#8221; title=&#8221;Vini Rosati&#8221; url_new_window=&#8221;off&#8221; use_icon=&#8221;off&#8221; icon_color=&#8221;#9dc6d8&#8243; use_circle=&#8221;off&#8221; circle_color=&#8221;#9dc6d8&#8243; use_circle_border=&#8221;off&#8221; circle_border_color=&#8221;#9dc6d8&#8243; icon_placement=&#8221;top&#8221; animation=&#8221;top&#8221; background_layout=&#8221;light&#8221; text_orientation=&#8221;center&#8221; image=&#8221;http:\/\/perlagesuite.com\/wp-content\/uploads\/2015\/03\/vino-rosato.jpg&#8221; use_icon_font_size=&#8221;off&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<p style=\"text-align: justify;\">I sistemi per produrre vini rosati sono diversi, anche se quello pi\u00f9 usato \u00e8 quello che prevede una breve macerazione delle vinacce nella parte liquida del mosto. Un&#8217;alternativa \u00e8 quella di utilizzare uve a bacca nera poco pigmentate e povere di tannini, oppure si pu\u00f2 mescolare un uvaggio uve a bacca nera e bianca. Non si pu\u00f2 miscelare un vino rosso ad un vino bianco! A dispetto del colore ed a prescindere dal sistema impiegato, \u00a0i vini rosati hanno caratteristiche organolettiche pi\u00f9 vicine a quelle dei vini bianchi. Sono destinati ad essere apprezzati in giovent\u00f9, grazie anche alle belle tonalit\u00e0 di colore, ai profumi delicati e fragranti ed alla freschezza dei sapori.<\/p>\n<p style=\"text-align: justify;\">I\u00a0<strong><i>vin gris<\/i><\/strong>\u00a0sono vini dal colore rosa piuttosto tenue. I vini grigi sono prodotti utilizzando le stesse procedure enologiche previste per i vini bianchi in cui l&#8217;unica differenza \u00e8 rappresentata dall&#8217;impiego di uve con capacit\u00e0 colorante molto bassa, come per esempio il Cinsaut Rose, Cinsaut Gris e Cinsaut.<\/p>\n<p style=\"text-align: justify;\">\u00a0I\u00a0<strong><i>blush wines<\/i><\/strong>\u00a0sono diventati celebri negli Stati Uniti prevalentemente grazie al fenomeno del White Zinfandel, prodotto con uva Zinfandel, notoriamente a bacca rossa, utilizzando le normali pratiche enologiche previste per i vini bianchi. Hanno un gusto abboccato ed una lieve effervescenza. In California alcune cantine producono\u00a0<i>blush wines<\/i>\u00a0secchi e maturati in botte e che tipicamente sono noti con il nome di\u00a0<i>vin gris<\/i>.<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PIGIATURA \/ DIRASPAPIGIATURA = deve essere sempre soffice per evitare un&#8217;eccessiva estrazione dei tannini, per questo sempre pi\u00f9 spesso la diraspatura \u00e8 realizzata contemporaneamente o prima della pigiatura. L&#8217;eliminazione dei raspi riduce la quantit\u00e0 di aromi erbacei e di alcol etilico assorbito durante la fermentazione. MOSTO CON VINACCE =\u00a0la macerazione \u00e8 il contatto delle bucce [&hellip;]<\/p>\n","protected":false},"author":49,"featured_media":744,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"project_category":[],"project_tag":[],"class_list":["post-1597","project","type-project","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.0 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Vinificazione in rosso - Perlage Suite<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/perlagesuite.com\/en\/project\/vinificazione-in-rosso\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vinificazione in rosso\" \/>\n<meta property=\"og:description\" content=\"PIGIATURA \/ DIRASPAPIGIATURA = deve essere sempre soffice per evitare un&#039;eccessiva estrazione dei tannini, per questo sempre pi\u00f9 spesso la diraspatura \u00e8 realizzata contemporaneamente o prima della pigiatura. L&#039;eliminazione dei raspi riduce la quantit\u00e0 di aromi erbacei e di alcol etilico assorbito durante la fermentazione. MOSTO CON VINACCE =\u00a0la macerazione \u00e8 il contatto delle bucce [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/perlagesuite.com\/en\/project\/vinificazione-in-rosso\/\" \/>\n<meta property=\"og:site_name\" content=\"Perlage Suite\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/chiarabassiperlagesuite\" \/>\n<meta property=\"article:modified_time\" content=\"2018-05-26T16:06:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/perlagesuite.com\/wp-content\/uploads\/2014\/11\/consistenza-vino-rosso.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"371\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@perlagesuite\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/project\\\/vinificazione-in-rosso\\\/\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/project\\\/vinificazione-in-rosso\\\/\",\"name\":\"Vinificazione in rosso - Perlage Suite\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/project\\\/vinificazione-in-rosso\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/project\\\/vinificazione-in-rosso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/consistenza-vino-rosso.jpg\",\"datePublished\":\"2015-03-08T22:19:13+00:00\",\"dateModified\":\"2018-05-26T16:06:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/project\\\/vinificazione-in-rosso\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/perlagesuite.com\\\/project\\\/vinificazione-in-rosso\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/project\\\/vinificazione-in-rosso\\\/#primaryimage\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/consistenza-vino-rosso.jpg\",\"contentUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/consistenza-vino-rosso.jpg\",\"width\":600,\"height\":371},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/project\\\/vinificazione-in-rosso\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/perlagesuite.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Progetti\",\"item\":\"https:\\\/\\\/perlagesuite.com\\\/project\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Vinificazione in rosso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#website\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/\",\"name\":\"Perlage Suite\",\"description\":\"Il Wine Blog di Chiara Bassi\",\"publisher\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/perlagesuite.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#organization\",\"name\":\"Chiara Bassi\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Chiara-Bassi-sommelier-wine-blogger-logo.png\",\"contentUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Chiara-Bassi-sommelier-wine-blogger-logo.png\",\"width\":512,\"height\":512,\"caption\":\"Chiara Bassi\"},\"image\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/chiarabassiperlagesuite\",\"https:\\\/\\\/x.com\\\/perlagesuite\",\"https:\\\/\\\/www.instagram.com\\\/perlagesuite\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Red wine vinification - Perlage Suite","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/perlagesuite.com\/en\/project\/vinificazione-in-rosso\/","og_locale":"en_GB","og_type":"article","og_title":"Vinificazione in rosso","og_description":"PIGIATURA \/ DIRASPAPIGIATURA = deve essere sempre soffice per evitare un'eccessiva estrazione dei tannini, per questo sempre pi\u00f9 spesso la diraspatura \u00e8 realizzata contemporaneamente o prima della pigiatura. L'eliminazione dei raspi riduce la quantit\u00e0 di aromi erbacei e di alcol etilico assorbito durante la fermentazione. MOSTO CON VINACCE =\u00a0la macerazione \u00e8 il contatto delle bucce [&hellip;]","og_url":"https:\/\/perlagesuite.com\/en\/project\/vinificazione-in-rosso\/","og_site_name":"Perlage Suite","article_publisher":"https:\/\/www.facebook.com\/chiarabassiperlagesuite","article_modified_time":"2018-05-26T16:06:57+00:00","og_image":[{"width":600,"height":371,"url":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2014\/11\/consistenza-vino-rosso.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@perlagesuite","twitter_misc":{"Estimated reading time":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/perlagesuite.com\/project\/vinificazione-in-rosso\/","url":"https:\/\/perlagesuite.com\/project\/vinificazione-in-rosso\/","name":"Red wine vinification - Perlage Suite","isPartOf":{"@id":"https:\/\/perlagesuite.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/perlagesuite.com\/project\/vinificazione-in-rosso\/#primaryimage"},"image":{"@id":"https:\/\/perlagesuite.com\/project\/vinificazione-in-rosso\/#primaryimage"},"thumbnailUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2014\/11\/consistenza-vino-rosso.jpg","datePublished":"2015-03-08T22:19:13+00:00","dateModified":"2018-05-26T16:06:57+00:00","breadcrumb":{"@id":"https:\/\/perlagesuite.com\/project\/vinificazione-in-rosso\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/perlagesuite.com\/project\/vinificazione-in-rosso\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/perlagesuite.com\/project\/vinificazione-in-rosso\/#primaryimage","url":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2014\/11\/consistenza-vino-rosso.jpg","contentUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2014\/11\/consistenza-vino-rosso.jpg","width":600,"height":371},{"@type":"BreadcrumbList","@id":"https:\/\/perlagesuite.com\/project\/vinificazione-in-rosso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/perlagesuite.com\/"},{"@type":"ListItem","position":2,"name":"Progetti","item":"https:\/\/perlagesuite.com\/project\/"},{"@type":"ListItem","position":3,"name":"Vinificazione in rosso"}]},{"@type":"WebSite","@id":"https:\/\/perlagesuite.com\/#website","url":"https:\/\/perlagesuite.com\/","name":"Perlage Suite","description":"Chiara Bassi's Wine Blog","publisher":{"@id":"https:\/\/perlagesuite.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/perlagesuite.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/perlagesuite.com\/#organization","name":"Chiara Bassi","url":"https:\/\/perlagesuite.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/perlagesuite.com\/#\/schema\/logo\/image\/","url":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2022\/03\/Chiara-Bassi-sommelier-wine-blogger-logo.png","contentUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2022\/03\/Chiara-Bassi-sommelier-wine-blogger-logo.png","width":512,"height":512,"caption":"Chiara Bassi"},"image":{"@id":"https:\/\/perlagesuite.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/chiarabassiperlagesuite","https:\/\/x.com\/perlagesuite","https:\/\/www.instagram.com\/perlagesuite\/"]}]}},"_links":{"self":[{"href":"http:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/project\/1597","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/project"}],"about":[{"href":"http:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/types\/project"}],"author":[{"embeddable":true,"href":"http:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"http:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/comments?post=1597"}],"version-history":[{"count":0,"href":"http:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/project\/1597\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/media\/744"}],"wp:attachment":[{"href":"http:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/media?parent=1597"}],"wp:term":[{"taxonomy":"project_category","embeddable":true,"href":"http:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/project_category?post=1597"},{"taxonomy":"project_tag","embeddable":true,"href":"http:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/project_tag?post=1597"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}