{"id":12211,"date":"2019-03-08T18:31:33","date_gmt":"2019-03-08T17:31:33","guid":{"rendered":"https:\/\/perlagesuite.com\/?p=12211"},"modified":"2019-05-24T20:17:16","modified_gmt":"2019-05-24T19:17:16","slug":"stelle-calici-vini-liguri-e-prodotti-locali-con-lo-chef-gian-piero-vivalda","status":"publish","type":"post","link":"https:\/\/perlagesuite.com\/en\/stelle-calici-vini-liguri-e-prodotti-locali-con-lo-chef-gian-piero-vivalda\/","title":{"rendered":"Stars &amp; Goblets: Ligurian wines and local products with Chef Gian Piero Vivalda"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;3.19.18&#8243;][et_pb_row _builder_version=&#8221;3.19.18&#8243;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.19.18&#8243;][et_pb_text _builder_version=&#8221;3.19.18&#8243;]<\/p>\n<p style=\"text-align: justify;\">Sembra ieri che sono stata per la prima volta in <strong>Liguria<\/strong>&#8230; invece sono gi\u00e0 passati pi\u00f9 di 4 mesi e sono successe tantissime cose. Ho conosciuto tante persone meravigliose che ruotano attorno al mondo di <strong>Stelle &amp; Calici<\/strong> e, in particolare, a <strong>Vite in Riviera <\/strong>[in foto il simpaticissimo gestore Gianni Boffredo, attendo che si stampa anche questo articolo dato che ho scelto proprio la nostra foto come copertina!]. Ho avuto l&#8217;occasione di assaggiare tanti <strong>prodotti liguri eccellenti<\/strong>, spesso anche <strong>Presidi Slow Food<\/strong>. Ho conosciuto cantine nuove e avuto nuove conferme da cantine che gi\u00e0 conoscevo perch\u00e9 mi avevano mandato i campioni dei loro vini nell&#8217;ultimo anno. Ho avuto modo di conoscere nuovi amici e riabbracciarne di &#8220;vecchi&#8221;. Ma soprattutto <strong>ho avuto l&#8217;opportunit\u00e0 di scoprire la cucina stellata di 3 chef Michelin&#8230; e questa sera \u00e8 il turno di Gian Piero Vivalda!\u00a0<\/strong><img decoding=\"async\" draggable=\"false\" class=\"emoji\" alt=\"\ud83d\ude0d\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/11\/svg\/1f60d.svg\" \/><\/p>\n<blockquote>\n<p style=\"text-align: justify;\"><strong>Stelle &amp; Calici<\/strong><span> \u00e8 una bellissima idea della rete d\u2019imprese \u201c<\/span><strong>Vite in Riviera<\/strong><span>\u201c. Nata nel 2015, raggruppa 25 aziende vitivinicole e olivicole della Riviera di Ponente, rendendole pi\u00f9 forti e competitive nella penetrazione del mercato ed \u00e8 una realt\u00e0 unica nella regione Liguria (e non solo l\u00ec!). <\/span><strong>Stelle &amp; Calici \u00e8 un viaggio gourmet tra i sapori della Liguria che si articola in 4 cene dove le eccellenze gastronomiche regionali di stagione e i presidi Slow Food sono interpretati da 4 chef stellati Michelin \u201cfuori sede\u201d e abbinati a vini DOP e IGP della Riviera di Ponente<\/strong><span>. E gi\u00e0 cos\u00ec, non ti solletica l\u2019idea di partecipare all&#8217;ultima tappa? Ci facciamo un bel brindisi insieme con lo <strong>spumante Pigan\u00f2 dei Viticoltori Ingauni<\/strong>?\u00a0<\/span><img decoding=\"async\" draggable=\"false\" class=\"emoji\" alt=\"\ud83d\ude0d\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/11\/svg\/1f60d.svg\" \/><\/p>\n<\/blockquote>\n<p>[\/et_pb_text][et_pb_image box_shadow_style=&#8221;preset3&#8243; animation_style=&#8221;zoom&#8221; src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2019\/03\/vite-in-riviera-gian-piero-vivalda-foto-eunice-brovida-4.jpg&#8221; _builder_version=&#8221;3.19.18&#8243;][\/et_pb_image][et_pb_text _builder_version=&#8221;3.19.18&#8243;]<\/p>\n<p style=\"text-align: justify;\">Stupenda questa foto di <strong>Eunice Brovida<\/strong> che ritrae, da sinistra, lo <strong>Chef Gian Piero Vivalda<\/strong>, <strong>Massimo Enrico<\/strong> (presidente di Vite in Riviera) e lo Chef <strong>Fabrizio Barontini<\/strong>.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;3.19.18&#8243;][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;3.19.18&#8243;][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2019\/03\/vite-in-riviera-stelle-e-calici-chef-gian-piero-vivalda-viaggio.jpg&#8221; _builder_version=&#8221;3.19.18&#8243; box_shadow_style=&#8221;preset3&#8243; animation_style=&#8221;zoom&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;3.19.18&#8243;][et_pb_text _builder_version=&#8221;3.19.18&#8243;]<\/p>\n<h3 style=\"text-align: justify;\">Vite in Riviera, Stelle e Calici &#8211; Il viaggio<\/h3>\n<p style=\"text-align: justify;\">Solo per questa volta sono andata in Liguria in treno&#8230; urgeva il servizio taxi di <strong>Morris nella sua bellissima Fiat 500 gialla<\/strong>! Durante il viaggio ci siamo divertiti a creare una serie di storie su Instagram&#8230; le hai viste?<\/p>\n<p style=\"text-align: justify;\">Che bella la linea ferroviaria che costeggia il. Mar Ligure! Un piacere percorrerla in una bellissima giornata di sole! Anche se per arrivarci \u00e8 stata lunga, molto lunga&#8230; Per fortuna abbiamo fatto una tappa all&#8217;<strong>agriturismo BioVio<\/strong> prima della cena per una ristoratrice <strong>merenda a base di torta di nocciole e caff\u00e8<\/strong>. Poi una bella doccia&#8230; e via all&#8217;aperitivo preparato dallo chef <strong>Fabrizio Barontini<\/strong>!\ud83d\ude0b<\/p>\n<p style=\"text-align: justify;\">\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;3.19.18&#8243;][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;3.19.18&#8243;][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2019\/03\/vite-in-riviera-stelle-e-calici-chef-gian-piero-vivalda.jpg&#8221; _builder_version=&#8221;3.19.18&#8243; box_shadow_style=&#8221;preset3&#8243; animation_style=&#8221;zoom&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;3.19.18&#8243;][et_pb_text _builder_version=&#8221;3.19.18&#8243;]<\/p>\n<h3 style=\"text-align: justify;\">Vite in Riviera, Stelle e Calici &#8211; Chef Gian Piero Vivalda<\/h3>\n<p style=\"text-align: justify;\">Ma chi \u00e8 lo <strong>Chef Gian Piero Vivalda<\/strong>, che ha conquistato la seconda stella Michelin nel suo ristorante <strong>Antica Corona Reale a Cervere<\/strong>, in provincia di Cuneo?<\/p>\n<blockquote>\n<p style=\"text-align: justify;\"><span style=\"font-size: 17px;\">Storico indirizzo Relais&amp;Chateaux tra Langhe e Monviso che nel 2016 ha celebrato il suo duecentesimo anniversario, il ristorante gestito da cinque generazioni\u00a0 dalla famiglia Vivalda nasce come cascina, per ottenere \u2013 poi \u2013 con il nuovo millennio i riconoscimenti culinari che tutti conoscono. Lo chef-patron Gian Piero, con trascorsi da Georges Blanc e Alain Ducasse, d\u00e0 vita a dei menu vocati all&#8217;eccellenza, proponendo una cucina colorata, profumata, trasparente e contraddistinta da esecuzioni di alto livello. La maison diventa presto un riferimento per gourmet italiani ed internazionali, ma anche per numerose aziende legate al territorio che gli forniscono capponi, faraone, vitelli, peperoni di Carmagnola, funghi porcini, e tanto ancora. [Ispettore Guida Michelin]<\/span><\/p>\n<\/blockquote>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;3.19.18&#8243;][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;3.19.18&#8243;][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2019\/03\/vite-in-riviera-stelle-e-calici-chef-gian-piero-vivalda-menu.jpg&#8221; _builder_version=&#8221;3.19.18&#8243; box_shadow_style=&#8221;preset3&#8243; animation_style=&#8221;zoom&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;3.19.18&#8243;][et_pb_text _builder_version=&#8221;3.19.18&#8243;]<\/p>\n<h3 style=\"text-align: justify;\">Vite in Riviera, Stelle e Calici &#8211; Il menu del 28 febbraio\/1 marzo<\/h3>\n<p style=\"text-align: justify;\">Ho trovato questo men\u00f9 il pi\u00f9 ben riuscito da un punto di vista della sua architettura. Leggendo i piatti si intrecciano <strong>ingredienti liguri e preparazioni piemontesi.<\/strong>.. e subito mi \u00e8 caduto l&#8217;occhio sulla <strong>finanziera, che amo follemente!<\/strong><\/p>\n<p style=\"text-align: justify;\">Il <strong>carciofo Spinoso d&#8217;Albenga<\/strong>, conosciuto anche come Violetto d&#8217;Albenga, \u00e8 un delizioso carciofo che ha la caratteristica di essere particolarmente tenero e di avere una spiccata tendenza dolce. I <strong>gamberi rossi di Oneglia<\/strong> sono deliziosi soprattutto crudi&#8230; e succhiare la testa dai riflessi violacei per me \u00e8 un&#8217;esperienza unica! Le <strong>olive taggiasche<\/strong> credo siano uno degli ingredienti liguri pi\u00f9 famosi&#8230; impossibile non amarle! Il <strong>tartufo nero della Val Pennavaire<\/strong> \u00e8 un&#8217;altra eccellenza di confine tra la Liguria e il Piemonte.\u00a0Il <strong>coniglio grigio di Carmagnola<\/strong> \u00e8 una razza tradizionale piemontese che deve il suo colore grazie al suo parente cincill\u00e0 di taglia media. Ha ottima resa, con tanti muscoli e carni tenere e poco stoppose. Il <strong>capretto di Roccaverano<\/strong> \u00e8 un altro delizioso ingrediente piemontese della zona delle Langhe. Il <strong>chinotto di Savona<\/strong> \u00e8 un Presidio Slow Food che consumerei ogni ora del giorno!\u00a0<span>Un tempo i chinotti si candivano con un procedimento lungo e laborioso che partiva dall\u2019acqua di mare, dove erano immersi per diverse settimane. \u00a0 Storicamente i chinotti nel maraschino erano considerati un delizioso digestivo che trovava posto sui banchi di bar italiani e francesi.\u00a0Perch\u00e9 ora non si usa pi\u00f9???<\/span><\/p>\n<p style=\"text-align: justify;\">\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;3.19.18&#8243;][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;3.19.18&#8243;][et_pb_gallery gallery_ids=&#8221;12273,12261,12263,12265,12267,12269,12271&#8243; fullwidth=&#8221;on&#8221; _builder_version=&#8221;3.19.18&#8243; box_shadow_style=&#8221;preset3&#8243; animation_style=&#8221;zoom&#8221; auto=&#8221;on&#8221; auto_speed=&#8221;2800&#8243;][\/et_pb_gallery][\/et_pb_column][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;3.19.18&#8243;][et_pb_text _builder_version=&#8221;3.19.18&#8243;]<\/p>\n<h3 style=\"text-align: justify;\">Vite in Riviera, Stelle e Calici &#8211; L&#8217;aperitivo dello Chef Fabrizio Barontini<\/h3>\n<p style=\"text-align: justify;\">Sicuramente \u00e8 stata la performance migliore tra tutti gli aperitivi di Stelle &amp; Calici. Era tutto delizioso e non saprei indicarti cosa ho gradito maggiormente. Forse il <strong>baccal\u00e0<\/strong>? Forse i <strong>paninetti con i mini hamburger di ceci e la salsa di cipolle rosse caramellate<\/strong>? Bellissima poi l&#8217;idea di valorizzare tutto con i fiori eduli, che non danno solo colore ma anche sapore&#8230;\u00a0<span>Lenticchia Carciofi e Begonia &#8211; Piselli, Caviale del Centa &#8211; Oliva Pomodoro e Agerato celestino, Polenta Baccal\u00e0 e Viola &#8211; Ceci Seppie nasturzio.<\/span><\/p>\n<p style=\"text-align: justify;\">Certo \u00e8 che lo <strong>spumante Pigan\u00f2 dei Viticoltori Ingauni<\/strong> si \u00e8 abbinato benissimo a tutti&#8230; sgrassando alla perfezione e valorizzando i gusti delicati elaborati dallo chef. Giallo paglierino, perlage fine e numeroso, con note di cedro e mango al naso e un gusto sapido e molto fresco.<\/p>\n<p style=\"text-align: justify;\">\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;3.19.18&#8243;][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;3.19.18&#8243;][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2019\/03\/vite-in-riviera-stelle-e-calici-chef-vivalda-gamberi-rossi-oneglia.jpg&#8221; _builder_version=&#8221;3.19.18&#8243; box_shadow_style=&#8221;preset3&#8243; animation_style=&#8221;zoom&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;3.19.18&#8243;][et_pb_text _builder_version=&#8221;3.19.18&#8243;]<\/p>\n<h3 style=\"text-align: justify;\">Chef Gian Piero Vivalda &#8211; l&#8217;antipasto: Martini di seppie del Golfo Ligure, carciofi Spina d&#8217;Albenga e Gamberi rossi di Oneglia<\/h3>\n<p style=\"text-align: justify;\"><strong>La seppia \u00e8 lavorata ad arte<\/strong>&#8230; e non \u00e8 per niente scontato neanche per uno chef del livello di Vivalda. <strong>I carciofi fritti sono perfetti e deliziosi.<\/strong> La purea di carciofo amalgama i sapori&#8230; buonissima. <strong>I gamberi rossi di Oneglia li avrei tanto tanto voluti crudi<\/strong>&#8230; anche se capisco che non \u00e8 facile inserire un crudo in un menu per cos\u00ec tante persone perch\u00e9 non a tutti piace. In abbinamento due <strong>vini Pigato RLP DOC 2017: Torre Pernice<\/strong> (di cui ti ho gi\u00e0 parlato nel mio scorso articolo che ti invito a leggere <a href=\"https:\/\/perlagesuite.com\/stelle-calici-vini-liguri-e-prodotti-locali-con-lo-chef-igles-corelli\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"text-decoration: underline;\"><strong>QUI<\/strong><\/span><\/a>) e <strong>Cantine Calleri<\/strong>. Si presenta giallo paglierino cristallino e consistente. Al naso \u00e8 molto citrino, iodato e salmastro, con piacevoli note di idrocarburi ed erbe aromatiche. In bocca ha una pseudocalorica presente, ma \u00e8 comunque fresco, piacevolmente grasso e lungo.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;3.19.18&#8243;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.19.18&#8243;][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2019\/03\/vite-in-riviera-stelle-e-calici-chef-vivalda-coniglio-grigio.jpg&#8221; _builder_version=&#8221;3.19.18&#8243; box_shadow_style=&#8221;preset3&#8243; animation_style=&#8221;zoom&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;3.19.18&#8243;]<\/p>\n<h3 style=\"text-align: justify;\">Chef Gian Piero Vivalda &#8211; il primo: Ravioli del plin di coniglio grigio, carciofo Spina d&#8217;Albenga e tartufo nero della Val Pennavaire<\/h3>\n<p style=\"text-align: justify;\">In assoluto <strong>il piatto pi\u00f9 riuscito della serata<\/strong>&#8230; e direi il primo pi\u00f9 riuscito di tutte le serate Stelle &amp; Calici fino ad oggi! La consistenza della pasta \u00e8 perfetta, il gusto del ripieno \u00e8 libidinoso, la purea di carciofi (la stessa dell&#8217;antipasto secondo me) \u00e8 sempre divina&#8230; e il tartufo \u00e8 lavorato in modo piacevolissimo. Tutti i sapori sono nitidi e molto equilibrati. In abbinamento due <strong>vini Rossese di Dolceacqua DOC<\/strong>. <strong>Ramoino<\/strong> ha un naso particolarmente interessante, intenso e speziato, con note di mirtilli, cacao, polvere di caff\u00e8. In bocca \u00e8 ancora intenso, morbido, elegante e freschissimo&#8230; nel complesso molto equilibrato. Ha un finale un po&#8217; ruvido (il tannino deve ancora arrotondarsi) piuttosto lungo. <strong>Foresti<\/strong> \u00e8 completamente diverso, gi\u00e0 dal colore che vira di pi\u00f9 sul granato. Sicuramente figlio di una vendemmia leggermente posticipata rispetto al primo, ha un olfatto pi\u00f9 ampio in cui alle note tostate e speziate si affiancano quelle di rosa essiccata, cuoio, ciliegia sotto spirito e frutta rossa in confettura. In bocca \u00e8 molto morbido ma comunque fresco, con un bel tannino e un finale piacevolissimo.<\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2019\/03\/vite-in-riviera-stelle-e-calici-chef-vivalda-capretto-di-roccaverano.jpg&#8221; _builder_version=&#8221;3.19.18&#8243; box_shadow_style=&#8221;preset3&#8243; animation_style=&#8221;zoom&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;3.19.18&#8243;]<\/p>\n<h3 style=\"text-align: justify;\">Chef Gian Piero Vivalda &#8211; il secondo: Capretto di Roccaverano allo spiedo d&#8217;ulivo, caponata d&#8217;inverno alle olive taggiasche e la sua finanziera<\/h3>\n<p style=\"text-align: justify;\">Ah, <strong>quanto amo la finanziera&#8230; e questa \u00e8 senza dubbio la pi\u00f9 buona che ho mai mangiato<\/strong>! Avrei leccato il fondo della pentola per almeno un&#8217;ora in un modo che neanche il mio volpino sarebbe riuscito! Discretamente tenero anche il capretto e deliziosa la sua versione &#8220;dorata&#8221;. In abbinamento abbiamo due <strong>vini \u00a0Granaccia RLP DOC 2015<\/strong> molto diversi tra loro. <strong>Shalok di Cantina Poggio dei Gorleri<\/strong> si presenta di un rosso rubino profondo e impenetrabile. Roteando il bicchiere forma archetti regolari e ravvicinatissimi che tradiscono il suo tenore alcolico elevato. Al naso si intrecciano note di inchiostro, sottobosco e marasca sotto spirito. In bocca \u00e8 rotondo, maturo, con note di frutta in confettura, spezie dolci. Un po&#8217; sbilanciata la pseudocalorica e un tannino ancora un po&#8217; aggressivo&#8230; ma comunque molto fresco e con un finale lunghissimo che vira al cacao. In bocca ha bisogno di ancora qualche mese di bottiglia per esprimersi al meglio. <strong>La granaccia di Innocenzo Turco<\/strong> \u00e8 completamente diversa&#8230; l&#8217;avevo gi\u00e0 assaggiata tra i campioni che mi avevano invitato a portare a casa la prima volta! Si presenta di un bel rosso rubino semi trasparente con riflessi granati. Al naso confettura di fragole, lamponi freschi, pepe bianco, rosa canina, pappa reale, cannella e noce moscata. In bocca \u00e8 spostato sulle durezze, molto sapido e con un tannino leggermente verde. Bella lunghezza finale.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;3.19.18&#8243;][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;3.19.18&#8243;][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2019\/03\/vite-in-riviera-stelle-e-calici-chef-gian-piero-vivalda-mousse-cioccolato.jpg&#8221; _builder_version=&#8221;3.19.18&#8243; box_shadow_style=&#8221;preset3&#8243; animation_style=&#8221;zoom&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;3.19.18&#8243;][et_pb_text _builder_version=&#8221;3.19.18&#8243;]<\/p>\n<h3 style=\"text-align: justify;\">Chef Gian Piero Vivalda &#8211; il dolce: Mousse di cioccolato bianco e chinotto di Savona<\/h3>\n<p style=\"text-align: justify;\">Che dolce straordinario! Chef Vivalda qui con me vince facile: mi drogo di cioccolato bianco quanto di chinotto di Savona&#8230; e se me li metti insieme godo in un modo indescrivibile! Buono, buonissimo! La gelatina di chinotto interna equilibrava con la sua tendenza amara la dolcezza del cioccolato bianco in maniera perfetta. In abbinamento il <strong>passito di Pigato 2010 de &#8220;La Vecchia Cantina&#8221;<\/strong> che ho trovato molto buono. Si presenta di un bel colore oro con riflessi ambra. Al naso note di zabaione, nocciola, caramello salato, noci di macadamia e pesca sciroppata. In bocca \u00e8 cos\u00ec sapido da avere quasi una tendenza marsalata. Grande struttura e grande lunghezza finale. Abbinamento perfetto grazie proprio alla sua sapidit\u00e0.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;3.19.18&#8243;][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;3.19.18&#8243;][et_pb_gallery gallery_ids=&#8221;12241,12239,12237,12231,12243,12233&#8243; fullwidth=&#8221;on&#8221; _builder_version=&#8221;3.19.18&#8243; box_shadow_style=&#8221;preset3&#8243; auto=&#8221;on&#8221; auto_speed=&#8221;2800&#8243;][\/et_pb_gallery][\/et_pb_column][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;3.19.18&#8243;][et_pb_text _builder_version=&#8221;3.19.18&#8243;]<\/p>\n<h3 style=\"text-align: justify;\">Vite in Riviera, Stelle e Calici &#8211; dopocena bolle ne abbiamo?<\/h3>\n<p style=\"text-align: justify;\">Vuoi non finire la cena con una bolla? Perfetta la scelta di Ramoino, con questo capolavoro de &#8220;La Vecchia Cantina&#8221; che non manca di farmi innamorare con il suo perlage cremosissimo, i suoi profumi citrini e mentolati e il suo equilibrio gusto-olfattivo. Non conosco la sboccatura&#8230; forse un po&#8217; recente, lo lascerei riposare ancora un po&#8217;.<\/p>\n<p style=\"text-align: justify;\">Tempo di riflessioni, foto, saluti, abbracci&#8230; dopo una cena di gran livello dove <strong>abbiamo mangiato divinamente e bevuto meglio<\/strong>. Il livello dei vini \u00e8 stato molto alto, non ho trovato note stonate&#8230; e fatico a dirti quale mi \u00e8 piaciuto di pi\u00f9. <strong>Gli abbinamenti sono stati tutti ben costruiti, con l&#8217;eccellenza sfiorata dai due Rossese di Dolceacqua con i ravioli del plin<\/strong>.<\/p>\n<p style=\"text-align: justify;\"><strong>Curatissimo il servizio dei ragazzi dell&#8217;Alberghiero Migliorini di Finale Ligure<\/strong>, che hanno soddisfatto ogni mia bizzarra richiesta sul servizio, sulle sputacchiere e sulle bottiglie.<\/p>\n<p style=\"text-align: justify;\">Questa volta <strong>era il turno dei sommelier della FISAR per il servizio in sala e devo dire che sono stati bravissimi e professionali<\/strong> anche se nelle spiegazioni dei vini sar\u00f2 sincera&#8230; <strong>la mancanza del delegato AIS di Imperia Augusto Manfredi io l&#8217;ho sentita tanto<\/strong>, tanto, tanto!<\/p>\n<p style=\"text-align: justify;\">\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;3.19.18&#8243;][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;3.19.18&#8243;][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2019\/03\/vite-in-riviera-stelle-e-calici-chef-gian-piero-vivalda-saluti.jpg&#8221; _builder_version=&#8221;3.19.18&#8243; box_shadow_style=&#8221;preset3&#8243; animation_style=&#8221;zoom&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;3.19.18&#8243;][et_pb_text _builder_version=&#8221;3.19.18&#8243;]<\/p>\n<h3 style=\"text-align: justify;\">Vite in Riviera, Stelle e Calici &#8211; uno spritz per salutarci!<\/h3>\n<p style=\"text-align: justify;\">Sar\u00e0 che ormai ci vediamo spesso, con chi pi\u00f9 e chi meno, ma \u00e8 sempre un piacere condividere queste belle esperienze con voi! Con i tre bravissimi instagrammers <strong>Adriano Amoretti, Matteo Franco e John Murnarne<\/strong> di <strong>@cantinasocial<\/strong> e con i miei cari colleghi blogger <strong>Patrizio Busa (tanninisetosi.it)<\/strong> e <strong>Morris Lazzoni<\/strong> <strong>(vinoperpassione.it)<\/strong>, il tempo non basta mai (e nemmeno da bere&#8230;). Ed eccoci quindi qui a fare l&#8217;ultimo brindisi prima di andare a dormire, questa volta a base di spritz preparato nell&#8217;unico bar di Ortovero aperto dopo una certa ora! Il barista mi ha guardato come un animale raro quando ho chiesto un Hugo&#8230;\u00a0<\/p>\n<p style=\"text-align: justify;\">Alla faccia di chi si fa le guerre e di chi non ha niente di meglio da fare di criticarsi&#8230; noi continuiamo a volerci bene&#8230; cheers!\u00a0\ud83e\udd42\ud83d\ude0d<\/p>\n<p style=\"text-align: justify;\">Se non mi venite a trovare prima nel mio adorato laghetto&#8230; appuntamento al 29 marzo per l&#8217;ultima tappa di Stelle &amp; Calici con lo Chef Marco Sacco (**Michelin).<\/p>\n<p style=\"text-align: justify;\">Mi \u00e8 dispiaciuto anche non salutare il mio vicino di tavolo e la sua dolce met\u00e0 in dolce attesa&#8230; un fenomeno di 24 anni che non conoscevo ma spero di rincontrare! Mi sono affascinata ormai alla loro storia d&#8217;amore&#8230; che bellini!! In bocca al lupo ragazzi!<\/p>\n<p style=\"text-align: justify;\">\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;3.19.18&#8243;][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;3.19.18&#8243;][et_pb_gallery gallery_ids=&#8221;12289,12291,12293&#8243; fullwidth=&#8221;on&#8221; _builder_version=&#8221;3.19.18&#8243; box_shadow_style=&#8221;preset3&#8243; auto=&#8221;on&#8221; auto_speed=&#8221;2800&#8243;][\/et_pb_gallery][\/et_pb_column][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;3.19.18&#8243;][et_pb_text _builder_version=&#8221;3.19.18&#8243;]<\/p>\n<h3 style=\"text-align: justify;\">Vite in Riviera, Stelle e Calici &#8211; ritorno al BioVio<\/h3>\n<p style=\"text-align: justify;\"><strong>Tornare all&#8217;agriturismo BioVio \u00e8 stato bellissimo<\/strong>. Sia chiaro, anche al Torre Pernice per la seconda tappa mi sono trovata davvero benissimo&#8230; ma com&#8217;\u00e8 che si dice? Il primo amore non si scorda mai! E nemmeno l&#8217;<strong>ospitalit\u00e0 di Chiara<\/strong> o le <strong>torte di sua figlia Carolina<\/strong>! A proposito&#8230; la torta alle nocciole del Piemonte con cui mi ha dato il benvenuto era a dir poco strepitosa&#8230; mi daresti la ricetta?\u00a0\ud83d\ude0d Questa volta ero in una stanza diversa dalla prima, al primo piano&#8230; davvero gigante e bellissima, quasi pi\u00f9 grande del mio appartamento (beh il soggiorno sicuramente pi\u00f9 grande\ud83d\ude01)! Le stanze hanno un comodissimo ascensore che entra direttamente in camera, e da come puoi vedere nelle foto \u00e8 stato fatto un lavoro di riqualificazione eccezionale!<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;3.19.18&#8243;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.19.18&#8243;][et_pb_image box_shadow_style=&#8221;preset3&#8243; animation_style=&#8221;zoom&#8221; src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2019\/03\/vite-in-riviera-gian-piero-vivalda-foto-eunice-brovida-1.jpg&#8221; _builder_version=&#8221;3.19.18&#8243;][\/et_pb_image][et_pb_text _builder_version=&#8221;3.19.18&#8243;]<\/p>\n<p style=\"text-align: justify;\">Insomma, anche la terza tappa del viaggio Stelle &amp; Calici organizzato da Vite in Riviera \u00e8 stata un&#8217;esperienza stupenda&#8230; non vedo l&#8217;ora che sia il 29 marzo per l&#8217;ultima tappa&#8230; anche se mi mancheranno questi soggiorni liguri! Sar\u00e0 il caso di organizzare ancora qualcosa di magico in Riviera? A proposito, ho deciso che stiler\u00f2 &#8220;il men\u00f9 perfetto&#8221; con i 4 piatti migliori di ogni serata&#8230; e anche con i 4 vini perfetti in abbinamento!<\/p>\n<p style=\"text-align: justify;\">Per ora ti svelo quella che \u00e8 la mia personale classifica dei piatti migliori, ovvero il mio &#8220;men\u00f9 combinato&#8221; costruito con un piatto di ogni chef secondo il mio personale indice di gradimento:<\/p>\n<p style=\"text-align: justify;\">\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;3.19.18&#8243;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;3.19.18&#8243;][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2019\/03\/vite-in-riviera-stelle-e-calici-chef-vivalda-coniglio-grigio.jpg&#8221; _builder_version=&#8221;3.19.18&#8243; box_shadow_style=&#8221;preset3&#8243; animation_style=&#8221;zoom&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;3.19.18&#8243;]<\/p>\n<p style=\"text-align: center;\">Stelle &amp; Calici, tappa 3 &#8211; primo<\/p>\n<p style=\"text-align: center;\"><strong>Chef Gian Piero Vivalda<\/strong><\/p>\n<p style=\"text-align: center;\">&#8220;Ravioli al plin di Coniglio Grigio, Carciofo spina d&#8217;Albenga e Tartufo Nero della Val Pennavaire&#8221;<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;3.19.18&#8243;][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2019\/02\/igles-corelli-vite-in-riviera-stelle-e-calici-vini-liguri-orneasco.jpg&#8221; _builder_version=&#8221;3.19.18&#8243; box_shadow_style=&#8221;preset3&#8243; animation_style=&#8221;zoom&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;3.19.18&#8243;]<\/p>\n<p style=\"text-align: center;\">Stelle &amp; Calici, tappa 2 &#8211; secondo<\/p>\n<p style=\"text-align: center;\"><strong>Chef Igles Corelli<\/strong><\/p>\n<p style=\"text-align: center;\">&#8220;Stinco e Pancia di Cabannina a maturazione spinta\u00a9 alle Visciole selvatiche e morbido di Sedano Rapa&#8221;<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;3.19.18&#8243;]<\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 17px;\"><\/span><a href=\"https:\/\/perlagesuite.com\/stelle-calici-vini-liguri-e-prodotti-locali-con-lo-chef-igles-corelli\/\" style=\"font-size: 17px;\"><span style=\"text-decoration: underline;\"><b>Leggi l&#8217;articolo QUI<\/b><\/span><\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;3.19.18&#8243;][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2018\/12\/stelle-e-calici-vini-liguri-riviera-di-ponente-7.jpg&#8221; _builder_version=&#8221;3.19.18&#8243; box_shadow_style=&#8221;preset3&#8243; animation_style=&#8221;zoom&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;3.19.18&#8243;]<\/p>\n<p style=\"text-align: center;\">Stelle &amp; Calici, tappa 1 &#8211; primo<\/p>\n<p style=\"text-align: center;\"><strong>Chef Tommaso Arrigoni<\/strong><\/p>\n<p style=\"text-align: center;\">&#8220;Crostata, crema di Limone, pera, cioccolato e cialda al cappero&#8221;<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;3.19.18&#8243;]<\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 17px;\"><\/span><a href=\"https:\/\/perlagesuite.com\/stelle-calici-1-tappa-vini-liguri-chef-stellati-liguria\/\" style=\"font-size: 17px;\"><span style=\"text-decoration: underline;\"><b>Leggi l&#8217;articolo QUI<\/b><\/span><\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;3.19.18&#8243;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.19.18&#8243;][et_pb_text _builder_version=&#8221;3.19.18&#8243;]<\/p>\n<p style=\"text-align: justify;\">Sar\u00e0 davvero l&#8217;antipasto il piatto della serata della quarta tappa?<\/p>\n<p style=\"text-align: justify;\">Riuscir\u00e0 lo<strong> Chef Marco Sacco del Ristorante Il Piccolo Lago (2 stelle Michelin)<\/strong> a confermare la mia idea di &#8220;menu combinato&#8221; perfetto??\u00a0\ud83d\ude0b<\/p>\n<p style=\"text-align: justify;\">Te lo racconto dopo il 29 marzo! Mi raccomando, ricordati di prenotare perch\u00e8 i posti sono limitatissimi e la serata del 28 marzo \u00e8 gi\u00e0 sold out!<\/p>\n<h4 style=\"text-align: justify;\">Hai mai degustato qualcuno di questi vini liguri? Hai mai assaggiato la cucina di uno di questi chef? Scrivimi in un commento qui sotto cosa ne pensi!<\/h4>\n<p>Cheers\u00a0\u2764\ud83c\udf77<\/p>\n<p>Chiara<\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][et_pb_image box_shadow_style=&#8221;preset3&#8243; animation_style=&#8221;zoom&#8221; src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2019\/03\/vite-in-riviera-gian-piero-vivalda-foto-eunice-brovida-2.jpg&#8221; _builder_version=&#8221;3.19.18&#8243;][\/et_pb_image][et_pb_text _builder_version=&#8221;3.19.18&#8243;]<\/p>\n<p style=\"text-align: justify;\">P.S. Morris, ma tu ti ricordi che cappero avevamo da ridere cos\u00ec?? Forse lo hai scritto nel tuo articolo su Vino per Passione&#8230; quindi se vi fa piacere andate subito a leggerlo cliccando <a href=\"https:\/\/www.vinoperpassione.com\/chef-vivalda-ospite-di-vite-in-riviera\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"text-decoration: underline;\"><strong>QUI<\/strong><\/span><\/a>.<\/p>\n<p style=\"text-align: justify;\">P.P.S. Per le foto pi\u00f9 belle, ovvero quelle senza il mio onnipresente logo, si ringrazia la fotografa Eunice Brovida. Per tutte le altre foto si ringrazia Sony Italia e <a href=\"https:\/\/universofoto.it\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"text-decoration: underline;\"><strong>UniversoFoto.it<\/strong><\/span><\/a> per avermi fornito il mio adorato gioiellino di macchina fotografica professionale compatta: la mitica <strong>Sony<\/strong>\u00a0<strong>RX100M4<\/strong>!<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;3.19.18&#8243;][et_pb_column type=&#8221;1_6&#8243; _builder_version=&#8221;3.19.18&#8243;][et_pb_code _builder_version=&#8221;3.19.18&#8243;]<iframe style=\"width:120px;height:240px;\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" frameborder=\"0\" src=\"\/\/rcm-eu.amazon-adsystem.com\/e\/cm?lt1=_blank&#038;bc1=000000&#038;IS2=1&#038;bg1=FFFFFF&#038;fc1=000000&#038;lc1=0000FF&#038;t=perlsuit-21&#038;language=it_IT&#038;o=29&#038;p=8&#038;l=as4&#038;m=amazon&#038;f=ifr&#038;ref=as_ss_li_til&#038;asins=8894307018&#038;linkId=6fd0567665a91c086c17a2d50b787199\"><\/iframe>[\/et_pb_code][\/et_pb_column][et_pb_column type=&#8221;1_6&#8243; _builder_version=&#8221;3.19.18&#8243;][et_pb_code _builder_version=&#8221;3.19.18&#8243;]<iframe style=\"width:120px;height:240px;\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" frameborder=\"0\" src=\"https:\/\/rcm-eu.amazon-adsystem.com\/e\/cm?ref=tf_til&#038;t=perlsuit-21&#038;m=amazon&#038;o=29&#038;p=8&#038;l=as1&#038;IS2=1&#038;asins=8862933169&#038;linkId=7c66ac8af1f053555c6af0bca523d86f&#038;bc1=FFFFFF&#038;lt1=_blank&#038;fc1=333333&#038;lc1=0066C0&#038;bg1=FFFFFF&#038;f=ifr\"><!-- [et_pb_line_break_holder] -->    <\/iframe>[\/et_pb_code][\/et_pb_column][et_pb_column type=&#8221;1_6&#8243; _builder_version=&#8221;3.19.18&#8243;][et_pb_code _builder_version=&#8221;3.19.18&#8243;]<iframe style=\"width:120px;height:240px;\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" frameborder=\"0\" src=\"https:\/\/rcm-eu.amazon-adsystem.com\/e\/cm?ref=tf_til&#038;t=perlsuit-21&#038;m=amazon&#038;o=29&#038;p=8&#038;l=as1&#038;IS2=1&#038;asins=B00005U2FA&#038;linkId=1010550a55e16f05f47ab6f6c8de5051&#038;bc1=FFFFFF&#038;lt1=_blank&#038;fc1=333333&#038;lc1=0066C0&#038;bg1=FFFFFF&#038;f=ifr\"><!-- [et_pb_line_break_holder] -->    <\/iframe>[\/et_pb_code][\/et_pb_column][et_pb_column type=&#8221;1_6&#8243; _builder_version=&#8221;3.19.18&#8243;][et_pb_code _builder_version=&#8221;3.19.18&#8243;]<iframe style=\"width:120px;height:240px;\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" frameborder=\"0\" src=\"https:\/\/rcm-eu.amazon-adsystem.com\/e\/cm?ref=tf_til&#038;t=perlsuit-21&#038;m=amazon&#038;o=29&#038;p=8&#038;l=as1&#038;IS2=1&#038;asins=B00AK4JSEU&#038;linkId=d6160178805bc285eac79f899e5bd6be&#038;bc1=FFFFFF&#038;lt1=_blank&#038;fc1=333333&#038;lc1=0066C0&#038;bg1=FFFFFF&#038;f=ifr\"><!-- [et_pb_line_break_holder] -->    <\/iframe>[\/et_pb_code][\/et_pb_column][et_pb_column type=&#8221;1_6&#8243; _builder_version=&#8221;3.19.18&#8243;][et_pb_code _builder_version=&#8221;3.19.18&#8243;]<iframe style=\"width:120px;height:240px;\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" frameborder=\"0\" src=\"https:\/\/rcm-eu.amazon-adsystem.com\/e\/cm?ref=tf_til&#038;t=perlsuit-21&#038;m=amazon&#038;o=29&#038;p=8&#038;l=as1&#038;IS2=1&#038;asins=B015RUJVYI&#038;linkId=69b4846bdd1fce8189ed7eb555b7fc41&#038;bc1=FFFFFF&#038;lt1=_blank&#038;fc1=333333&#038;lc1=0066C0&#038;bg1=FFFFFF&#038;f=ifr\"><!-- [et_pb_line_break_holder] -->    <\/iframe>[\/et_pb_code][\/et_pb_column][et_pb_column type=&#8221;1_6&#8243; _builder_version=&#8221;3.19.18&#8243;][et_pb_code _builder_version=&#8221;3.19.18&#8243;]<iframe style=\"width:120px;height:240px;\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" frameborder=\"0\" src=\"https:\/\/rcm-eu.amazon-adsystem.com\/e\/cm?ref=tf_til&#038;t=perlsuit-21&#038;m=amazon&#038;o=29&#038;p=8&#038;l=as1&#038;IS2=1&#038;asins=B001M8APXG&#038;linkId=8851659caf66698dea73e936823b2b16&#038;bc1=FFFFFF&#038;lt1=_blank&#038;fc1=333333&#038;lc1=0066C0&#038;bg1=FFFFFF&#038;f=ifr\"><!-- [et_pb_line_break_holder] -->    <\/iframe>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sembra ieri che sono stata per la prima volta in Liguria&#8230; invece sono gi\u00e0 passati pi\u00f9 di 4 mesi e sono successe tantissime cose. Ho conosciuto tante persone meravigliose che ruotano attorno al mondo di Stelle &amp; Calici e, in particolare, a Vite in Riviera [in foto il simpaticissimo gestore Gianni Boffredo, attendo che si [&hellip;]<\/p>\n","protected":false},"author":49,"featured_media":12313,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[298],"tags":[],"class_list":["post-12211","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-degustazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.0 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Stelle &amp; Calici: vini liguri e prodotti locali con lo Chef Gian Piero Vivalda - Perlage Suite<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/perlagesuite.com\/en\/stelle-calici-vini-liguri-e-prodotti-locali-con-lo-chef-gian-piero-vivalda\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Stelle &amp; Calici: vini liguri e prodotti locali con lo Chef Gian Piero Vivalda\" \/>\n<meta property=\"og:description\" content=\"Sembra ieri che sono stata per la prima volta in Liguria... invece sono gi\u00e0 passati pi\u00f9 di 4 mesi e sono successe tantissime cose. Ho conosciuto tante persone meravigliose che ruotano attorno al mondo di Stelle &amp; Calici e, in particolare, a Vite in Riviera [in foto il simpaticissimo gestore Gianni Boffredo, attendo che si [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/perlagesuite.com\/en\/stelle-calici-vini-liguri-e-prodotti-locali-con-lo-chef-gian-piero-vivalda\/\" \/>\n<meta property=\"og:site_name\" content=\"Perlage Suite\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/chiarabassiperlagesuite\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-08T17:31:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-24T19:17:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/perlagesuite.com\/wp-content\/uploads\/2019\/03\/vite-in-riviera-gian-piero-vivalda-foto-eunice-brovida-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"710\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Chiara Bassi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@perlagesuite\" \/>\n<meta name=\"twitter:site\" content=\"@perlagesuite\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Chiara Bassi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"18 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/stelle-calici-vini-liguri-e-prodotti-locali-con-lo-chef-gian-piero-vivalda\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/stelle-calici-vini-liguri-e-prodotti-locali-con-lo-chef-gian-piero-vivalda\\\/\"},\"author\":{\"name\":\"Chiara Bassi\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/person\\\/81b257517a1007c1a823318ac86c6013\"},\"headline\":\"Stelle &#038; Calici: vini liguri e prodotti locali con lo Chef Gian Piero Vivalda\",\"datePublished\":\"2019-03-08T17:31:33+00:00\",\"dateModified\":\"2019-05-24T19:17:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/stelle-calici-vini-liguri-e-prodotti-locali-con-lo-chef-gian-piero-vivalda\\\/\"},\"wordCount\":3578,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/stelle-calici-vini-liguri-e-prodotti-locali-con-lo-chef-gian-piero-vivalda\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/vite-in-riviera-gian-piero-vivalda-foto-eunice-brovida-3.jpg\",\"articleSection\":[\"Degustazioni\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/perlagesuite.com\\\/stelle-calici-vini-liguri-e-prodotti-locali-con-lo-chef-gian-piero-vivalda\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/stelle-calici-vini-liguri-e-prodotti-locali-con-lo-chef-gian-piero-vivalda\\\/\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/stelle-calici-vini-liguri-e-prodotti-locali-con-lo-chef-gian-piero-vivalda\\\/\",\"name\":\"Stelle & Calici: vini liguri e prodotti locali con lo Chef Gian Piero Vivalda - Perlage Suite\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/stelle-calici-vini-liguri-e-prodotti-locali-con-lo-chef-gian-piero-vivalda\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/stelle-calici-vini-liguri-e-prodotti-locali-con-lo-chef-gian-piero-vivalda\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/vite-in-riviera-gian-piero-vivalda-foto-eunice-brovida-3.jpg\",\"datePublished\":\"2019-03-08T17:31:33+00:00\",\"dateModified\":\"2019-05-24T19:17:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/stelle-calici-vini-liguri-e-prodotti-locali-con-lo-chef-gian-piero-vivalda\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/perlagesuite.com\\\/stelle-calici-vini-liguri-e-prodotti-locali-con-lo-chef-gian-piero-vivalda\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/stelle-calici-vini-liguri-e-prodotti-locali-con-lo-chef-gian-piero-vivalda\\\/#primaryimage\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/vite-in-riviera-gian-piero-vivalda-foto-eunice-brovida-3.jpg\",\"contentUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/vite-in-riviera-gian-piero-vivalda-foto-eunice-brovida-3.jpg\",\"width\":1080,\"height\":710,\"caption\":\"vite-in-riviera-gian-piero-vivalda\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/stelle-calici-vini-liguri-e-prodotti-locali-con-lo-chef-gian-piero-vivalda\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/perlagesuite.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Stelle &#038; Calici: vini liguri e prodotti locali con lo Chef Gian Piero Vivalda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#website\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/\",\"name\":\"Perlage Suite\",\"description\":\"Il Wine Blog di Chiara Bassi\",\"publisher\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/perlagesuite.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#organization\",\"name\":\"Chiara Bassi\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Chiara-Bassi-sommelier-wine-blogger-logo.png\",\"contentUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Chiara-Bassi-sommelier-wine-blogger-logo.png\",\"width\":512,\"height\":512,\"caption\":\"Chiara Bassi\"},\"image\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/chiarabassiperlagesuite\",\"https:\\\/\\\/x.com\\\/perlagesuite\",\"https:\\\/\\\/www.instagram.com\\\/perlagesuite\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/person\\\/81b257517a1007c1a823318ac86c6013\",\"name\":\"Chiara Bassi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g\",\"caption\":\"Chiara Bassi\"},\"sameAs\":[\"https:\\\/\\\/perlagesuite.com\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Stars &amp; Goblets: Ligurian wines and local products with Chef Gian Piero Vivalda - Perlage Suite","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/perlagesuite.com\/en\/stelle-calici-vini-liguri-e-prodotti-locali-con-lo-chef-gian-piero-vivalda\/","og_locale":"en_GB","og_type":"article","og_title":"Stelle & Calici: vini liguri e prodotti locali con lo Chef Gian Piero Vivalda","og_description":"Sembra ieri che sono stata per la prima volta in Liguria... invece sono gi\u00e0 passati pi\u00f9 di 4 mesi e sono successe tantissime cose. Ho conosciuto tante persone meravigliose che ruotano attorno al mondo di Stelle &amp; Calici e, in particolare, a Vite in Riviera [in foto il simpaticissimo gestore Gianni Boffredo, attendo che si [&hellip;]","og_url":"https:\/\/perlagesuite.com\/en\/stelle-calici-vini-liguri-e-prodotti-locali-con-lo-chef-gian-piero-vivalda\/","og_site_name":"Perlage Suite","article_publisher":"https:\/\/www.facebook.com\/chiarabassiperlagesuite","article_published_time":"2019-03-08T17:31:33+00:00","article_modified_time":"2019-05-24T19:17:16+00:00","og_image":[{"width":1080,"height":710,"url":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2019\/03\/vite-in-riviera-gian-piero-vivalda-foto-eunice-brovida-3.jpg","type":"image\/jpeg"}],"author":"Chiara Bassi","twitter_card":"summary_large_image","twitter_creator":"@perlagesuite","twitter_site":"@perlagesuite","twitter_misc":{"Written by":"Chiara Bassi","Estimated reading time":"18 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/perlagesuite.com\/stelle-calici-vini-liguri-e-prodotti-locali-con-lo-chef-gian-piero-vivalda\/#article","isPartOf":{"@id":"https:\/\/perlagesuite.com\/stelle-calici-vini-liguri-e-prodotti-locali-con-lo-chef-gian-piero-vivalda\/"},"author":{"name":"Chiara Bassi","@id":"https:\/\/perlagesuite.com\/#\/schema\/person\/81b257517a1007c1a823318ac86c6013"},"headline":"Stelle &#038; Calici: vini liguri e prodotti locali con lo Chef Gian Piero Vivalda","datePublished":"2019-03-08T17:31:33+00:00","dateModified":"2019-05-24T19:17:16+00:00","mainEntityOfPage":{"@id":"https:\/\/perlagesuite.com\/stelle-calici-vini-liguri-e-prodotti-locali-con-lo-chef-gian-piero-vivalda\/"},"wordCount":3578,"commentCount":0,"publisher":{"@id":"https:\/\/perlagesuite.com\/#organization"},"image":{"@id":"https:\/\/perlagesuite.com\/stelle-calici-vini-liguri-e-prodotti-locali-con-lo-chef-gian-piero-vivalda\/#primaryimage"},"thumbnailUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2019\/03\/vite-in-riviera-gian-piero-vivalda-foto-eunice-brovida-3.jpg","articleSection":["Degustazioni"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/perlagesuite.com\/stelle-calici-vini-liguri-e-prodotti-locali-con-lo-chef-gian-piero-vivalda\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/perlagesuite.com\/stelle-calici-vini-liguri-e-prodotti-locali-con-lo-chef-gian-piero-vivalda\/","url":"https:\/\/perlagesuite.com\/stelle-calici-vini-liguri-e-prodotti-locali-con-lo-chef-gian-piero-vivalda\/","name":"Stars &amp; Goblets: Ligurian wines and local products with Chef Gian Piero Vivalda - Perlage Suite","isPartOf":{"@id":"https:\/\/perlagesuite.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/perlagesuite.com\/stelle-calici-vini-liguri-e-prodotti-locali-con-lo-chef-gian-piero-vivalda\/#primaryimage"},"image":{"@id":"https:\/\/perlagesuite.com\/stelle-calici-vini-liguri-e-prodotti-locali-con-lo-chef-gian-piero-vivalda\/#primaryimage"},"thumbnailUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2019\/03\/vite-in-riviera-gian-piero-vivalda-foto-eunice-brovida-3.jpg","datePublished":"2019-03-08T17:31:33+00:00","dateModified":"2019-05-24T19:17:16+00:00","breadcrumb":{"@id":"https:\/\/perlagesuite.com\/stelle-calici-vini-liguri-e-prodotti-locali-con-lo-chef-gian-piero-vivalda\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/perlagesuite.com\/stelle-calici-vini-liguri-e-prodotti-locali-con-lo-chef-gian-piero-vivalda\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/perlagesuite.com\/stelle-calici-vini-liguri-e-prodotti-locali-con-lo-chef-gian-piero-vivalda\/#primaryimage","url":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2019\/03\/vite-in-riviera-gian-piero-vivalda-foto-eunice-brovida-3.jpg","contentUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2019\/03\/vite-in-riviera-gian-piero-vivalda-foto-eunice-brovida-3.jpg","width":1080,"height":710,"caption":"vite-in-riviera-gian-piero-vivalda"},{"@type":"BreadcrumbList","@id":"https:\/\/perlagesuite.com\/stelle-calici-vini-liguri-e-prodotti-locali-con-lo-chef-gian-piero-vivalda\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/perlagesuite.com\/"},{"@type":"ListItem","position":2,"name":"Stelle &#038; Calici: vini liguri e prodotti locali con lo Chef Gian Piero Vivalda"}]},{"@type":"WebSite","@id":"https:\/\/perlagesuite.com\/#website","url":"https:\/\/perlagesuite.com\/","name":"Perlage Suite","description":"Chiara Bassi's Wine Blog","publisher":{"@id":"https:\/\/perlagesuite.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/perlagesuite.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/perlagesuite.com\/#organization","name":"Chiara Bassi","url":"https:\/\/perlagesuite.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/perlagesuite.com\/#\/schema\/logo\/image\/","url":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2022\/03\/Chiara-Bassi-sommelier-wine-blogger-logo.png","contentUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2022\/03\/Chiara-Bassi-sommelier-wine-blogger-logo.png","width":512,"height":512,"caption":"Chiara Bassi"},"image":{"@id":"https:\/\/perlagesuite.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/chiarabassiperlagesuite","https:\/\/x.com\/perlagesuite","https:\/\/www.instagram.com\/perlagesuite\/"]},{"@type":"Person","@id":"https:\/\/perlagesuite.com\/#\/schema\/person\/81b257517a1007c1a823318ac86c6013","name":"Chiara Bassi","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g","caption":"Chiara Bassi"},"sameAs":["https:\/\/perlagesuite.com"]}]}},"_links":{"self":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/posts\/12211","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/comments?post=12211"}],"version-history":[{"count":0,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/posts\/12211\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/media\/12313"}],"wp:attachment":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/media?parent=12211"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/categories?post=12211"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/tags?post=12211"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}