{"id":16355,"date":"2019-08-28T15:38:14","date_gmt":"2019-08-28T14:38:14","guid":{"rendered":"https:\/\/perlagesuite.com\/?p=16355"},"modified":"2019-08-28T17:36:21","modified_gmt":"2019-08-28T16:36:21","slug":"il-sommelier-chi-deve-servire-per-primo-a-tavola","status":"publish","type":"post","link":"https:\/\/perlagesuite.com\/en\/il-sommelier-chi-deve-servire-per-primo-a-tavola\/","title":{"rendered":"Sommelier: who should serve first at the table?"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;3.27&#8243; fb_built=&#8221;1&#8243; _i=&#8221;0&#8243; _address=&#8221;0&#8243;][et_pb_row _builder_version=&#8221;3.27&#8243; _i=&#8221;0&#8243; _address=&#8221;0.0&#8243;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.27&#8243; _i=&#8221;0&#8243; _address=&#8221;0.0.0&#8243;][et_pb_text _builder_version=&#8221;3.27&#8243; _i=&#8221;0&#8243; _address=&#8221;0.0.0.0&#8243;]<\/p>\n<p style=\"text-align: justify;\">Una delle domande che mi fate pi\u00f9 spesso riguarda le precedenze, ovvero: &#8220;<strong>il sommelier chi deve servire per primo a tavola<\/strong>?&#8221; FISAR o AIS non importa, le regole sono identiche per qualsiasi Associazione. Se non avessi studiato, da donna, ti direi che per galanteria il sommelier deve servire per primo le donne&#8230; e in effetti \u00e8 quasi sempre cos\u00ec! <strong>Le regole del corretto servizio di sala ci insegnano che il vino va servito prima alla donna pi\u00f9 anziana e si prosegue fino ad arrivare alla pi\u00f9 giovane<\/strong>. Su questo punto per\u00f2 ho diverse perplessit\u00e0: mi \u00e8 infatti capitato spesso di andare al ristorante insieme ad altre colleghe giornaliste e blogger pi\u00f9 o meno coetanee. Diciamo pure che tutte rientravamo nell&#8217;arco compreso tra i 28 e i 40 anni, ecco. Indovinare l&#8217;et\u00e0 non \u00e8 sempre facile e, in caso di errori madornali, la gaffe \u00e8 assicurata! Per questo trovo questa regola corretta <strong>solo nel caso in cui la differenza di et\u00e0 sia davvero davvero evidente<\/strong>! Poi <strong>ti immagini un intero tavolo di signore sommelier e addette ai lavori che SANNO che tu sommelier servirai per primo la donna che CREDI pi\u00f9 anziana?<\/strong> Aiuto! Per non parlare di quella mia compagna di classe con cui andavo ogni gioved\u00ec in enoteca a Ravenna a bere un calice di vino rosso e servivano sempre lei per prima, anche quando eravamo in tre o pi\u00f9. Ricordo che una volta venne da me sconvolta e mi disse: &#8220;l&#8217;ho googlato! So perch\u00e9 mi servono sempre per prima!&#8221; Ora che le sue zampe di gallina fossero evidenti e che sul mio viso non ci fosse la minima traccia di una ruga \u00e8 un dato di fatto, per\u00f2 in effetti lei era -giustamente- molto scocciata della cosa, dato che all&#8217;epoca dei fatti eravamo entrambe al secondo o terzo anno di Ingegneria.<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;3.27&#8243; inline_fonts=&#8221;Delius Unicase&#8221; _i=&#8221;1&#8243; _address=&#8221;0.0.0.1&#8243;]<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: 'Delius Unicase';\"><strong>Servizio del vino: occasione informale<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">Quindi il sommelier chi deve servire per primo a tavola? Se stai leggendo questo articolo e sei <strong>un aspirante sommelier che deve sostenere l&#8217;esame AIS ti consiglio di attenerti alla regola e di scrivere che \u00e8 corretto partire dal servire la donna pi\u00f9 anziana e tenere sempre per ultimo il referente<\/strong>, ovvero colui che ti ha chiesto la bottiglia. Tuttavia mi voglio permettere di darti un consiglio, da donna, da esperta, da giornalista&#8230; da sorella maggiore che ti vuole sapere vivo e non divorato da un pastore alsaziano dopo che la donna che credevi pi\u00f9 vecchia (e non lo era) ti ha fatto a pezzi e ha nascosto il tuo cadavere nella sua cantina (e non parlo di cantina vini!). Guarda il tuo tavolo e scegli una donna con un dettaglio vistoso -trucco, parrucco o abbigliamento- perch\u00e9 se l&#8217;ha scelto e indossato, vuol dire che lei \u00e8 assolutamente felice se lo noterai. Poi lancia una frase brillante tipo: &#8220;<strong>parto a servire questa incantevole signora\/signorina\/ragazza perch\u00e9 ha una spilla del mio colore preferito!<\/strong>&#8221; o ancora meglio &#8220;<strong>comincio il servizio da lei perch\u00e9 ha la stessa acconciatura che aveva la mia ragazza il giorno che l&#8217;ho conosciuta!<\/strong>&#8220;. \ud83d\ude0d TAAAAAC, in un solo secondo ne hai stese almeno 4: sei brillante, romantico, non hai fatto riferimenti all&#8217;et\u00e0, hai notato un dettaglio per la quale ella ha investito tempo e\/o soldi e non hai nemmeno usato la pericolosissima formula signora o signorina che non piace a nessuno. Perch\u00e9 diciamocelo, a me quando mi chiamano &#8220;signora&#8221; mi sento vecchia. E poi non sono nemmeno fidanzata, figurati sposata. E mica me lo ricordo sempre che sopra i 18 anni per il buon vecchio Monsignor Giovanni Della Casa siamo tutte signore, sai? \ud83d\ude31 Certo, \u00e8 sempre una forma di riguardo dire &#8220;signora&#8221; o &#8220;signorina&#8221;, ma fidati di me: se puoi EVITA. Glissa. Cancella queste due parole dal tuo vocabolario, a meno che non le vedi indosso uno sbirlocchero al dito che costa pi\u00f9 della tua macchina e una fede sopra o sotto, comunque non a fianco. Se invece c&#8217;\u00e8 una suora o un parroco stai a cavallo: servi loro per primi e passa la paura!<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;3.27&#8243; inline_fonts=&#8221;Delius Unicase&#8221; _i=&#8221;2&#8243; _address=&#8221;0.0.0.2&#8243;]<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: 'Delius Unicase';\"><strong>Servizio del vino: occasione formale<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">In un pranzo o una cena formale invece\u00a0il sommelier chi deve servire per primo a tavola? Devi sapere che per queste occasioni esiste un Cerimoniale di Stato che impone un preciso ordine per il servizio del vino:<span><\/span><\/p>\n<ol>\n<li style=\"text-align: justify;\">Papa<\/li>\n<li style=\"text-align: justify;\">Cardinali<\/li>\n<li style=\"text-align: justify;\">Capi di Stato<\/li>\n<li style=\"text-align: justify;\">Presidenti della Camera e del Senato<\/li>\n<li style=\"text-align: justify;\">Presidente del Consiglio dei Ministri<\/li>\n<li style=\"text-align: justify;\">Ministri<\/li>\n<li style=\"text-align: justify;\">Ambasciatori<\/li>\n<li style=\"text-align: justify;\">Segretari di Partito<\/li>\n<li style=\"text-align: justify;\">Presidenti delle Regioni<\/li>\n<li style=\"text-align: justify;\">Capo di Stato Maggiore della Difesa<\/li>\n<li style=\"text-align: justify;\">Arcivescovi<\/li>\n<li style=\"text-align: justify;\">Vescovi<\/li>\n<li style=\"text-align: justify;\">Ambasciatori della Repubblica<\/li>\n<li style=\"text-align: justify;\">Deputati del Parlamento (italiano ed europeo)<\/li>\n<li style=\"text-align: justify;\">Sindaci delle citt\u00e0<\/li>\n<li style=\"text-align: justify;\">Cavalieri del Lavoro<\/li>\n<li style=\"text-align: justify;\">Prefetti<\/li>\n<li style=\"text-align: justify;\">Capitani di grandi industrie<\/li>\n<li style=\"text-align: justify;\">Capo della Polizia<\/li>\n<li style=\"text-align: justify;\">Capo di Stato Maggiore delle diverse Armi<\/li>\n<\/ol>\n<p style=\"text-align: justify;\"><span>In questi pranzi ufficiali <b>NON DEVI far assaggiare il vino a nessuno degli invitati perch\u00e9 lo hai gi\u00e0 controllato tu.<\/b><span class=\"Apple-converted-space\">\u00a0Occhio per\u00f2 che non ci sia del veleno che non si sa mai con i tempi che corrono&#8230;\u00a0\ud83d\ude07<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span>E niente, ora ti sfido a ricordarti l\u2019esatto ordine. Se ti capita di dover affrontare un servizio di questo tipo, scrivitelo su un polso, che sulla mano con la bottiglia bagnata potrebbe cancellarsi! Ma poi come li riconosci??? Che abbiano nel segnaposto scritto anche il ruolo oltre che il nome? Mmmmh a me scrivere il ruolo invece del nome nel segnaposto pare una di quelle cafonate&#8230;<\/span><\/p>\n<p style=\"text-align: justify;\"><span>Tu cosa ne pensi?\u00a0\ud83d\ude01<\/span><\/p>\n<p style=\"text-align: justify;\">Cheers<\/p>\n<p style=\"text-align: justify;\">Chiara<\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;3_5,2_5&#8243; _builder_version=&#8221;3.27&#8243; _i=&#8221;1&#8243; _address=&#8221;0.1&#8243;][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;3.27&#8243; _i=&#8221;0&#8243; _address=&#8221;0.1.0&#8243;][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2019\/03\/come-diventare-sommelier-chiara-bassi-libro-2.png&#8221; url=&#8221;https:\/\/perlagesuite.com\/prodotto\/come-diventare-sommelier-esame-ais-corso-sommelier\/&#8221; _builder_version=&#8221;3.27&#8243; _i=&#8221;0&#8243; _address=&#8221;0.1.0.0&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;3.27&#8243; _i=&#8221;1&#8243; _address=&#8221;0.1.1&#8243;][et_pb_text _builder_version=&#8221;3.27&#8243; inline_fonts=&#8221;Delius Unicase&#8221; _i=&#8221;0&#8243; _address=&#8221;0.1.1.0&#8243;]<\/p>\n<p style=\"text-align: center;\"><span style=\"font-family: 'Delius Unicase'; font-weight: normal;\"><strong>Hai gi\u00e0 comprato il mio libro &#8220;Come diventare Sommelier&#8221;?<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">C&#8217;\u00e8 proprio tutto quello che devi sapere per studiare, ma anche tanto altro per non fare pericolose gaffe come questa! O forse no&#8230;\u00a0\ud83e\udd23<\/p>\n<p style=\"text-align: justify;\"><span>Il manuale \u00e8 pensato per tutti gli aspiranti sommelier, ma \u00e8 utilissimo anche per i \u201cgi\u00e0 sommelier\u201d che vogliono ripassare o per i winelover che vogliono cominciare a dare basi concrete alla loro passione.<\/span><\/p>\n<p style=\"text-align: justify;\"><span><\/span><\/p>\n<p style=\"text-align: justify;\"><span> <b><div class=\"cr-trustbadgef\"><div class=\"cr-badge badge_size_small cr-trustbadge-border\" style=\"background-color:#FFFFFF;\">\n\n\t<div class=\"badge__store\">Perlage Suite<\/div>\n\n\t<div class=\"badge__nowrap\">\n\t\t<div class=\"badge__stars\">\n\t\t\t\t\t\t\t<div class=\"badge__star\">\n\t\t\t\t\t<div class=\"badge__star-icon badge__star-icon_type_empty\"><\/div>\n\t\t\t\t\t<div class=\"badge__star-icon badge__star-icon_type_fill\" style=\"width: 100%\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"badge__star\">\n\t\t\t\t\t<div class=\"badge__star-icon badge__star-icon_type_empty\"><\/div>\n\t\t\t\t\t<div class=\"badge__star-icon badge__star-icon_type_fill\" style=\"width: 100%\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"badge__star\">\n\t\t\t\t\t<div class=\"badge__star-icon badge__star-icon_type_empty\"><\/div>\n\t\t\t\t\t<div class=\"badge__star-icon badge__star-icon_type_fill\" style=\"width: 100%\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"badge__star\">\n\t\t\t\t\t<div class=\"badge__star-icon badge__star-icon_type_empty\"><\/div>\n\t\t\t\t\t<div class=\"badge__star-icon badge__star-icon_type_fill\" style=\"width: 100%\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"badge__star\">\n\t\t\t\t\t<div class=\"badge__star-icon badge__star-icon_type_empty\"><\/div>\n\t\t\t\t\t<div class=\"badge__star-icon badge__star-icon_type_fill\" style=\"width: 61%\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"badge__verified verified\">\n\t\t\t<div class=\"verified__logo\"><\/div>\n\t\t\t<div class=\"verified__text\">Independently verified<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"badge__rating rating\">\n\t\t\t\t\t<span class=\"rating__store\">4.61 rating<\/span> <span class=\"rating__reviews\">(465 reviews)<\/span>\n\t\t\t<\/div>\n\n\t\t\t<a href=\"https:\/\/www.cusrev.com\/reviews\/perlagesuite.com\" rel=\"nofollow noopener noreferrer\" target=\"_blank\" aria-label=\"Perlage Suite\">\n\t\t\t<span class=\"badge__link\"><\/span>\n\t\t<\/a>\n\t\n<\/div>\n<\/div><\/b><\/span><\/p>\n<p>[\/et_pb_text][et_pb_button button_url=&#8221;https:\/\/perlagesuite.com\/prodotto\/come-diventare-sommelier-esame-ais-corso-sommelier\/&#8221; button_text=&#8221;Scopri di pi\u00f9!&#8221; button_alignment=&#8221;center&#8221; _builder_version=&#8221;3.27&#8243; _i=&#8221;1&#8243; _address=&#8221;0.1.1.1&#8243;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una delle domande che mi fate pi\u00f9 spesso riguarda le precedenze, ovvero: &#8220;il sommelier chi deve servire per primo a tavola?&#8221; FISAR o AIS non importa, le regole sono identiche per qualsiasi Associazione. Se non avessi studiato, da donna, ti direi che per galanteria il sommelier deve servire per primo le donne&#8230; e in effetti [&hellip;]<\/p>\n","protected":false},"author":49,"featured_media":16384,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[328],"tags":[],"class_list":["post-16355","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-diventare-sommelier"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.0 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Sommelier: chi deve servire per primo a tavola? - Perlage Suite<\/title>\n<meta name=\"description\" content=\"Il sommelier chi deve servire per primo a tavola? Occhio a cominciare con la donna che CREDI pi\u00f9 anziana.. sia mai che abbia con s\u00e9 lo spray al peperoncino!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/perlagesuite.com\/en\/il-sommelier-chi-deve-servire-per-primo-a-tavola\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sommelier: chi deve servire per primo a tavola?\" \/>\n<meta property=\"og:description\" content=\"Il sommelier chi deve servire per primo a tavola? Occhio a cominciare con la donna che CREDI pi\u00f9 anziana.. sia mai che abbia con s\u00e9 lo spray al peperoncino!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/perlagesuite.com\/en\/il-sommelier-chi-deve-servire-per-primo-a-tavola\/\" \/>\n<meta property=\"og:site_name\" content=\"Perlage Suite\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/chiarabassiperlagesuite\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-28T14:38:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-08-28T16:36:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/perlagesuite.com\/wp-content\/uploads\/2019\/08\/sommelier-chi-deve-servire-per-primo-a-tavola-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Chiara Bassi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@perlagesuite\" \/>\n<meta name=\"twitter:site\" content=\"@perlagesuite\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Chiara Bassi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/il-sommelier-chi-deve-servire-per-primo-a-tavola\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/il-sommelier-chi-deve-servire-per-primo-a-tavola\\\/\"},\"author\":{\"name\":\"Chiara Bassi\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/person\\\/81b257517a1007c1a823318ac86c6013\"},\"headline\":\"Sommelier: chi deve servire per primo a tavola?\",\"datePublished\":\"2019-08-28T14:38:14+00:00\",\"dateModified\":\"2019-08-28T16:36:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/il-sommelier-chi-deve-servire-per-primo-a-tavola\\\/\"},\"wordCount\":1127,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/il-sommelier-chi-deve-servire-per-primo-a-tavola\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/sommelier-chi-deve-servire-per-primo-a-tavola-1.jpg\",\"articleSection\":[\"Didattica Sommelier\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/perlagesuite.com\\\/il-sommelier-chi-deve-servire-per-primo-a-tavola\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/il-sommelier-chi-deve-servire-per-primo-a-tavola\\\/\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/il-sommelier-chi-deve-servire-per-primo-a-tavola\\\/\",\"name\":\"Sommelier: chi deve servire per primo a tavola? - Perlage Suite\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/il-sommelier-chi-deve-servire-per-primo-a-tavola\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/il-sommelier-chi-deve-servire-per-primo-a-tavola\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/sommelier-chi-deve-servire-per-primo-a-tavola-1.jpg\",\"datePublished\":\"2019-08-28T14:38:14+00:00\",\"dateModified\":\"2019-08-28T16:36:21+00:00\",\"description\":\"Il sommelier chi deve servire per primo a tavola? Occhio a cominciare con la donna che CREDI pi\u00f9 anziana.. sia mai che abbia con s\u00e9 lo spray al peperoncino!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/il-sommelier-chi-deve-servire-per-primo-a-tavola\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/perlagesuite.com\\\/il-sommelier-chi-deve-servire-per-primo-a-tavola\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/il-sommelier-chi-deve-servire-per-primo-a-tavola\\\/#primaryimage\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/sommelier-chi-deve-servire-per-primo-a-tavola-1.jpg\",\"contentUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/sommelier-chi-deve-servire-per-primo-a-tavola-1.jpg\",\"width\":1080,\"height\":720,\"caption\":\"il sommelier chi deve servire per primo a tavola\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/il-sommelier-chi-deve-servire-per-primo-a-tavola\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/perlagesuite.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sommelier: chi deve servire per primo a tavola?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#website\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/\",\"name\":\"Perlage Suite\",\"description\":\"Il Wine Blog di Chiara Bassi\",\"publisher\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/perlagesuite.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#organization\",\"name\":\"Chiara Bassi\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Chiara-Bassi-sommelier-wine-blogger-logo.png\",\"contentUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Chiara-Bassi-sommelier-wine-blogger-logo.png\",\"width\":512,\"height\":512,\"caption\":\"Chiara Bassi\"},\"image\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/chiarabassiperlagesuite\",\"https:\\\/\\\/x.com\\\/perlagesuite\",\"https:\\\/\\\/www.instagram.com\\\/perlagesuite\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/person\\\/81b257517a1007c1a823318ac86c6013\",\"name\":\"Chiara Bassi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g\",\"caption\":\"Chiara Bassi\"},\"sameAs\":[\"https:\\\/\\\/perlagesuite.com\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Sommelier: Who should serve first at the table? - Perlage Suite","description":"Who should the sommelier serve first at the table? Be careful to start with the woman you BELIEVE to be the oldest... heaven forbid she should have pepper spray with her!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/perlagesuite.com\/en\/il-sommelier-chi-deve-servire-per-primo-a-tavola\/","og_locale":"en_GB","og_type":"article","og_title":"Sommelier: chi deve servire per primo a tavola?","og_description":"Il sommelier chi deve servire per primo a tavola? Occhio a cominciare con la donna che CREDI pi\u00f9 anziana.. sia mai che abbia con s\u00e9 lo spray al peperoncino!","og_url":"https:\/\/perlagesuite.com\/en\/il-sommelier-chi-deve-servire-per-primo-a-tavola\/","og_site_name":"Perlage Suite","article_publisher":"https:\/\/www.facebook.com\/chiarabassiperlagesuite","article_published_time":"2019-08-28T14:38:14+00:00","article_modified_time":"2019-08-28T16:36:21+00:00","og_image":[{"width":1080,"height":720,"url":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2019\/08\/sommelier-chi-deve-servire-per-primo-a-tavola-1.jpg","type":"image\/jpeg"}],"author":"Chiara Bassi","twitter_card":"summary_large_image","twitter_creator":"@perlagesuite","twitter_site":"@perlagesuite","twitter_misc":{"Written by":"Chiara Bassi","Estimated reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/perlagesuite.com\/il-sommelier-chi-deve-servire-per-primo-a-tavola\/#article","isPartOf":{"@id":"https:\/\/perlagesuite.com\/il-sommelier-chi-deve-servire-per-primo-a-tavola\/"},"author":{"name":"Chiara Bassi","@id":"https:\/\/perlagesuite.com\/#\/schema\/person\/81b257517a1007c1a823318ac86c6013"},"headline":"Sommelier: chi deve servire per primo a tavola?","datePublished":"2019-08-28T14:38:14+00:00","dateModified":"2019-08-28T16:36:21+00:00","mainEntityOfPage":{"@id":"https:\/\/perlagesuite.com\/il-sommelier-chi-deve-servire-per-primo-a-tavola\/"},"wordCount":1127,"commentCount":0,"publisher":{"@id":"https:\/\/perlagesuite.com\/#organization"},"image":{"@id":"https:\/\/perlagesuite.com\/il-sommelier-chi-deve-servire-per-primo-a-tavola\/#primaryimage"},"thumbnailUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2019\/08\/sommelier-chi-deve-servire-per-primo-a-tavola-1.jpg","articleSection":["Didattica Sommelier"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/perlagesuite.com\/il-sommelier-chi-deve-servire-per-primo-a-tavola\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/perlagesuite.com\/il-sommelier-chi-deve-servire-per-primo-a-tavola\/","url":"https:\/\/perlagesuite.com\/il-sommelier-chi-deve-servire-per-primo-a-tavola\/","name":"Sommelier: Who should serve first at the table? - Perlage Suite","isPartOf":{"@id":"https:\/\/perlagesuite.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/perlagesuite.com\/il-sommelier-chi-deve-servire-per-primo-a-tavola\/#primaryimage"},"image":{"@id":"https:\/\/perlagesuite.com\/il-sommelier-chi-deve-servire-per-primo-a-tavola\/#primaryimage"},"thumbnailUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2019\/08\/sommelier-chi-deve-servire-per-primo-a-tavola-1.jpg","datePublished":"2019-08-28T14:38:14+00:00","dateModified":"2019-08-28T16:36:21+00:00","description":"Who should the sommelier serve first at the table? Be careful to start with the woman you BELIEVE to be the oldest... heaven forbid she should have pepper spray with her!","breadcrumb":{"@id":"https:\/\/perlagesuite.com\/il-sommelier-chi-deve-servire-per-primo-a-tavola\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/perlagesuite.com\/il-sommelier-chi-deve-servire-per-primo-a-tavola\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/perlagesuite.com\/il-sommelier-chi-deve-servire-per-primo-a-tavola\/#primaryimage","url":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2019\/08\/sommelier-chi-deve-servire-per-primo-a-tavola-1.jpg","contentUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2019\/08\/sommelier-chi-deve-servire-per-primo-a-tavola-1.jpg","width":1080,"height":720,"caption":"il sommelier chi deve servire per primo a tavola"},{"@type":"BreadcrumbList","@id":"https:\/\/perlagesuite.com\/il-sommelier-chi-deve-servire-per-primo-a-tavola\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/perlagesuite.com\/"},{"@type":"ListItem","position":2,"name":"Sommelier: chi deve servire per primo a tavola?"}]},{"@type":"WebSite","@id":"https:\/\/perlagesuite.com\/#website","url":"https:\/\/perlagesuite.com\/","name":"Perlage Suite","description":"Chiara Bassi's Wine Blog","publisher":{"@id":"https:\/\/perlagesuite.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/perlagesuite.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/perlagesuite.com\/#organization","name":"Chiara Bassi","url":"https:\/\/perlagesuite.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/perlagesuite.com\/#\/schema\/logo\/image\/","url":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2022\/03\/Chiara-Bassi-sommelier-wine-blogger-logo.png","contentUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2022\/03\/Chiara-Bassi-sommelier-wine-blogger-logo.png","width":512,"height":512,"caption":"Chiara Bassi"},"image":{"@id":"https:\/\/perlagesuite.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/chiarabassiperlagesuite","https:\/\/x.com\/perlagesuite","https:\/\/www.instagram.com\/perlagesuite\/"]},{"@type":"Person","@id":"https:\/\/perlagesuite.com\/#\/schema\/person\/81b257517a1007c1a823318ac86c6013","name":"Chiara Bassi","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g","caption":"Chiara Bassi"},"sameAs":["https:\/\/perlagesuite.com"]}]}},"_links":{"self":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/posts\/16355","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/comments?post=16355"}],"version-history":[{"count":0,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/posts\/16355\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/media\/16384"}],"wp:attachment":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/media?parent=16355"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/categories?post=16355"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/tags?post=16355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}