{"id":17750,"date":"2019-10-10T12:20:39","date_gmt":"2019-10-10T11:20:39","guid":{"rendered":"https:\/\/perlagesuite.com\/?p=17750"},"modified":"2020-10-15T10:52:10","modified_gmt":"2020-10-15T09:52:10","slug":"grandi-vigne-vini-iper-2019","status":"publish","type":"post","link":"https:\/\/perlagesuite.com\/en\/grandi-vigne-vini-iper-2019\/","title":{"rendered":"Grandi Vigne: 36 quality wines at an incredible price you can find at Iper"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;3.29.2&#8243; fb_built=&#8221;1&#8243; _i=&#8221;0&#8243; _address=&#8221;0&#8243;][et_pb_row _builder_version=&#8221;3.29.2&#8243; _i=&#8221;0&#8243; _address=&#8221;0.0&#8243;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.29.2&#8243; _i=&#8221;0&#8243; _address=&#8221;0.0.0&#8243;][et_pb_text _builder_version=&#8221;3.29.2&#8243; _i=&#8221;0&#8243; _address=&#8221;0.0.0.0&#8243;]<\/p>\n<p style=\"text-align: justify;\"><span>Sabato 5 ottobre sono stata invitata alla <a href=\"https:\/\/www.iper.it\/magazine\/354-degustazione-vini-un-viaggio-di-eleganza.htm\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"text-decoration: underline;\"><strong>degustazione vini<\/strong><\/span><\/a> \u201c<strong>Giro d\u2019Italia in 80 vini<\/strong>\u201d del <strong>progetto \u201cGrandi Vigne\u201d di Iper<\/strong> presso il Centro Commerciale Portello di Milano. L\u2019Iper Portello di Milano \u00e8 comodissimo da raggiungere anche in Metro perch\u00e9 sulla nuova linea lilla c\u2019\u00e8 proprio la fermata \u201cPortello\u201d che si trova a 5 minuti a piedi dall\u2019ipermercato. Oltretutto non ero mai salita su una metropolitana senza conducente e mi \u00e8 piaciuto tantissimo sfrecciare sui binari sotterranei di Milano in primissima fila davanti al grande vetro del treno! Arrivata all\u2019Iper sono stata accolta da una <strong>gentilissima Raffaella Roani dell\u2019agenzia Arvis<\/strong>, che mi sento di consigliare a tutti per la professionalit\u00e0: lavoro con tantissime agenzie stampa e agenzie di marketing e raramente mi capita di incontrare persone cos\u00ec precise e organizzate! La prima parte della giornata \u00e8 stata organizzata allo Chalet degli Eventi, allestito con grande cura: deliziosi i tavolini con cavalletto di betulla e le erbe aromatiche ovunque. Io adoro le erbe aromatiche, anche se le piantine di basilico tremano solo al mio avvicinarsi per un certo passaparola che si \u00e8 creato sulla mia presunta vena omicida nei confronti di queste profumatissime\u00a0<\/span>creature! (Sono tutte voci, giuro!\u00a0\ud83d\ude07\ud83d\ude05)<\/p>\n<p style=\"text-align: justify;\">[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2019\/10\/vini-supermercato-grandi-vigne-iper-2.jpg&#8221; _builder_version=&#8221;3.29.2&#8243; _i=&#8221;1&#8243; _address=&#8221;0.0.0.1&#8243;][\/et_pb_image][et_pb_text _builder_version=&#8221;3.29.2&#8243; _i=&#8221;2&#8243; _address=&#8221;0.0.0.2&#8243;]<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 17px; text-align: justify;\">L&#8217;<\/span><strong style=\"font-size: 17px; text-align: justify;\">enologo Fabrizio Stecca<\/strong><span style=\"font-size: 17px; text-align: justify;\"> ci ha piacevolmente introdotto il progetto Grandi Vigne e accompagnato insieme alla brava Ilaria in un viaggio multisensoriale di abbinamento tra olio, vino e cibo. In effetti <\/span><strong style=\"font-size: 17px; text-align: justify;\">ho trovato interessanti anche gli oli extra vergine d&#8217;oliva proposti, in particolare quello dell&#8217;azienda Bonomini &#8220;Passioni di Verona&#8221; Veneto Valpolicella DOP.\u00a0<\/strong><span style=\"font-size: 17px; text-align: justify;\">Dopo mi sono sguinzagliata per le bellissime casette divise sia per regione, sia per vini biologici o senza solfiti aggiunti. Dentro ci ho trovato sommelier molto preparati e spesso anche gli stessi produttori ed \u00e8 stato un piacere parlare con alcuni di loro!<\/span><\/p>\n<p style=\"text-align: justify;\">Grandi Vigne \u00e8 &#8220;una ricerca rigorosa, un sogno condiviso e il desiderio di offrire a tutti l&#8217;esperienza unica di incontrare la qualit\u00e0 e l&#8217;eccellenza di piccoli produttori italiani. Grandi Vigne \u00e8 un progetto di salvaguardia della tradizione vinicola del nostro Paese, frutto di impegno e di esperienza. E di una vera e propria scelta di passione.&#8221; In pratica <em>Iper, La grande i<\/em> \u00e8 al fianco dei piccoli produttori in questo progetto etico win to win: da un lato il consumatore pu\u00f2 bere bene a un prezzo molto conveniente, dall&#8217;altro i piccoli produttori possono avere una visibilit\u00e0 maggiore su tutto il territorio italiano, intercettando un pubblico diverso da quello che \u00e8 normalmente in loro target. In realt\u00e0, dato che da quanto ho visto i produttori escono con una linea esclusiva per Grandi Vigne che non \u00e8 con il loro marchio consueto, pi\u00f9 che di visibilit\u00e0 parlerei di opportunit\u00e0. Intercettando un&#8217;altra ampia fetta di pubblico possono infatti avere maggiori risorse da impiegare nel mantenere e nell&#8217;accrescere i loro standard qualitativi.<\/p>\n<p style=\"text-align: justify;\">Come sai sono una wine blogger &#8220;pratica&#8221;, mi piace andare al sodo delle cose e creare contenuti di valore per te che hai piacere di leggermi&#8230; quindi invece di farti la solita, inutile, sviolinata sul perch\u00e9 <strong>reputo Grandi Vigne un progetto davvero interessante che merita da parte tua una grande attenzione<\/strong>, voglio segnalarti i vini pi\u00f9 buoni che ho degustato, con tanto di punteggio e note&#8230; in modo che <strong>puoi andare dal tuo Iper di fiducia gi\u00e0 stasera e approfittare di questo favoloso sconto del 30%! Mi raccomando, i prezzi che trovi in questo articolo sono validi fino al 20 ottobre 2019<\/strong>, c&#8217;\u00e8 pochissimo tempo ancora!<\/p>\n<p style=\"text-align: justify;\">Breve nota che sembra banale, ma non lo \u00e8 affatto! Ti premetto che ognuno dei punteggi in centesimi che ho dato sono in funzione del rapporto qualit\u00e0\/prezzo rispetto alla tipologia del vino stesso. Ovviamente non puoi paragonare, ad esempio, un Rosso Piceno DOC a un Merlot Marca Trevigiana IGT anche se sono entrambi rossi, costano praticamente uguali e hanno un punteggio simile. Invece di dividerti i vini per Regione ho preferito ordinarteli per punteggio nella rispettiva fascia di prezzo in modo da agevolarti nel preparare la tua &#8220;lista della spesa&#8221;. Fammi sapere in un commento se ti \u00e8 piaciuta questa idea!\u00a0\ud83d\ude0d<strong><\/strong><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;3.29.2&#8243; hover_enabled=&#8221;0&#8243; _i=&#8221;3&#8243; _address=&#8221;0.0.0.3&#8243;]<\/p>\n<h3 style=\"text-align: center;\"><strong>Grandi Vigne: Vini sotto i 5 \u20ac, i migliori (&gt;75\/100)<\/strong><\/h3>\n<p style=\"text-align: justify;\">Sono sincera, quando penso che si pu\u00f2 comprare un vino buono e fatto bene con meno di 5 \u20ac sono sempre incredula: del resto io per prima ammetto di non comprare vino al supermercato. A mia discolpa dico che in realt\u00e0 non compro vino da nessuna parte: mi arrivano talmente tanti campioni da degustare a casa che faccio gi\u00e0 fatica a stare gi\u00e0 dietro a quelli!\u00a0\ud83d\ude05 Di questa batteria di vini sotto i 5 \u20ac i tre che mi hanno rubato il cuore sono il Merlot Marca Trevigiana, La lacrima di Morro d&#8217;Alba e il Sangiovese Superiore di Romagna <a href=\"https:\/\/www.iper.it\/grandi-vigne.php\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"text-decoration: underline;\"><strong>Senza Solfiti<\/strong><\/span> <\/a>Aggiunti.<\/p>\n<p style=\"text-align: justify;\">\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_4,1_4,1_4,1_4&#8243; _builder_version=&#8221;3.29.2&#8243; _i=&#8221;1&#8243; _address=&#8221;0.1&#8243;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;3.29.2&#8243; _i=&#8221;0&#8243; _address=&#8221;0.1.0&#8243;][et_pb_circle_counter title=&#8221;Merlot marca trevigiana igt %22senza%22 senza solfiti aggiunti scontato \u20ac 4,49&#8243; number=&#8221;96&#8243; percent_sign=&#8221;off&#8221; bar_bg_color=&#8221;#e02b20&#8243; _builder_version=&#8221;3.29.2&#8243; title_font=&#8221;Delius Unicase||||||||&#8221; title_text_align=&#8221;center&#8221; title_font_size=&#8221;14px&#8221; _i=&#8221;0&#8243; _address=&#8221;0.1.0.0&#8243;][\/et_pb_circle_counter][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;3.29.2&#8243; _i=&#8221;1&#8243; _address=&#8221;0.1.1&#8243;][et_pb_circle_counter title=&#8221;Lacrima di morro d&#8217;alba doc %22don de re%22 scontato \u20ac 4,29&#8243; number=&#8221;94&#8243; percent_sign=&#8221;off&#8221; bar_bg_color=&#8221;#e02b20&#8243; _builder_version=&#8221;3.29.2&#8243; title_font=&#8221;Delius Unicase||||||||&#8221; title_text_align=&#8221;center&#8221; title_font_size=&#8221;14px&#8221; _i=&#8221;0&#8243; _address=&#8221;0.1.1.0&#8243;][\/et_pb_circle_counter][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;3.29.2&#8243; _i=&#8221;2&#8243; _address=&#8221;0.1.2&#8243;][et_pb_circle_counter title=&#8221;Rosso piceno superiore doc %22ferola%22 scont. \u20ac3,69&#8243; number=&#8221;91&#8243; percent_sign=&#8221;off&#8221; bar_bg_color=&#8221;#e02b20&#8243; _builder_version=&#8221;3.29.2&#8243; title_font=&#8221;Delius Unicase||||||||&#8221; title_text_align=&#8221;center&#8221; title_font_size=&#8221;14px&#8221; _i=&#8221;0&#8243; _address=&#8221;0.1.2.0&#8243;][\/et_pb_circle_counter][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;3.29.2&#8243; _i=&#8221;3&#8243; _address=&#8221;0.1.3&#8243;][et_pb_circle_counter title=&#8221;Ribolla gialla vino spumante Brut %22Il Zardin%22 scontato \u20ac 4,89&#8243; number=&#8221;90&#8243; percent_sign=&#8221;off&#8221; bar_bg_color=&#8221;#e02b20&#8243; _builder_version=&#8221;3.29.2&#8243; title_font=&#8221;Delius Unicase||||||||&#8221; title_text_align=&#8221;center&#8221; title_font_size=&#8221;14px&#8221; _i=&#8221;0&#8243; _address=&#8221;0.1.3.0&#8243;][\/et_pb_circle_counter][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_4,1_4,1_4,1_4&#8243; _builder_version=&#8221;3.29.2&#8243; _i=&#8221;2&#8243; _address=&#8221;0.2&#8243;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;3.29.2&#8243; _i=&#8221;0&#8243; _address=&#8221;0.2.0&#8243;][et_pb_circle_counter title=&#8221;sangiovese superiore romagna doc senza solfiti aggiunti scontato \u20ac 4,79&#8243; number=&#8221;82&#8243; percent_sign=&#8221;off&#8221; bar_bg_color=&#8221;#e02b20&#8243; _builder_version=&#8221;3.29.2&#8243; title_font=&#8221;Delius Unicase||||||||&#8221; title_text_align=&#8221;center&#8221; title_font_size=&#8221;14px&#8221; _i=&#8221;0&#8243; _address=&#8221;0.2.0.0&#8243;][\/et_pb_circle_counter][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;3.29.2&#8243; _i=&#8221;1&#8243; _address=&#8221;0.2.1&#8243;][et_pb_circle_counter title=&#8221;barbera oltrep\u00f2 pavese doc senza solfiti aggiunti scont. \u20ac 4,79&#8243; number=&#8221;81&#8243; percent_sign=&#8221;off&#8221; bar_bg_color=&#8221;#e02b20&#8243; _builder_version=&#8221;3.29.2&#8243; title_font=&#8221;Delius Unicase||||||||&#8221; title_text_align=&#8221;center&#8221; title_font_size=&#8221;14px&#8221; _i=&#8221;0&#8243; _address=&#8221;0.2.1.0&#8243;][\/et_pb_circle_counter][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;3.29.2&#8243; _i=&#8221;2&#8243; _address=&#8221;0.2.2&#8243;][et_pb_circle_counter title=&#8221;prosecco treviso doc Extra dry %22val del galinel%22 scontato \u20ac 4,65&#8243; number=&#8221;80&#8243; percent_sign=&#8221;off&#8221; bar_bg_color=&#8221;#e02b20&#8243; _builder_version=&#8221;3.29.2&#8243; title_font=&#8221;Delius Unicase||||||||&#8221; title_text_align=&#8221;center&#8221; title_font_size=&#8221;14px&#8221; _i=&#8221;0&#8243; _address=&#8221;0.2.2.0&#8243;][\/et_pb_circle_counter][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;3.29.2&#8243; _i=&#8221;3&#8243; _address=&#8221;0.2.3&#8243;][et_pb_circle_counter title=&#8221;merlot veneto igt biologico %22Canal lia%22 scontato \u20ac 3,95 &#8221; number=&#8221;80&#8243; percent_sign=&#8221;off&#8221; bar_bg_color=&#8221;#e02b20&#8243; _builder_version=&#8221;3.29.2&#8243; title_font=&#8221;Delius Unicase||||||||&#8221; title_text_align=&#8221;center&#8221; title_font_size=&#8221;14px&#8221; _i=&#8221;0&#8243; _address=&#8221;0.2.3.0&#8243;][\/et_pb_circle_counter][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_4,1_4,1_4,1_4&#8243; _builder_version=&#8221;3.29.2&#8243; _i=&#8221;3&#8243; _address=&#8221;0.3&#8243;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;3.29.2&#8243; _i=&#8221;0&#8243; _address=&#8221;0.3.0&#8243;][et_pb_circle_counter title=&#8221;Malvasia bianca salento igt %22La sabelluccia%22 \u20ac 3,69&#8243; number=&#8221;80&#8243; percent_sign=&#8221;off&#8221; bar_bg_color=&#8221;#e02b20&#8243; _builder_version=&#8221;3.29.2&#8243; title_font=&#8221;Delius Unicase||||||||&#8221; title_text_align=&#8221;center&#8221; title_font_size=&#8221;14px&#8221; _i=&#8221;0&#8243; _address=&#8221;0.3.0.0&#8243;][\/et_pb_circle_counter][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;3.29.2&#8243; _i=&#8221;1&#8243; _address=&#8221;0.3.1&#8243;][et_pb_circle_counter title=&#8221;Negramaro Rosso Salento IGT %22La Galiarda%22 scont. \u20ac 3,69&#8243; number=&#8221;80&#8243; percent_sign=&#8221;off&#8221; bar_bg_color=&#8221;#e02b20&#8243; _builder_version=&#8221;3.29.2&#8243; title_font=&#8221;Delius Unicase||||||||&#8221; title_text_align=&#8221;center&#8221; title_font_size=&#8221;14px&#8221; _i=&#8221;0&#8243; _address=&#8221;0.3.1.0&#8243;][\/et_pb_circle_counter][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;3.29.2&#8243; _i=&#8221;2&#8243; _address=&#8221;0.3.2&#8243;][et_pb_circle_counter title=&#8221;Lambrusco Rosso Secco Reggiano DOC %22Valle scura%22 scontato \u20ac 2,99&#8243; number=&#8221;78&#8243; percent_sign=&#8221;off&#8221; bar_bg_color=&#8221;#e02b20&#8243; _builder_version=&#8221;3.29.2&#8243; title_font=&#8221;Delius Unicase||||||||&#8221; title_text_align=&#8221;center&#8221; title_font_size=&#8221;14px&#8221; _i=&#8221;0&#8243; _address=&#8221;0.3.2.0&#8243;][\/et_pb_circle_counter][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;3.29.2&#8243; _i=&#8221;3&#8243; _address=&#8221;0.3.3&#8243;][et_pb_circle_counter title=&#8221;Morellino di Scansano DOCG %22La Fagnina%22 scontato \u20ac 4,39&#8243; number=&#8221;78&#8243; percent_sign=&#8221;off&#8221; bar_bg_color=&#8221;#e02b20&#8243; _builder_version=&#8221;3.29.2&#8243; title_font=&#8221;Delius Unicase||||||||&#8221; title_text_align=&#8221;center&#8221; title_font_size=&#8221;14px&#8221; _i=&#8221;0&#8243; _address=&#8221;0.3.3.0&#8243;][\/et_pb_circle_counter][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_4,1_4,1_4,1_4&#8243; _builder_version=&#8221;3.29.2&#8243; _i=&#8221;4&#8243; _address=&#8221;0.4&#8243;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;3.29.2&#8243; _i=&#8221;0&#8243; _address=&#8221;0.4.0&#8243;][et_pb_circle_counter title=&#8221;inzolia-grillo sicilia doc biologico %22Laila%22 scontato \u20ac 3,69&#8243; number=&#8221;76&#8243; percent_sign=&#8221;off&#8221; bar_bg_color=&#8221;#e02b20&#8243; _builder_version=&#8221;3.29.2&#8243; title_font=&#8221;Delius Unicase||||||||&#8221; title_text_align=&#8221;center&#8221; title_font_size=&#8221;14px&#8221; _i=&#8221;0&#8243; _address=&#8221;0.4.0.0&#8243;][\/et_pb_circle_counter][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;3.29.2&#8243; _i=&#8221;1&#8243; _address=&#8221;0.4.1&#8243;][et_pb_circle_counter title=&#8221;bonarda oltrep\u00f2 pavese doc %22Campo dei salici%22 scontato \u20ac 3,29&#8243; number=&#8221;75&#8243; percent_sign=&#8221;off&#8221; bar_bg_color=&#8221;#e02b20&#8243; _builder_version=&#8221;3.29.2&#8243; title_font=&#8221;Delius Unicase||||||||&#8221; title_text_align=&#8221;center&#8221; title_font_size=&#8221;14px&#8221; _i=&#8221;0&#8243; _address=&#8221;0.4.1.0&#8243;][\/et_pb_circle_counter][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;3.29.2&#8243; _i=&#8221;2&#8243; _address=&#8221;0.4.2&#8243;][et_pb_circle_counter title=&#8221;Barbera dell&#8217;Oltrep\u00f2 Pavese DOC %22I Monticelli%22 Scontato \u20ac 3,25&#8243; number=&#8221;75&#8243; percent_sign=&#8221;off&#8221; bar_bg_color=&#8221;#e02b20&#8243; _builder_version=&#8221;3.29.2&#8243; title_font=&#8221;Delius Unicase||||||||&#8221; title_text_align=&#8221;center&#8221; title_font_size=&#8221;14px&#8221; _i=&#8221;0&#8243; _address=&#8221;0.4.2.0&#8243;][\/et_pb_circle_counter][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;3.29.2&#8243; _i=&#8221;3&#8243; _address=&#8221;0.4.3&#8243;][et_pb_circle_counter title=&#8221;Sangiovese superiore Romagna DOC %22Mazzolano%22 Scontato  \u20ac 4,49&#8243; number=&#8221;75&#8243; percent_sign=&#8221;off&#8221; bar_bg_color=&#8221;#e02b20&#8243; _builder_version=&#8221;3.29.2&#8243; title_font=&#8221;Delius Unicase||||||||&#8221; title_text_align=&#8221;center&#8221; title_font_size=&#8221;14px&#8221; _i=&#8221;0&#8243; _address=&#8221;0.4.3.0&#8243;][\/et_pb_circle_counter][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;3.29.2&#8243; _i=&#8221;5&#8243; _address=&#8221;0.5&#8243;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.29.2&#8243; _i=&#8221;0&#8243; _address=&#8221;0.5.0&#8243;][et_pb_text _builder_version=&#8221;3.29.2&#8243; _i=&#8221;0&#8243; _address=&#8221;0.5.0.0&#8243;]<\/p>\n<h3 style=\"text-align: center;\"><strong>Grandi Vigne: Vini nella fascia di prezzo 5-10 \u20ac, i migliori\u00a0<\/strong><strong>(&gt;75\/100)<\/strong><\/h3>\n<p style=\"text-align: justify;\">\u00a0In questa fascia di prezzo troverai quelle che, secondo me, sono state le bevute migliori. Scegli liberamente tra questi vini e riempiti letteralmente la macchina: avrai vini quotidiani di grandissimo pregio con un rapporto qualit\u00e0 prezzo che ancora non ci credo nemmeno io, giuro! A incominciare dal <strong>Muller Thurgau<\/strong>, un vino che normalmente non mi fa impazzire e qui mi \u00e8 piaciuto cos\u00ec tanto da volermene comprare una bottiglia, forse per merito del suo naso intensissimo ed elegante. Il <strong>Valtellina Superiore<\/strong> \u00e8 pazzesco, ha un naso di spremuta di arancia rossa e mora matura che sfuma nella cannella. Uno <strong>spumante Trento DOC<\/strong> cos\u00ec buono a questo prezzo non lo commento nemmeno, davvero.<\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2019\/10\/vini-supermercato-grandi-vigne-iper-3.jpg&#8221; _builder_version=&#8221;3.29.2&#8243; _i=&#8221;1&#8243; _address=&#8221;0.5.0.1&#8243;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_4,1_4,1_4,1_4&#8243; _builder_version=&#8221;3.29.2&#8243; _i=&#8221;6&#8243; _address=&#8221;0.6&#8243;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;3.29.2&#8243; _i=&#8221;0&#8243; _address=&#8221;0.6.0&#8243;][et_pb_circle_counter title=&#8221;Muller Thurgau alto adige doc %22Kenzel%22 scontato \u20ac 6,89&#8243; number=&#8221;98&#8243; percent_sign=&#8221;off&#8221; bar_bg_color=&#8221;#e02b20&#8243; _builder_version=&#8221;3.29.2&#8243; title_font=&#8221;Delius Unicase||||||||&#8221; title_text_align=&#8221;center&#8221; title_font_size=&#8221;14px&#8221; _i=&#8221;0&#8243; _address=&#8221;0.6.0.0&#8243;][\/et_pb_circle_counter][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;3.29.2&#8243; _i=&#8221;1&#8243; _address=&#8221;0.6.1&#8243;][et_pb_circle_counter title=&#8221;Trento DOC  Brut %22Maso Carpine%22 scontato \u20ac 6,89&#8243; number=&#8221;98&#8243; percent_sign=&#8221;off&#8221; bar_bg_color=&#8221;#e02b20&#8243; _builder_version=&#8221;3.29.2&#8243; title_font=&#8221;Delius Unicase||||||||&#8221; title_text_align=&#8221;center&#8221; title_font_size=&#8221;14px&#8221; _i=&#8221;0&#8243; _address=&#8221;0.6.1.0&#8243;][\/et_pb_circle_counter][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;3.29.2&#8243; _i=&#8221;2&#8243; _address=&#8221;0.6.2&#8243;][et_pb_circle_counter title=&#8221;Valtellina Superiore DOCG %22Sassella%22 Scontato \u20ac 8,29&#8243; number=&#8221;96&#8243; percent_sign=&#8221;off&#8221; bar_bg_color=&#8221;#e02b20&#8243; _builder_version=&#8221;3.29.2&#8243; title_font=&#8221;Delius Unicase||||||||&#8221; title_text_align=&#8221;center&#8221; title_font_size=&#8221;14px&#8221; _i=&#8221;0&#8243; _address=&#8221;0.6.2.0&#8243;][\/et_pb_circle_counter][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;3.29.2&#8243; _i=&#8221;3&#8243; _address=&#8221;0.6.3&#8243;][et_pb_circle_counter title=&#8221;Gewurtztraminer alto adige doc %22Branden%22 scontato \u20ac 8,29&#8243; number=&#8221;94&#8243; percent_sign=&#8221;off&#8221; bar_bg_color=&#8221;#e02b20&#8243; _builder_version=&#8221;3.29.2&#8243; title_font=&#8221;Delius Unicase||||||||&#8221; title_text_align=&#8221;center&#8221; title_font_size=&#8221;14px&#8221; _i=&#8221;0&#8243; _address=&#8221;0.6.3.0&#8243;][\/et_pb_circle_counter][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_4,1_4,1_4,1_4&#8243; _builder_version=&#8221;3.29.2&#8243; _i=&#8221;7&#8243; _address=&#8221;0.7&#8243;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;3.29.2&#8243; _i=&#8221;0&#8243; _address=&#8221;0.7.0&#8243;][et_pb_circle_counter title=&#8221;bolgheri rosso doc %22i Rusignoli%22 scont. \u20ac 9,39&#8243; number=&#8221;92&#8243; percent_sign=&#8221;off&#8221; bar_bg_color=&#8221;#e02b20&#8243; _builder_version=&#8221;3.29.2&#8243; title_font=&#8221;Delius Unicase||||||||&#8221; title_text_align=&#8221;center&#8221; title_font_size=&#8221;14px&#8221; _i=&#8221;0&#8243; _address=&#8221;0.7.0.0&#8243;][\/et_pb_circle_counter][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;3.29.2&#8243; _i=&#8221;1&#8243; _address=&#8221;0.7.1&#8243;][et_pb_circle_counter title=&#8221;Vin santo del chianti doc %22Cantini%22 Scontato \u20ac 24,40&#8243; number=&#8221;89&#8243; percent_sign=&#8221;off&#8221; bar_bg_color=&#8221;#e02b20&#8243; _builder_version=&#8221;3.29.2&#8243; title_font=&#8221;Delius Unicase||||||||&#8221; title_text_align=&#8221;center&#8221; title_font_size=&#8221;14px&#8221; _i=&#8221;0&#8243; _address=&#8221;0.7.1.0&#8243;][\/et_pb_circle_counter][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;3.29.2&#8243; _i=&#8221;2&#8243; _address=&#8221;0.7.2&#8243;][et_pb_circle_counter title=&#8221;Aglianico del Vulture DOC %22Nevio%22 Scontato \u20ac 7,99&#8243; number=&#8221;86&#8243; percent_sign=&#8221;off&#8221; bar_bg_color=&#8221;#e02b20&#8243; _builder_version=&#8221;3.29.2&#8243; title_font=&#8221;Delius Unicase||||||||&#8221; title_text_align=&#8221;center&#8221; title_font_size=&#8221;14px&#8221; _i=&#8221;0&#8243; _address=&#8221;0.7.2.0&#8243;][\/et_pb_circle_counter][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;3.29.2&#8243; _i=&#8221;3&#8243; _address=&#8221;0.7.3&#8243;][et_pb_circle_counter title=&#8221;Etna Rosso doc %22Sciara Scura%22 scontato \u20ac 7,59&#8243; number=&#8221;85&#8243; percent_sign=&#8221;off&#8221; bar_bg_color=&#8221;#e02b20&#8243; _builder_version=&#8221;3.29.2&#8243; title_font=&#8221;Delius Unicase||||||||&#8221; title_text_align=&#8221;center&#8221; title_font_size=&#8221;14px&#8221; _i=&#8221;0&#8243; _address=&#8221;0.7.3.0&#8243;][\/et_pb_circle_counter][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_4,1_4,1_4,1_4&#8243; _builder_version=&#8221;3.29.2&#8243; _i=&#8221;8&#8243; _address=&#8221;0.8&#8243;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;3.29.2&#8243; _i=&#8221;0&#8243; _address=&#8221;0.8.0&#8243;][et_pb_circle_counter title=&#8221;Rosso di montalcino doc %22San piero%22 scontato \u20ac 8,69&#8243; number=&#8221;84&#8243; percent_sign=&#8221;off&#8221; bar_bg_color=&#8221;#e02b20&#8243; _builder_version=&#8221;3.29.2&#8243; title_font=&#8221;Delius Unicase||||||||&#8221; title_text_align=&#8221;center&#8221; title_font_size=&#8221;14px&#8221; _i=&#8221;0&#8243; _address=&#8221;0.8.0.0&#8243;][\/et_pb_circle_counter][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;3.29.2&#8243; _i=&#8221;1&#8243; _address=&#8221;0.8.1&#8243;][et_pb_circle_counter title=&#8221;Chianti classico docg %22La vittoria%22 scontato  \u20ac 5,49&#8243; number=&#8221;83&#8243; percent_sign=&#8221;off&#8221; bar_bg_color=&#8221;#e02b20&#8243; _builder_version=&#8221;3.29.2&#8243; title_font=&#8221;Delius Unicase||||||||&#8221; title_text_align=&#8221;center&#8221; title_font_size=&#8221;14px&#8221; _i=&#8221;0&#8243; _address=&#8221;0.8.1.0&#8243;][\/et_pb_circle_counter][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;3.29.2&#8243; _i=&#8221;2&#8243; _address=&#8221;0.8.2&#8243;][et_pb_circle_counter title=&#8221;Montefalco rosso DOC %22Il Montagnolo%22 Scontato \u20ac 5,49&#8243; number=&#8221;82&#8243; percent_sign=&#8221;off&#8221; bar_bg_color=&#8221;#e02b20&#8243; _builder_version=&#8221;3.29.2&#8243; title_font=&#8221;Delius Unicase||||||||&#8221; title_text_align=&#8221;center&#8221; title_font_size=&#8221;14px&#8221; _i=&#8221;0&#8243; _address=&#8221;0.8.2.0&#8243;][\/et_pb_circle_counter][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;3.29.2&#8243; _i=&#8221;3&#8243; _address=&#8221;0.8.3&#8243;][et_pb_circle_counter title=&#8221;Vermentino bolgheri doc %22duplice filar%22 scontato \u20ac 6,59&#8243; number=&#8221;82&#8243; percent_sign=&#8221;off&#8221; bar_bg_color=&#8221;#e02b20&#8243; _builder_version=&#8221;3.29.2&#8243; title_font=&#8221;Delius Unicase||||||||&#8221; title_text_align=&#8221;center&#8221; title_font_size=&#8221;14px&#8221; _i=&#8221;0&#8243; _address=&#8221;0.8.3.0&#8243;][\/et_pb_circle_counter][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_4,1_4,1_4,1_4&#8243; _builder_version=&#8221;3.29.2&#8243; _i=&#8221;9&#8243; _address=&#8221;0.9&#8243;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;3.29.2&#8243; _i=&#8221;0&#8243; _address=&#8221;0.9.0&#8243;][et_pb_circle_counter title=&#8221;Passerina vino spumante brut %22Le prete%22 scontato \u20ac 4,49&#8243; number=&#8221;79&#8243; percent_sign=&#8221;off&#8221; bar_bg_color=&#8221;#e02b20&#8243; _builder_version=&#8221;3.29.2&#8243; title_font=&#8221;Delius Unicase||||||||&#8221; title_text_align=&#8221;center&#8221; title_font_size=&#8221;14px&#8221; _i=&#8221;0&#8243; _address=&#8221;0.9.0.0&#8243;][\/et_pb_circle_counter][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;3.29.2&#8243; _i=&#8221;1&#8243; _address=&#8221;0.9.1&#8243;][et_pb_circle_counter title=&#8221;Lugana DOC %22Il penacin%22 scontato \u20ac5,89&#8243; number=&#8221;78&#8243; percent_sign=&#8221;off&#8221; bar_bg_color=&#8221;#e02b20&#8243; _builder_version=&#8221;3.29.2&#8243; title_font=&#8221;Delius Unicase||||||||&#8221; title_text_align=&#8221;center&#8221; title_font_size=&#8221;14px&#8221; _i=&#8221;0&#8243; _address=&#8221;0.9.1.0&#8243;][\/et_pb_circle_counter][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;3.29.2&#8243; _i=&#8221;2&#8243; _address=&#8221;0.9.2&#8243;][et_pb_circle_counter title=&#8221;Ribolla gialla friuli colli orientali doc %22moalm\u00e0cie%22 scont. \u20ac 5,45&#8243; number=&#8221;75&#8243; percent_sign=&#8221;off&#8221; bar_bg_color=&#8221;#e02b20&#8243; _builder_version=&#8221;3.29.2&#8243; title_font=&#8221;Delius Unicase||||||||&#8221; title_text_align=&#8221;center&#8221; title_font_size=&#8221;13px&#8221; _i=&#8221;0&#8243; _address=&#8221;0.9.2.0&#8243;][\/et_pb_circle_counter][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;3.29.2&#8243; _i=&#8221;3&#8243; _address=&#8221;0.9.3&#8243;][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;3.29.2&#8243; _i=&#8221;10&#8243; _address=&#8221;0.10&#8243;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.29.2&#8243; _i=&#8221;0&#8243; _address=&#8221;0.10.0&#8243;][et_pb_text _builder_version=&#8221;3.29.2&#8243; _i=&#8221;0&#8243; _address=&#8221;0.10.0.0&#8243;]<\/p>\n<h3 style=\"text-align: center;\"><strong>Grandi Vigne: Vini nella fascia di prezzo 10-15 \u20ac, i migliori\u00a0<\/strong><strong>(&gt;75\/100)<\/strong><\/h3>\n<p style=\"text-align: justify;\">In questa fascia di prezzo nella linea Grandi Vigne in sconto non ci sono molti vini e alcuni non mi hanno fatto impazzire. Per\u00f2 una menzione d&#8217;onore la merita questo Franciacorta che, nella sua declinazione Brut, \u00e8 stato davvero capace di colpirmi.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_4,1_4,1_4,1_4&#8243; _builder_version=&#8221;3.29.2&#8243; _i=&#8221;11&#8243; _address=&#8221;0.11&#8243;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;3.29.2&#8243; _i=&#8221;0&#8243; _address=&#8221;0.11.0&#8243;][et_pb_circle_counter title=&#8221;Franciacorta DOCG Brut %22la Chiesuola%22 Scontato \u20ac 10,40&#8243; number=&#8221;98&#8243; percent_sign=&#8221;off&#8221; bar_bg_color=&#8221;#e02b20&#8243; _builder_version=&#8221;3.29.2&#8243; title_font=&#8221;Delius Unicase||||||||&#8221; title_text_align=&#8221;center&#8221; title_font_size=&#8221;14px&#8221; _i=&#8221;0&#8243; _address=&#8221;0.11.0.0&#8243;][\/et_pb_circle_counter][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;3.29.2&#8243; _i=&#8221;1&#8243; _address=&#8221;0.11.1&#8243;][et_pb_circle_counter title=&#8221;Passito di pantelleria %22gelka%22 Scontato \u20ac 13,90&#8243; number=&#8221;89&#8243; percent_sign=&#8221;off&#8221; bar_bg_color=&#8221;#e02b20&#8243; _builder_version=&#8221;3.29.2&#8243; title_font=&#8221;Delius Unicase||||||||&#8221; title_text_align=&#8221;center&#8221; title_font_size=&#8221;14px&#8221; _i=&#8221;0&#8243; _address=&#8221;0.11.1.0&#8243;][\/et_pb_circle_counter][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;3.29.2&#8243; _i=&#8221;2&#8243; _address=&#8221;0.11.2&#8243;][et_pb_circle_counter title=&#8221;Franciacorta DOCG Brut Sat\u00e9n %22Rive mure%22 Scontato \u20ac 13,10&#8243; number=&#8221;82&#8243; percent_sign=&#8221;off&#8221; bar_bg_color=&#8221;#e02b20&#8243; _builder_version=&#8221;3.29.2&#8243; title_font=&#8221;Delius Unicase||||||||&#8221; title_text_align=&#8221;center&#8221; title_font_size=&#8221;14px&#8221; _i=&#8221;0&#8243; _address=&#8221;0.11.2.0&#8243;][\/et_pb_circle_counter][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;3.29.2&#8243; _i=&#8221;3&#8243; _address=&#8221;0.11.3&#8243;][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;3.29.2&#8243; _i=&#8221;12&#8243; _address=&#8221;0.12&#8243;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.29.2&#8243; _i=&#8221;0&#8243; _address=&#8221;0.12.0&#8243;][et_pb_text _builder_version=&#8221;3.29.2&#8243; _i=&#8221;0&#8243; _address=&#8221;0.12.0.0&#8243;]<\/p>\n<h3 style=\"text-align: center;\"><strong>Grandi Vigne: Vini sopra i 15 \u20ac, i migliori\u00a0<\/strong><strong>(&gt;75\/100)<\/strong><\/h3>\n<p style=\"text-align: justify;\">Purtroppo in degustazione non ho trovato altri vini del progetto Grandi Vigne sopra i 15 \u20ac, pertanto non so dirti come siano. Anzi, se sei riuscito ad assaggiare l&#8217;Amarone della Valpolicella Classico DOCG &#8220;I filari del Pigno&#8221; che scontato costa \u20ac 17,90 o il Montepulciano d&#8217;Abruzzo Colline Teramane DOCG che scontato costa \u20ac 24,90 ti invito a segnalarmi la tua opinione in un commento in modo che sia utile a tutti! Grazie di cuore!\u00a0\ud83d\ude0d<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_4,1_4,1_4,1_4&#8243; _builder_version=&#8221;3.29.2&#8243; _i=&#8221;13&#8243; _address=&#8221;0.13&#8243;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;3.29.2&#8243; _i=&#8221;0&#8243; _address=&#8221;0.13.0&#8243;][et_pb_circle_counter title=&#8221;Sforzato di Valtellina DOCG %22La Tecia%22 Scontato \u20ac 17,40&#8243; number=&#8221;86&#8243; percent_sign=&#8221;off&#8221; bar_bg_color=&#8221;#e02b20&#8243; _builder_version=&#8221;3.29.2&#8243; title_font=&#8221;Delius Unicase||||||||&#8221; title_text_align=&#8221;center&#8221; title_font_size=&#8221;14px&#8221; _i=&#8221;0&#8243; _address=&#8221;0.13.0.0&#8243;][\/et_pb_circle_counter][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;3.29.2&#8243; _i=&#8221;1&#8243; _address=&#8221;0.13.1&#8243;][et_pb_circle_counter title=&#8221;Vin santo del chianti doc %22Cantini%22 \u20ac 24,40&#8243; number=&#8221;85&#8243; percent_sign=&#8221;off&#8221; bar_bg_color=&#8221;#e02b20&#8243; _builder_version=&#8221;3.29.2&#8243; title_font=&#8221;Delius Unicase||||||||&#8221; title_text_align=&#8221;center&#8221; title_font_size=&#8221;14px&#8221; _i=&#8221;0&#8243; _address=&#8221;0.13.1.0&#8243;][\/et_pb_circle_counter][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;3.29.2&#8243; _i=&#8221;2&#8243; _address=&#8221;0.13.2&#8243;][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;3.29.2&#8243; _i=&#8221;3&#8243; _address=&#8221;0.13.3&#8243;][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;3.29.2&#8243; _i=&#8221;14&#8243; _address=&#8221;0.14&#8243;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.29.2&#8243; _i=&#8221;0&#8243; _address=&#8221;0.14.0&#8243;][et_pb_text _builder_version=&#8221;3.29.2&#8243; _i=&#8221;0&#8243; _address=&#8221;0.14.0.0&#8243;]<\/p>\n<p style=\"text-align: justify;\"><strong>I vini &#8220;Grandi Vigne&#8221; sono in vendita in esclusiva presso <em>Iper, La grande i<\/em>, in 21 ipermercati divisi in 4 regioni del Nord Italia<\/strong> che ti riporto qui sotto. Personalmente ti consiglio di recarti, con la scusa di fare scorta, a uno di questi centri anche se non sei immediatamente in zona: i vini hanno un rapporto qualit\u00e0 prezzo cos\u00ec straordinario che per me valgono tranquillamente una cinquantina di km&#8230; a patto di riempire il bagagliaio dopo aver fatto accuratamente posto nella tua cantinetta.\ud83e\udd23<\/p>\n<h3>Grandi Vigne in Lombardia:<\/h3>\n<ul>\n<li style=\"text-align: justify;\">Montebello della Battaglia (PV) &#8211; Centro Commerciale Montebello;<\/li>\n<li style=\"text-align: justify;\">Gadesco (CR) &#8211; Centro Commerciale Cremona Due;<\/li>\n<li style=\"text-align: justify;\">Brembate (BG) &#8211; Centro Commerciale Brembate;<\/li>\n<li style=\"text-align: justify;\">Orio al Serio (BG) &#8211; Centro Commerciale Orio Center;<\/li>\n<li style=\"text-align: justify;\">Seriate (BG) &#8211; Centro Commerciale Alle Valli;<\/li>\n<li style=\"text-align: justify;\">Milano &#8211; Centro Commerciale <em>Iper, La grande i<\/em>;<\/li>\n<li style=\"text-align: justify;\">Milano &#8211; Centro Commerciale Piazza Portello;<\/li>\n<li style=\"text-align: justify;\"><strong>Arese (MI) &#8211; Centro Commerciale Il Centro &#8211; Presto si terr\u00e0 un evento bellissimo proprio come questo, rimani aggiornato!<\/strong><\/li>\n<li style=\"text-align: justify;\">Busnago (MI) &#8211; Centro Commerciale Il Globo;<\/li>\n<li style=\"text-align: justify;\">Magenta (MI) &#8211; Centro Commerciale <em>Iper, La grande i<\/em>;<\/li>\n<li style=\"text-align: justify;\">Rozzano (MI) &#8211; Centro Commerciale Fiordaliso;<\/li>\n<li style=\"text-align: justify;\">Vittuone (MI) &#8211; Centro Commerciale Il Destriero Shopping Center;<\/li>\n<li style=\"text-align: justify;\">Varese &#8211; Centro Commerciale Belforte<\/li>\n<li style=\"text-align: justify;\">Solbiate Olona (VA) &#8211; Centro Commerciale Le Betulle;<\/li>\n<li style=\"text-align: justify;\">Grandate (CO) &#8211; Centro Commerciale <em>Iper, La grande i<\/em>;<\/li>\n<li style=\"text-align: justify;\">Monza (MB) &#8211; Centro Commerciale<em>Iper, La grande i<\/em>;<\/li>\n<li style=\"text-align: justify;\">Lonato (BS) &#8211; Centro Commerciale Il Leone Shopping Center.<\/li>\n<\/ul>\n<h3>Grandi Vigne in Piemonte:<\/h3>\n<ul>\n<li>Serravalle Scrivia (AL) &#8211; Centro Commerciale Serravalle;<\/li>\n<li>Tortona (AL) &#8211; Centro Commerciale Oasi Tortona;<\/li>\n<\/ul>\n<h3>Grandi Vigne in Veneto:<\/h3>\n<ul>\n<li>Castelfranco Veneto (TV) &#8211; Centro Commerciale I Giardini del sole;<\/li>\n<li>San Martino Buon Albergo (VR) &#8211; Centro Commerciale Le Corti Venete<\/li>\n<\/ul>\n<h3>Grandi Vigne in Emilia-Romagna:<\/h3>\n<ul>\n<li>Savignano sul Rubicone (FC) &#8211; Centro Commerciale Romagna Center;<\/li>\n<\/ul>\n<p>\u00a0Cheers\ud83c\udf77<\/p>\n<p>Chiara<\/p>\n<p style=\"text-align: justify;\">PS <strong>Ci tengo molto che mi scrivi in un commento se conoscevi gi\u00e0 il progetto &#8220;Grandi Vigne&#8221; e se hai gi\u00e0 degustato, o degusterai, qualcuno dei vigni che ti ho segnalato.<\/strong> Oppure se hai da segnalarmi anche altri vini di questo progetto che hai bevuto e che secondo te sono meritevoli di nota. Un&#8217;ultima cosa&#8230; tu compri vino al supermercato? Se s\u00ec, quale e per quale occasione? Grazie di cuore in anticipo per il tuo commento!<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sabato 5 ottobre sono stata invitata alla degustazione vini \u201cGiro d\u2019Italia in 80 vini\u201d del progetto \u201cGrandi Vigne\u201d di Iper presso il Centro Commerciale Portello di Milano. L\u2019Iper Portello di Milano \u00e8 comodissimo da raggiungere anche in Metro perch\u00e9 sulla nuova linea lilla c\u2019\u00e8 proprio la fermata \u201cPortello\u201d che si trova a 5 minuti a [&hellip;]<\/p>\n","protected":false},"author":49,"featured_media":17877,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[298],"tags":[],"class_list":["post-17750","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-degustazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.0 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Grandi Vigne: 36 vini di qualit\u00e0 a un prezzo incredibile che trovi all&#039;Iper - Perlage Suite<\/title>\n<meta name=\"description\" content=\"Sabato 5 ottobre ho degustato tutti gli 80 vini italiani che fanno parte del progetto Grandi Vigne di Iper. Ecco la mia selezione dei vini da comprare.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/perlagesuite.com\/en\/grandi-vigne-vini-iper-2019\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Grandi Vigne: 36 vini di qualit\u00e0 a un prezzo incredibile che trovi all&#039;Iper\" \/>\n<meta property=\"og:description\" content=\"Sabato 5 ottobre ho degustato tutti gli 80 vini italiani che fanno parte del progetto Grandi Vigne di Iper. Ecco la mia selezione dei vini da comprare.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/perlagesuite.com\/en\/grandi-vigne-vini-iper-2019\/\" \/>\n<meta property=\"og:site_name\" content=\"Perlage Suite\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/chiarabassiperlagesuite\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-10T11:20:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-15T09:52:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/perlagesuite.com\/wp-content\/uploads\/2019\/10\/vini-supermercato-grandi-vigne-iper-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Chiara Bassi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@perlagesuite\" \/>\n<meta name=\"twitter:site\" content=\"@perlagesuite\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Chiara Bassi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"18 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/grandi-vigne-vini-iper-2019\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/grandi-vigne-vini-iper-2019\\\/\"},\"author\":{\"name\":\"Chiara Bassi\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/person\\\/81b257517a1007c1a823318ac86c6013\"},\"headline\":\"Grandi Vigne: 36 vini di qualit\u00e0 a un prezzo incredibile che trovi all&#8217;Iper\",\"datePublished\":\"2019-10-10T11:20:39+00:00\",\"dateModified\":\"2020-10-15T09:52:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/grandi-vigne-vini-iper-2019\\\/\"},\"wordCount\":3653,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/grandi-vigne-vini-iper-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/vini-supermercato-grandi-vigne-iper-4.jpg\",\"articleSection\":[\"Degustazioni\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/perlagesuite.com\\\/grandi-vigne-vini-iper-2019\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/grandi-vigne-vini-iper-2019\\\/\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/grandi-vigne-vini-iper-2019\\\/\",\"name\":\"Grandi Vigne: 36 vini di qualit\u00e0 a un prezzo incredibile che trovi all'Iper - Perlage Suite\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/grandi-vigne-vini-iper-2019\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/grandi-vigne-vini-iper-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/vini-supermercato-grandi-vigne-iper-4.jpg\",\"datePublished\":\"2019-10-10T11:20:39+00:00\",\"dateModified\":\"2020-10-15T09:52:10+00:00\",\"description\":\"Sabato 5 ottobre ho degustato tutti gli 80 vini italiani che fanno parte del progetto Grandi Vigne di Iper. Ecco la mia selezione dei vini da comprare.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/grandi-vigne-vini-iper-2019\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/perlagesuite.com\\\/grandi-vigne-vini-iper-2019\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/grandi-vigne-vini-iper-2019\\\/#primaryimage\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/vini-supermercato-grandi-vigne-iper-4.jpg\",\"contentUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/vini-supermercato-grandi-vigne-iper-4.jpg\",\"width\":1080,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/grandi-vigne-vini-iper-2019\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/perlagesuite.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Grandi Vigne: 36 vini di qualit\u00e0 a un prezzo incredibile che trovi all&#8217;Iper\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#website\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/\",\"name\":\"Perlage Suite\",\"description\":\"Il Wine Blog di Chiara Bassi\",\"publisher\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/perlagesuite.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#organization\",\"name\":\"Chiara Bassi\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Chiara-Bassi-sommelier-wine-blogger-logo.png\",\"contentUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Chiara-Bassi-sommelier-wine-blogger-logo.png\",\"width\":512,\"height\":512,\"caption\":\"Chiara Bassi\"},\"image\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/chiarabassiperlagesuite\",\"https:\\\/\\\/x.com\\\/perlagesuite\",\"https:\\\/\\\/www.instagram.com\\\/perlagesuite\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/person\\\/81b257517a1007c1a823318ac86c6013\",\"name\":\"Chiara Bassi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g\",\"caption\":\"Chiara Bassi\"},\"sameAs\":[\"https:\\\/\\\/perlagesuite.com\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Grandi Vigne: 36 quality wines at an incredible price you can find at Iper - Perlage Suite","description":"On Saturday 5 October, I tasted all 80 Italian wines that are part of Iper's Grandi Vigne project. Here is my selection of wines to buy.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/perlagesuite.com\/en\/grandi-vigne-vini-iper-2019\/","og_locale":"en_GB","og_type":"article","og_title":"Grandi Vigne: 36 vini di qualit\u00e0 a un prezzo incredibile che trovi all'Iper","og_description":"Sabato 5 ottobre ho degustato tutti gli 80 vini italiani che fanno parte del progetto Grandi Vigne di Iper. Ecco la mia selezione dei vini da comprare.","og_url":"https:\/\/perlagesuite.com\/en\/grandi-vigne-vini-iper-2019\/","og_site_name":"Perlage Suite","article_publisher":"https:\/\/www.facebook.com\/chiarabassiperlagesuite","article_published_time":"2019-10-10T11:20:39+00:00","article_modified_time":"2020-10-15T09:52:10+00:00","og_image":[{"width":1080,"height":720,"url":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2019\/10\/vini-supermercato-grandi-vigne-iper-4.jpg","type":"image\/jpeg"}],"author":"Chiara Bassi","twitter_card":"summary_large_image","twitter_creator":"@perlagesuite","twitter_site":"@perlagesuite","twitter_misc":{"Written by":"Chiara Bassi","Estimated reading time":"18 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/perlagesuite.com\/grandi-vigne-vini-iper-2019\/#article","isPartOf":{"@id":"https:\/\/perlagesuite.com\/grandi-vigne-vini-iper-2019\/"},"author":{"name":"Chiara Bassi","@id":"https:\/\/perlagesuite.com\/#\/schema\/person\/81b257517a1007c1a823318ac86c6013"},"headline":"Grandi Vigne: 36 vini di qualit\u00e0 a un prezzo incredibile che trovi all&#8217;Iper","datePublished":"2019-10-10T11:20:39+00:00","dateModified":"2020-10-15T09:52:10+00:00","mainEntityOfPage":{"@id":"https:\/\/perlagesuite.com\/grandi-vigne-vini-iper-2019\/"},"wordCount":3653,"commentCount":0,"publisher":{"@id":"https:\/\/perlagesuite.com\/#organization"},"image":{"@id":"https:\/\/perlagesuite.com\/grandi-vigne-vini-iper-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2019\/10\/vini-supermercato-grandi-vigne-iper-4.jpg","articleSection":["Degustazioni"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/perlagesuite.com\/grandi-vigne-vini-iper-2019\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/perlagesuite.com\/grandi-vigne-vini-iper-2019\/","url":"https:\/\/perlagesuite.com\/grandi-vigne-vini-iper-2019\/","name":"Grandi Vigne: 36 quality wines at an incredible price you can find at Iper - Perlage Suite","isPartOf":{"@id":"https:\/\/perlagesuite.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/perlagesuite.com\/grandi-vigne-vini-iper-2019\/#primaryimage"},"image":{"@id":"https:\/\/perlagesuite.com\/grandi-vigne-vini-iper-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2019\/10\/vini-supermercato-grandi-vigne-iper-4.jpg","datePublished":"2019-10-10T11:20:39+00:00","dateModified":"2020-10-15T09:52:10+00:00","description":"On Saturday 5 October, I tasted all 80 Italian wines that are part of Iper's Grandi Vigne project. Here is my selection of wines to buy.","breadcrumb":{"@id":"https:\/\/perlagesuite.com\/grandi-vigne-vini-iper-2019\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/perlagesuite.com\/grandi-vigne-vini-iper-2019\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/perlagesuite.com\/grandi-vigne-vini-iper-2019\/#primaryimage","url":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2019\/10\/vini-supermercato-grandi-vigne-iper-4.jpg","contentUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2019\/10\/vini-supermercato-grandi-vigne-iper-4.jpg","width":1080,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/perlagesuite.com\/grandi-vigne-vini-iper-2019\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/perlagesuite.com\/"},{"@type":"ListItem","position":2,"name":"Grandi Vigne: 36 vini di qualit\u00e0 a un prezzo incredibile che trovi all&#8217;Iper"}]},{"@type":"WebSite","@id":"https:\/\/perlagesuite.com\/#website","url":"https:\/\/perlagesuite.com\/","name":"Perlage Suite","description":"Chiara Bassi's Wine Blog","publisher":{"@id":"https:\/\/perlagesuite.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/perlagesuite.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/perlagesuite.com\/#organization","name":"Chiara Bassi","url":"https:\/\/perlagesuite.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/perlagesuite.com\/#\/schema\/logo\/image\/","url":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2022\/03\/Chiara-Bassi-sommelier-wine-blogger-logo.png","contentUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2022\/03\/Chiara-Bassi-sommelier-wine-blogger-logo.png","width":512,"height":512,"caption":"Chiara Bassi"},"image":{"@id":"https:\/\/perlagesuite.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/chiarabassiperlagesuite","https:\/\/x.com\/perlagesuite","https:\/\/www.instagram.com\/perlagesuite\/"]},{"@type":"Person","@id":"https:\/\/perlagesuite.com\/#\/schema\/person\/81b257517a1007c1a823318ac86c6013","name":"Chiara Bassi","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g","caption":"Chiara Bassi"},"sameAs":["https:\/\/perlagesuite.com"]}]}},"_links":{"self":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/posts\/17750","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/comments?post=17750"}],"version-history":[{"count":0,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/posts\/17750\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/media\/17877"}],"wp:attachment":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/media?parent=17750"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/categories?post=17750"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/tags?post=17750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}