{"id":19196,"date":"2019-11-06T16:36:36","date_gmt":"2019-11-06T15:36:36","guid":{"rendered":"https:\/\/perlagesuite.com\/?p=19196"},"modified":"2020-10-15T10:50:37","modified_gmt":"2020-10-15T09:50:37","slug":"amarone-della-valpolicella-riserva-musella-famiglie-storiche","status":"publish","type":"post","link":"https:\/\/perlagesuite.com\/en\/amarone-della-valpolicella-riserva-musella-famiglie-storiche\/","title":{"rendered":"Amarone della Valpolicella Riserva: a toast to Dad on his birthday"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.0.5&#8243;][et_pb_row _builder_version=&#8221;4.0.5&#8243;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.0.5&#8243;][et_pb_text _builder_version=&#8221;4.0.5&#8243;]<\/p>\n<p style=\"text-align: justify;\">Ho deciso di interrompere tutto quello che stavo facendo perch\u00e8 in realt\u00e0 non stavo facendo niente sul serio, dato che dall&#8217;una di stanotte il mio pensiero \u00e8 costantemente rivolto al fatto che <strong>oggi \u00e8 primo compleanno di mio padre che passo senza di te pap\u00e0<\/strong> da quando sono nata. Un pianto ininterrotto cullato dal rumore della pioggia sul tetto fino a che non mi sono addormentata per appena un paio d&#8217;ore alle prime luci dell&#8217;alba. Stanotte ho realizzato che ho perso il mio faro e sto navigando a vista in un oceano di dolore e, nonostante sia passato quasi un anno da quando sei mancato, mi rendo conto che ogni giorno \u00e8 peggio del precedente, che il dolore non si attenua, ma cresce. Non credo di aver fatto pi\u00f9 di due ore consecutive quest&#8217;anno senza piangere almeno un minuto, anche se ho cercato di non farlo vedere perch\u00e8 ci sono mille cose da fare e percorsi da completare. La consapevolezza che hai fatto tantissimo sempre per aiutarmi mi spinge a voler tagliare il traguardo, perch\u00e8 tu per primo meriti che io ci riesca. Non sono stata perfetta su niente, n\u00e9 nei miei rapporti personali, n\u00e9 nel mio lavoro. Ho accettato comportamenti inaccettabili da chi mi stava accanto per paura di affrontare questo dolore da sola, per poi capire che non ero sola perch\u00e8 mamma e Fabrizio mi sono stati accanto ogni secondo. E non solo loro. Ho cercato di trovare il senso della mia vita, ma onestamente non ne vedo il senso se non posso condividerla con te. L&#8217;Amore che provo per te, pap\u00e0, \u00e8 qualcosa di cos\u00ec unico e totalizzante che, perdona la mia presunzione, credo pochi possano capire. Per questo ho deciso ora di aprirmi una buona bottiglia di vino e buttare fuori tutto quello che ho dentro. Dato che questa per me \u00e8 &#8220;la settimana dell&#8217;Amarone&#8221;, iniziata con <a href=\"https:\/\/perlagesuite.com\/amarone-della-valpolicella-cosa-abbinare-mangiare\/\"><span style=\"text-decoration: underline;\"><strong>Garbole al Ristorante Tre Cristi di Milano<\/strong><\/span><\/a>, proseguita a Verona con <strong>Pietro Zardini<\/strong> e ultimata domani da <strong>Massimago<\/strong>, ho deciso di raccontarti dell&#8217;<strong>Amarone della Valpolicella Riserva<\/strong> che mi ha colpito di pi\u00f9 durante una cena di gala organizzata a Milano dall&#8217;Associazione le <strong>Famiglie Storiche<\/strong> dell&#8217;Amarone: <strong>Musella Riserva 2012<\/strong>. Tu pap\u00e0 adoravi l&#8217;Amarone e, in generale, i vini passiti secchi quindi so che oggi non potrei stappare bottiglia migliore.<\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2019\/11\/famiglie-storiche-amarone-della-valpolicella-riserva.jpg&#8221; _builder_version=&#8221;4.0.5&#8243;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.0.5&#8243;]<\/p>\n<h3 style=\"text-align: center;\">Perch\u00e8 ho usato un calice Napoleon?<\/h3>\n<p style=\"text-align: justify;\">Probabilmente la mia scelta di utilizzare un bicchiere da Cognac ti ha incuriosito, ma personalmente lo consiglio &#8220;un trucchetto&#8221; che dovresti annotarti quando decidi di degustare un grande rosso in estemporanea e non vuoi aspettare il tempo di ossigenazione, e non hai in casa un altro calice particolarmente ampio. Proprio in questi giorni <strong>sono stata intervistata da Alma per il numero di Gennaio della rivista &#8220;Cose di Casa&#8221;<\/strong>\u00a0(lo trovi in edicola da fine dicembre, ricordati di comprarlo e fammi sapere se il pezzo ti piace!) e abbiamo parlato di bicchieri da vino. In particolare mi ha chiesto come coprire il maggior numero di vini con la minore tipologia di bicchieri. Naturalmente il Napoleon \u00e8 una di quelle che ti consiglio di avere! Questo bicchiere \u00e8 perfetto anche per ossigenare i vini rossi impegnativi come l&#8217;Amarone della Valpolicella Riserva! Ti consiglio di comprare i <a href=\"https:\/\/amzn.to\/2oWbGui\"><span style=\"text-decoration: underline;\"><strong>Bormioli Michelangelo Masterpiece in confezione da 4 pezzi che trovi su Amazon a questo link<\/strong><\/span><\/a>.<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.0.5&#8243;]<\/p>\n<h3 style=\"text-align: center;\">Amarone ella Valpolicella Riserva, Musella 2012: Caratteristiche &amp; vinificazione<\/h3>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">I grappoli sono scelti con cura e, dopo essere raccolti manualmente in cassette, vengono disposti in una speciale stanza ventilata ad appassire. Le uve perdono almeno il 35% del loro peso iniziale in un processo di concentrazione degli zuccheri, dei tannini nobili e delle sostanze aromatiche. In gennaio avviene la pigiatura soffice e parte la fermentazione a bassa temperatura. Il vino resta 24 mesi in parte in tonneau di rovere francese e in parte di botti di grandi dimensioni (700, 1500 e 3000 litri). Dopo l&#8217;imbottigliamento affina almeno un anno in bottiglia prima di essere messo in commercio.<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.0.5&#8243;]<\/p>\n<h3 style=\"text-align: center;\">Amarone ella Valpolicella Riserva, Musella 2012: La degustazione<\/h3>\n<p style=\"text-align: justify;\">L&#8217;Amarone \u00e8 un vino che ha bisogno di tempo, di tanto tempo. Questo 2012 \u00e8 un giovane che promette molto molto bene, ma mi riservo di assaggiare la seconda bottiglia che ho in cantina tra una decina d&#8217;anni! Quello che mi \u00e8 piaciuto particolarmente di questo amarone \u00e8 la sua finezza, sia al naso sia in bocca. Si presenta di un bellissimo colore rosso rubino semitrasparente. Gi\u00e0 roteando il bicchiere mostra tutta la sua consistenza. Al naso un delicato profumo di corteccia bagnata, fungo porcino, noce moscata, cioccolato e ciliegia sotto spirito. In bocca \u00e8 coerente, fresco, morbido, con un tannino che deve ancora arrotondarsi e dimostra tutta la sua potenzialit\u00e0 di invecchiamento. Alcolico e potente con un finale lungo.<\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2019\/01\/buoni-propositi-2019-foto-famiglia-chiara-bassi.jpg&#8221; _builder_version=&#8221;4.0.5&#8243;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.0.5&#8243;]<\/p>\n<p style=\"text-align: justify;\">Caro pap\u00e0, se tu fossi stato qui con me e mamma saremmo stati a mangiare al <strong>Ristorante Tentazioni a Costa Volpino<\/strong> come per tutti i tuoi ultimi compleanni. Invece ci ho pranzato da sola. Come in questa foto, per il tuo 60esimo compleanno, l&#8217;ultimo compleanno che abbiamo festeggiato senza la malattia. Avremmo stappato un buon Amarone della Valpolicella Riserva e avresti mangiato gli gnocchi che fa Sandro e che ti piacevano tanto, mentre Giacomo ci avrebbe coccolato con mille attenzioni. Poi avremmo fatto una passeggiata a Lovere. Invece il regalo per il tuo compleanno l&#8217;ho fatto a mamma, uno splendido <a href=\"https:\/\/blossomsuite.com\/prodotto\/paphiopedilum-spicerianum\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"text-decoration: underline;\"><strong>Paphiopedilum spicerianum<\/strong><\/span><\/a> direttamente dal nostro sito <a href=\"https:\/\/blossomsuite.com\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"text-decoration: underline;\"><strong>g<\/strong><strong>ardening blog Blossom Suite<\/strong><\/span><\/a>. Non \u00e8 la stessa cosa, ma dicono che le orchidee sono una medicina per l&#8217;anima.<\/p>\n<p style=\"text-align: justify;\">Caro pap\u00e0,\u00a0spero che per il tuo prossimo compleanno, il 6 novembre 2020, potr\u00f2 fare un viaggio in Argentina e starmene una settimana a Buenos Aires a degustare vini grandiosi nella tua terra natia. I <a href=\"https:\/\/perlagesuite.com\/festa-del-papa-vini-argentini\/\"><span style=\"text-decoration: underline;\"><strong>vini argentini<\/strong><\/span><\/a> sono meravigliosi. E spero di mangiare il vero asado. Era un viaggio che ci eravamo ripromessi di fare insieme, ma che far\u00f2 da sola nella speranza di trovare un po&#8217; di pace.<\/p>\n<p style=\"text-align: justify;\">Ora che mi sono &#8220;sfogata&#8221; posso tornare a lavorare.<\/p>\n<p style=\"text-align: justify;\">Ma oggi resto off-line per tutti, scusatemi.<\/p>\n<p style=\"text-align: justify;\">Cheers\u00a0\ud83c\udf39\ud83c\udf77<\/p>\n<p style=\"text-align: justify;\">Chiara<\/p>\n<p style=\"text-align: justify;\">\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.0.5&#8243;]<\/p>\n<p style=\"text-align: justify;\">P.S. Questo libro per me \u00e8 cos\u00ec importante perch\u00e8 \u00e8 l&#8217;ultimo progetto che abbiamo fatto insieme. Non dimenticher\u00f2 mai il mese di ottobre 2018 quando mentre facevi una chemioterapia che ti ammazzava e ormai avevi perso anche la vista cercavi di correggermi la bozza di questo libro. Entravi e uscivi dall&#8217;ospedale in un&#8217;emergenza continua. Appena il libro \u00e8 stato pronto ti hanno ricoverato definitivamente. Come che avessi dato il massimo e poi avessi finito le risorse per lottare. So che c&#8217;\u00e8 qualche errore, ma ho scelto di non toccare questa prima edizione che resta la pi\u00f9 bella e importante, la pi\u00f9 umana. Per me era fondamentale che uscisse cos\u00ec, il giorno del tuo compleanno dell&#8217;anno scorso&#8230; perch\u00e8 darti questa soddisfazione \u00e8 stato l&#8217;ultimo regalo che ho potuto farti.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.0.5&#8243;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.0.5&#8243;][et_pb_wc_images product=&#8221;10582&#8243; _builder_version=&#8221;4.0.5&#8243;][\/et_pb_wc_images][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.0.5&#8243;][et_pb_wc_title product=&#8221;10582&#8243; _builder_version=&#8221;4.0.5&#8243;][\/et_pb_wc_title][et_pb_wc_rating product=&#8221;10582&#8243; _builder_version=&#8221;4.0.5&#8243;][\/et_pb_wc_rating][et_pb_wc_description product=&#8221;10582&#8243; _builder_version=&#8221;4.0.5&#8243;][\/et_pb_wc_description][et_pb_wc_price product=&#8221;10582&#8243; _builder_version=&#8221;4.0.5&#8243;][\/et_pb_wc_price][et_pb_wc_add_to_cart product=&#8221;10582&#8243; _builder_version=&#8221;4.0.5&#8243;][\/et_pb_wc_add_to_cart][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ho deciso di interrompere tutto quello che stavo facendo perch\u00e8 in realt\u00e0 non stavo facendo niente sul serio, dato che dall&#8217;una di stanotte il mio pensiero \u00e8 costantemente rivolto al fatto che oggi \u00e8 primo compleanno di mio padre che passo senza di te pap\u00e0 da quando sono nata. Un pianto ininterrotto cullato dal rumore [&hellip;]<\/p>\n","protected":false},"author":49,"featured_media":19208,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-19196","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-categorizzato"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.0 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Amarone della Valpolicella Riserva: un brindisi a pap\u00e0 - Perlage Suite<\/title>\n<meta name=\"description\" content=\"Oggi sarebbe stato il 63esimo compleanno di mio pap\u00e0 e per questo ho stappato un vino che lui avrebbe adorato: un Amarone della Valpolicella Riserva!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/perlagesuite.com\/en\/amarone-della-valpolicella-riserva-musella-famiglie-storiche\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Amarone della Valpolicella Riserva: un brindisi a pap\u00e0 per il suo compleanno\" \/>\n<meta property=\"og:description\" content=\"Oggi sarebbe stato il 63esimo compleanno di mio pap\u00e0 e per questo ho stappato un vino che lui avrebbe adorato: un Amarone della Valpolicella Riserva!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/perlagesuite.com\/en\/amarone-della-valpolicella-riserva-musella-famiglie-storiche\/\" \/>\n<meta property=\"og:site_name\" content=\"Perlage Suite\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/chiarabassiperlagesuite\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-06T15:36:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-15T09:50:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/perlagesuite.com\/wp-content\/uploads\/2019\/11\/amarone-della-valpolicella-riserva-musella.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Chiara Bassi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@perlagesuite\" \/>\n<meta name=\"twitter:site\" content=\"@perlagesuite\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Chiara Bassi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/amarone-della-valpolicella-riserva-musella-famiglie-storiche\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/amarone-della-valpolicella-riserva-musella-famiglie-storiche\\\/\"},\"author\":{\"name\":\"Chiara Bassi\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/person\\\/81b257517a1007c1a823318ac86c6013\"},\"headline\":\"Amarone della Valpolicella Riserva: un brindisi a pap\u00e0 per il suo compleanno\",\"datePublished\":\"2019-11-06T15:36:36+00:00\",\"dateModified\":\"2020-10-15T09:50:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/amarone-della-valpolicella-riserva-musella-famiglie-storiche\\\/\"},\"wordCount\":1331,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/amarone-della-valpolicella-riserva-musella-famiglie-storiche\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/amarone-della-valpolicella-riserva-musella.jpg\",\"articleSection\":[\"Non categorizzato\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/perlagesuite.com\\\/amarone-della-valpolicella-riserva-musella-famiglie-storiche\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/amarone-della-valpolicella-riserva-musella-famiglie-storiche\\\/\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/amarone-della-valpolicella-riserva-musella-famiglie-storiche\\\/\",\"name\":\"Amarone della Valpolicella Riserva: un brindisi a pap\u00e0 - Perlage Suite\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/amarone-della-valpolicella-riserva-musella-famiglie-storiche\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/amarone-della-valpolicella-riserva-musella-famiglie-storiche\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/amarone-della-valpolicella-riserva-musella.jpg\",\"datePublished\":\"2019-11-06T15:36:36+00:00\",\"dateModified\":\"2020-10-15T09:50:37+00:00\",\"description\":\"Oggi sarebbe stato il 63esimo compleanno di mio pap\u00e0 e per questo ho stappato un vino che lui avrebbe adorato: un Amarone della Valpolicella Riserva!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/amarone-della-valpolicella-riserva-musella-famiglie-storiche\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/perlagesuite.com\\\/amarone-della-valpolicella-riserva-musella-famiglie-storiche\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/amarone-della-valpolicella-riserva-musella-famiglie-storiche\\\/#primaryimage\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/amarone-della-valpolicella-riserva-musella.jpg\",\"contentUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/amarone-della-valpolicella-riserva-musella.jpg\",\"width\":1080,\"height\":720,\"caption\":\"amarone della valpolicella riserva musella\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/amarone-della-valpolicella-riserva-musella-famiglie-storiche\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/perlagesuite.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Amarone della Valpolicella Riserva: un brindisi a pap\u00e0 per il suo compleanno\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#website\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/\",\"name\":\"Perlage Suite\",\"description\":\"Il Wine Blog di Chiara Bassi\",\"publisher\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/perlagesuite.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#organization\",\"name\":\"Chiara Bassi\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Chiara-Bassi-sommelier-wine-blogger-logo.png\",\"contentUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Chiara-Bassi-sommelier-wine-blogger-logo.png\",\"width\":512,\"height\":512,\"caption\":\"Chiara Bassi\"},\"image\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/chiarabassiperlagesuite\",\"https:\\\/\\\/x.com\\\/perlagesuite\",\"https:\\\/\\\/www.instagram.com\\\/perlagesuite\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/person\\\/81b257517a1007c1a823318ac86c6013\",\"name\":\"Chiara Bassi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g\",\"caption\":\"Chiara Bassi\"},\"sameAs\":[\"https:\\\/\\\/perlagesuite.com\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Amarone della Valpolicella Riserva: a toast to Dad - Perlage Suite","description":"Today would have been my dad's 63rd birthday and for that I uncorked a wine he would have loved: an Amarone della Valpolicella Riserva!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/perlagesuite.com\/en\/amarone-della-valpolicella-riserva-musella-famiglie-storiche\/","og_locale":"en_GB","og_type":"article","og_title":"Amarone della Valpolicella Riserva: un brindisi a pap\u00e0 per il suo compleanno","og_description":"Oggi sarebbe stato il 63esimo compleanno di mio pap\u00e0 e per questo ho stappato un vino che lui avrebbe adorato: un Amarone della Valpolicella Riserva!","og_url":"https:\/\/perlagesuite.com\/en\/amarone-della-valpolicella-riserva-musella-famiglie-storiche\/","og_site_name":"Perlage Suite","article_publisher":"https:\/\/www.facebook.com\/chiarabassiperlagesuite","article_published_time":"2019-11-06T15:36:36+00:00","article_modified_time":"2020-10-15T09:50:37+00:00","og_image":[{"width":1080,"height":720,"url":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2019\/11\/amarone-della-valpolicella-riserva-musella.jpg","type":"image\/jpeg"}],"author":"Chiara Bassi","twitter_card":"summary_large_image","twitter_creator":"@perlagesuite","twitter_site":"@perlagesuite","twitter_misc":{"Written by":"Chiara Bassi","Estimated reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/perlagesuite.com\/amarone-della-valpolicella-riserva-musella-famiglie-storiche\/#article","isPartOf":{"@id":"https:\/\/perlagesuite.com\/amarone-della-valpolicella-riserva-musella-famiglie-storiche\/"},"author":{"name":"Chiara Bassi","@id":"https:\/\/perlagesuite.com\/#\/schema\/person\/81b257517a1007c1a823318ac86c6013"},"headline":"Amarone della Valpolicella Riserva: un brindisi a pap\u00e0 per il suo compleanno","datePublished":"2019-11-06T15:36:36+00:00","dateModified":"2020-10-15T09:50:37+00:00","mainEntityOfPage":{"@id":"https:\/\/perlagesuite.com\/amarone-della-valpolicella-riserva-musella-famiglie-storiche\/"},"wordCount":1331,"commentCount":0,"publisher":{"@id":"https:\/\/perlagesuite.com\/#organization"},"image":{"@id":"https:\/\/perlagesuite.com\/amarone-della-valpolicella-riserva-musella-famiglie-storiche\/#primaryimage"},"thumbnailUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2019\/11\/amarone-della-valpolicella-riserva-musella.jpg","articleSection":["Non categorizzato"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/perlagesuite.com\/amarone-della-valpolicella-riserva-musella-famiglie-storiche\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/perlagesuite.com\/amarone-della-valpolicella-riserva-musella-famiglie-storiche\/","url":"https:\/\/perlagesuite.com\/amarone-della-valpolicella-riserva-musella-famiglie-storiche\/","name":"Amarone della Valpolicella Riserva: a toast to Dad - Perlage Suite","isPartOf":{"@id":"https:\/\/perlagesuite.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/perlagesuite.com\/amarone-della-valpolicella-riserva-musella-famiglie-storiche\/#primaryimage"},"image":{"@id":"https:\/\/perlagesuite.com\/amarone-della-valpolicella-riserva-musella-famiglie-storiche\/#primaryimage"},"thumbnailUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2019\/11\/amarone-della-valpolicella-riserva-musella.jpg","datePublished":"2019-11-06T15:36:36+00:00","dateModified":"2020-10-15T09:50:37+00:00","description":"Today would have been my dad's 63rd birthday and for that I uncorked a wine he would have loved: an Amarone della Valpolicella Riserva!","breadcrumb":{"@id":"https:\/\/perlagesuite.com\/amarone-della-valpolicella-riserva-musella-famiglie-storiche\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/perlagesuite.com\/amarone-della-valpolicella-riserva-musella-famiglie-storiche\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/perlagesuite.com\/amarone-della-valpolicella-riserva-musella-famiglie-storiche\/#primaryimage","url":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2019\/11\/amarone-della-valpolicella-riserva-musella.jpg","contentUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2019\/11\/amarone-della-valpolicella-riserva-musella.jpg","width":1080,"height":720,"caption":"amarone della valpolicella riserva musella"},{"@type":"BreadcrumbList","@id":"https:\/\/perlagesuite.com\/amarone-della-valpolicella-riserva-musella-famiglie-storiche\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/perlagesuite.com\/"},{"@type":"ListItem","position":2,"name":"Amarone della Valpolicella Riserva: un brindisi a pap\u00e0 per il suo compleanno"}]},{"@type":"WebSite","@id":"https:\/\/perlagesuite.com\/#website","url":"https:\/\/perlagesuite.com\/","name":"Perlage Suite","description":"Chiara Bassi's Wine Blog","publisher":{"@id":"https:\/\/perlagesuite.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/perlagesuite.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/perlagesuite.com\/#organization","name":"Chiara Bassi","url":"https:\/\/perlagesuite.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/perlagesuite.com\/#\/schema\/logo\/image\/","url":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2022\/03\/Chiara-Bassi-sommelier-wine-blogger-logo.png","contentUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2022\/03\/Chiara-Bassi-sommelier-wine-blogger-logo.png","width":512,"height":512,"caption":"Chiara Bassi"},"image":{"@id":"https:\/\/perlagesuite.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/chiarabassiperlagesuite","https:\/\/x.com\/perlagesuite","https:\/\/www.instagram.com\/perlagesuite\/"]},{"@type":"Person","@id":"https:\/\/perlagesuite.com\/#\/schema\/person\/81b257517a1007c1a823318ac86c6013","name":"Chiara Bassi","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g","caption":"Chiara Bassi"},"sameAs":["https:\/\/perlagesuite.com"]}]}},"_links":{"self":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/posts\/19196","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/comments?post=19196"}],"version-history":[{"count":0,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/posts\/19196\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/media\/19208"}],"wp:attachment":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/media?parent=19196"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/categories?post=19196"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/tags?post=19196"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}