{"id":26525,"date":"2020-11-04T16:52:14","date_gmt":"2020-11-04T15:52:14","guid":{"rendered":"https:\/\/perlagesuite.com\/?p=26525"},"modified":"2021-07-26T12:22:54","modified_gmt":"2021-07-26T11:22:54","slug":"grandtour-collection-gioielli-roma","status":"publish","type":"post","link":"https:\/\/perlagesuite.com\/en\/grandtour-collection-gioielli-roma\/","title":{"rendered":"GrandTour Collection: a postcard from Via dei Coronari, Rome \u2764\ufe0f"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.6.6&#8243; _module_preset=&#8221;default&#8221;][et_pb_row _builder_version=&#8221;4.6.6&#8243; _module_preset=&#8221;default&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.6.6&#8243; _module_preset=&#8221;default&#8221;][et_pb_text _builder_version=&#8221;4.6.6&#8243; _module_preset=&#8221;default&#8221;]<\/p>\n<p style=\"text-align: justify;\">Il primo gioiello che ho comprato da ragazzina \u00e8 stato un cammeo arancione che raffigurava una giovane donna. <strong>Ero a Roma<\/strong>, in una &#8220;fuori gita&#8221; con dei miei compagni del <strong>Liceo Artistico<\/strong> di Ravenna e sono passati quasi vent&#8217;anni, ma ne fui cos\u00ec affascinata che me lo ricordo come fosse ieri. Non era particolarmente bello o pregiato, ma <strong>quel cammeo esercitava su di me un fascino unico<\/strong>. Per questo quando ho visto per la prima volta la\u00a0<strong>GrandTour Collection<\/strong> mi sono innamorata immediatamente della <strong>qualit\u00e0 dei materiali e della realizzazione unita del design fresco capace di adattarsi a qualsiasi et\u00e0 e a qualsiasi stile<\/strong>. Ho letto la <strong>storia della Famiglia Borrazzi d&#8217;Eramo, artigiani e antiquari romani che da tre generazioni portano l&#8217;arte nel mondo dalla loro galleria in Via dei Coronari, nel centro storico della Citt\u00e0 Eterna<\/strong>.<\/p>\n<p style=\"text-align: justify;\"><strong>Via dei Coronari, quale luogo poteva essere pi\u00f9 perfetto per creare questa collezione?<\/strong> Immagina i pellegrini sulla via di San Pietro che acquistano qui preziose <em>corone di rose <\/em>mentre passano dinanzi\u00a0la casa che Papa Sisto VI don\u00f2 &#8211; insieme a una vigna nel belvedere vaticano &#8211; a Fiammetta Michaelis, cortigiana amante di Cesare Borgia. Immagina\u00a0<strong>i suoi scorci nei film<\/strong> che hanno fatto la storia del cinema italiano &#8211; mi viene in mente il regista Michelangelo Antonioni -, il bugnato del palazzo dei principi viterbesi Del Drago, le numerose botteghe dei rigattieri trasformate poi in <strong>splendidi negozi di antiquariato<\/strong>, scomparsi uno dopo l&#8217;altro in virt\u00f9 dell&#8217;egemonia di Ikea e dell&#8217;arredamento &#8220;usa e getta&#8221;, in realt\u00e0 pi\u00f9 getta che usa. Immagina un negozio capace di resistere al passare dalle generazioni, dove il passare del tempo \u00e8 stato visto come l&#8217;occasione di rinnovarsi, crescere, essere, custodire.<\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2020\/11\/via-dei-coronari-roma-grandtour-collection.jpg&#8221; alt=&#8221;grand tour collection via dei coronari&#8221; title_text=&#8221;via-dei-coronari-roma-grandtour-collection&#8221; align=&#8221;center&#8221; force_fullwidth=&#8221;on&#8221; _builder_version=&#8221;4.6.6&#8243; _module_preset=&#8221;default&#8221; box_shadow_style=&#8221;preset3&#8243;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.6.6&#8243; _module_preset=&#8221;default&#8221;]<\/p>\n<p style=\"text-align: justify;\">Hai mai sentito qualcuno dirti &#8220;<strong>parto per il Grand Tour<\/strong>&#8220;? Ci fu un tempo che gli aristocratici partivano per un viaggio che era considerato pi\u00f9 una missione che solo turismo. <strong>L&#8217;obiettivo del Grand Tour era<em> conoscere<\/em>. Conoscere la storia, l&#8217;arte, la politica studiando la lingua, comprando opere d&#8217;arte, visitando le rovine e godendosi la &#8220;dolce vita&#8221; del luogo<\/strong>. <strong>Le mete preferite? Ovviamente Italia e Francia<\/strong>. <strong>Le tappe pi\u00f9 importanti erano Venezia, Roma, Napoli e Taormina<\/strong>. Ci si &#8220;perdeva&#8221; dalle ville palladiane alle rovine romane, dal neoclassico napoletano al barocco siciliano. La Sicilia poi offriva la possibilit\u00e0 di studiare l&#8217;arte greca senza spostarsi ulteriormente&#8230; e all&#8217;epoca non c&#8217;erano n\u00e9 gli aerei n\u00e9 le compagnie low cost. Ancora oggi l&#8217;Italia \u00e8 una delle mete pi\u00f9 ambite da tutti tranne che dagli italiani. Io sono cos\u00ec orgogliosa di essere italiana che quando sento dire da qualcuno &#8220;viviamo in un Paese di merda e vorrei andarmene&#8221; mi piange il cuore. <strong>Io non lascer\u00f2 mai l&#8217;Italia<\/strong>. Potrei dividermi tra Francia e Italia, questo s\u00ec. Amo la Francia come fosse il mio Paese. E l&#8217;Italia? L&#8217;Italia \u00e8 imperfetta, ma chi non lo \u00e8? <strong>L&#8217;Italia \u00e8 genio e follia e a me questo basta<\/strong>.<\/p>\n<p style=\"text-align: justify;\"><strong>Uno dei momenti pi\u00f9 importanti del Grand Tour era farsi fare un ritratto da un importante pittore e incisore dell&#8217;epoca<\/strong>\u00a0come Canaletto. Mi viene naturale pensare che <strong>farsi fare il ritratto su un oggetto piccolo come il cammeo fosse assai pi\u00f9 comodo che far viaggiare una tela di dimensioni maggiori<\/strong>. Allo stesso modo &#8211;\u00a0<strong>quando comprare opere d&#8217;arte non era possibile <\/strong>&#8211;\u00a0<strong>un cammeo che le raffigurava era il souvenir perfetto<\/strong>!<\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2020\/11\/grandtourcollection-via-dei-coronari-roma.jpg&#8221; alt=&#8221;grandtour collection via dei coronari&#8221; title_text=&#8221;grandtourcollection-via-dei-coronari-roma&#8221; _builder_version=&#8221;4.6.6&#8243; _module_preset=&#8221;default&#8221; box_shadow_style=&#8221;preset3&#8243;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.6.6&#8243; _module_preset=&#8221;default&#8221;]<\/p>\n<p style=\"text-align: justify;\"><strong>Il primo gioiello che ho scelto \u00e8 stato il bracciale della linea Square raffigurante un grande cammeo quadrato con Amore e Psiche di colore blu<\/strong>, il preferito dai miei genitori. Amore e Psiche \u00e8 una favola di Apuleio che racconta la storia d&#8217;amore tra il Dio Cupido e la principessa Psiche. La dea Venere, gelosa dell&#8217;incredibile bellezza di Psiche, chiese a suo figlio, il bellissimo dio dell&#8217;Amore Cupido di scagliarle una freccia e farla innamorare dell&#8217;uomo pi\u00f9 brutto della terra. Lui accett\u00f2, ma quando la vide rimase cos\u00ec incantato dalla sua bellezza che una delle sue frecce lo colp\u00ec e lo fece innamorare perdutamente di Psiche. Il giovane dio ogni sera, di nascosto dalla madre, andava dalla giovane fanciulla e consumava notti di grande passione. Il detto &#8220;la curiosit\u00e0 \u00e8 donna&#8221; nasce proprio da questa favola perch\u00e8 Psiche, per ben 2 volte, rischi\u00f2 di perdere il suo amato a causa della sua curiosit\u00e0. Tuttavia, dopo aver superato una serie di prove e aver fallito l&#8217;ultima, Amore riesce a far trasformare Psiche in una dea e a sposarla. Dalla loro unione nacque una bellissima bambina. Dato che mia madre ha vissuto un amore cos\u00ec grande col mio pap\u00e0 recentemente scomparso (anche un po&#8217; osteggiato), ho deciso di regalarle questo bracciale con l&#8217;augurio che, ogni volta che i suoi occhi si poseranno su questo splendido cammeo, si ricorder\u00e0 dell&#8217;amore che ha vissuto e del suo frutto: me (se vuoi leggere la <a href=\"https:\/\/amzn.to\/3872FCN\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"text-decoration: underline;\"><strong>favola di Amore e Psiche ti consiglio questo libro su Amazon<\/strong><\/span><\/a>).<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.6.6&#8243; _module_preset=&#8221;default&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.6.6&#8243; _module_preset=&#8221;default&#8221;][et_pb_code _builder_version=&#8221;4.6.6&#8243; _module_preset=&#8221;default&#8221;]<\/p>\n<blockquote class=\"instagram-media\" data-instgrm-captioned data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/CG-GWeBn3-6\/?utm_source=ig_embed&#038;utm_campaign=loading\" data-instgrm-version=\"13\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:540px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\">\n<div style=\"padding:16px;\"> <a href=\"https:\/\/www.instagram.com\/p\/CG-GWeBn3-6\/?utm_source=ig_embed&#038;utm_campaign=loading\" style=\" background:#FFFFFF; line-height:0; padding:0 0; text-align:center; text-decoration:none; width:100%;\" target=\"_blank\" rel=\"noopener noreferrer\"> <\/p>\n<div style=\" display: flex; flex-direction: row; align-items: center;\">\n<div style=\"background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\">\n<div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div>\n<div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div>\n<\/div>\n<\/div>\n<div style=\"padding: 19% 0;\"><\/div>\n<div style=\"display:block; height:50px; margin:0 auto 12px; width:50px;\"><svg width=\"50px\" height=\"50px\" viewBox=\"0 0 60 60\" version=\"1.1\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"https:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g transform=\"translate(-511.000000, -20.000000)\" fill=\"#000000\"><g><path d=\"M556.869,30.41 C554.814,30.41 553.148,32.076 553.148,34.131 C553.148,36.186 554.814,37.852 556.869,37.852 C558.924,37.852 560.59,36.186 560.59,34.131 C560.59,32.076 558.924,30.41 556.869,30.41 M541,60.657 C535.114,60.657 530.342,55.887 530.342,50 C530.342,44.114 535.114,39.342 541,39.342 C546.887,39.342 551.658,44.114 551.658,50 C551.658,55.887 546.887,60.657 541,60.657 M541,33.886 C532.1,33.886 524.886,41.1 524.886,50 C524.886,58.899 532.1,66.113 541,66.113 C549.9,66.113 557.115,58.899 557.115,50 C557.115,41.1 549.9,33.886 541,33.886 M565.378,62.101 C565.244,65.022 564.756,66.606 564.346,67.663 C563.803,69.06 563.154,70.057 562.106,71.106 C561.058,72.155 560.06,72.803 558.662,73.347 C557.607,73.757 556.021,74.244 553.102,74.378 C549.944,74.521 548.997,74.552 541,74.552 C533.003,74.552 532.056,74.521 528.898,74.378 C525.979,74.244 524.393,73.757 523.338,73.347 C521.94,72.803 520.942,72.155 519.894,71.106 C518.846,70.057 518.197,69.06 517.654,67.663 C517.244,66.606 516.755,65.022 516.623,62.101 C516.479,58.943 516.448,57.996 516.448,50 C516.448,42.003 516.479,41.056 516.623,37.899 C516.755,34.978 517.244,33.391 517.654,32.338 C518.197,30.938 518.846,29.942 519.894,28.894 C520.942,27.846 521.94,27.196 523.338,26.654 C524.393,26.244 525.979,25.756 528.898,25.623 C532.057,25.479 533.004,25.448 541,25.448 C548.997,25.448 549.943,25.479 553.102,25.623 C556.021,25.756 557.607,26.244 558.662,26.654 C560.06,27.196 561.058,27.846 562.106,28.894 C563.154,29.942 563.803,30.938 564.346,32.338 C564.756,33.391 565.244,34.978 565.378,37.899 C565.522,41.056 565.552,42.003 565.552,50 C565.552,57.996 565.522,58.943 565.378,62.101 M570.82,37.631 C570.674,34.438 570.167,32.258 569.425,30.349 C568.659,28.377 567.633,26.702 565.965,25.035 C564.297,23.368 562.623,22.342 560.652,21.575 C558.743,20.834 556.562,20.326 553.369,20.18 C550.169,20.033 549.148,20 541,20 C532.853,20 531.831,20.033 528.631,20.18 C525.438,20.326 523.257,20.834 521.349,21.575 C519.376,22.342 517.703,23.368 516.035,25.035 C514.368,26.702 513.342,28.377 512.574,30.349 C511.834,32.258 511.326,34.438 511.181,37.631 C511.035,40.831 511,41.851 511,50 C511,58.147 511.035,59.17 511.181,62.369 C511.326,65.562 511.834,67.743 512.574,69.651 C513.342,71.625 514.368,73.296 516.035,74.965 C517.703,76.634 519.376,77.658 521.349,78.425 C523.257,79.167 525.438,79.673 528.631,79.82 C531.831,79.965 532.853,80.001 541,80.001 C549.148,80.001 550.169,79.965 553.369,79.82 C556.562,79.673 558.743,79.167 560.652,78.425 C562.623,77.658 564.297,76.634 565.965,74.965 C567.633,73.296 568.659,71.625 569.425,69.651 C570.167,67.743 570.674,65.562 570.82,62.369 C570.966,59.17 571,58.147 571,50 C571,41.851 570.966,40.831 570.82,37.631\"><\/path><\/g><\/g><\/g><\/svg><\/div>\n<div style=\"padding-top: 8px;\">\n<div style=\" color:#3897f0; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:550; line-height:18px;\"> Visualizza questo post su Instagram<\/div>\n<\/div>\n<div style=\"padding: 12.5% 0;\"><\/div>\n<div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\">\n<div>\n<div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div>\n<div style=\"background-color: #F4F4F4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div>\n<div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div>\n<\/div>\n<div style=\"margin-left: 8px;\">\n<div style=\" background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div>\n<div style=\" width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg)\"><\/div>\n<\/div>\n<div style=\"margin-left: auto;\">\n<div style=\" width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div>\n<div style=\" background-color: #F4F4F4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div>\n<div style=\" width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div>\n<\/div>\n<\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\">\n<div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div>\n<div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div>\n<\/div>\n<p><\/a><pee style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; line-height:17px; margin-bottom:0; margin-top:8px; overflow:hidden; padding:8px 0 7px; text-align:center; text-overflow:ellipsis; white-space:nowrap;\"><a href=\"https:\/\/www.instagram.com\/p\/CG-GWeBn3-6\/?utm_source=ig_embed&#038;utm_campaign=loading\" style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:normal; line-height:17px; text-decoration:none;\" target=\"_blank\" rel=\"noopener noreferrer\">Un post condiviso da Chiara Bassi \u00a9\ufe0fPerlage Suite\ud83c\udf77 (@perlagesuite)<\/a> in data: <time style=\" font-family:Arial,sans-serif; font-size:14px; line-height:17px;\" datetime=\"2020-10-30T14:02:15+00:00\">30 Ott 2020 alle ore 7:02 PDT<\/time><\/pee><\/div>\n<\/blockquote>\n<p> <script async src=\"\/\/www.instagram.com\/embed.js\"><\/script>[\/et_pb_code][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.6.6&#8243; _module_preset=&#8221;default&#8221;][et_pb_text _builder_version=&#8221;4.6.6&#8243; _module_preset=&#8221;default&#8221;]<\/p>\n<p style=\"text-align: justify;\">Trovo questo bracciale perfetto per mia madre, una bellissima appassionata di Storia dell&#8217;Arte che dimostra molti meno anni e ha un look giovane e dinamico. Dal vivo \u00e8 ancora pi\u00f9 bello e non vedo l&#8217;ora che col tempo acquisti quella patina capace di renderlo ancora pi\u00f9 prezioso. In generale la Linea Square \u00e8 molto elegante e importante, perfetta per valorizzare qualsiasi outfit. Ci sono 4 soggetti tra cui puoi scegliere: la lupa capitolina, Fetonte, le colombe di Plinio e, ovviamente, Amore e Psiche. Il bracciale di pelle pu\u00f2 essere nero, blu, o bianco&#8230; a me piace molto il blu per la sua versatilit\u00e0.<\/p>\n<p style=\"text-align: justify;\"><strong>GrandTour Collection \u00e8 la versione 2.0 di quei colti souvenir che i ricchi d&#8217;Europa portavano dall&#8217;Italia raffiguranti le pi\u00f9 belle opere d&#8217;arte del neoclassicismo custodite a Roma<\/strong>. <strong>Roberto e Michela Borrazzi hanno innovato il cammeo scegliendo materiali <\/strong>&#8211; preziosi ma accessibili &#8211;<strong> e inediti<\/strong> come il plexiglass e le moderne resine create per loro in esclusiva, <strong>e antichi<\/strong> come l&#8217;oro e il bronzo con la tecnica di fusione a cera persa. \u00a0<strong>L&#8217;uso del colore<\/strong>, dalle tinte classiche a quelle forti, <strong>ha reso i loro gioielli contemporanei<\/strong>. <strong>Per i viaggiatori colti di oggi che vogliono portare con s\u00e9 un angolo di Roma o per chi a Roma sogna di andare, e coltiva il suo sogno ammirando e portando un gioiello GrandTour<\/strong>.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.6.6&#8243; _module_preset=&#8221;default&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.6.6&#8243; _module_preset=&#8221;default&#8221;][et_pb_text _builder_version=&#8221;4.6.6&#8243; _module_preset=&#8221;default&#8221;]<\/p>\n<p style=\"text-align: justify;\"><strong>Ho scelto per me il bracciale filodoro che raffigura Dioniso, il dio dell&#8217;estasi, della fertilit\u00e0, del vino, dell&#8217;ebbrezza e della liberazione dei sensi.<\/strong> Dioniso \u00e8 l&#8217;essenza del creato nel suo perenne e selvaggio fluire, lo spirito divino di una realt\u00e0 smisurata, l&#8217;elemento primigenio del cosmo, la frenetica corrente di vita che tutto pervade. Mi riconosco tantissimo nella figura di Dioniso e non solo per il suo legame col vino, ma per questa sua natura errante che racchiude in s\u00e9 la gioia e la rabbia, fallimento e successo, fino al traguardo finale &#8211; l&#8217;immortalit\u00e0 &#8211; e il ritorno in patria finalmente riscattato. Di Dioniso condivido anche l&#8217;istinto, il forte senso di giustizia che talvolta pu\u00f2 accecare come un&#8217;inutile sete di vendetta. <strong>La raffigurazione \u00e8 una testa di Dioniso giovane, con una corona di edera, conservata nei Musei Capitolini.<\/strong><\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2020\/11\/grandtour-collection-gioielli-bracciale-filodoro.jpg&#8221; alt=&#8221;grandtour collection bracciale filodoro&#8221; title_text=&#8221;grandtour-collection-gioielli-bracciale-filodoro&#8221; _builder_version=&#8221;4.6.6&#8243; _module_preset=&#8221;default&#8221; box_shadow_style=&#8221;preset3&#8243;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.6.6&#8243; _module_preset=&#8221;default&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.6.6&#8243; _module_preset=&#8221;default&#8221;][et_pb_text _builder_version=&#8221;4.9.10&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p style=\"text-align: justify;\">Ho deciso di abbinarci degli <a href=\"https:\/\/www.grandtourcollection.com\/it\/gioielli\/tutti-i-gioielli\/orecchini\/orecchini-hore-amo\/or1-dioniso-baccante-porfido.html\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"text-decoration: underline;\"><strong>orecchini stupendi Hore Amo<\/strong><\/span><\/a>, il pezzo di cui mi sono davvero innamorata. Semplici ed eleganti, raffigurano Dioniso e la Baccante. Menade, Tiade o Baccante sono i nomi delle sacerdotesse di Bacco che celebravano il dio cantando, danzando ed errando per monti e boschi agitando il tirso, una picca avviluppata dall&#8217;edera soprattutto sulla sommit\u00e0. Pi\u00f9 propriamente le Menadi sono le figure mitologiche seguaci del Dio, mentre le Baccanti sono le donne umane che lo veneravano. Nella mitologia classica sono l&#8217;oggetto del desiderio dei satiri.<\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2020\/11\/grandtour-collection-gioielli-cammei-orecchini-dioniso-porfido.jpg&#8221; alt=&#8221;grandtour collection gioielli cammei orecchini&#8221; title_text=&#8221;grandtour-collection-gioielli-cammei-orecchini-dioniso-porfido&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.6.6&#8243; _module_preset=&#8221;default&#8221; box_shadow_style=&#8221;preset3&#8243;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.6.6&#8243; _module_preset=&#8221;default&#8221;]<\/p>\n<p style=\"text-align: justify;\">La bellezza degli orecchini Hore Amo \u00e8 che sono completamente personalizzabili! Questo modello semplice e raffinato, leggerissimo e per questo portabile tutta la giornata anche da una winelover con i lobi sensibili come i miei, illumina e impreziosisce il mio viso. Puoi scegliere tra tantissimi soggetti mitologici e tra ben 14 colori, impossibile resistere!\u00a0\ud83d\ude0d Poi ci sono tante altre collezioni da scoprire sul sito web <span style=\"text-decoration: underline;\"><strong><a href=\"http:\/\/www.grandtourcollection.com\">www.grandtourcollection.com<\/a><\/strong><\/span><strong>\u00a0<span>\u2764\ufe0f<\/span><\/strong><\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2020\/11\/chiara-bassi-grandtour-collection-orecchini.jpg&#8221; alt=&#8221;chiara bassi grandtour collection orecchini&#8221; title_text=&#8221;chiara-bassi-grandtour-collection-orecchini&#8221; _builder_version=&#8221;4.6.6&#8243; _module_preset=&#8221;default&#8221; box_shadow_style=&#8221;preset3&#8243;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.6.6&#8243; _module_preset=&#8221;default&#8221;]<\/p>\n<p style=\"text-align: justify;\"><span>In questo giorno buio, in cui l&#8217;Italia sta per chiudersi ancora, <strong>un regalo da portare \u00e8 ancora pi\u00f9 prezioso perch\u00e8 ci fa sentire pi\u00f9 vicini<\/strong>. Se siamo vicini siamo distanti e se siamo lontani possiamo solo sentirci o vederci al di l\u00e0 di uno schermo. Per\u00f2 <strong>possiamo donare o donarci qualcosa di prezioso, made in Italy, che racconti una storia<\/strong>, un ricordo o, semplicemente, rappresenti il nostro affetto. Io abito in Lombardia, zona rossa nuovamente in lockdown totale a causa del Coronavirus e la mia mamma abita in Romagna. Sicuramente fino almeno al 3 dicembre non potremo vederci, ma l&#8217;idea di sapere che indossa questo bracciale che le ho regalato domenica scorsa mi riempie il cuore.<\/span><\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2020\/11\/amore-e-psiche-favola.jpg&#8221; alt=&#8221;amore e psiche favola&#8221; title_text=&#8221;amore-e-psiche-favola&#8221; _builder_version=&#8221;4.6.6&#8243; _module_preset=&#8221;default&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.6.6&#8243; _module_preset=&#8221;default&#8221;]<\/p>\n<p style=\"text-align: justify;\">Dioniso, Baccante, Amore e Psiche (qui sopra lo splendido quadro di David), Minerva, Ercole e il Toro, Cupido, Medusa, Pegaso, Minerva&#8230; ci sono tantissimi miti e altrettante storie, favole, vicende tra cui scegliere. E poi c&#8217;\u00e8 Roma e la lupa capitolina perch\u00e8 \u00a0-seppur stuprata negli anni &#8211; la citt\u00e0 eterna sar\u00e0 sempre la pi\u00f9 bella del mondo. Una cartolina da Roma, un piccolo souvenir di un viaggio fatto o sognato, un&#8217;eccellenza artigiana da indossare. Un gioiello capace di raccontare chi lo regala e chi lo riceve.<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.6.6&#8243; _module_preset=&#8221;default&#8221;]<\/p>\n<p style=\"text-align: justify;\">E la volont\u00e0 che tutto finisca per spostarci senza pensieri, viaggiare, conoscere. Non vedo l&#8217;ora di riscoprire la gioia vera di fare un nuovo Gran Tour con mio marito Francesco. Attraverseremo l&#8217;Italia in macchina fino a raggiungere Taormina, come due giovani dell&#8217;ottocento. Cammineremo tra vie incantate, assaggeremo piatti e vini capaci di rubarci emozioni, baci e sorrisi. Al ritorno ci fermeremo sicuramente a Roma, in via dei Coronari, e sceglieremo due braccialetti identici <a href=\"https:\/\/www.grandtourcollection.com\/it\/br4configuratore-easy-hore.html\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"text-decoration: underline;\"><strong>GrandTour linea Easy Hore<\/strong><\/span><\/a> con la venditrice di amorini color perla e il caucci\u00f9 blu per lui e bordeaux per me. E poi li porteremo ogni giorno, per ricordarci del nostro bellissimo viaggio in cui siamo cresciuti come coppia e abbiamo conosciuto tante cose nuove della terra in cui abbiamo avuto la fortuna di nascere.<\/p>\n<p style=\"text-align: justify;\">Cheers <span>\ud83c\udf77<\/span><\/p>\n<p style=\"text-align: justify;\">Chiara<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.grandtourcollection.com\/it\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"text-decoration: underline;\"><strong>GrandTour Collection<\/strong><\/span><\/a> |\u00a0Via dei Coronari, 32 &#8211; 00186 Roma | <span style=\"text-decoration: underline;\"><strong><a href=\"mailto:info@grandtourcollection.com\">info@grandtourcollection.com<\/a><a href=\"mailto:info@grandtourcollection.com\" target=\"_blank\" rel=\"noopener noreferrer\"><\/a><\/strong><\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.6.6&#8243; _module_preset=&#8221;default&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.6.6&#8243; _module_preset=&#8221;default&#8221;][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2019\/10\/tenute-la-montina-degustazione-franciacorta-1.jpg&#8221; alt=&#8221;tenute la montina degustazione franciacorta 1.&#8221; title_text=&#8221;tenute-la-montina-degustazione-franciacorta-1&#8243; _builder_version=&#8221;4.6.6&#8243; _module_preset=&#8221;default&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.6.6&#8243; _module_preset=&#8221;default&#8221;][et_pb_text _builder_version=&#8221;4.6.6&#8243; _module_preset=&#8221;default&#8221;]<\/p>\n<p style=\"text-align: justify;\"><strong>P.S. Per questa foto di copertina ho scelto come modella per il bracciale la bellissima bottiglia di Franciacorta Sat\u00e9n La Montina che ho intenzione di stappare questa domenica per il nostro 2 mese di Matrimonio. <\/strong>Questa cantina \u00e8 perfetta perch\u00e8 deve il suo nome a <strong>Giovanni Battista Montini, poi diventato Paolo VI<\/strong>, un Papa a volte criticato altre dimenticato a cui si deve invece il primo dialogo della Chiesa con la modernit\u00e0. Di origine bresciane, il suo avo Benedetto Montini &#8211; propretario della casa padronale &#8211; ha originato il toponimo Montina su cui oggi sorge l&#8217;azienda franciacortina proprietaria della <strong>Famiglia Bozza<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Se vuoi saperne di pi\u00f9 su questa meravigliosa azienda della Franciacorta ti invito a leggere questi articoli:<\/p>\n<ul>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/perlagesuite.com\/la-montina-una-serata-stupenda-in-franciacorta\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"text-decoration: underline;\"><strong>La Montina: una verticale stupenda in (e di) Franciacorta<\/strong><\/span><\/a> &#8211; 23 ottobre 2019<a href=\"https:\/\/perlagesuite.com\/la-montina-una-serata-stupenda-in-franciacorta\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"text-decoration: underline;\"><strong><\/strong><\/span><\/a><\/li>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/perlagesuite.com\/tutti-i-colori-del-franciacorta-con-la-montina\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"text-decoration: underline;\"><strong>La Montina: Tutti i colori del Franciacorta<\/strong><\/span><\/a> &#8211; 25 marzo 2015<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.6.6&#8243; _module_preset=&#8221;default&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.6.6&#8243; _module_preset=&#8221;default&#8221;][et_pb_divider color=&#8221;#da413d&#8221; _builder_version=&#8221;4.6.6&#8243; _module_preset=&#8221;default&#8221;][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.0.6&#8243; global_module=&#8221;21425&#8243;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.0.6&#8243;][et_pb_wc_images product=&#8221;10582&#8243; show_product_gallery=&#8221;off&#8221; _builder_version=&#8221;4.9.4&#8243;][\/et_pb_wc_images][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.0.6&#8243;][et_pb_wc_title product=&#8221;10582&#8243; _builder_version=&#8221;4.0.6&#8243;][\/et_pb_wc_title][et_pb_text _builder_version=&#8221;4.9.4&#8243; text_font=&#8221;Delius Unicase||||||||&#8221;]<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ff0000;\"><span style=\"caret-color: #ff0000;\"><b>Tutti i miei appunti sul vino e sul cibo in un solo libro.<\/b><\/span><\/span><\/p>\n<p>[\/et_pb_text][et_pb_wc_rating product=&#8221;10582&#8243; _builder_version=&#8221;4.0.6&#8243;][\/et_pb_wc_rating][et_pb_wc_price product=&#8221;10582&#8243; _builder_version=&#8221;4.0.6&#8243;][\/et_pb_wc_price][et_pb_wc_add_to_cart product=&#8221;10582&#8243; _builder_version=&#8221;4.0.6&#8243;][\/et_pb_wc_add_to_cart][et_pb_text _builder_version=&#8221;4.9.4&#8243; text_font=&#8221;Delius Unicase||||||||&#8221;]<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ff0000;\"><strong>IN OMAGGIO<\/strong><\/span>, solo per chi compra il mio libro su questo blog, una copia della <strong>Prima Edizione da Collezione della mia Guida Vini Spumanti &#8220;500 Bolle in 500&#8221;<\/strong>, prezzo di copertina 25,30 \u20ac. [Fino ad esaurimento scorte]<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il primo gioiello che ho comprato da ragazzina \u00e8 stato un cammeo arancione che raffigurava una giovane donna. Ero a Roma, in una &#8220;fuori gita&#8221; con dei miei compagni del Liceo Artistico di Ravenna e sono passati quasi vent&#8217;anni, ma ne fui cos\u00ec affascinata che me lo ricordo come fosse ieri. Non era particolarmente bello [&hellip;]<\/p>\n","protected":false},"author":49,"featured_media":26573,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"2880","footnotes":""},"categories":[499],"tags":[],"class_list":["post-26525","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-grand-tour"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.0 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>GrandTour Collection: una cartolina da via dei Coronari, Roma \u2764\ufe0f - Perlage Suite<\/title>\n<meta name=\"description\" content=\"GrandTour Collection non \u00e8 solo una splendida collezione di gioielli Made in Italy, \u00e8 la sintesi tra storia e modernit\u00e0. Come la Citt\u00e0 Eterna.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/perlagesuite.com\/en\/grandtour-collection-gioielli-roma\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GrandTour Collection: una cartolina da via dei Coronari, Roma \u2764\ufe0f\" \/>\n<meta property=\"og:description\" content=\"GrandTour Collection non \u00e8 solo una splendida collezione di gioielli Made in Italy, \u00e8 la sintesi tra storia e modernit\u00e0. Come la Citt\u00e0 Eterna.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/perlagesuite.com\/en\/grandtour-collection-gioielli-roma\/\" \/>\n<meta property=\"og:site_name\" content=\"Perlage Suite\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/chiarabassiperlagesuite\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-04T15:52:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-26T11:22:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/perlagesuite.com\/wp-content\/uploads\/2020\/11\/grandtour-collection-la-montina-gioielli-franciacorta.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1060\" \/>\n\t<meta property=\"og:image:height\" content=\"707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Chiara Bassi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@perlagesuite\" \/>\n<meta name=\"twitter:site\" content=\"@perlagesuite\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Chiara Bassi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/grandtour-collection-gioielli-roma\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/grandtour-collection-gioielli-roma\\\/\"},\"author\":{\"name\":\"Chiara Bassi\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/person\\\/81b257517a1007c1a823318ac86c6013\"},\"headline\":\"GrandTour Collection: una cartolina da via dei Coronari, Roma \u2764\ufe0f\",\"datePublished\":\"2020-11-04T15:52:14+00:00\",\"dateModified\":\"2021-07-26T11:22:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/grandtour-collection-gioielli-roma\\\/\"},\"wordCount\":2568,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/grandtour-collection-gioielli-roma\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/grandtour-collection-la-montina-gioielli-franciacorta.jpg\",\"articleSection\":[\"Grand Tour\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/perlagesuite.com\\\/grandtour-collection-gioielli-roma\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/grandtour-collection-gioielli-roma\\\/\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/grandtour-collection-gioielli-roma\\\/\",\"name\":\"GrandTour Collection: una cartolina da via dei Coronari, Roma \u2764\ufe0f - Perlage Suite\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/grandtour-collection-gioielli-roma\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/grandtour-collection-gioielli-roma\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/grandtour-collection-la-montina-gioielli-franciacorta.jpg\",\"datePublished\":\"2020-11-04T15:52:14+00:00\",\"dateModified\":\"2021-07-26T11:22:54+00:00\",\"description\":\"GrandTour Collection non \u00e8 solo una splendida collezione di gioielli Made in Italy, \u00e8 la sintesi tra storia e modernit\u00e0. Come la Citt\u00e0 Eterna.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/grandtour-collection-gioielli-roma\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/perlagesuite.com\\\/grandtour-collection-gioielli-roma\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/grandtour-collection-gioielli-roma\\\/#primaryimage\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/grandtour-collection-la-montina-gioielli-franciacorta.jpg\",\"contentUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/grandtour-collection-la-montina-gioielli-franciacorta.jpg\",\"width\":1060,\"height\":707,\"caption\":\"grandtour collection la montina\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/grandtour-collection-gioielli-roma\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/perlagesuite.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"GrandTour Collection: una cartolina da via dei Coronari, Roma \u2764\ufe0f\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#website\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/\",\"name\":\"Perlage Suite\",\"description\":\"Il Wine Blog di Chiara Bassi\",\"publisher\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/perlagesuite.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#organization\",\"name\":\"Chiara Bassi\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Chiara-Bassi-sommelier-wine-blogger-logo.png\",\"contentUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Chiara-Bassi-sommelier-wine-blogger-logo.png\",\"width\":512,\"height\":512,\"caption\":\"Chiara Bassi\"},\"image\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/chiarabassiperlagesuite\",\"https:\\\/\\\/x.com\\\/perlagesuite\",\"https:\\\/\\\/www.instagram.com\\\/perlagesuite\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/person\\\/81b257517a1007c1a823318ac86c6013\",\"name\":\"Chiara Bassi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g\",\"caption\":\"Chiara Bassi\"},\"sameAs\":[\"https:\\\/\\\/perlagesuite.com\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"GrandTour Collection: a postcard from Via dei Coronari, Rome \u2764\ufe0f - Perlage Suite","description":"GrandTour Collection is not only a splendid collection of Made in Italy jewellery, it is the synthesis of history and modernity. Like the Eternal City.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/perlagesuite.com\/en\/grandtour-collection-gioielli-roma\/","og_locale":"en_GB","og_type":"article","og_title":"GrandTour Collection: una cartolina da via dei Coronari, Roma \u2764\ufe0f","og_description":"GrandTour Collection non \u00e8 solo una splendida collezione di gioielli Made in Italy, \u00e8 la sintesi tra storia e modernit\u00e0. Come la Citt\u00e0 Eterna.","og_url":"https:\/\/perlagesuite.com\/en\/grandtour-collection-gioielli-roma\/","og_site_name":"Perlage Suite","article_publisher":"https:\/\/www.facebook.com\/chiarabassiperlagesuite","article_published_time":"2020-11-04T15:52:14+00:00","article_modified_time":"2021-07-26T11:22:54+00:00","og_image":[{"width":1060,"height":707,"url":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2020\/11\/grandtour-collection-la-montina-gioielli-franciacorta.jpg","type":"image\/jpeg"}],"author":"Chiara Bassi","twitter_card":"summary_large_image","twitter_creator":"@perlagesuite","twitter_site":"@perlagesuite","twitter_misc":{"Written by":"Chiara Bassi","Estimated reading time":"13 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/perlagesuite.com\/grandtour-collection-gioielli-roma\/#article","isPartOf":{"@id":"https:\/\/perlagesuite.com\/grandtour-collection-gioielli-roma\/"},"author":{"name":"Chiara Bassi","@id":"https:\/\/perlagesuite.com\/#\/schema\/person\/81b257517a1007c1a823318ac86c6013"},"headline":"GrandTour Collection: una cartolina da via dei Coronari, Roma \u2764\ufe0f","datePublished":"2020-11-04T15:52:14+00:00","dateModified":"2021-07-26T11:22:54+00:00","mainEntityOfPage":{"@id":"https:\/\/perlagesuite.com\/grandtour-collection-gioielli-roma\/"},"wordCount":2568,"commentCount":0,"publisher":{"@id":"https:\/\/perlagesuite.com\/#organization"},"image":{"@id":"https:\/\/perlagesuite.com\/grandtour-collection-gioielli-roma\/#primaryimage"},"thumbnailUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2020\/11\/grandtour-collection-la-montina-gioielli-franciacorta.jpg","articleSection":["Grand Tour"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/perlagesuite.com\/grandtour-collection-gioielli-roma\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/perlagesuite.com\/grandtour-collection-gioielli-roma\/","url":"https:\/\/perlagesuite.com\/grandtour-collection-gioielli-roma\/","name":"GrandTour Collection: a postcard from Via dei Coronari, Rome \u2764\ufe0f - Perlage Suite","isPartOf":{"@id":"https:\/\/perlagesuite.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/perlagesuite.com\/grandtour-collection-gioielli-roma\/#primaryimage"},"image":{"@id":"https:\/\/perlagesuite.com\/grandtour-collection-gioielli-roma\/#primaryimage"},"thumbnailUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2020\/11\/grandtour-collection-la-montina-gioielli-franciacorta.jpg","datePublished":"2020-11-04T15:52:14+00:00","dateModified":"2021-07-26T11:22:54+00:00","description":"GrandTour Collection is not only a splendid collection of Made in Italy jewellery, it is the synthesis of history and modernity. Like the Eternal City.","breadcrumb":{"@id":"https:\/\/perlagesuite.com\/grandtour-collection-gioielli-roma\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/perlagesuite.com\/grandtour-collection-gioielli-roma\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/perlagesuite.com\/grandtour-collection-gioielli-roma\/#primaryimage","url":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2020\/11\/grandtour-collection-la-montina-gioielli-franciacorta.jpg","contentUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2020\/11\/grandtour-collection-la-montina-gioielli-franciacorta.jpg","width":1060,"height":707,"caption":"grandtour collection la montina"},{"@type":"BreadcrumbList","@id":"https:\/\/perlagesuite.com\/grandtour-collection-gioielli-roma\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/perlagesuite.com\/"},{"@type":"ListItem","position":2,"name":"GrandTour Collection: una cartolina da via dei Coronari, Roma \u2764\ufe0f"}]},{"@type":"WebSite","@id":"https:\/\/perlagesuite.com\/#website","url":"https:\/\/perlagesuite.com\/","name":"Perlage Suite","description":"Chiara Bassi's Wine Blog","publisher":{"@id":"https:\/\/perlagesuite.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/perlagesuite.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/perlagesuite.com\/#organization","name":"Chiara Bassi","url":"https:\/\/perlagesuite.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/perlagesuite.com\/#\/schema\/logo\/image\/","url":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2022\/03\/Chiara-Bassi-sommelier-wine-blogger-logo.png","contentUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2022\/03\/Chiara-Bassi-sommelier-wine-blogger-logo.png","width":512,"height":512,"caption":"Chiara Bassi"},"image":{"@id":"https:\/\/perlagesuite.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/chiarabassiperlagesuite","https:\/\/x.com\/perlagesuite","https:\/\/www.instagram.com\/perlagesuite\/"]},{"@type":"Person","@id":"https:\/\/perlagesuite.com\/#\/schema\/person\/81b257517a1007c1a823318ac86c6013","name":"Chiara Bassi","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g","caption":"Chiara Bassi"},"sameAs":["https:\/\/perlagesuite.com"]}]}},"_links":{"self":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/posts\/26525","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/comments?post=26525"}],"version-history":[{"count":0,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/posts\/26525\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/media\/26573"}],"wp:attachment":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/media?parent=26525"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/categories?post=26525"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/tags?post=26525"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}