{"id":2697,"date":"2015-06-22T14:40:54","date_gmt":"2015-06-22T13:40:54","guid":{"rendered":"http:\/\/perlagesuite.com\/?p=2697"},"modified":"2020-10-15T11:50:06","modified_gmt":"2020-10-15T10:50:06","slug":"domande-risposte-esame-ais-2015","status":"publish","type":"post","link":"https:\/\/perlagesuite.com\/en\/domande-risposte-esame-ais-2015\/","title":{"rendered":"Questions &amp; Answers of the 2015 AIS Examination"},"content":{"rendered":"<p>[et_pb_section][et_pb_row][et_pb_column type=&#8221;4_4&#8243;][et_pb_text admin_label=&#8221;Testo&#8221; background_layout=&#8221;light&#8221; text_orientation=&#8221;left&#8221; text_line_height=&#8221;2em&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<p style=\"text-align: justify;\">Grazie soprattutto al lavoro di\u00a0Elisa Maniezzo, una mia cara lettrice che sento spesso per email e con cui ho scoperto diverse cose in comune, oggi vi posto un po&#8217; di domande che hanno\u00a0caratterizzato gli esami AIS 2015&#8230; tra cui il mio \ud83d\ude09<\/p>\n<p style=\"text-align: justify;\">Superare l&#8217;esame AIS e diventare sommelier non \u00e8 una cosa da prendere sotto gamba, pertanto se avete intenzione di provare a dare l&#8217;esame dopo l&#8217;estate vi consiglio di investire un&#8217;ora al giorno del vostro tempo per prepararvi fin da subito! Prima di postarvi le domande vi ricordo queste risorse utili per superare l&#8217;esame AIS e diventare sommelier:<\/p>\n<ul>\n<li style=\"text-align: justify;\"><a href=\"http:\/\/perlagesuite.com\/tecniche-studio-esame-sommelier\/\" target=\"_blank\" rel=\"noopener noreferrer\">5 tecniche per studiare meno e meglio per l&#8217;esame da sommelier<\/a><\/li>\n<li style=\"text-align: justify;\"><a href=\"http:\/\/perlagesuite.com\/come-superare-esame-ais-e-diventare-sommelier\/\" target=\"_blank\" rel=\"noopener noreferrer\">Come superare l&#8217;esame AIS e diventare sommelier<\/a><\/li>\n<li style=\"text-align: justify;\"><a href=\"http:\/\/perlagesuite.com\/come-riconoscere-se-un-vino-sa-di-tappo\/\" target=\"_blank\" rel=\"noopener noreferrer\">Come riconoscere se un vino sa di tappo?<\/a><\/li>\n<li style=\"text-align: justify;\"><a href=\"http:\/\/perlagesuite.com\/project\/sudafrica\/\" target=\"_blank\" rel=\"noopener noreferrer\">Vini &amp; Vitigni del Sudafrica<\/a><\/li>\n<li style=\"text-align: justify;\"><a href=\"http:\/\/perlagesuite.com\/project\/nuova-zelanda\/\" target=\"_blank\" rel=\"noopener noreferrer\">Storia, Vini &amp; Vitigni della Nuova Zelanda<\/a><\/li>\n<li style=\"text-align: justify;\"><a href=\"http:\/\/perlagesuite.com\/strumenti-del-sommelier\/\" target=\"_blank\" rel=\"noopener noreferrer\">Gli strumenti del Sommelier<\/a><\/li>\n<li style=\"text-align: justify;\"><a href=\"http:\/\/perlagesuite.com\/diventare-sommelier\/\" target=\"_blank\" rel=\"noopener noreferrer\">Diventare Sommelier<\/a><\/li>\n<\/ul>\n<p>E adesso cominciamo! \ud83d\ude09<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row][et_pb_column type=&#8221;4_4&#8243;][et_pb_toggle admin_label=&#8221;descrivi qualit\u00e0&#8221; title=&#8221;Definisci la qualit\u00e0 di un vino. (cos\u2019\u00e8, da cosa \u00e8 determinata, la scala di valori)&#8221; open=&#8221;off&#8221; body_line_height=&#8221;2em&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<p style=\"text-align: justify;\">La qualit\u00e0 riassume i valori dell&#8217;esame gustativo e si\u00a0riferisce al livello qualitativo del vino. Per i vini di un livello discreto \u00e8 quasi sempre\u00a0<strong>fine<\/strong>, puo&#8217; scendere sull&#8217;<strong>abbastanza fine<\/strong>\u00a0e si colloca sul\u00a0<strong>comune<\/strong>\u00a0per i vini piu&#8217; modesti. Scala:<\/p>\n<ol>\n<li style=\"text-align: justify;\">comune<\/li>\n<li style=\"text-align: justify;\">poco fine<\/li>\n<li style=\"text-align: justify;\">abbastanza fine<\/li>\n<li style=\"text-align: justify;\">fine<\/li>\n<li style=\"text-align: justify;\">eccellente<\/li>\n<\/ol>\n<p>[\/et_pb_toggle][et_pb_toggle admin_label=&#8221;descrivi equilibrio&#8221; title=&#8221;Definisci l&#8217;equilibrio di un vino. (cos\u2019\u00e8, da cosa \u00e8 determinata, la scala di valori)&#8221; open=&#8221;off&#8221; body_line_height=&#8221;2em&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<p style=\"text-align: justify;\">L&#8217;equilibrio, nella scheda di degustazione, rappresenta la bilancia tra le durezze e le morbidezze di un vino e si pu\u00f2 ricavare solo dopo aver analizzato queste. L\u2019equilibrio ideale si percepisce quando morbidezze e durezze sono in adeguata contrapposizione. Nella valutazione occorre tenere presente la tipologia del vino: nei vini giovani, vivaci e frizzanti \u00e8 accettabile leggera predominanza delle durezze, al contrario in un vino maturo si accetta leggera predominanza delle morbidezze. La scala di valori \u00e8:<\/p>\n<ol>\n<li style=\"text-align: justify;\">poco equilibrato<\/li>\n<li style=\"text-align: justify;\">abbastanza equilibrato<\/li>\n<li style=\"text-align: justify;\">equilibrato<\/li>\n<\/ol>\n<p>[\/et_pb_toggle][et_pb_toggle admin_label=&#8221;descrivi sensazioni tattili&#8221; title=&#8221;Definisci le sensazioni tattili di un vino. (cos\u2019\u00e8, da cosa \u00e8 determinata, la scala di valori)&#8221; open=&#8221;off&#8221; body_line_height=&#8221;2em&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<ol>\n<li style=\"text-align: justify;\"><strong>SENSAZIONE TERMICA<\/strong>: legata alla temperatura di servizio del vino. Alzando o abbassando la temperatura variano le percezioni dei 4 sapori fondamentali.\u00a0<b>Dolcezza e morbidezza sono pi\u00f9 percettibili all&#8217;aumento della temperatura mentre sapidit\u00e0 e amarezza lo sono con l&#8217;abbassamento della temperatura<\/b>. L&#8217;acidit\u00e0 non viene direttamente influenzata dal variare della temperatura ma si pu\u00f2 attenuare alzandola\u00a0perch\u00e9\u00a0aumentando dolcezza e morbidezza questa si sente meno.<\/li>\n<li style=\"text-align: justify;\"><strong>SENSAZIONE PSEUDOCALORICA:<\/strong> (non c&#8217;entra nulla con la sensazione termica!) \u00e8 una sensazione di calore, di bruciore, di disidratazione, dovuta alla presenza della componente alcolica (non \u00e8 la gradazione alcolica!).<\/li>\n<li style=\"text-align: justify;\"><strong>SENSAZIONE<\/strong>\u00a0<b>ASTRINGENTE<\/b>: secchezza e rugosit\u00e0 dovuta alla presenza del tannino che reagisce con la mucina, una proteina della saliva, ed attenua la salivazione, in alcuni casi fino alla disidratazione. I tannini sono destinati nel tempo a decrescere perch\u00e9 con l&#8217;invecchiamento del vino precipitano.<\/li>\n<li style=\"text-align: justify;\"><span style=\"color: #000000;\"><b>SENSAZIONE PUNGENTE<\/b>: \u00e8 una sensazione dovuta alla presenza di CO<\/span><span style=\"font-size: small;\">2<\/span>\u00a0ed \u00e8 avvertibile come un pizzicore. E&#8217; una peculiarit\u00e0 dei vini frizzanti e degli spumanti.<\/li>\n<li style=\"text-align: justify;\"><b>SENSAZIONE CONSISTENTE<\/b>: \u00e8 la percezione di che tipo di sostanza si tratta (acquosa, fluida, viscosa, ecc.)<\/li>\n<\/ol>\n<p>[\/et_pb_toggle][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fullwidth=&#8221;off&#8221; specialty=&#8221;off&#8221;][et_pb_row][et_pb_column type=&#8221;4_4&#8243;][et_pb_toggle admin_label=&#8221;mineralit\u00e0&#8221; title=&#8221;Definisci il concetto di mineralit\u00e0 ed usa un vino od un vitigno come esempio.&#8221; open=&#8221;off&#8221; body_line_height=&#8221;2em&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<p style=\"text-align: justify;\">La mineralit\u00e0 \u00e8 l&#8217;insieme di sensazioni olfattive riconducibili ad alcune pietre, minerali e metalli. Alcuni degustatori classificano come sentori minerali le sensazioni di zolfo, catrame, affumicato e gomma bruciata. Altri l&#8217;associano alla salinit\u00e0,\u00a0\u00a0tipica dei vini prodotti nei vigneti a ridosso del mare o che comunque risentono del forte influsso delle brezze marine&#8230; ma non \u00e8 da confondere con la sapidit\u00e0 del vino.<\/p>\n<p>[\/et_pb_toggle][et_pb_toggle admin_label=&#8221;etereo&#8221; title=&#8221;Definisci il concetto di etereo ed usa un vino od un vitigno come esempio.&#8221; open=&#8221;off&#8221; body_line_height=&#8221;2em&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<p style=\"text-align: justify;\">Si dice di un vino invecchiato che presenta profumi derivanti dalla combinazione dei polialcoli. Il vino assume sentori\u00a0inebrianti e pungenti che ricordano il caratteristico sentore dei solventi per vernice. Fanno parte dei sentori eterei:\u00a0ceralacca, smalto, iodio, ecc., e sono dovuti dalla combinazione di eteri, esteri e acetali.<\/p>\n<p>[\/et_pb_toggle][et_pb_toggle admin_label=&#8221;fragrante, erbaceo, minerale&#8221; title=&#8221;Definisci il concetto di fruttato, fragrante ed erbaceo ed usa tre vini come esempi.&#8221; open=&#8221;off&#8221; body_line_height=&#8221;2em&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<p style=\"text-align: justify;\"><strong>FRUTTATO:<\/strong> presente nei vini giovani.\u00a0Nei bianchi si ritrovano solitamente frutti a polpa bianca, in quelli rossi frutti a polpa rossa. Albicocca, ananas, banana, ciliegia, fragola, ribes, lampone, mora, mela cotogna, prugna, agrumi, frutti esotici&#8230; Vino: Emozioni Lato R di Leone Conti &#8211; centesimino di Romagna vendemmia tardiva in cui sono molto forti i\u00a0sentori di ciliegia.<\/p>\n<p><strong>FRAGRANTE<\/strong>: \u00e8 un aggettivo che sottolinea l&#8217;eleganza di un vino. Si usa in due casi:<\/p>\n<ol>\n<li>nei vini bianchi giovani per sottolineare un particolare bouquet floreale. Vino: GoldMuskateller di St. Micheal Eppan &#8211; alto adige moscato giallo in cui \u00e8 presente un bouquet di salvia e fiori bianchi davvero fragrante.<\/li>\n<li>vini bianchi evoluti, champagne per sottolineare i sentori di burro e crosta di pane. Vino: Riserva Villa Baiana di La Montina &#8211; Franciacorta riserva in cui \u00e8 presente il sentore di lievito e crosta di pane.<\/li>\n<\/ol>\n<p>[\/et_pb_toggle][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fullwidth=&#8221;off&#8221; specialty=&#8221;off&#8221;][et_pb_row][et_pb_column type=&#8221;4_4&#8243;][et_pb_toggle admin_label=&#8221;nuova zelanda&#8221; title=&#8221;Elenca le zone vitivinicole ed i vitigni della Nuova Zelanda.&#8221; open=&#8221;off&#8221; body_line_height=&#8221;2em&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<p style=\"text-align: justify;\"><strong>Vitigni chiave<\/strong>\u00a0= bacca nera:\u00a0<b>pinot nero, merlot, cabernet sauvignon, cabernet franc,\u00a0sirah<\/b>; bacca bianca:\u00a0<strong>sauvignon blanc,\u00a0<\/strong><strong>chardonnay,\u00a0pinot grigio, riesling.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Zone chiave<\/strong>\u00a0= Isola del Nord: Auckland, Gisborne,\u00a0<strong>Hawke\u2019s Bay (cabernet sauvignon e merlot), Martinborough (pinot nero)<\/strong>. Isola del Sud: Nelson,\u00a0<strong>Marlborough (sauvignon e chardonnay),<\/strong>\u00a0Canterbury,\u00a0<strong>Central Otago (Pinot nero)<\/strong>.<\/p>\n<p>[\/et_pb_toggle][et_pb_toggle admin_label=&#8221;sudafrica&#8221; title=&#8221;Elenca le zone vitivinicole ed i vitigni del Sudafrica.&#8221; open=&#8221;off&#8221; body_line_height=&#8221;2em&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<p style=\"text-align: justify;\"><strong>Vitigni<\/strong>\u00a0= bacca bianca:\u00a0<strong>chenin blanc\u00a0<\/strong>(20% delle vigne, molto produttivo, pu\u00f2 dare vini molto diversi a seconda delle rese per ceppo, degli obiettivi e delle tecniche enologiche applicate. Perfetto per elaborare vini secchi e freschi, fruttati e non molto intensi. Se evoluto qualche anno offre profumi inattesi di frutta matura e di gardenia, anice e fum\u00e9 con finale mandorlato. Si presta anche alla vendemmia tardiva con muffa nobile, non eccellente),<strong>\u00a0colombard, sauvignon blanc, chardonnay<\/strong>; bacca nera:\u00a0<strong>cabernet sauvignon, syrah, pinotage, merlot<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Zone chiave<\/strong>\u00a0=\u00a0<strong>Stellenbosch, Paarl, Worcester, Constantia, Walker Bay<\/strong><\/p>\n<p>[\/et_pb_toggle][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fullwidth=&#8221;off&#8221; specialty=&#8221;off&#8221;][et_pb_row][et_pb_column type=&#8221;4_4&#8243;][et_pb_toggle admin_label=&#8221;vitigni puglia&#8221; title=&#8221;Elenca 10 vitigni della Puglia.&#8221; open=&#8221;off&#8221; body_line_height=&#8221;2em&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<p style=\"text-align: justify;\"><strong>A bacca bianca:<\/strong> biancolello, bombino bianco, francavilla, garganego, verdeca, mantonico, pampanino, procanico, iuvarella, rossetto, ottenese.<\/p>\n<p style=\"text-align: justify;\"><strong>A bacca nera:<\/strong> bombino nero, ciliegiolo, ellenica, glianico, uva di troia, zinfadel, piede di colombo, morettone, ottavianello, negroamaro.<\/p>\n<p>[\/et_pb_toggle][et_pb_toggle admin_label=&#8221;vitigni veneto&#8221; title=&#8221;Elenca 10 vitigni autoctoni del Veneto.&#8221; open=&#8221;off&#8221; body_line_height=&#8221;2em&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<p style=\"text-align: justify;\"><strong>A bacca bianca<\/strong>: bianchetta trevigiana, boschera, durella, friulano, garganega, glera, greco, ugni blanc, verduzzo trevigiano, vespaiolo.<\/p>\n<p><strong>A bacca nera<\/strong>: ancellotta, corvina, franconia, lancellotta, molinara, pavana, raboso piave, rondinella, schiava, turchetta.<\/p>\n<p>[\/et_pb_toggle][et_pb_toggle admin_label=&#8221;vitigni campania&#8221; title=&#8221;Elenca 10 vitigni della Campania.&#8221; open=&#8221;off&#8221; body_line_height=&#8221;2em&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<p style=\"text-align: justify;\"><strong>A bacca bianca<\/strong>:\u00a0\u00a0bombino, cacchione, coda di volpe, falanghina, fiano, forestiera, ginestra, greco di tufo, janculella, pepella.<\/p>\n<p><strong>A bacca nera<\/strong>:\u00a0aglianico, casavecchia, cesanese, ciliegiolo, ellenica, greco nero, morettone, olivella nera, piede di colombo, piede di palumbo, piedirosso, sangioveto, sciascinoso.<\/p>\n<p>[\/et_pb_toggle][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fullwidth=&#8221;off&#8221; specialty=&#8221;off&#8221;][et_pb_row][et_pb_column type=&#8221;4_4&#8243;][et_pb_toggle admin_label=&#8221;docg friuli&#8221; title=&#8221;Elenca le DOCG del Friuli.&#8221; open=&#8221;off&#8221; body_line_height=&#8221;2em&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<ol>\n<li>Colli orientali del Friuli Picolit<\/li>\n<li>Lison<\/li>\n<li>Ramandolo<\/li>\n<li>Rossazzo<\/li>\n<\/ol>\n<p>[\/et_pb_toggle][et_pb_toggle admin_label=&#8221;docg veneto&#8221; title=&#8221;Elenca le DOCG del Veneto.&#8221; open=&#8221;off&#8221; body_line_height=&#8221;2em&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<ol>\n<li>Amarone della Valpolicella<\/li>\n<li>Bagnoli Friularo<\/li>\n<li>Bardolino Superiore<\/li>\n<li>Asolo &#8211; Prosecco<\/li>\n<li>Colli di Conegliano<\/li>\n<li>Colli Euganei Fior d&#8217;arancio<\/li>\n<li>Conegliano Valdobbiadene &#8211; Prosecco<\/li>\n<li>Lison<\/li>\n<li>Montello<\/li>\n<li>Piave Malanotte<\/li>\n<li>Recioto della Valpolicella<\/li>\n<li>Recioto di Gambellara<\/li>\n<li>Recioto di Soave<\/li>\n<li>Soave Superiore<\/li>\n<\/ol>\n<p>[\/et_pb_toggle][et_pb_toggle admin_label=&#8221;docg lombardia&#8221; title=&#8221;Elenca le DOCG della Lombardia.&#8221; open=&#8221;off&#8221; body_line_height=&#8221;2em&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<ol>\n<li>Franciacorta<\/li>\n<li>Oltrep\u00f2 Pavese Metodo Classico<\/li>\n<li>Moscato di Scanzo<\/li>\n<li>Valtellina Superiore<\/li>\n<li>Sfursat di Valtellina<\/li>\n<\/ol>\n<p>[\/et_pb_toggle][et_pb_toggle admin_label=&#8221;docg umbria&#8221; title=&#8221;Elenca le DOCG dell&#8217;Umbria.&#8221; open=&#8221;off&#8221; body_line_height=&#8221;2em&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<ol>\n<li>Montefalco Sagrantino Passito<\/li>\n<li>Sagrantino di Montefalco<\/li>\n<li>Torgiano Rosso Riserva<\/li>\n<\/ol>\n<p>[\/et_pb_toggle][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fullwidth=&#8221;off&#8221; specialty=&#8221;off&#8221;][et_pb_row][et_pb_column type=&#8221;4_4&#8243;][et_pb_toggle admin_label=&#8221;formaggi crosta lavata&#8221; title=&#8221;Elenca 5 formaggi a crosta lavata.&#8221; open=&#8221;off&#8221; body_line_height=&#8221;2em&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<p style=\"text-align: justify;\">I formaggi a crosta lavata o crosta rossa sono quei formaggi la cui superficie viene lavata e spazzolata al fine di eliminare le eventuali muffe che si formano, permettendo la crescita di un particolare tipo di batteri che conferiscono alla crosta la tipica colorazione rosso-marrone.\u00a0andando ad incidere direttamente sul sapore e sull&#8217;aroma del formaggio e viene eseguita principalmente con acqua, ma anche con birra o brandy.<\/p>\n<ol>\n<li style=\"text-align: justify;\">Taleggio DOP<\/li>\n<li style=\"text-align: justify;\">Fontina DOP<\/li>\n<li style=\"text-align: justify;\">Appenzeller<\/li>\n<li style=\"text-align: justify;\">Beaufort<\/li>\n<li style=\"text-align: justify;\">Groviera<\/li>\n<\/ol>\n<p>[\/et_pb_toggle][et_pb_toggle admin_label=&#8221;formaggi erborinati&#8221; title=&#8221;Elenca 5 formaggi erborinati.&#8221; open=&#8221;off&#8221; body_line_height=&#8221;2em&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<p style=\"text-align: justify;\">I formaggi a pasta erborinata sono chiamati anche formaggi blu. Il loro processo di lavorazione prevede la comparsa di striature e chiazze verde-blu all&#8217;interno della pasta dovute alla formazione di miceli colorati dati dalle colture di funghi del genere penicillium alle quali le forme vengono sottoposte. Tipi:<\/p>\n<ol>\n<li style=\"text-align: justify;\">Gorgonzola<\/li>\n<li style=\"text-align: justify;\">Roquefort<\/li>\n<li style=\"text-align: justify;\">Stilton<\/li>\n<li style=\"text-align: justify;\">Castelmagno<\/li>\n<li style=\"text-align: justify;\">Blu di Corsica<\/li>\n<\/ol>\n<p>[\/et_pb_toggle][et_pb_toggle admin_label=&#8221;formaggi a pasta dura&#8221; title=&#8221;Elenca 5 formaggi a pasta dura.&#8221; open=&#8221;off&#8221; body_line_height=&#8221;2em&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<p>Sono quei formaggi dove la % di acqua \u00e8 relativamente bassa, compresa tra il 30 ed il 40 %. Tipi:<\/p>\n<ol>\n<li>Grana<\/li>\n<li>Asiago<\/li>\n<li>Bitto<\/li>\n<li>Pecorino<\/li>\n<li>Parmigiano<\/li>\n<\/ol>\n<p>[\/et_pb_toggle][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fullwidth=&#8221;off&#8221; specialty=&#8221;off&#8221;][et_pb_row][et_pb_column type=&#8221;4_4&#8243;][et_pb_toggle admin_label=&#8221;risotto zucca&#8221; title=&#8221;Descrivi le sensazioni organolettiche del risotto di zucca e proponi un vino da abbinare.&#8221; open=&#8221;off&#8221; body_line_height=&#8221;2em&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<p>Il risotto alla zucca ha 3 ingredienti fondamentali (oltre, ovviamente, al riso) che danno 3 sensazioni fondamentali:<\/p>\n<ul>\n<li>zucca &#8211; tendenza dolce<\/li>\n<li>formaggio a pasta dura tipo parmigiano (per la mantecata) &#8211; succulenza<\/li>\n<li>burro (per la mantecatura) &#8211; grassezza tendente all&#8217;untuosit\u00e0 (il burro \u00e8 sciolto)<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Per questo i vini da abbinare, per contrapposizione, devono contrastare la tendenza dolce della zucca, la succulenza del parmigiano e la grassezza del burro. A questo punto la proposta verte su un metodo classico tipo Franciacorta, Brut od Extra Brut.<\/p>\n<p>[\/et_pb_toggle][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fullwidth=&#8221;off&#8221; specialty=&#8221;off&#8221;][et_pb_row][et_pb_column type=&#8221;4_4&#8243;][et_pb_toggle admin_label=&#8221;fermentazione&#8221; title=&#8221;Descrivi il processo di fermentazione.&#8221; open=&#8221;off&#8221; body_line_height=&#8221;2em&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<p style=\"text-align: justify;\">La fermentazione \u00e8 un processo ossidativo anaerobico svolto da numerosi organismi a carico di particolari sostanze chimiche per la produzione di energia necessaria alla loro sopravvivenza. Il vino viene prodotto a partire da soluzioni zuccherine ottenute dallo schiacciamento del grappolo d&#8217;uva lasciate a fermentare con i lieviti unicellulari del genere saccharomyces presenti sulla buccia dell&#8217;acino o provenienti da colture selezionate. Il lievito in condizioni anaerobiche, trasforma 100 g di zucchero in 51 g di alcool etilico, con un rendimento in volume del 65,5 %. Questo \u00e8 un rendimento ideale, nella realt\u00e0 una parte dello zucchero disponibile \u00e8 utilizzata dal lievito per moltiplicarsi, inoltre durante la fermentazione i lieviti del mosto producono, oltre l&#8217;alcol e l&#8217;anidride carbonica, anche prodotti secondari (glicerina, acido acetico, acido succinico) che contribuiscono a caratterizzare l&#8217;aroma del prodotto finito.\u00a0Il rendimento reale quindi si approssima al 60% in volume.<\/p>\n<p>[\/et_pb_toggle][et_pb_toggle admin_label=&#8221;distillazione&#8221; title=&#8221;Descrivi il procedimento di distillazione.&#8221; open=&#8221;off&#8221; body_line_height=&#8221;2em&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<p style=\"text-align: justify;\">Procedimento fisico che permette di separare i componenti volatili di un fermentato in base al loro diverso punto di ebollizione con un duplice obiettivo: da un lato si concentra l\u2019alcol etilico presente nel fermentato dal 5 \u2013 12\u00b0 % fino al 65 \u2013 94\u00b0 %, dall\u2019altro si selezionano le sostanze che rendono pregiato un distillato e si eliminano quelle scadenti.<\/p>\n<ol>\n<li style=\"text-align: justify;\">\n<h4>Preparazione del mosto &#8211;\u00a0a\u00a0partire da cereali, tuberi, uva, vino, canna da zucchero, frutti e miele.<\/h4>\n<\/li>\n<li style=\"text-align: justify;\">\n<h4>Fermentazione Mosto &#8211; aggiungendo lieviti saccaromiceti in 3-4 giorni si ottiene circa il 12 % di alcol etilico.<\/h4>\n<\/li>\n<li style=\"text-align: justify;\">\n<h4>Distillazione &#8211; separazione dei componenti volatili di un fermentato per il loro diverso punto di ebollizione.<\/h4>\n<\/li>\n<li style=\"text-align: justify;\">\n<h4>Stabilizzazione &#8211;\u00a0Riposo in botte, aggiunta dosata di acqua distillata,\u00a0refrigerazione e filtrazione.<\/h4>\n<\/li>\n<\/ol>\n<p><span style=\"text-decoration: underline;\"><strong><a href=\"http:\/\/perlagesuite.com\/project\/distillati\/\">Qui trovi tutti gli approfondimenti sui distillati e gli appunti sui diversi tipi di distillato!<\/a><\/strong><\/span><\/p>\n<p>[\/et_pb_toggle][et_pb_toggle admin_label=&#8221;macerazione carbonica&#8221; title=&#8221;Descrivi la macerazione carbonica.&#8221; open=&#8221;off&#8221; body_line_height=&#8221;2em&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<p style=\"text-align: justify;\">La macerazione carbonica si applica prima della vinificazione vera e propria. I grappoli interi sono posti in vasche sature di CO2, dove sono lasciati per periodi compresi tra 5-10 giorni a circa 30 \u00b0C per favorire la produzione di sostanze profumate e di glicerina, la migrazione di pigmenti ed altri componenti dalla buccia alla polpa e la demolizione di parte dell\u2019acido malico. Per evitare pericolose ossidazioni si aggiunge anidride solforosa. Queste condizioni favoriscono una parziale fermentazione intracellulare, senza l\u2019intervento dei lieviti che saranno aggiunti solo dopo. La fermentazione alcolica sar\u00e0 poi veloce, da 2 a 4 giorni e i vini avranno colori intensi e molto vivaci, profumi floreali, fruttati e vinosi, saranno freschi ma gi\u00e0 equilibrati, con tannini delicati ed inadatti all\u2019invecchiamento. Per questo i novelli sono gli unici vini ad essere messi in commercio cos\u00ec presto, a partire dal 6 novembre dello stesso anno della vendemmia che deve essere riportato sull\u2019etichetta.<\/p>\n<p>[\/et_pb_toggle][et_pb_toggle admin_label=&#8221;maturazione aromatica&#8221; title=&#8221;Descrivi la maturazione aromatica e fai degli esempi.&#8221; open=&#8221;off&#8221; body_line_height=&#8221;2em&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<p style=\"text-align: justify;\">La\u00a0<em>maturazione aromatica<\/em>\u00a0\u00e8 legata all\u2019accumulo degli aromi varietali, soprattutto del gruppo dei terpeni; l\u2019accumulo di sostanze aromatiche nelle bucce tende ad aumentare durante la maturazione, per poi diminuire se questa viene prolungata.<\/p>\n<p>[\/et_pb_toggle][et_pb_toggle admin_label=&#8221;maturazione fenolica&#8221; title=&#8221;Descrivi la maturazione fenolica e fai degli esempi.&#8221; open=&#8221;off&#8221; body_line_height=&#8221;2em&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<p style=\"text-align: justify;\">La\u00a0<i>maturazione fenolica<\/i>\u00a0coinvolge la componente fenolica dell\u2019uva, pi\u00f9 concentrata nella buccia; lasciando maturare le uve un po\u2019 pi\u00f9 a lungo, si ha un incremento della componente fenolica che contribuisce a rendere il vino pi\u00f9 strutturato e ricco di tannini, e una leggera diminuzione di quella che rende il colore pieno e compatto.<\/p>\n<p>[\/et_pb_toggle][et_pb_toggle admin_label=&#8221;maturazione tecnologica&#8221; title=&#8221;Descrivi la maturazione tecnologica e fai degli esempi.&#8221; open=&#8221;off&#8221; body_line_height=&#8221;2em&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<p style=\"text-align: justify;\">La\u00a0<i>maturazione tecnologica<\/i>\u00a0\u00e8 valutata in base al rapporto tra zuccheri e acidi; con il passare del tempo gli zuccheri aumentano e gli acidi diminuiscono, soprattutto il malico, il pi\u00f9 aspro e aggressivo; di conseguenza, quando si vuole ottenere un mosto pi\u00f9 ricco di acidi fissi la raccolta delle uve viene un po\u2019 anticipata; se si vuole ottenere, invece, un mosto ricco di zuccheri occorre invece ritardare la vendemmia.<\/p>\n<p>[\/et_pb_toggle][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fullwidth=&#8221;off&#8221; specialty=&#8221;off&#8221;][et_pb_row][et_pb_column type=&#8221;4_4&#8243;][et_pb_toggle admin_label=&#8221;vitigni aromatici e vitigni aromatizzati&#8221; title=&#8221;Descrivi la differenza tra vitigni aromatici e vini aromatizzati.&#8221; open=&#8221;off&#8221; body_line_height=&#8221;2em&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<p style=\"text-align: justify;\">Un vino \u00e8 aromatico se \u00e8 ottenuto da un vitigno aromatico. Un vino \u00e8 aromatizzato se al vino\/mosto fermo di almeno 10\u00b0vol si aggiungono alcol, zucchero o mosto, e poi erbe\/spezie aromatizzanti in giusta proporzione.<\/p>\n<p style=\"text-align: justify;\">Approfondimenti:<\/p>\n<p style=\"text-align: justify;\"><span style=\"text-decoration: underline;\"><strong><a href=\"http:\/\/perlagesuite.com\/come-superare-esame-ais-e-diventare-sommelier\/\">Scopri cosa \u00e8 successo quando mi hanno fatto questa domanda apparentemente innocua!<\/a><\/strong><\/span><\/p>\n<p>[\/et_pb_toggle][et_pb_toggle admin_label=&#8221;perlage&#8221; title=&#8221;Come il perlage influenza le caratteristiche del vino?&#8221; open=&#8221;off&#8221; body_line_height=&#8221;2em&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<p>Il perlage accentua i profumi e\u00a0le\u00a0durezze.<\/p>\n<p>[\/et_pb_toggle][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fullwidth=&#8221;off&#8221; specialty=&#8221;off&#8221;][et_pb_row][et_pb_column type=&#8221;4_4&#8243;][et_pb_text admin_label=&#8221;Testo&#8221; background_layout=&#8221;light&#8221; text_orientation=&#8221;left&#8221; text_line_height=&#8221;2em&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221;]<\/p>\n<p style=\"text-align: justify;\">Queste domande &amp; risposte sono in continuo aggiornamento \ud83d\ude42 Se hai altre domande da aggiungere a queste, ti chiedo il piacere di scrivermele in un commento! Provveder\u00f2 personalmente a trovare le risposte pi\u00f9 corrette!<\/p>\n<p style=\"text-align: justify;\">Aiutatemi ad aiutare chi deve ancora superare l&#8217;esame per diventare sommelier! E ancora un grazie di cuore ad Elisa per avermi aiutato a stilare questa raccolta!<\/p>\n<p style=\"text-align: justify;\">Un abbraccio,<\/p>\n<p style=\"text-align: justify;\">Chiara<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p><div class=\"et_pb_section et_pb_section_0 et_section_regular\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_pb_row et_pb_row_0 et_pb_row_empty\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div> Grazie soprattutto al lavoro di\u00a0Elisa Maniezzo, una mia cara lettrice che sento spesso per email e con cui ho scoperto diverse cose in comune, oggi vi posto un po&#8217; di domande che hanno\u00a0caratterizzato gli esami AIS 2015&#8230; tra cui il mio \ud83d\ude09 Superare l&#8217;esame AIS e diventare sommelier non \u00e8 una cosa da prendere [&hellip;]<\/p>\n","protected":false},"author":49,"featured_media":2704,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[328],"tags":[],"class_list":["post-2697","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-diventare-sommelier"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.0 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Domande &amp; Risposte dell&#039;esame AIS 2015 - Perlage Suite<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/perlagesuite.com\/en\/domande-risposte-esame-ais-2015\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Domande &amp; Risposte dell&#039;esame AIS 2015\" \/>\n<meta property=\"og:description\" content=\"Grazie soprattutto al lavoro di\u00a0Elisa Maniezzo, una mia cara lettrice che sento spesso per email e con cui ho scoperto diverse cose in comune, oggi vi posto un po&#039; di domande che hanno\u00a0caratterizzato gli esami AIS 2015... tra cui il mio ;-) Superare l&#039;esame AIS e diventare sommelier non \u00e8 una cosa da prendere [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/perlagesuite.com\/en\/domande-risposte-esame-ais-2015\/\" \/>\n<meta property=\"og:site_name\" content=\"Perlage Suite\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/chiarabassiperlagesuite\" \/>\n<meta property=\"article:published_time\" content=\"2015-06-22T13:40:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-15T10:50:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/perlagesuite.com\/wp-content\/uploads\/2015\/06\/vignetta-sommelier-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"633\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Chiara Bassi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@perlagesuite\" \/>\n<meta name=\"twitter:site\" content=\"@perlagesuite\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Chiara Bassi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"16 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/domande-risposte-esame-ais-2015\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/domande-risposte-esame-ais-2015\\\/\"},\"author\":{\"name\":\"Chiara Bassi\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/person\\\/81b257517a1007c1a823318ac86c6013\"},\"headline\":\"Domande &#038; Risposte dell&#8217;esame AIS 2015\",\"datePublished\":\"2015-06-22T13:40:54+00:00\",\"dateModified\":\"2020-10-15T10:50:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/domande-risposte-esame-ais-2015\\\/\"},\"wordCount\":3197,\"commentCount\":14,\"publisher\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/domande-risposte-esame-ais-2015\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/vignetta-sommelier-1.jpg\",\"articleSection\":[\"Didattica Sommelier\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/perlagesuite.com\\\/domande-risposte-esame-ais-2015\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/domande-risposte-esame-ais-2015\\\/\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/domande-risposte-esame-ais-2015\\\/\",\"name\":\"Domande & Risposte dell'esame AIS 2015 - Perlage Suite\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/domande-risposte-esame-ais-2015\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/domande-risposte-esame-ais-2015\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/vignetta-sommelier-1.jpg\",\"datePublished\":\"2015-06-22T13:40:54+00:00\",\"dateModified\":\"2020-10-15T10:50:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/domande-risposte-esame-ais-2015\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/perlagesuite.com\\\/domande-risposte-esame-ais-2015\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/domande-risposte-esame-ais-2015\\\/#primaryimage\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/vignetta-sommelier-1.jpg\",\"contentUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/vignetta-sommelier-1.jpg\",\"width\":1024,\"height\":633,\"caption\":\"Domande esame ais 2022 diventare sommelier\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/domande-risposte-esame-ais-2015\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/perlagesuite.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Domande &#038; Risposte dell&#8217;esame AIS 2015\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#website\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/\",\"name\":\"Perlage Suite\",\"description\":\"Il Wine Blog di Chiara Bassi\",\"publisher\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/perlagesuite.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#organization\",\"name\":\"Chiara Bassi\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Chiara-Bassi-sommelier-wine-blogger-logo.png\",\"contentUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Chiara-Bassi-sommelier-wine-blogger-logo.png\",\"width\":512,\"height\":512,\"caption\":\"Chiara Bassi\"},\"image\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/chiarabassiperlagesuite\",\"https:\\\/\\\/x.com\\\/perlagesuite\",\"https:\\\/\\\/www.instagram.com\\\/perlagesuite\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/person\\\/81b257517a1007c1a823318ac86c6013\",\"name\":\"Chiara Bassi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g\",\"caption\":\"Chiara Bassi\"},\"sameAs\":[\"https:\\\/\\\/perlagesuite.com\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"AIS 2015 Exam Questions &amp; Answers - Perlage Suite","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/perlagesuite.com\/en\/domande-risposte-esame-ais-2015\/","og_locale":"en_GB","og_type":"article","og_title":"Domande & Risposte dell'esame AIS 2015","og_description":"Grazie soprattutto al lavoro di\u00a0Elisa Maniezzo, una mia cara lettrice che sento spesso per email e con cui ho scoperto diverse cose in comune, oggi vi posto un po' di domande che hanno\u00a0caratterizzato gli esami AIS 2015... tra cui il mio ;-) Superare l'esame AIS e diventare sommelier non \u00e8 una cosa da prendere [&hellip;]","og_url":"https:\/\/perlagesuite.com\/en\/domande-risposte-esame-ais-2015\/","og_site_name":"Perlage Suite","article_publisher":"https:\/\/www.facebook.com\/chiarabassiperlagesuite","article_published_time":"2015-06-22T13:40:54+00:00","article_modified_time":"2020-10-15T10:50:06+00:00","og_image":[{"width":1024,"height":633,"url":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2015\/06\/vignetta-sommelier-1.jpg","type":"image\/jpeg"}],"author":"Chiara Bassi","twitter_card":"summary_large_image","twitter_creator":"@perlagesuite","twitter_site":"@perlagesuite","twitter_misc":{"Written by":"Chiara Bassi","Estimated reading time":"16 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/perlagesuite.com\/domande-risposte-esame-ais-2015\/#article","isPartOf":{"@id":"https:\/\/perlagesuite.com\/domande-risposte-esame-ais-2015\/"},"author":{"name":"Chiara Bassi","@id":"https:\/\/perlagesuite.com\/#\/schema\/person\/81b257517a1007c1a823318ac86c6013"},"headline":"Domande &#038; Risposte dell&#8217;esame AIS 2015","datePublished":"2015-06-22T13:40:54+00:00","dateModified":"2020-10-15T10:50:06+00:00","mainEntityOfPage":{"@id":"https:\/\/perlagesuite.com\/domande-risposte-esame-ais-2015\/"},"wordCount":3197,"commentCount":14,"publisher":{"@id":"https:\/\/perlagesuite.com\/#organization"},"image":{"@id":"https:\/\/perlagesuite.com\/domande-risposte-esame-ais-2015\/#primaryimage"},"thumbnailUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2015\/06\/vignetta-sommelier-1.jpg","articleSection":["Didattica Sommelier"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/perlagesuite.com\/domande-risposte-esame-ais-2015\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/perlagesuite.com\/domande-risposte-esame-ais-2015\/","url":"https:\/\/perlagesuite.com\/domande-risposte-esame-ais-2015\/","name":"AIS 2015 Exam Questions &amp; Answers - Perlage Suite","isPartOf":{"@id":"https:\/\/perlagesuite.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/perlagesuite.com\/domande-risposte-esame-ais-2015\/#primaryimage"},"image":{"@id":"https:\/\/perlagesuite.com\/domande-risposte-esame-ais-2015\/#primaryimage"},"thumbnailUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2015\/06\/vignetta-sommelier-1.jpg","datePublished":"2015-06-22T13:40:54+00:00","dateModified":"2020-10-15T10:50:06+00:00","breadcrumb":{"@id":"https:\/\/perlagesuite.com\/domande-risposte-esame-ais-2015\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/perlagesuite.com\/domande-risposte-esame-ais-2015\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/perlagesuite.com\/domande-risposte-esame-ais-2015\/#primaryimage","url":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2015\/06\/vignetta-sommelier-1.jpg","contentUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2015\/06\/vignetta-sommelier-1.jpg","width":1024,"height":633,"caption":"Domande esame ais 2022 diventare sommelier"},{"@type":"BreadcrumbList","@id":"https:\/\/perlagesuite.com\/domande-risposte-esame-ais-2015\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/perlagesuite.com\/"},{"@type":"ListItem","position":2,"name":"Domande &#038; Risposte dell&#8217;esame AIS 2015"}]},{"@type":"WebSite","@id":"https:\/\/perlagesuite.com\/#website","url":"https:\/\/perlagesuite.com\/","name":"Perlage Suite","description":"Chiara Bassi's Wine Blog","publisher":{"@id":"https:\/\/perlagesuite.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/perlagesuite.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/perlagesuite.com\/#organization","name":"Chiara Bassi","url":"https:\/\/perlagesuite.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/perlagesuite.com\/#\/schema\/logo\/image\/","url":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2022\/03\/Chiara-Bassi-sommelier-wine-blogger-logo.png","contentUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2022\/03\/Chiara-Bassi-sommelier-wine-blogger-logo.png","width":512,"height":512,"caption":"Chiara Bassi"},"image":{"@id":"https:\/\/perlagesuite.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/chiarabassiperlagesuite","https:\/\/x.com\/perlagesuite","https:\/\/www.instagram.com\/perlagesuite\/"]},{"@type":"Person","@id":"https:\/\/perlagesuite.com\/#\/schema\/person\/81b257517a1007c1a823318ac86c6013","name":"Chiara Bassi","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g","caption":"Chiara Bassi"},"sameAs":["https:\/\/perlagesuite.com"]}]}},"_links":{"self":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/posts\/2697","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/comments?post=2697"}],"version-history":[{"count":0,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/posts\/2697\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/media\/2704"}],"wp:attachment":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/media?parent=2697"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/categories?post=2697"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/tags?post=2697"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}