{"id":27071,"date":"2020-12-02T18:32:21","date_gmt":"2020-12-02T17:32:21","guid":{"rendered":"https:\/\/perlagesuite.com\/?p=27071"},"modified":"2022-10-04T16:39:48","modified_gmt":"2022-10-04T15:39:48","slug":"vini-umbri","status":"publish","type":"post","link":"https:\/\/perlagesuite.com\/en\/vini-umbri\/","title":{"rendered":"Umbrian wines: territory, grape varieties, wines and gastronomy"},"content":{"rendered":"\n[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.7.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_row _builder_version=&#8221;4.7.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.7.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_text _builder_version=&#8221;4.7.4&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;]<p style=\"text-align: justify;\"><strong>L&#8217;Umbria \u00e8 una regione dell&#8217;Italia Centrale che spesso non ha l&#8217;importanza che merita nel panorama enologico italiano<\/strong>. I <strong>vini umbri<\/strong> sono stati per me una piacevole scoperta per cui ringrazio l&#8217;amico e collega <strong>Federico Scarponi, miglior sommelier dell&#8217;Umbria 2011<\/strong> per avermi fatto fare una interessantissima panoramica. Federico ha aperto il piccolo <a href=\"https:\/\/3tselezionewineshop.com\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"text-decoration: underline;\"><strong>wine shop online 3T Selezione<\/strong><\/span><\/a> con delle vere e proprie chicche del suo territorio (e non solo).<\/p>\n<p style=\"text-align: justify;\">Anzi, quest&#8217;anno <strong>cosa ne pensi di fare qualche buona bottiglia di vino umbro come regalo di Natale?<\/strong> Nel wine shop di Federico la consegna a domicilio \u00e8 gratuita con un minimo di 59\u20ac. Dato che col nuovo DCPM non ci possiamo muovere al di fuori del nostro comune scambiarci regali di Natale personalmente sar\u00e0 impossibile&#8230; <span>\ud83d\ude29\u00a0<\/span>quindi tanto vale approfittare degli shop online (che comunque io trovo comodissimi!).<\/p>\n<p style=\"text-align: justify;\">Prima di studiare i vini umbri, facciamo insieme una piccola degustazione di questo territorio.<\/p>\n[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2020\/12\/vino-sagrantino-di-montefalco-trabalza-vini-umbri.jpg&#8221; _builder_version=&#8221;4.7.4&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243; alt=&#8221;vini umbri sagrantino di montefalco trabalza&#8221; title_text=&#8221;vino-sagrantino-di-montefalco-trabalza-vini-umbri&#8221; box_shadow_style=&#8221;preset3&#8243;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.7.4&#8243; _module_preset=&#8221;default&#8221; header_3_font=&#8221;Delius Unicase|700|||||||&#8221; header_3_font_size=&#8221;20px&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;]<h3>Vini umbri: una carrellata di degustazioni con Federico di 3T Selezione<\/h3>\n<p style=\"text-align: justify;\">Federico mi ha proposto 6 etichette presenti nel suo wine shop:<\/p>\n<ul>\n<li><a href=\"https:\/\/3tselezionewineshop.com\/products\/sagrantino-di-montefalco-2015?_pos=1&amp;_sid=a249aeadc&amp;_ss=r\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"text-decoration: underline;\"><strong>Montefalco Sagrantino DOCG 2015 di Trabalza<\/strong><\/span><\/a><\/li>\n<li><a href=\"https:\/\/3tselezionewineshop.com\/products\/piantata-2018?_pos=1&amp;_sid=b6b708203&amp;_ss=r\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"text-decoration: underline;\"><strong>&#8220;Piantata&#8221; Umbria IGT Sangiovese 2018 di Cantina Cenci<\/strong><\/span><\/a><\/li>\n<li><a href=\"https:\/\/3tselezionewineshop.com\/products\/intenso-2015?_pos=1&amp;_sid=4e2a7a026&amp;_ss=r\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"text-decoration: underline;\"><strong>&#8220;Intenso&#8221; Umbria IGT Rosso 2015 di Tenuta Baroni<\/strong><\/span><\/a><\/li>\n<li><a href=\"https:\/\/3tselezionewineshop.com\/products\/casale-dei-ceci-2019?_pos=1&amp;_sid=78cbc944b&amp;_ss=r\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"text-decoration: underline;\"><strong>[Vino bianco] &#8220;Casale dei Ceci&#8221; Umbria IGT Grechetto di Lumiluna<\/strong><\/span><\/a><\/li>\n<li><a href=\"https:\/\/3tselezionewineshop.com\/products\/filare-maiore-2018?_pos=1&amp;_sid=a43db4601&amp;_ss=r\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"text-decoration: underline;\"><strong>[Vino bianco] &#8220;Filare Maiore&#8221; Umbria IGP Bianco 2019 di Cantina La Spina di Moreno Peccia<\/strong><\/span><\/a><\/li>\n<li><a href=\"https:\/\/3tselezionewineshop.com\/products\/viognier-2018?_pos=1&amp;_sid=65578598d&amp;_ss=r\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"text-decoration: underline;\"><strong>[Vino bianco] Viognier Umbria IGT 2018 di Madonna del Latte<\/strong><\/span><\/a><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Intanto sono tutti vini di grande qualit\u00e0. In particolare <strong>il Viognier \u00e8 un vino eseguito da manuale (meraviglioso col branzino al forno) mentre<\/strong>\u00a0<strong>il Filare Maiore<\/strong> \u00e8 interessante anche per il suo essere un <strong>trebbiano spoletino in purezza<\/strong>. Se per\u00f2 devo dirti cosa mi ha colpito tra questi vini bianchi \u00e8 senza dubbio l&#8217;<strong>Umbria Grechetto IGT 2018 &#8220;Casale dei Ceci&#8221;<\/strong>. Si presenta di un bellissimo colore giallo dorato intenso e brillante. Al naso \u00e8 complesso, con note di pera matura e qualche sentore ossidato molto piacevole. In bocca tanta struttura e sapidit\u00e0, con una persistente nota ammandorlata. Il rapporto qualit\u00e0 prezzo (\u00e8 in vendita a 11\u20ac) mi ha confermato l&#8217;apprezzamento. Ci ho abbinato i paccheri con broccoli e orata leggermente piccanti e devo dire che \u00e8 stata una cena deliziosa!<\/p>\n<p style=\"text-align: justify;\">Per quanto riguarda i rossi, <strong>Intenso<\/strong> \u00e8 un vino perfetto per accompagnare con discrezione qualsiasi piatto non troppo saporito. Ha raggiunto il suo apice e si avvia un percorso di maturit\u00e0. Ha un buon rapporto qualit\u00e0 prezzo (viene venduto a 12\u20ac) ed \u00e8 da bere subito. Anche se con la tagliata di petto d&#8217;anatra niente mi entusiasma di pi\u00f9 di un gewurztraminer alsaziano servito leggermente freddo, l&#8217;ha accompagnata con grande piacevolezza. <strong>Piantata<\/strong> \u00e8 un sangiovese molto buono, perfetto per dare agli irriducibili del Chianti Riserva un&#8217;occasione per cambiare. Pronto oggi, \u00e8 morbidissimo e abbastanza fruttato e ricco di note di spezie dolci e tostature.<\/p>\n<p style=\"text-align: justify;\">La chicca tra i vini rossi per\u00f2 \u00e8 questo <strong>Sagrantino Montefalco 2015 di Trabalza<\/strong> che ho trovato davvero meraviglioso! Ci ho abbinato i paccheri con fonduta di gorgonzola e cipolla di Tropea. Si presenta di un colore rosso rubino intenso e profondo, appena trasparente. Al naso \u00e8 molto complesso, con note di inchiostro, cacao amaro, pepe nero, gelso maturo, mandorla fresca e pino mugo. In bocca \u00e8 imponente, ancora ruvido ma piacevole, fresco, tannico e molto persistente. Si gode bene ora, ma sono certa che tra qualche anno sar\u00e0 ancora migliore. Ottimo rapporto qualit\u00e0 prezzo (22,50\u20ac a bottiglia).<\/p>\n<p style=\"text-align: justify;\">\n[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2020\/12\/vini-umbri-degustazione-grechetto-trebbiano-spoletino-viognier.jpg&#8221; _builder_version=&#8221;4.7.4&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243; alt=&#8221;vini umbri&#8221; title_text=&#8221;vini-umbri-degustazione-grechetto-trebbiano-spoletino-viognier&#8221; box_shadow_style=&#8221;preset3&#8243;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.7.4&#8243; _module_preset=&#8221;default&#8221; header_3_font=&#8221;Delius Unicase|700|||||||&#8221; header_3_font_size=&#8221;20px&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;]<h3>Adesso basta bere, si torna a studiare!!!<\/h3>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<h3>Vini umbri: storia della vite<\/h3>\n<p style=\"text-align: justify;\">La storia della vite, come testimoniano i reperti rinvenuti nelle tombe etrusche, \u00e8 molto antica. Gli Etruschi, presenti in umbria dal VII secolo a.C. coltiv\u00f2 la vite per usare il &#8220;vino&#8221; soprattutto nei riti religiosi. I Romani ci diedero notizie dei vini umbri molto contrastate, a testimoniare la grande differenza qualitativa e di apprezzamento che variava da zona a zona. Per molti secoli perdemmo totalmente le notizie dei vini umbri, per poi ritrovare come spesso accade i monaci a coltivare la vite, soprattutto avviarono produzioni interessanti dal punto di vista qualitativo e quantitativo i Cisterensi e i seguaci di San Benedetto da Norcia. Nel 1549 Sante Lancerio, bottigliere di papa Paolo III Farnese, nell&#8217;annotare i gusti del pontefice definisce eccellente il vino rosso &#8220;sucano&#8221; delle parti di Orvieto. Intorno al 1600 Andrea Bacci dar\u00e0 un quadro ampio anche se un po&#8217; confuso dei vini umbri. L&#8217;Orvieto resta il cavallo di battaglia e all&#8217;epoca era gi\u00e0 imbottigliato in fiaschette impagliate.<\/p>\n<p style=\"text-align: justify;\">Nei secoli successivi le notizie dei vini umbri si faranno sempre pi\u00f9 rade tranne per quanto riguarda l&#8217;Orvieto. Poco prima della distruzione avuta con la fillossera, si parla quindi intorno al 1850 sappiamo di vini rossi da uve sangiovese e sagrantino a Montefalco, del trebbiano sulle colline e del trebbianello in pianura. Solo con il secondo dopoguerra si avr\u00e0 un rinnovamento della viticoltura umbra e compariranno le prime denominazioni d&#8217;origine.<\/p>\n[\/et_pb_text][et_pb_divider _builder_version=&#8221;4.7.4&#8243; _module_preset=&#8221;default&#8221; color=&#8221;#da413d&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;][\/et_pb_divider][et_pb_text _builder_version=&#8221;4.7.4&#8243; _module_preset=&#8221;default&#8221; header_3_font=&#8221;Delius Unicase|700|||||||&#8221; header_3_font_size=&#8221;20px&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;]<p style=\"text-align: justify;\">Da qui comincia una riproduzione parziale del<strong> &#8220;capitolo 4.2.13 Umbria&#8221; da pagina 197 del mio libro cartaceo <a href=\"https:\/\/perlagesuite.com\/prodotto\/come-diventare-sommelier-esame-ais-corso-sommelier\/\"><span><span style=\"text-decoration: underline;\">&#8220;Come diventare Sommelier: tutti i miei appunti in un solo libro&#8221;<\/span>.<\/span><\/a><\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\"><strong>.<\/strong><\/span><\/p>\n<h3>Vini umbri: clima<\/h3>\n<ul>\n<li style=\"text-align: justify;\"><span><b>Temperature<\/b><\/span><span> = A seconda delle zone il <b>clima \u00e8 da temperato subcontinentale a temperato mediterraneo<\/b>. Gli inverni non sono troppo freddi e le estati sono calde, asciutte e ventilate.<\/span><\/li>\n<li style=\"text-align: justify;\"><span><b>Piogge<\/b><\/span><span> = <b>Non piove molto<\/b>, e comunque le piogge sono ben distribuite lungo tutto l\u2019anno.<\/span><\/li>\n<\/ul>\n[\/et_pb_text][et_pb_text _builder_version=&#8221;4.7.4&#8243; _module_preset=&#8221;default&#8221; header_3_font=&#8221;Delius Unicase|700|||||||&#8221; header_3_font_size=&#8221;20px&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;]<h3>Vini umbri: terreni<\/h3>\n<ul>\n<li><span>Dove oggi ci sono le pianure ieri c\u2019erano laghi, poi colmati da depositi alluvionali.<\/span><\/li>\n<li><span>Terreni <b>argilloso-calcarei<\/b>, con marne, tufi e rocce vulcaniche.<\/span><\/li>\n<li style=\"text-align: justify;\"><span>Nella zona del Torgiano i rilievi hanno terreni con <strong>sedimenti lacustri e torrentizi<\/strong> composti di argille con lignite, sabbie e ciottoli, resti vegetali e di mammiferi dell&#8217;antico lago Tiberino.<\/span><\/li>\n<\/ul>\n[\/et_pb_text][et_pb_text _builder_version=&#8221;4.7.4&#8243; _module_preset=&#8221;default&#8221; header_3_font=&#8221;Delius Unicase|700|||||||&#8221; header_3_font_size=&#8221;20px&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;]<h3>Vini umbri: vitigni<\/h3>\n<ul>\n<li style=\"text-align: justify;\"><span><b>A bacca bianca<\/b><\/span><span> = Canaiolo bianco, malvasia bianca lunga, trebbiano giallo, trebbiano toscano, <b>grechetto<\/b>, malvasia bianca, riesling, trebbiano toscano, verdello, verdicchio bianco.<\/span><\/li>\n<li style=\"text-align: justify;\"><span><b>A bacca nera<\/b><\/span><span> = Ciliegiolo, gamay, montepulciano, merlot, <b>sagrantino<\/b>, <b>sangiovese<\/b>.<\/span><\/li>\n<\/ul>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.7.4&#8243; _module_preset=&#8221;default&#8221; column_structure=&#8221;1_2,1_2&#8243;][et_pb_column _builder_version=&#8221;4.7.4&#8243; _module_preset=&#8221;default&#8221; type=&#8221;1_2&#8243;][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2020\/12\/umbria.jpg&#8221; _builder_version=&#8221;4.7.4&#8243; _module_preset=&#8221;default&#8221; alt=&#8221;vini umbri&#8221; title_text=&#8221;umbria&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column _builder_version=&#8221;4.7.4&#8243; _module_preset=&#8221;default&#8221; type=&#8221;1_2&#8243;][et_pb_text _builder_version=&#8221;4.7.4&#8243; _module_preset=&#8221;default&#8221; header_3_font=&#8221;Delius Unicase|700|||||||&#8221; header_3_font_size=&#8221;20px&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;]<h3>Vini umbri: zone &amp; vini chiave<\/h3>\n<ul>\n<li style=\"text-align: justify;\"><span><b>Assisi<\/b><\/span><span> = Vino bianco da uve trebbiano spoletino raramente vinificate in purezza, pi\u00f9 spesso in combinazione con trebbiano toscano e grechetto.<\/span><\/li>\n<li style=\"text-align: justify;\"><span><b>COLLI ALTOTIBERINI<\/b><\/span><span> = Vino bianco da uve trebbiano toscano e vino rosso da uve sangiovese che pu\u00f2 essere anche Riserva.<\/span><\/li>\n<li style=\"text-align: justify;\"><span><b>Colli amerini<\/b><\/span><span> = Vini rossi interessanti da sangiovese e ciliegiolo.<\/span><\/li>\n<li style=\"text-align: justify;\"><span><b>Colli del lago Trasimeno<\/b><\/span><span> = Vini bianchi da uve grechetto, trebbiano toscano, verdello.<\/span><\/li>\n<li style=\"text-align: justify;\"><span><b>Colli Martani<\/b><\/span><span><b> <\/b><\/span><span>= Greco di Todi e Sagrantino.<\/span><\/li>\n<li style=\"text-align: justify;\"><span><b>COLLI PERUGINI<\/b><\/span><span> = Vini rossi da uve sangiovese con una buona acidit\u00e0 e sentori di cioccolato, frutta a bacca nera e spezie pi\u00f9 o meno dolci. Vini bianchi minerali da uve grechetto e trebbiano toscano. Vini spumanti da vitigni internazionali. Vin Santo da uve grechetto.<\/span><\/li>\n<li style=\"text-align: justify;\"><span><b>Orvieto<\/b><\/span><span> = Se i vini bianchi secchi hanno mediamente una qualit\u00e0 organolettica non stupefacente, i muffati invece sono interessantissimi.<\/span><\/li>\n<li style=\"text-align: justify;\"><span><b>Montefalco<\/b><\/span><span> = Sagrantino Montefalco, secco o passito.<\/span><\/li>\n<li style=\"text-align: justify;\"><span><b>Torgiano<\/b><\/span><span> = Torgiano Rosso Riserva da uve sangiovese e canaiolo nero. Ma in questa zona si produce anche un ottimo Torgiano bianco da uve trebbiano toscano e grechetto.<\/span><\/li>\n<\/ul>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.7.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_column _builder_version=&#8221;4.7.4&#8243; _module_preset=&#8221;default&#8221; type=&#8221;4_4&#8243;][et_pb_text _builder_version=&#8221;4.7.4&#8243; _module_preset=&#8221;default&#8221; header_3_font=&#8221;Delius Unicase|700|||||||&#8221; header_3_font_size=&#8221;20px&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;]<h3 style=\"text-align: justify;\">Vini umbri: Sottozone, DOC &amp; DOCG<\/h3>\n<p style=\"text-align: justify;\"><span>[R] = Rosso; [B] = Bianco; [T] = Rosato; [S] = Spumante o Frizzante; [*] = In corso<\/span><\/p>\n<ul>\n<li style=\"text-align: justify;\"><span><b>DOCG<\/b><\/span><span> = Montefalco Sagrantino [R], Torgiano Rosso Riserva [R].<\/span><\/li>\n<li style=\"text-align: justify;\"><span><b>DOC<\/b><\/span><span> = Amelia [R,B,T], Assisi [R,B,T], Colli Altotiberini [R,B,T,S], Colli del Trasimeno o Trasimeno [R,B,T,S], Colli Martani [R,B,S], Colli Perugini [R,B,T,S], Lago di Corbara [R,B], Montefalco [R,B], Orvieto [B], Rosso Orvietano o Orvietano Rosso [R], Spoleto [B,S], Todi [R,B], Torgiano [R,B,T,S].<\/span><\/li>\n<\/ul>\n[\/et_pb_text][et_pb_text _builder_version=&#8221;4.7.4&#8243; _module_preset=&#8221;default&#8221; header_3_font=&#8221;Delius Unicase|700|||||||&#8221; header_3_font_size=&#8221;20px&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;]<h3>Vini umbri: piatti tipici &amp; abbinamento cibo-vino<\/h3>\n<ul>\n<li style=\"text-align: justify;\"><span><b>Strangozzi al tartufo<\/b><\/span><span> = Pasta lunga di semola e acqua la cui forma ricorda delle tagliatelle spesse. Si saltano in una padella dove si \u00e8 rosolato uno spicchio d\u2019aglio in olio extravergine di oliva e sciolta un\u2019acciuga. A cottura ultimata si aggiunge il tartufo tagliato a lamelle sottili. In questa preparazione abbiamo una duplice tendenza amara data dall&#8217;acciuga e dal tartufo, la sapidit\u00e0 data dall&#8217;acciuga e una grande intensit\u00e0 e persistenza aromatica data dal tartufo. Si abbina bene a un <b>vino rosso morbido, strutturato e molto persistente<\/b> come un <b>Torgiano Rosso Riserva<\/b>.<\/span><\/li>\n<\/ul>\n[\/et_pb_text][et_pb_text _builder_version=&#8221;4.7.4&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;]<p style=\"text-align: justify;\"><strong>Il contenuto di questo articolo didattico \u00e8 una riproduzione parziale del &#8220;capitolo 4.2.13 Umbria&#8221; da pagina 197 del mio libro cartaceo <a href=\"https:\/\/perlagesuite.com\/prodotto\/come-diventare-sommelier-esame-ais-corso-sommelier\/\"><span style=\"text-decoration: underline;\">&#8220;Come diventare Sommelier: tutti i miei appunti in un solo libro&#8221;<\/span><\/a> che puoi comprare subito cliccando <a href=\"https:\/\/perlagesuite.com\/prodotto\/come-diventare-sommelier-esame-ais-corso-sommelier\/\"><span style=\"text-decoration: underline;\">QUI<\/span><\/a>.<\/strong><\/p>\n<p style=\"text-align: justify;\">Come sempre spero che questo articolo ti sia piaciuto e ti sia stato utile.<\/p>\n<p style=\"text-align: justify;\">Cheers\u00a0<span>\ud83c\udf77<\/span><\/p>\n<p style=\"text-align: justify;\">Chiara<\/p>\n[\/et_pb_text][et_pb_divider color=&#8221;#da413d&#8221; _builder_version=&#8221;4.7.4&#8243; _module_preset=&#8221;default&#8221;][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.0.6&#8243; global_module=&#8221;21425&#8243;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.0.6&#8243;][et_pb_wc_images product=&#8221;10582&#8243; _builder_version=&#8221;4.0.6&#8243;][\/et_pb_wc_images][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.0.6&#8243;][et_pb_wc_title product=&#8221;10582&#8243; _builder_version=&#8221;4.0.6&#8243;][\/et_pb_wc_title][et_pb_wc_rating product=&#8221;10582&#8243; _builder_version=&#8221;4.0.6&#8243;][\/et_pb_wc_rating][et_pb_wc_description product=&#8221;10582&#8243; _builder_version=&#8221;4.0.6&#8243;][\/et_pb_wc_description][et_pb_wc_price product=&#8221;10582&#8243; _builder_version=&#8221;4.0.6&#8243;][\/et_pb_wc_price][et_pb_wc_add_to_cart product=&#8221;10582&#8243; _builder_version=&#8221;4.0.6&#8243;][\/et_pb_wc_add_to_cart][et_pb_text _builder_version=&#8221;4.0.6&#8243; text_font=&#8221;Delius Unicase||||||||&#8221;]<p style=\"text-align: justify;\"><span style=\"color: #ff0000;\"><strong>IN OMAGGIO<\/strong><\/span>, solo per chi compra il mio libro su Perlage Suite, una copia della <strong>Prima Edizione da Collezione della mia Guida Vini Spumanti &#8220;500 Bolle in 500&#8221;<\/strong>, prezzo di copertina 25,30 \u20ac.<\/p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;Umbria \u00e8 una regione dell&#8217;Italia Centrale che spesso non ha l&#8217;importanza che merita nel panorama enologico italiano. I vini umbri sono stati per me una piacevole scoperta per cui ringrazio l&#8217;amico e collega Federico Scarponi, miglior sommelier dell&#8217;Umbria 2011 per avermi fatto fare una interessantissima panoramica. Federico ha aperto il piccolo wine shop online 3T [&hellip;]<\/p>\n","protected":false},"author":49,"featured_media":27090,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"2880","footnotes":""},"categories":[328],"tags":[],"class_list":["post-27071","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-diventare-sommelier"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.0 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Vini umbri: territorio, vitigni, vini e gastronomia | Perlage Suite<\/title>\n<meta name=\"description\" content=\"I vini umbri sono un&#039;eccellenza del vino italiano e oggi ti parler\u00f2 di clima, terreni, vitigni idonei, zone vitivinicole e piatti tipici.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/perlagesuite.com\/en\/vini-umbri\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vini umbri: territorio, vitigni, vini e gastronomia\" \/>\n<meta property=\"og:description\" content=\"I vini umbri sono un&#039;eccellenza del vino italiano e oggi ti parler\u00f2 di clima, terreni, vitigni idonei, zone vitivinicole e piatti tipici.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/perlagesuite.com\/en\/vini-umbri\/\" \/>\n<meta property=\"og:site_name\" content=\"Perlage Suite\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/chiarabassiperlagesuite\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-02T17:32:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-04T15:39:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/perlagesuite.com\/wp-content\/uploads\/2020\/12\/vini-umbri-abbinamento-tagliata-petto-anatra.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Chiara Bassi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@perlagesuite\" \/>\n<meta name=\"twitter:site\" content=\"@perlagesuite\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Chiara Bassi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/vini-umbri\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/vini-umbri\\\/\"},\"author\":{\"name\":\"Chiara Bassi\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/person\\\/81b257517a1007c1a823318ac86c6013\"},\"headline\":\"Vini umbri: territorio, vitigni, vini e gastronomia\",\"datePublished\":\"2020-12-02T17:32:21+00:00\",\"dateModified\":\"2022-10-04T15:39:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/vini-umbri\\\/\"},\"wordCount\":1943,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/vini-umbri\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/vini-umbri-abbinamento-tagliata-petto-anatra.jpg\",\"articleSection\":[\"Didattica Sommelier\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/perlagesuite.com\\\/vini-umbri\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/vini-umbri\\\/\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/vini-umbri\\\/\",\"name\":\"Vini umbri: territorio, vitigni, vini e gastronomia | Perlage Suite\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/vini-umbri\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/vini-umbri\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/vini-umbri-abbinamento-tagliata-petto-anatra.jpg\",\"datePublished\":\"2020-12-02T17:32:21+00:00\",\"dateModified\":\"2022-10-04T15:39:48+00:00\",\"description\":\"I vini umbri sono un'eccellenza del vino italiano e oggi ti parler\u00f2 di clima, terreni, vitigni idonei, zone vitivinicole e piatti tipici.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/vini-umbri\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/perlagesuite.com\\\/vini-umbri\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/vini-umbri\\\/#primaryimage\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/vini-umbri-abbinamento-tagliata-petto-anatra.jpg\",\"contentUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/vini-umbri-abbinamento-tagliata-petto-anatra.jpg\",\"width\":1080,\"height\":720,\"caption\":\"vini umbri tagliata petto anatra\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/vini-umbri\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/perlagesuite.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vini umbri: territorio, vitigni, vini e gastronomia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#website\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/\",\"name\":\"Perlage Suite\",\"description\":\"Il Wine Blog di Chiara Bassi\",\"publisher\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/perlagesuite.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#organization\",\"name\":\"Chiara Bassi\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Chiara-Bassi-sommelier-wine-blogger-logo.png\",\"contentUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Chiara-Bassi-sommelier-wine-blogger-logo.png\",\"width\":512,\"height\":512,\"caption\":\"Chiara Bassi\"},\"image\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/chiarabassiperlagesuite\",\"https:\\\/\\\/x.com\\\/perlagesuite\",\"https:\\\/\\\/www.instagram.com\\\/perlagesuite\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/person\\\/81b257517a1007c1a823318ac86c6013\",\"name\":\"Chiara Bassi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g\",\"caption\":\"Chiara Bassi\"},\"sameAs\":[\"https:\\\/\\\/perlagesuite.com\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Umbrian wines: territory, grape varieties, wines and gastronomy | Perlage Suite","description":"Umbrian wines are an excellence of Italian wine and today I will tell you about climate, soils, suitable grape varieties, wine-growing areas and typical dishes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/perlagesuite.com\/en\/vini-umbri\/","og_locale":"en_GB","og_type":"article","og_title":"Vini umbri: territorio, vitigni, vini e gastronomia","og_description":"I vini umbri sono un'eccellenza del vino italiano e oggi ti parler\u00f2 di clima, terreni, vitigni idonei, zone vitivinicole e piatti tipici.","og_url":"https:\/\/perlagesuite.com\/en\/vini-umbri\/","og_site_name":"Perlage Suite","article_publisher":"https:\/\/www.facebook.com\/chiarabassiperlagesuite","article_published_time":"2020-12-02T17:32:21+00:00","article_modified_time":"2022-10-04T15:39:48+00:00","og_image":[{"width":1080,"height":720,"url":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2020\/12\/vini-umbri-abbinamento-tagliata-petto-anatra.jpg","type":"image\/jpeg"}],"author":"Chiara Bassi","twitter_card":"summary_large_image","twitter_creator":"@perlagesuite","twitter_site":"@perlagesuite","twitter_misc":{"Written by":"Chiara Bassi","Estimated reading time":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/perlagesuite.com\/vini-umbri\/#article","isPartOf":{"@id":"https:\/\/perlagesuite.com\/vini-umbri\/"},"author":{"name":"Chiara Bassi","@id":"https:\/\/perlagesuite.com\/#\/schema\/person\/81b257517a1007c1a823318ac86c6013"},"headline":"Vini umbri: territorio, vitigni, vini e gastronomia","datePublished":"2020-12-02T17:32:21+00:00","dateModified":"2022-10-04T15:39:48+00:00","mainEntityOfPage":{"@id":"https:\/\/perlagesuite.com\/vini-umbri\/"},"wordCount":1943,"commentCount":0,"publisher":{"@id":"https:\/\/perlagesuite.com\/#organization"},"image":{"@id":"https:\/\/perlagesuite.com\/vini-umbri\/#primaryimage"},"thumbnailUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2020\/12\/vini-umbri-abbinamento-tagliata-petto-anatra.jpg","articleSection":["Didattica Sommelier"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/perlagesuite.com\/vini-umbri\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/perlagesuite.com\/vini-umbri\/","url":"https:\/\/perlagesuite.com\/vini-umbri\/","name":"Umbrian wines: territory, grape varieties, wines and gastronomy | Perlage Suite","isPartOf":{"@id":"https:\/\/perlagesuite.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/perlagesuite.com\/vini-umbri\/#primaryimage"},"image":{"@id":"https:\/\/perlagesuite.com\/vini-umbri\/#primaryimage"},"thumbnailUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2020\/12\/vini-umbri-abbinamento-tagliata-petto-anatra.jpg","datePublished":"2020-12-02T17:32:21+00:00","dateModified":"2022-10-04T15:39:48+00:00","description":"Umbrian wines are an excellence of Italian wine and today I will tell you about climate, soils, suitable grape varieties, wine-growing areas and typical dishes.","breadcrumb":{"@id":"https:\/\/perlagesuite.com\/vini-umbri\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/perlagesuite.com\/vini-umbri\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/perlagesuite.com\/vini-umbri\/#primaryimage","url":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2020\/12\/vini-umbri-abbinamento-tagliata-petto-anatra.jpg","contentUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2020\/12\/vini-umbri-abbinamento-tagliata-petto-anatra.jpg","width":1080,"height":720,"caption":"vini umbri tagliata petto anatra"},{"@type":"BreadcrumbList","@id":"https:\/\/perlagesuite.com\/vini-umbri\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/perlagesuite.com\/"},{"@type":"ListItem","position":2,"name":"Vini umbri: territorio, vitigni, vini e gastronomia"}]},{"@type":"WebSite","@id":"https:\/\/perlagesuite.com\/#website","url":"https:\/\/perlagesuite.com\/","name":"Perlage Suite","description":"Chiara Bassi's Wine Blog","publisher":{"@id":"https:\/\/perlagesuite.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/perlagesuite.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/perlagesuite.com\/#organization","name":"Chiara Bassi","url":"https:\/\/perlagesuite.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/perlagesuite.com\/#\/schema\/logo\/image\/","url":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2022\/03\/Chiara-Bassi-sommelier-wine-blogger-logo.png","contentUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2022\/03\/Chiara-Bassi-sommelier-wine-blogger-logo.png","width":512,"height":512,"caption":"Chiara Bassi"},"image":{"@id":"https:\/\/perlagesuite.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/chiarabassiperlagesuite","https:\/\/x.com\/perlagesuite","https:\/\/www.instagram.com\/perlagesuite\/"]},{"@type":"Person","@id":"https:\/\/perlagesuite.com\/#\/schema\/person\/81b257517a1007c1a823318ac86c6013","name":"Chiara Bassi","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g","caption":"Chiara Bassi"},"sameAs":["https:\/\/perlagesuite.com"]}]}},"_links":{"self":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/posts\/27071","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/comments?post=27071"}],"version-history":[{"count":0,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/posts\/27071\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/media\/27090"}],"wp:attachment":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/media?parent=27071"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/categories?post=27071"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/tags?post=27071"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}