{"id":27419,"date":"2021-01-01T19:54:59","date_gmt":"2021-01-01T18:54:59","guid":{"rendered":"https:\/\/perlagesuite.com\/?p=27419"},"modified":"2021-01-01T22:34:10","modified_gmt":"2021-01-01T21:34:10","slug":"oroscopo-2021-brindiamo-a-un-nuovo-anno-di-cambiamenti","status":"publish","type":"post","link":"https:\/\/perlagesuite.com\/en\/oroscopo-2021-brindiamo-a-un-nuovo-anno-di-cambiamenti\/","title":{"rendered":"Horoscope 2021: Here's to a new year of change for the sign of Taurus"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.7.7&#8243; _module_preset=&#8221;default&#8221;][et_pb_row _builder_version=&#8221;4.7.7&#8243; _module_preset=&#8221;default&#8221;][et_pb_column _builder_version=&#8221;4.7.7&#8243; _module_preset=&#8221;default&#8221; type=&#8221;4_4&#8243;][et_pb_text _builder_version=&#8221;4.7.7&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p style=\"text-align: justify;\"><strong>Cominciare un nuovo anno con un brindisi<\/strong> (anzi due) <strong>e una piccola riflessione che affonda le radici nel mio oroscopo 2021 per me \u00e8 ormai una tradizione<\/strong>. Trovo sia molto bello poi partire dall&#8217;anno precedente, guardando se le aspettative sono state allineate con i risultati. Nel mio articolo &#8220;<a href=\"https:\/\/perlagesuite.com\/oroscopo-2020\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"text-decoration: underline;\"><strong>Oroscopo 2020: cosa stappiamo per festeggiare l&#8217;anno della svolta?<\/strong><\/span><\/a>&#8221; scrivevo mentre degustavo il Radicale di Bellenda:<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">L&#8217;<strong>oroscopo 2020 toro<\/strong> dice che ho praticamente tutti i pianeti a favore e che questo indica un anno pieno di cambiamenti, capace di depennare tutta la lista dei miei propositi, a patto di non rimandare nulla. Dice che nel 2020 incontrer\u00f2 la persona giusta per me, e in effetti l&#8217;altro ieri ho &#8220;ufficializzato&#8221; la mia nuova relazione e pensato, per la prima volta nella mia vita, che ho un ragazzo a cui non cambierei nemmeno una virgola. L&#8217;oroscopo 2020 dice che devo fare progetti di coppia e di lavoro perch\u00e8 sar\u00e0 un anno rivoluzionario, <em>radicale<\/em>. Dice che devo volare in alto perch\u00e8 godr\u00f2 di tutto quello che serve per realizzare tutto quello che sogno e anche delle giuste occasioni. Cavolo, ma io ci voglio credere! Anzi, mi impegner\u00f2 al massimo perch\u00e8 sia cos\u00ec! A dicembre 2020 ricapitolando sar\u00f2 felicemente fidanzata, magra e pi\u00f9 famosa della Ferragni, perfetto! Ora mi stappo subito un buon vino per festeggiare!<span>\ud83d\ude0e \ud83d\ude0d<\/span><\/p>\n<p style=\"text-align: justify;\"><\/blockquote>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2020\/10\/chiara-bassi-francesco-saldi-matrimonio-monte-isola.jpg&#8221; _builder_version=&#8221;4.7.7&#8243; _module_preset=&#8221;default&#8221; box_shadow_style=&#8221;preset3&#8243; alt=&#8221;chiara bassi matrimonio&#8221; title_text=&#8221;chiara-bassi-francesco-saldi-matrimonio-monte-isola&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.7.7&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243; header_3_font=&#8221;Delius Unicase|700|||||||&#8221; header_3_font_size=&#8221;20px&#8221;]<\/p>\n<h3 style=\"text-align: justify;\">Oroscopo 2021: vediamo cosa \u00e8 successo effettivamente nel 2020&#8230;<\/h3>\n<h4 style=\"text-align: justify;\">Il 1 gennaio 2021 sono felicemente fidanzata?<\/h4>\n<p style=\"text-align: justify;\">Era il 5 gennaio 2020 quando ho scritto quelle parole e se mi avessero detto che quest&#8217;anno mi sarei sposata avrei riso per 10 minuti di fila. Nella mia aspettativa migliore c&#8217;era l&#8217;essere felicemente fidanzata, non certo un amore dirompente culminato in un matrimonio dopo 9 mesi (di cui quasi 8 di convivenza&#8230;)! Eppure \u00e8 successo. E anche chi si \u00e8 divertito a chiacchierare pensando che era un matrimonio riparatore \u00e8 stato smentito&#8230; dal momento che <strong>nella mia pancia attualmente c&#8217;\u00e8 solo la mia adorata boeuf bourguignon<\/strong>! Salvo davvero un cambiamento radicale in cui io onestamente non credo affatto non ho mai voluto figli e mai ne vorr\u00f2 &#8211; e mio marito lo sa bene &#8211; quindi il nostro \u00e8 stato davvero un matrimonio d&#8217;amore! Francesco \u00e8 la mia anima gemella e lo penso sempre, anche quando la boeuf bourguignon gliela rovescerei in testa!\u00a0<span>\ud83e\udd23<\/span><\/p>\n<h4>Il 1 gennaio 2021 sono magra?<\/h4>\n<p style=\"text-align: justify;\">Ehm&#8230; no! In effetti ho perso 8 kg per il matrimonio, ma sono ancora lontana dal mio peso forma. A mia discolpa ricordo che vivo in Lombardia e la quarantena non ha certo aiutato! Il mio buon proposito per il 2021 sar\u00e0 raggiungere i 65 kg entro il 31 dicembre e sappiate che per capodanno pubblicher\u00f2 una foto con i miei piedi sulla bilancia quindi&#8230; dalle 8 di stasera comincio l&#8217;unica dieta che fa per me: il digiuno intermittente. Fino ad ora \u00e8 l&#8217;unico regime alimentare che \u00e8 compatibile con il mio carattere e il mio lavoro&#8230; e l&#8217;unico che mi abbia mai dato risultati! Dice che in 32 settimane sar\u00f2 65 kg&#8230; io mi d\u00f2 20 settimane in pi\u00f9 per sicurezza quindi vi mostrer\u00f2 i risultati il prossimo capodanno!\u00a0<span>\ud83e\udd23<\/span><\/p>\n<h4 style=\"text-align: justify;\"><span>Il 1 gennaio 2021 sono pi\u00f9 famosa della Ferragni?<\/span><\/h4>\n<p style=\"text-align: justify;\">Ehm&#8230; quasi dai! <span>\ud83e\udd23<\/span>\u00a0Del resto non so se le stelle avevano previsto la pandemia! Per\u00f2 il 2020 \u00e8 stato comunque un anno lavorativo importante perch\u00e8 <strong>ho preso decisioni pazzesche sia per il mio blog, sia per la terza (e ultima) edizione del mio libro &#8220;Come diventare Sommelier&#8221; che pubblicher\u00f2 l&#8217;8 maggio 2021<\/strong> in occasione del mio compleanno! E comunque il mio wine blog \u00e8 cresciuto tantissimo quest&#8217;anno nonostante il disastro in cui verte il settore ristorativo quindi <strong>il bilancio \u00e8 comunque positivo<\/strong>! Segno che l&#8217;interesse per il vino non cala&#8230; anzi cresce! <strong>E crescono gli acquisti negli e-commerce quindi questo \u00e8 il momento di investire in un piccolo grande shop online<\/strong>. A questo proposto ti ricordo che sono anche una sviluppatrice web, quindi puoi\u00a0<a href=\"mailto:info@perlagesuite.com\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"text-decoration: underline;\"><strong>inviarmi una e-mail<\/strong><\/span><\/a> per costruire insieme una bellissima vetrina per i tuoi prodotti enogastronomici capace di vendere ovunque 24 ore su 24 e 7 giorni su 7, anche mentre la tua cantina, i negozi o i ristoranti sono chiusi!<\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/01\/chiara-bassi-francesco-saldi-paco.jpg&#8221; _builder_version=&#8221;4.7.7&#8243; _module_preset=&#8221;default&#8221; box_shadow_style=&#8221;preset3&#8243; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243; alt=&#8221;oroscopo 2021 chiara bassi francesco saldi paco&#8221; title_text=&#8221;chiara-bassi-francesco-saldi-paco&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.7.7&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h4 style=\"text-align: justify;\">Cosa dice l&#8217;oroscopo 2021 per i nati sotto il segno del toro?<\/h4>\n<p style=\"text-align: justify;\"><strong>L&#8217;oroscopo 2021 del toro dice che non sar\u00e0 un anno molto fortunato. Io per\u00f2 nella fortuna non ho mai creduto. Credo nei sogni che diventano idee e nelle idee che diventano azioni. E credo che le azioni unite alla capacit\u00e0 di correggere il tiro quando serve siano la chiave di qualsiasi successo desideri.<\/strong><\/p>\n<p style=\"text-align: justify;\">L&#8217;oroscopo 2021 dice che noi del toro quest&#8217;anno vivremo sulle montagne russe, tra picchi di felicit\u00e0, ostacoli, imprevisti e fallimenti. E un bel &#8220;sti tappi&#8221; non ce lo mettiamo? La vita \u00e8 questa, un meraviglioso alternarsi di gioie e dolori. <strong>La vera fortuna \u00e8 che il copione della nostra vita lo scriviamo noi.<\/strong><\/p>\n<p style=\"text-align: justify;\">Personalmente il 2020 si \u00e8 chiuso nel migliore dei modi: ho cucinato per la prima volta a mio marito Francesco uno dei miei cavalli di battaglia: la <a href=\"https:\/\/perlagesuite.com\/ricetta-boeuf-bourguignon-julia-child\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"text-decoration: underline;\"><strong>boeuf bourguignon di Julia Child (clicca QUI per la foto-ricetta originale)<\/strong><\/span><\/a> e <strong>ci ho abbinato il Vino Nobile di Montepulciano di Podere Casanova<\/strong> (di cui avevo gi\u00e0 scritto <a href=\"https:\/\/perlagesuite.com\/podere-casanova-montepulciano\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"text-decoration: underline;\"><strong>QUI<\/strong><\/span><\/a>). L&#8217;anno non \u00e8 terminato come pensavo: avevo previsto di guardare i fuochi d&#8217;artificio sul lago a mezzanotte dal nostro terrazzo della camera da letto e poi fare l&#8217;amore sorseggiando<strong> il .G di Le Vigne di Alice, Conegliano Valdobbiadene Prosecco Superiore 2015 sboccatura 2018<\/strong>\u00a0(ogni riferimento a fatti che sarebbero potuti accadere \u00e8 puramente casuale) invece alle 23 mio marito era stecchito sul divano. La boeuf bourguignon l&#8217;ha steso.\u00a0<span>\ud83d\ude05<\/span><\/p>\n<p style=\"text-align: justify;\">\n[\/et_pb_text][et_pb_signup provider=&#8221;mailpoet&#8221; mailpoet_list=&#8221;PEPEblu|49&#8243; success_message=&#8221;Controlla la tua e-mail: hai appena ricevuto un mio messaggio per confermare la tua iscrizione! Se non lo visualizzi controlla in spam o nella cartella %22promozioni%22 di Gmail. Grazie e a presto!&#8221; title=&#8221;Ti piace questo contenuto?&#8221; button_text=&#8221;Iscriviti subito!&#8221; description=&#8221;<\/p>\n<p style=%22text-align: justify;%22>Iscriviti alla mia newsletter per non perderti nessun nuovo articolo del mio blog!<\/p>\n<p style=%22text-align: justify;%22>Non ti invier\u00f2 SPAM, ma solo la notifica dei nuovi articoli! Di tanto in tanto potrai ricevere anche qualche coupon per acquistare vino o partecipare ad eventi con condizioni speciali riservate ai lettori del mio blog!<\/p>\n<p style=%22text-align: justify;%22>Cheers \ud83e\udd29\ud83e\udd42<\/p>\n<p>&#8221; footer_content=&#8221;Iscrivendoti accetti le condizioni della <a href=%22https:\/\/perlagesuite.com\/privacy-2\/%22 data-et-target-link=%22_blank%22 rel=%22noopener noreferrer%22><span style=%22text-decoration: underline;%22><strong>Privacy<\/strong><\/span><\/a> di Perlage Suite.&#8221; _builder_version=&#8221;4.7.7&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Delius Unicase|700|||||||&#8221; header_font_size=&#8221;22px&#8221; body_font=&#8221;Delius||||||||&#8221; background_color=&#8221;#008c96&#8243; box_shadow_style=&#8221;preset3&#8243; box_shadow_color=&#8221;rgba(0,140,150,0.6)&#8221; global_module=&#8221;27234&#8243;][\/et_pb_signup][et_pb_text _builder_version=&#8221;4.7.7&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243; header_3_font=&#8221;Delius Unicase|700|||||||&#8221; header_3_font_size=&#8221;20px&#8221;]<\/p>\n<h3 style=\"text-align: justify;\">Due brindisi che vi consiglio assolutamente di fare&#8230;<\/h3>\n<h4 style=\"text-align: justify;\">Vino Nobile di Montepulciano DOCG 2016 Podere Casanova<\/h4>\n<p style=\"text-align: justify;\">Si presenta di un bel rosso rubino intenso e impenetrabile, consistente. Al naso \u00e8 elegante e fine, con note di pepe nero, mandorla, scorza d&#8217;arancia, legno, stecche di cannella e pino mugo. In bocca \u00e8 piacevolissimo, elegantissimo, morbidissimo, con una buona struttura e un tannino ben amalgamato. In bocca ha un lungo finale speziato. Un Vino Nobile di Montepulciano straordinario, esattamente nelle mie corde.<\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/01\/oroscopo-2021-vino-nobile-di-montepulciano-podere-casanova.jpg&#8221; _builder_version=&#8221;4.7.7&#8243; _module_preset=&#8221;default&#8221; box_shadow_style=&#8221;preset3&#8243; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243; alt=&#8221;oroscopo 2021 vino nobile di montepulciano&#8221; title_text=&#8221;oroscopo-2021-vino-nobile-di-montepulciano-podere-casanova&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.7.7&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243; header_3_font=&#8221;Delius Unicase|700|||||||&#8221; header_3_font_size=&#8221;20px&#8221;]<\/p>\n<h4 style=\"text-align: justify;\">.G Valdobbiadene Prosecco Superiore DOCG 2015 Le Vigne di Alice<\/h4>\n<p style=\"text-align: justify;\">Ho parlato cos\u00ec tante volte di questo vino da risultare quasi noiosa. L&#8217;annata 2010 l&#8217;ho scelto prima <a href=\"https:\/\/perlagesuite.com\/matrimonio-a-tema-vino-i-6-vini-che-ho-scelto\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"text-decoration: underline;\"><strong>per il nostro matrimonio<\/strong><\/span><\/a>, poi per una <a href=\"https:\/\/perlagesuite.com\/sassi-di-matera-storia-cosa-vedere\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"text-decoration: underline;\"><strong>serata romantica nella vasca da bagno durante la nostra luna di miele a Matera<\/strong><\/span><\/a>. Trovo il .G un vero capolavoro, la dimostrazione vivente che il prosecco vinificato metodo classico ha potenzialit\u00e0 insospettabili.<\/p>\n<p style=\"text-align: justify;\">Giallo paglierino brillante con riflessi oro verde. Il perlage \u00e8 fine, numeroso e persistente. Al naso \u00e8 piacevolissimo, con note di pera matura, marmellata di limone, mandorla fresca, aneto e cumino. In bocca \u00e8 coerente, freschissimo, sapido con un sapore ancora pi\u00f9 agrumato, salino e di erbe aromatiche. Finale lungo e grande bevibilit\u00e0.<\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/01\/le-vigne-di-alice-prosecco-superiore-metodo-classico.jpg&#8221; _builder_version=&#8221;4.7.7&#8243; _module_preset=&#8221;default&#8221; alt=&#8221;le vigne di alice prosecco superiore oroscopo 2021&#8243; title_text=&#8221;le-vigne-di-alice-prosecco-superiore-metodo-classico&#8221; box_shadow_style=&#8221;preset3&#8243; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.7.7&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h4 style=\"text-align: justify;\">E il 1 gennaio 2021?<\/h4>\n<p style=\"text-align: justify;\">Per noi \u00e8 cominciato ancora meglio perch\u00e8 Francesco mi ha dato una grande idea: riciclare gli avanzi della Boeuf Bourguignon di ieri sera per preparare una pasta per il pranzo. Cavolo, perch\u00e8 non ci ho pensato prima? L&#8217;ho aggiunto alla <a href=\"https:\/\/perlagesuite.com\/ricetta-boeuf-bourguignon-julia-child\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"text-decoration: underline;\"><strong>ricetta originale di Julia Child<\/strong><\/span><\/a> perch\u00e8 il risultato \u00e8 davvero fantastico! Per prepare i miei &#8220;<strong>paccheri alla Bourguignon<\/strong>&#8221; basta sciogliere in una padella una noce di burro e aggiungere gli avanzi a temperatura ambiente (ne bastano 2 o 3 pezzettoni). Mentre l&#8217;acqua salata per la pasta bolle, con una forchetta o con un pestello, \u00a0schiacciate i pezzi di carne che sono cos\u00ec teneri da sfilacciarsi. Cuocete i paccheri e teneteli al dente, nel frattempo aggiungete 1 mestolo scarso di acqua di cottura al sugo. Scolate i paccheri e aggiungeteli nella padella col sugo, mettete una noce di burro e mescolate accuratamente. Spegnete il fuoco appena \u00e8 tutto ben amalgamato. <strong>In abbinamento ovviamente vi consiglio il Vino Nobile di Montepulciano 2016 di Podere Casanova<\/strong>!<\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/01\/boeuf-bourguignon-pasta-riciclo-avanzi-ricetta.jpg&#8221; _builder_version=&#8221;4.7.7&#8243; _module_preset=&#8221;default&#8221; box_shadow_style=&#8221;preset3&#8243; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243; alt=&#8221;oroscopo 2021 boeuf bourguignon ricetta avanzi&#8221; title_text=&#8221;boeuf-bourguignon-pasta-riciclo-avanzi-ricetta&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.7.7&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p style=\"text-align: justify;\"><strong>Non vedo l&#8217;ora di andarli a trovare personalmente con mio marito e la mia testimone di nozze, Marina Tagliaferri dell&#8217;agenzia stampa Agor\u00e0.<\/strong><\/p>\n<p style=\"text-align: justify;\">Ti auguro un anno pieno di felicit\u00e0, successi e grandi bottiglie stappate!<\/p>\n<p style=\"text-align: justify;\">Cheers\u00a0<span>\ud83c\udf77<\/span><\/p>\n<p style=\"text-align: justify;\">Chiara<\/p>\n<p>[\/et_pb_text][et_pb_divider _builder_version=&#8221;4.7.7&#8243; _module_preset=&#8221;default&#8221; color=&#8221;#da413d&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.0.6&#8243; global_module=&#8221;21425&#8243;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.0.6&#8243;][et_pb_wc_images product=&#8221;10582&#8243; _builder_version=&#8221;4.0.6&#8243;][\/et_pb_wc_images][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.0.6&#8243;][et_pb_wc_title product=&#8221;10582&#8243; _builder_version=&#8221;4.0.6&#8243;][\/et_pb_wc_title][et_pb_wc_rating product=&#8221;10582&#8243; _builder_version=&#8221;4.0.6&#8243;][\/et_pb_wc_rating][et_pb_wc_description product=&#8221;10582&#8243; _builder_version=&#8221;4.0.6&#8243;][\/et_pb_wc_description][et_pb_wc_price product=&#8221;10582&#8243; _builder_version=&#8221;4.0.6&#8243;][\/et_pb_wc_price][et_pb_wc_add_to_cart product=&#8221;10582&#8243; _builder_version=&#8221;4.0.6&#8243;][\/et_pb_wc_add_to_cart][et_pb_text _builder_version=&#8221;4.0.6&#8243; text_font=&#8221;Delius Unicase||||||||&#8221;]<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ff0000;\"><strong>IN OMAGGIO<\/strong><\/span>, solo per chi compra il mio libro su Perlage Suite, una copia della <strong>Prima Edizione da Collezione della mia Guida Vini Spumanti &#8220;500 Bolle in 500&#8221;<\/strong>, prezzo di copertina 25,30 \u20ac.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cominciare un nuovo anno con un brindisi (anzi due) e una piccola riflessione che affonda le radici nel mio oroscopo 2021 per me \u00e8 ormai una tradizione. Trovo sia molto bello poi partire dall&#8217;anno precedente, guardando se le aspettative sono state allineate con i risultati. Nel mio articolo &#8220;Oroscopo 2020: cosa stappiamo per festeggiare l&#8217;anno [&hellip;]<\/p>\n","protected":false},"author":49,"featured_media":27458,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"2880","footnotes":""},"categories":[428],"tags":[],"class_list":["post-27419","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-champagne-vini-spumanti"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.0 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Oroscopo 2021: brindiamo a un nuovo anno di cambiamenti - Perlage Suite<\/title>\n<meta name=\"description\" content=\"Cosa dice l&#039;oroscopo 2021? Come sapete non ci credo, ma come ogni anno brindo con voi scegliendo un vino (anzi due) e facendo una riflessione.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/perlagesuite.com\/en\/oroscopo-2021-brindiamo-a-un-nuovo-anno-di-cambiamenti\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Oroscopo 2021: brindiamo a un nuovo anno di cambiamenti per il segno del toro\" \/>\n<meta property=\"og:description\" content=\"Cosa dice l&#039;oroscopo 2021? Come sapete non ci credo, ma come ogni anno brindo con voi scegliendo un vino (anzi due) e facendo una riflessione.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/perlagesuite.com\/en\/oroscopo-2021-brindiamo-a-un-nuovo-anno-di-cambiamenti\/\" \/>\n<meta property=\"og:site_name\" content=\"Perlage Suite\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/chiarabassiperlagesuite\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-01T18:54:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-01T21:34:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/01\/oroscopo-2021-boeuf-bourguignon-ricetta-podere-casanova.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Chiara Bassi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@perlagesuite\" \/>\n<meta name=\"twitter:site\" content=\"@perlagesuite\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Chiara Bassi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/oroscopo-2021-brindiamo-a-un-nuovo-anno-di-cambiamenti\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/oroscopo-2021-brindiamo-a-un-nuovo-anno-di-cambiamenti\\\/\"},\"author\":{\"name\":\"Chiara Bassi\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/person\\\/81b257517a1007c1a823318ac86c6013\"},\"headline\":\"Oroscopo 2021: brindiamo a un nuovo anno di cambiamenti per il segno del toro\",\"datePublished\":\"2021-01-01T18:54:59+00:00\",\"dateModified\":\"2021-01-01T21:34:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/oroscopo-2021-brindiamo-a-un-nuovo-anno-di-cambiamenti\\\/\"},\"wordCount\":1952,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/oroscopo-2021-brindiamo-a-un-nuovo-anno-di-cambiamenti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/oroscopo-2021-boeuf-bourguignon-ricetta-podere-casanova.jpg\",\"articleSection\":[\"Champagne &amp; Spumanti\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/perlagesuite.com\\\/oroscopo-2021-brindiamo-a-un-nuovo-anno-di-cambiamenti\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/oroscopo-2021-brindiamo-a-un-nuovo-anno-di-cambiamenti\\\/\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/oroscopo-2021-brindiamo-a-un-nuovo-anno-di-cambiamenti\\\/\",\"name\":\"Oroscopo 2021: brindiamo a un nuovo anno di cambiamenti - Perlage Suite\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/oroscopo-2021-brindiamo-a-un-nuovo-anno-di-cambiamenti\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/oroscopo-2021-brindiamo-a-un-nuovo-anno-di-cambiamenti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/oroscopo-2021-boeuf-bourguignon-ricetta-podere-casanova.jpg\",\"datePublished\":\"2021-01-01T18:54:59+00:00\",\"dateModified\":\"2021-01-01T21:34:10+00:00\",\"description\":\"Cosa dice l'oroscopo 2021? Come sapete non ci credo, ma come ogni anno brindo con voi scegliendo un vino (anzi due) e facendo una riflessione.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/oroscopo-2021-brindiamo-a-un-nuovo-anno-di-cambiamenti\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/perlagesuite.com\\\/oroscopo-2021-brindiamo-a-un-nuovo-anno-di-cambiamenti\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/oroscopo-2021-brindiamo-a-un-nuovo-anno-di-cambiamenti\\\/#primaryimage\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/oroscopo-2021-boeuf-bourguignon-ricetta-podere-casanova.jpg\",\"contentUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/oroscopo-2021-boeuf-bourguignon-ricetta-podere-casanova.jpg\",\"width\":1080,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/oroscopo-2021-brindiamo-a-un-nuovo-anno-di-cambiamenti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/perlagesuite.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Oroscopo 2021: brindiamo a un nuovo anno di cambiamenti per il segno del toro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#website\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/\",\"name\":\"Perlage Suite\",\"description\":\"Il Wine Blog di Chiara Bassi\",\"publisher\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/perlagesuite.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#organization\",\"name\":\"Chiara Bassi\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Chiara-Bassi-sommelier-wine-blogger-logo.png\",\"contentUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Chiara-Bassi-sommelier-wine-blogger-logo.png\",\"width\":512,\"height\":512,\"caption\":\"Chiara Bassi\"},\"image\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/chiarabassiperlagesuite\",\"https:\\\/\\\/x.com\\\/perlagesuite\",\"https:\\\/\\\/www.instagram.com\\\/perlagesuite\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/person\\\/81b257517a1007c1a823318ac86c6013\",\"name\":\"Chiara Bassi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g\",\"caption\":\"Chiara Bassi\"},\"sameAs\":[\"https:\\\/\\\/perlagesuite.com\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Horoscope 2021: Here's to a new year of change - Perlage Suite","description":"What does horoscope 2021 say? As you know I don't believe in it, but like every year I toast with you by choosing a wine (actually two) and making a reflection.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/perlagesuite.com\/en\/oroscopo-2021-brindiamo-a-un-nuovo-anno-di-cambiamenti\/","og_locale":"en_GB","og_type":"article","og_title":"Oroscopo 2021: brindiamo a un nuovo anno di cambiamenti per il segno del toro","og_description":"Cosa dice l'oroscopo 2021? Come sapete non ci credo, ma come ogni anno brindo con voi scegliendo un vino (anzi due) e facendo una riflessione.","og_url":"https:\/\/perlagesuite.com\/en\/oroscopo-2021-brindiamo-a-un-nuovo-anno-di-cambiamenti\/","og_site_name":"Perlage Suite","article_publisher":"https:\/\/www.facebook.com\/chiarabassiperlagesuite","article_published_time":"2021-01-01T18:54:59+00:00","article_modified_time":"2021-01-01T21:34:10+00:00","og_image":[{"width":1080,"height":720,"url":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/01\/oroscopo-2021-boeuf-bourguignon-ricetta-podere-casanova.jpg","type":"image\/jpeg"}],"author":"Chiara Bassi","twitter_card":"summary_large_image","twitter_creator":"@perlagesuite","twitter_site":"@perlagesuite","twitter_misc":{"Written by":"Chiara Bassi","Estimated reading time":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/perlagesuite.com\/oroscopo-2021-brindiamo-a-un-nuovo-anno-di-cambiamenti\/#article","isPartOf":{"@id":"https:\/\/perlagesuite.com\/oroscopo-2021-brindiamo-a-un-nuovo-anno-di-cambiamenti\/"},"author":{"name":"Chiara Bassi","@id":"https:\/\/perlagesuite.com\/#\/schema\/person\/81b257517a1007c1a823318ac86c6013"},"headline":"Oroscopo 2021: brindiamo a un nuovo anno di cambiamenti per il segno del toro","datePublished":"2021-01-01T18:54:59+00:00","dateModified":"2021-01-01T21:34:10+00:00","mainEntityOfPage":{"@id":"https:\/\/perlagesuite.com\/oroscopo-2021-brindiamo-a-un-nuovo-anno-di-cambiamenti\/"},"wordCount":1952,"commentCount":0,"publisher":{"@id":"https:\/\/perlagesuite.com\/#organization"},"image":{"@id":"https:\/\/perlagesuite.com\/oroscopo-2021-brindiamo-a-un-nuovo-anno-di-cambiamenti\/#primaryimage"},"thumbnailUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/01\/oroscopo-2021-boeuf-bourguignon-ricetta-podere-casanova.jpg","articleSection":["Champagne &amp; Spumanti"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/perlagesuite.com\/oroscopo-2021-brindiamo-a-un-nuovo-anno-di-cambiamenti\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/perlagesuite.com\/oroscopo-2021-brindiamo-a-un-nuovo-anno-di-cambiamenti\/","url":"https:\/\/perlagesuite.com\/oroscopo-2021-brindiamo-a-un-nuovo-anno-di-cambiamenti\/","name":"Horoscope 2021: Here's to a new year of change - Perlage Suite","isPartOf":{"@id":"https:\/\/perlagesuite.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/perlagesuite.com\/oroscopo-2021-brindiamo-a-un-nuovo-anno-di-cambiamenti\/#primaryimage"},"image":{"@id":"https:\/\/perlagesuite.com\/oroscopo-2021-brindiamo-a-un-nuovo-anno-di-cambiamenti\/#primaryimage"},"thumbnailUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/01\/oroscopo-2021-boeuf-bourguignon-ricetta-podere-casanova.jpg","datePublished":"2021-01-01T18:54:59+00:00","dateModified":"2021-01-01T21:34:10+00:00","description":"What does horoscope 2021 say? As you know I don't believe in it, but like every year I toast with you by choosing a wine (actually two) and making a reflection.","breadcrumb":{"@id":"https:\/\/perlagesuite.com\/oroscopo-2021-brindiamo-a-un-nuovo-anno-di-cambiamenti\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/perlagesuite.com\/oroscopo-2021-brindiamo-a-un-nuovo-anno-di-cambiamenti\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/perlagesuite.com\/oroscopo-2021-brindiamo-a-un-nuovo-anno-di-cambiamenti\/#primaryimage","url":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/01\/oroscopo-2021-boeuf-bourguignon-ricetta-podere-casanova.jpg","contentUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/01\/oroscopo-2021-boeuf-bourguignon-ricetta-podere-casanova.jpg","width":1080,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/perlagesuite.com\/oroscopo-2021-brindiamo-a-un-nuovo-anno-di-cambiamenti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/perlagesuite.com\/"},{"@type":"ListItem","position":2,"name":"Oroscopo 2021: brindiamo a un nuovo anno di cambiamenti per il segno del toro"}]},{"@type":"WebSite","@id":"https:\/\/perlagesuite.com\/#website","url":"https:\/\/perlagesuite.com\/","name":"Perlage Suite","description":"Chiara Bassi's Wine Blog","publisher":{"@id":"https:\/\/perlagesuite.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/perlagesuite.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/perlagesuite.com\/#organization","name":"Chiara Bassi","url":"https:\/\/perlagesuite.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/perlagesuite.com\/#\/schema\/logo\/image\/","url":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2022\/03\/Chiara-Bassi-sommelier-wine-blogger-logo.png","contentUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2022\/03\/Chiara-Bassi-sommelier-wine-blogger-logo.png","width":512,"height":512,"caption":"Chiara Bassi"},"image":{"@id":"https:\/\/perlagesuite.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/chiarabassiperlagesuite","https:\/\/x.com\/perlagesuite","https:\/\/www.instagram.com\/perlagesuite\/"]},{"@type":"Person","@id":"https:\/\/perlagesuite.com\/#\/schema\/person\/81b257517a1007c1a823318ac86c6013","name":"Chiara Bassi","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g","caption":"Chiara Bassi"},"sameAs":["https:\/\/perlagesuite.com"]}]}},"_links":{"self":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/posts\/27419","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/comments?post=27419"}],"version-history":[{"count":0,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/posts\/27419\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/media\/27458"}],"wp:attachment":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/media?parent=27419"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/categories?post=27419"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/tags?post=27419"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}