{"id":28180,"date":"2021-02-26T15:29:32","date_gmt":"2021-02-26T14:29:32","guid":{"rendered":"https:\/\/perlagesuite.com\/?p=28180"},"modified":"2021-03-05T18:25:34","modified_gmt":"2021-03-05T17:25:34","slug":"timorasso-derthona-vitigno-vino","status":"publish","type":"post","link":"https:\/\/perlagesuite.com\/en\/timorasso-derthona-vitigno-vino\/","title":{"rendered":"Timorasso: from vine to wine, tasting Derthona"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221;][et_pb_row _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221;][et_pb_text _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221;]<\/p>\n<p style=\"text-align: justify;\">Per capire un vino fino in fondo \u00e8 necessario, come prima cosa, conoscere il vitigno con cui viene elaborato. Per questo quando <strong>Federica di Aroma Wine Bar, l&#8217;Enoteca di Tortona<\/strong> specializzata nel<strong>\u00a0Derthona Timorasso<span style=\"text-decoration: underline;\"><\/span><a href=\"https:\/\/www.aromawinebar.it\/derthona-timorasso\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"text-decoration: underline;\"><\/span><\/a><\/strong>, mi ha proposto di parlare di questo vino ho accettato con grande piacere. Ho parlato con Federica al telefono per ore, dato che siamo ancora in zona arancione con parecchie sfumature di rosso e, anche se questo \u00e8 il mio lavoro, non mi sembra prudente andarla a trovare adesso. Il Coronavirus si sta accanendo ancora su Brescia e meno ci muoviamo meglio \u00e8&#8230; ed \u00e8 ora che se lo mettano in testa un po&#8217; tutti o ne usciremo nell&#8217;anno del mai. Federica ha un bellissimo palato e una grande passione: parlare con lei di vino \u00e8 entusiasmante. Ho apprezzato moltissimo la sua volont\u00e0 di proporre varie annate di Derthona Timorasso e ho degustato con piacere i vari campioni che mi ha inviato. Prima di raccontarti le mie degustazioni per\u00f2 ti voglio parlare un po&#8217; di questo vitigno capace di creare un <span style=\"text-decoration: underline;\"><a href=\"https:\/\/www.aromawinebar.it\/derthona-timorasso\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>vino piemontese<\/strong><\/a><\/span> bianco straordinario.<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221; header_3_font=&#8221;Delius Unicase|700|||||||&#8221; header_3_font_size=&#8221;20px&#8221;]<\/p>\n<h3>Timorasso: il vitigno<\/h3>\n<p style=\"text-align: justify;\">Se si parla di vitigni a bacca bianca autoctoni il Timorasso \u00e8 probabilmente nella mia top 10. Coltivato nella provincia di Alessandria fin dall&#8217;antichit\u00e0,\u00a0<span>se ne hanno testimonianze gi\u00e0 nel XIV secolo, nel Trattato di agronomia di Pietro de\u2019 Crescenzi, e nel Bollettino Ampelografico del Di Rovasenda, del 1885 che lo collocavano come il vitigno pi\u00f9 coltivato del tortonese.<\/span><\/p>\n<p style=\"text-align: justify;\">La sua foglia \u00e8 molto caratteristica perch\u00e8 \u00e8 un po&#8217; pi\u00f9 piccola della media, pentagonale e quinquelobata, con il seno peziolare (dove \u00e8 attaccata al resto della pianta) a U con gli estremi convergenti, un po&#8217; chiusi. La pagina superiore \u00e8 di colore verde cupo opaco ed \u00e8 quasi glabra. La pagina inferiore \u00e8 ti colore verde bottiglia con nervature sporgenti e tomento vellutato. In botanica il tomento \u00e8 l&#8217;insieme di peli pi\u00f9 o meno lunghi, assai fitti e talvolta intrecciati, che eventualmente ricopre la superficie delle foglie. In autunno diventano di un bellissimo giallo intenso.<\/p>\n<p style=\"text-align: justify;\">Il grappolo quando \u00e8 maturo si presenta abbastanza grande (circa 20 cm) e compatto, spesso alato. Se trovi dei grappoli radi dipendono da qualche problema di allegagione e acinellatura verde. L&#8217;acino \u00e8 piuttosto grosso, sferoide e regolare. La buccia \u00e8 spessa e consistente, di colore verde giallo e molto pruinosa. La polpa \u00e8 succosa e carnosa, di sapore neutro. Il succo \u00e8 incolore. Sono sempre presenti due vinaccioli a forma di pera.<\/p>\n<p style=\"text-align: justify;\"><span>Data la sua scarsa vigoria e la sua produzione limitata, nel corso dei secoli \u00e8 stato lentamente abbandonato a favore delle uve a bacca rossa pi\u00f9 produttive e meno delicate come barbera e croatina. Solo negli anni &#8217;80 un gruppo di vignaioli lungimiranti, primo tra tutti Walter Massa, ha deciso di dargli nuova vita capendo le sue straordinarie potenzialit\u00e0.<\/span><\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/02\/timorasso-vitigno.jpg&#8221; alt=&#8221;timorasso vitigno&#8221; title_text=&#8221;timorasso-vitigno&#8221; _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221; box_shadow_style=&#8221;preset3&#8243;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221; header_3_font=&#8221;Delius Unicase|700|||||||&#8221; header_3_font_size=&#8221;20px&#8221;]<\/p>\n<h3>Timorasso: il vino<\/h3>\n<p style=\"text-align: justify;\"><span>Parlare di caratteristiche del vino prodotto \u00e8 impossibile date le differenti vinificazioni. Tuttavia, per darti un&#8217;idea generale, ti dir\u00f2 che il timorasso vinificato in bianco \u00e8 un vino che si pu\u00f2 assimilare a certi riesling per via degli <strong>idrocarburi<\/strong> meravigliosi che \u00e8 capace di esprimere, soprattutto dopo un periodo anche lungo di affinamento in bottiglia. Generalmente \u00e8 un vino molto strutturato, <strong>alcolico e sapido<\/strong>, caratterizzato da un <strong>grande potenziale di invecchiamento<\/strong> che lo rende ancora pi\u00f9 equilibrato e affascinante. Dato che la sua zona di produzione \u00e8 molto circoscritta, oserei dire limitata, \u00e8 sicuramente un <strong>vino di nicchia<\/strong> per appassionati di grandi vini bianchi.<\/span><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221; header_3_font=&#8221;Delius Unicase|700|||||||&#8221; header_3_font_size=&#8221;20px&#8221;]<\/p>\n<h3>Timorasso: le degustazioni di Derthona<\/h3>\n<p style=\"text-align: justify;\">Tra i Derthona Timorasso che ho assaggiato ce ne sono stati 2 che mi hanno particolarmente entusiasmato&#8230; senza scomodare i pi\u00f9 blasonati Cru di Vigneti Massa tipo il Montecitorio o il Costa del Vento, anch&#8217;essi nell&#8217;interessante selezione Federica. Ho scelto di parlarti proprio di questi anche perch\u00e8 in un&#8217;interessante chiacchierata che ho tenuto su ClubHouse nessuno dei partecipanti conosceva queste due etichette che per me meritano assolutamente di essere scoperte. E tu li hai mai assaggiati?<\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/02\/derthona-timorasso-lacrime-del-bricco-boveri-giacomo.jpg&#8221; alt=&#8221;derthona timorasso vino piemontese&#8221; title_text=&#8221;derthona-timorasso-lacrime-del-bricco-boveri-giacomo&#8221; _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221; box_shadow_style=&#8221;preset3&#8243;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221; header_3_font=&#8221;Delius|700|||||||&#8221;]<\/p>\n<h3>Derthona Timorasso &#8220;Lacrime del Bricco&#8221;, Vigneti Boveri Giacomo 2017<\/h3>\n<p style=\"text-align: justify;\">Alla fine, seppur tentennando, ho scelto questo come miglior Derthona Timorasso della degustazione che ho fatto con Federica. Una tecnica ineccepibile per un vino che d\u00e0 tanta, tantissima soddisfazione sia da solo sia accompagnato ai miei tajarin!<\/p>\n<p style=\"text-align: justify;\">Si presenta di un bellissimo giallo paglierino brillante con riflessi oro verde. Roteando il bicchiere forma archetti regolari e il vino scende lento. Naso intenso e caratteristico con note di succo di lime, cedro candito, miele di tiglio e idrocarburo che viene fuori in modo pi\u00f9 intenso dopo una decina di minuti che la bottiglia \u00e8 aperta. In bocca \u00e8 coerente e equilibratissimo, citrino, fresco e caldo con una pseudocalorica bilanciata e una bella sapidit\u00e0. Lungo finale amaricante.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.aromawinebar.it\/derthona-timorasso-lacrime-del-bricco\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"text-decoration: underline;\"><strong>Clicca QUI per maggiori informazioni su questo Timorasso di Vigneti Boveri Giacomo<\/strong><\/span><\/a>.<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.9.1&#8243; _module_preset=&#8221;default&#8221; header_3_font=&#8221;Delius|700|||||||&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h3>Derthona Timorasso, Vignaioli Battegazzore 2018<\/h3>\n<p style=\"text-align: justify;\">Di impatto \u00e8 quello che mi \u00e8 piaciuto di pi\u00f9&#8230; anche se dal punto di vista tecnico quello di Boveri \u00e8 &#8220;pi\u00f9 perfetto&#8221; mentre questo presenta un leggero squilibrio sulla pseudocalorica, complessivamente bilanciato da acidit\u00e0 e sapidit\u00e0.<\/p>\n<p style=\"text-align: justify;\">Si presenta di un bellissimo giallo oro carico brillante e roteando il bicchiere forma archetti regolari confessandoci una certa alcolicit\u00e0. Al naso \u00e8 caratteristico ed elegante, con note di agrumi molto marcate, prugna, mandorla e accenni di idrocarburi. In bocca \u00e8 caldo, strutturato e sapido, con una pseudocalorica piuttosto tosta. Lungo finale ammandorlato.<\/p>\n<p style=\"text-align: justify;\"><span style=\"text-decoration: underline;\"><a href=\"https:\/\/www.aromawinebar.it\/derthona-timorasso-battegazzore\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Clicca QUI per maggiori informazioni su questo Timorasso di Vignaioli Bottegazzore<\/strong><\/a><\/span><\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/02\/tajarin-ricetta-ragu-di-fegato-cucina-piemontese.jpg&#8221; alt=&#8221;timorasso tajarin ricetta cucina piemontese&#8221; title_text=&#8221;tajarin-ricetta-ragu-di-fegato-cucina-piemontese&#8221; _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221; box_shadow_style=&#8221;preset3&#8243;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221; header_3_font=&#8221;Delius Unicase|700|||||||&#8221; header_3_font_size=&#8221;20px&#8221; header_4_font=&#8221;Delius|700|||||||&#8221;]<\/p>\n<h3>Tajarin: un abbinamento vino piemontese-cibo piemontese!<\/h3>\n<p style=\"text-align: justify;\">Quando si parla di abbinamento cibo vino, ti consiglier\u00f2 sempre un abbinamento territoriale. Ed \u00e8 cos\u00ec che per questi due Derthona Timorasso ho scomodato lei, Rosa Vercellana, diventata poi contessa di Mirafiori e Fontanafredda. Nota come Bela Rosin, fu prima amante e poi moglie morganatica di Re Vittorio Emanuele II. Mi innamorai della loro storia quando fui ospite con l&#8217;amico Guido Barosio, allora direttore di La Presse e del Torino Magazine, dello splendido Relais Bella Rosina nel Parco della Mandria, nei dintorni di Venaria Reale&#8230; era il lontano luglio 2012! Possibile siano gi\u00e0 passati quasi 9 anni?<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">Lei, Rosa Vercellana, era una donna bella e semplice, ottima cuoca di stampo casalingo.<\/p>\n<p style=\"text-align: justify;\">Lui, Vittorio Emanuele II, era costretto dall&#8217;etichetta di corte e dagli impegni di Stato a prendere parte a pranzi ufficiali e banchetti, ma non li amava, e non faceva nulla per nascondere noia e insofferenza.<\/p>\n<p style=\"text-align: justify;\">Cos\u00ec lei, Rosin, lo confortava preparandogli piatti meno elaborati ma pi\u00f9 di suo gusto come i tajarin, pasta fresca sottile e ricchissima di uova che il re sembra apprezzasse molto.<\/p>\n<p style=\"text-align: right;\"><a href=\"https:\/\/amzn.to\/3aVPsO8\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"text-decoration: underline;\"><strong>Gli Aristopiatti<\/strong><\/span><\/a>, Lydia Capasso<\/p>\n<\/blockquote>\n<h4 style=\"text-align: justify;\">Tajarin, ingredienti per 3 mangioni (ovvero 2 porzioni abbondanti e resta quella per la schiscetta di mio marito il giorno dopo!)<\/h4>\n<ul>\n<li style=\"text-align: justify;\">250g di semola rimacinata di grano duro<\/li>\n<li style=\"text-align: justify;\">10 tuorli<\/li>\n<\/ul>\n<h4>Tajarin, preparazione:<\/h4>\n<ol>\n<li style=\"text-align: justify;\">Separa i tuorli dagli albumi (che puoi riutilizzare per preparare delle squisite meringhe).<\/li>\n<li style=\"text-align: justify;\">Aggiungi la farina e impasta o a mano o con la planetaria con la foglia o col gancio (io ho usato il gancio).<\/li>\n<li style=\"text-align: justify;\">Dopo qualche minuto otterrai un impasto omogeneo, un po&#8217; duro. Fai una palla e coprilo con una ciotola, lascia riposare per circa 10 minuti (intanto ti dedichi al rag\u00f9 di fegato).<\/li>\n<li style=\"text-align: justify;\">Stendi la pasta con il matterello poi passa alla macchina per pasta, irrinunciabile la mia adorata Marcato Classic Atlas (la puoi comprare su Amazon <a href=\"https:\/\/amzn.to\/3qTgz1Q\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"text-decoration: underline;\"><strong>QUI<\/strong><\/span><\/a>) che mi accompagna da quando sono andata a vivere fuori casa nel lontano 2006. Ho steso fino allo spessore 5, poi ho tagliato le sfoglie con una rotella fino ad avere circa 30 cm di lunghezza e le ho passate una dopo l&#8217;altra nella fila dei tagliolini. In pochi minuti questi squisiti tajarin erano pronti!<\/li>\n<\/ol>\n<h4>Rag\u00f9 di fegato, ingredienti:<\/h4>\n<ul>\n<li style=\"text-align: justify;\">300g di fegato di bovino<\/li>\n<li style=\"text-align: justify;\">100g di carota, sedano e cipolla a cubetti<\/li>\n<li style=\"text-align: justify;\">1\/2 bicchiere di latte intero<\/li>\n<li style=\"text-align: justify;\">1\/2 tubetto di concentrato di pomodoro<\/li>\n<li style=\"text-align: justify;\">1\/2 bicchiere (da acqua, circa 150g) di Timorasso<\/li>\n<li style=\"text-align: justify;\">1 noce di strutto o 2 cucchiai d&#8217;olio extravergine di oliva<\/li>\n<li style=\"text-align: justify;\">Acqua calda QB<\/li>\n<li>noce moscata, sale<\/li>\n<\/ul>\n<h4>Rag\u00f9 di fegato, preparazione:<\/h4>\n<ol>\n<li>Rosola nello strutto (o nell&#8217;olio) i cubetti di sedano carota e cipolla.<\/li>\n<li>Taglia il fegato di bovino a striscioline grossolane e aggiungilo nella padella quando le verdure sono tenere.<\/li>\n<li>Sfuma con il vino e aspetta che evapora.<\/li>\n<li>Stempra il concentrato di pomodoro in un po&#8217; d&#8217;acqua calda e aggiungilo.<\/li>\n<li>Copri la carne con acqua calda &#8211; deve essere totalmente immersa &#8211; e mescola con cura.<\/li>\n<li>Lascia sobbollire per un paio di minuti poi aggiungi il latte, il sale e la noce moscata e lascia cuocere il tempo che prepari i tajarin a fuoco dolce (se lo prepari prima anche per un&#8217;oretta&#8230; diventa ancora pi\u00f9 buono!).<\/li>\n<\/ol>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/02\/derthona-timorasso-aroma-wine-bar-enoteca-tortona.jpg&#8221; alt=&#8221;derthona timorasso aroma wine bar enoteca tortona tajarin&#8221; title_text=&#8221;derthona-timorasso-aroma-wine-bar-enoteca-tortona&#8221; _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221; box_shadow_style=&#8221;preset3&#8243;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221; header_3_font=&#8221;Delius Unicase|700|||||||&#8221; header_3_font_size=&#8221;20px&#8221; header_4_font=&#8221;Delius|700|||||||&#8221;]<\/p>\n<h3>Infine un&#8217;ultima degustazione: una chicca per gli amanti dei vini naturali&#8230;<\/h3>\n<p style=\"text-align: justify;\">Prima di questo vino una doverosa premessa: non sono una talebana dei vini naturali, anzi&#8230; tra le due sono una talebana all&#8217;incontrario. A me il vino interessa che sia buono e tante volte vedo pi\u00f9 un preciso collocamento di marketing che un vero interesse alla naturalit\u00e0. Inoltre, come \u00e8 emerso anche nella mia Room su ClubHouse di ieri sera, \u00e8 paradossale che nel 2021 dobbiamo scrivere che un vino \u00e8 naturale o che un cibo non contiene olio di palma! Eppure cos\u00ec ci siamo ridotti e non possiamo fare altro che sperare che ci sia un&#8217;improbabile inversione di tendenza nel prossimo futuro. Di fianco a pi\u00f9 o meno grandi, o grandissimi, produttori che riducono i concetti di <em>biologico<\/em> o di <em>naturale<\/em>\u00a0in un claim per abbracciare una pi\u00f9 ampia fetta di consumatori, c&#8217;\u00e8 anche qualche piccolo produttore che lo fa perch\u00e8 ci crede davvero. Ecco, questo \u00e8 sicuramente il caso del vino qui sotto.<\/p>\n<h4>&#8220;Phoenix&#8221; 2020, Viticoltori il vino e le rose<\/h4>\n<p style=\"text-align: justify;\">Si presenta di un giallo oro carico e brillante. Al naso \u00e8 particolare, sicuramente si sente che \u00e8 un vino naturale&#8230; o almeno io ormai li individuo subito. Il timorasso \u00e8 irriconoscibile per come lo intendiamo, ma \u00e8 comunque interessante. Mi ricorda il sake giapponese. Si riconoscono il cedro, il lievito, la mela e la salsa di soia. in bocca \u00e8 coerente, equilibrato e persistente con un finale delicatamente agrumato.<\/p>\n<p style=\"text-align: justify;\">Quindi, se cerchi un Timorasso convenzionale ti consiglio di puntare su uno dei due Derthona (o entrambi) tra quelli precedentemente degustati. Se invece vuoi provare come si pu\u00f2 esprimere questo vitigno con un approccio completamente diverso questo vino \u00e8 perfetto.<\/p>\n<p style=\"text-align: justify;\"><span><a href=\"https:\/\/www.aromawinebar.it\/aroma-wine-shop\/TIMORASSO-PHOENIX-NATURALE-IL-VINO-E-LE-ROSE-p276706112\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Clicca QUI per maggiori informazioni su questo Timorasso di Viticoltori il vino e le rose<\/strong><\/a><\/span><\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/02\/phoenix-vino-naturale-timorasso.jpg&#8221; alt=&#8221;timorasso phoenix vino piemontese naturale&#8221; title_text=&#8221;phoenix-vino-naturale-timorasso&#8221; _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221; box_shadow_style=&#8221;preset3&#8243;][\/et_pb_image][et_pb_signup provider=&#8221;mailpoet&#8221; mailpoet_list=&#8221;PEPEblu|49&#8243; success_message=&#8221;Controlla la tua e-mail: hai appena ricevuto un mio messaggio per confermare la tua iscrizione! Se non lo visualizzi controlla in spam o nella cartella %22promozioni%22 di Gmail. Grazie e a presto!&#8221; title=&#8221;Ti piace questo contenuto?&#8221; button_text=&#8221;Iscriviti subito!&#8221; description=&#8221;<\/p>\n<p style=%22text-align: justify;%22>Iscriviti alla mia newsletter per non perderti nessun nuovo articolo del mio blog!<\/p>\n<p style=%22text-align: justify;%22>Non ti invier\u00f2 SPAM, ma solo la notifica dei nuovi articoli! Di tanto in tanto potrai ricevere anche qualche coupon per acquistare vino o partecipare ad eventi con condizioni speciali riservate ai lettori del mio blog!<\/p>\n<p style=%22text-align: justify;%22>Cheers \ud83e\udd29\ud83e\udd42<\/p>\n<p>&#8221; footer_content=&#8221;Iscrivendoti accetti le condizioni della <a href=%22https:\/\/perlagesuite.com\/privacy-2\/%22 data-et-target-link=%22_blank%22 rel=%22noopener noreferrer%22><span style=%22text-decoration: underline;%22><strong>Privacy<\/strong><\/span><\/a> di Perlage Suite.&#8221; _builder_version=&#8221;4.7.7&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Delius Unicase|700|||||||&#8221; header_font_size=&#8221;22px&#8221; body_font=&#8221;Delius||||||||&#8221; background_color=&#8221;#008c96&#8243; box_shadow_style=&#8221;preset3&#8243; box_shadow_color=&#8221;rgba(0,140,150,0.6)&#8221; global_module=&#8221;27234&#8243;][\/et_pb_signup][et_pb_text _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221;]<\/p>\n<p>Ho degustato ancora un Timorasso di cui mi piacerebbe parlarti, ma essendo uno spumante metodo classico te lo racconto nei prossimi giorni in un articolo dedicato proprio al vino piemontese spumante!<\/p>\n<p style=\"text-align: justify;\">A questo punto non vedo l&#8217;ora di andare a trovare Federica a Tortona: la sua <strong>Aroma Wine Bar Enoteca \u00e8 stupenda<\/strong>&#8230; <strong>un piccolo tempio di design, cibi e vini per appassionati che non hanno fretta<\/strong>&#8230; proprio come me! Nel frattempo ti segnalo che questi Timorasso e un&#8217;altra serie di vini frutto di grande qualit\u00e0 e ricerca sono disponibili nel suo <a href=\"https:\/\/www.aromawinebar.it\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"text-decoration: underline;\"><strong>wine shop online<\/strong><\/span><\/a>&#8230; che ne dici, <strong>ci beviamo su in quest&#8217;ennesima quarantena?<\/strong><\/p>\n<p>Cheers<\/p>\n<p>Chiara<\/p>\n<p>[\/et_pb_text][et_pb_divider color=&#8221;gcid-65af285e-4bd3-4ea9-81b6-b2c2b9f89915&#8243; _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{%22gcid-65af285e-4bd3-4ea9-81b6-b2c2b9f89915%22:%91%22color%22%93}&#8221;][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.0.6&#8243; global_module=&#8221;21425&#8243;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.0.6&#8243;][et_pb_wc_images product=&#8221;10582&#8243; _builder_version=&#8221;4.0.6&#8243;][\/et_pb_wc_images][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.0.6&#8243;][et_pb_wc_title product=&#8221;10582&#8243; _builder_version=&#8221;4.0.6&#8243;][\/et_pb_wc_title][et_pb_wc_rating product=&#8221;10582&#8243; _builder_version=&#8221;4.0.6&#8243;][\/et_pb_wc_rating][et_pb_wc_description product=&#8221;10582&#8243; _builder_version=&#8221;4.0.6&#8243;][\/et_pb_wc_description][et_pb_wc_price product=&#8221;10582&#8243; _builder_version=&#8221;4.0.6&#8243;][\/et_pb_wc_price][et_pb_wc_add_to_cart product=&#8221;10582&#8243; _builder_version=&#8221;4.0.6&#8243;][\/et_pb_wc_add_to_cart][et_pb_text _builder_version=&#8221;4.0.6&#8243; text_font=&#8221;Delius Unicase||||||||&#8221;]<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ff0000;\"><strong>IN OMAGGIO<\/strong><\/span>, solo per chi compra il mio libro su Perlage Suite, una copia della <strong>Prima Edizione da Collezione della mia Guida Vini Spumanti &#8220;500 Bolle in 500&#8221;<\/strong>, prezzo di copertina 25,30 \u20ac.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Per capire un vino fino in fondo \u00e8 necessario, come prima cosa, conoscere il vitigno con cui viene elaborato. Per questo quando Federica di Aroma Wine Bar, l&#8217;Enoteca di Tortona specializzata nel\u00a0Derthona Timorasso, mi ha proposto di parlare di questo vino ho accettato con grande piacere. Ho parlato con Federica al telefono per ore, dato [&hellip;]<\/p>\n","protected":false},"author":49,"featured_media":28201,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"2880","footnotes":""},"categories":[298],"tags":[],"class_list":["post-28180","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-degustazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.0 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Timorasso: dal vitigno al vino, degustando Derthona - Perlage Suite<\/title>\n<meta name=\"description\" content=\"Grazie ad Aroma Wine Bar, Enoteca a Tortona, ho avuto l&#039;opportunit\u00e0 di degustare alcune interpretazioni di Derthona Timorasso e non solo!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/perlagesuite.com\/en\/timorasso-derthona-vitigno-vino\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Timorasso: dal vitigno al vino, degustando Derthona\" \/>\n<meta property=\"og:description\" content=\"Grazie ad Aroma Wine Bar, Enoteca a Tortona, ho avuto l&#039;opportunit\u00e0 di degustare alcune interpretazioni di Derthona Timorasso e non solo!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/perlagesuite.com\/en\/timorasso-derthona-vitigno-vino\/\" \/>\n<meta property=\"og:site_name\" content=\"Perlage Suite\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/chiarabassiperlagesuite\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-26T14:29:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-05T17:25:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/02\/derthona-timorasso-aroma-wine-bar-enoteca-tortona-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Chiara Bassi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@perlagesuite\" \/>\n<meta name=\"twitter:site\" content=\"@perlagesuite\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Chiara Bassi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/timorasso-derthona-vitigno-vino\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/timorasso-derthona-vitigno-vino\\\/\"},\"author\":{\"name\":\"Chiara Bassi\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/person\\\/81b257517a1007c1a823318ac86c6013\"},\"headline\":\"Timorasso: dal vitigno al vino, degustando Derthona\",\"datePublished\":\"2021-02-26T14:29:32+00:00\",\"dateModified\":\"2021-03-05T17:25:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/timorasso-derthona-vitigno-vino\\\/\"},\"wordCount\":2466,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/timorasso-derthona-vitigno-vino\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/derthona-timorasso-aroma-wine-bar-enoteca-tortona-2.jpg\",\"articleSection\":[\"Degustazioni\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/perlagesuite.com\\\/timorasso-derthona-vitigno-vino\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/timorasso-derthona-vitigno-vino\\\/\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/timorasso-derthona-vitigno-vino\\\/\",\"name\":\"Timorasso: dal vitigno al vino, degustando Derthona - Perlage Suite\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/timorasso-derthona-vitigno-vino\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/timorasso-derthona-vitigno-vino\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/derthona-timorasso-aroma-wine-bar-enoteca-tortona-2.jpg\",\"datePublished\":\"2021-02-26T14:29:32+00:00\",\"dateModified\":\"2021-03-05T17:25:34+00:00\",\"description\":\"Grazie ad Aroma Wine Bar, Enoteca a Tortona, ho avuto l'opportunit\u00e0 di degustare alcune interpretazioni di Derthona Timorasso e non solo!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/timorasso-derthona-vitigno-vino\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/perlagesuite.com\\\/timorasso-derthona-vitigno-vino\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/timorasso-derthona-vitigno-vino\\\/#primaryimage\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/derthona-timorasso-aroma-wine-bar-enoteca-tortona-2.jpg\",\"contentUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/derthona-timorasso-aroma-wine-bar-enoteca-tortona-2.jpg\",\"width\":1080,\"height\":720,\"caption\":\"derthona timorasso aroma wine bar vino piemontese\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/timorasso-derthona-vitigno-vino\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/perlagesuite.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Timorasso: dal vitigno al vino, degustando Derthona\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#website\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/\",\"name\":\"Perlage Suite\",\"description\":\"Il Wine Blog di Chiara Bassi\",\"publisher\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/perlagesuite.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#organization\",\"name\":\"Chiara Bassi\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Chiara-Bassi-sommelier-wine-blogger-logo.png\",\"contentUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Chiara-Bassi-sommelier-wine-blogger-logo.png\",\"width\":512,\"height\":512,\"caption\":\"Chiara Bassi\"},\"image\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/chiarabassiperlagesuite\",\"https:\\\/\\\/x.com\\\/perlagesuite\",\"https:\\\/\\\/www.instagram.com\\\/perlagesuite\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/person\\\/81b257517a1007c1a823318ac86c6013\",\"name\":\"Chiara Bassi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g\",\"caption\":\"Chiara Bassi\"},\"sameAs\":[\"https:\\\/\\\/perlagesuite.com\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Timorasso: from vine to wine, tasting Derthona - Perlage Suite","description":"Thanks to Aroma Wine Bar, an Enoteca in Tortona, I had the opportunity to taste some interpretations of Derthona Timorasso and more!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/perlagesuite.com\/en\/timorasso-derthona-vitigno-vino\/","og_locale":"en_GB","og_type":"article","og_title":"Timorasso: dal vitigno al vino, degustando Derthona","og_description":"Grazie ad Aroma Wine Bar, Enoteca a Tortona, ho avuto l'opportunit\u00e0 di degustare alcune interpretazioni di Derthona Timorasso e non solo!","og_url":"https:\/\/perlagesuite.com\/en\/timorasso-derthona-vitigno-vino\/","og_site_name":"Perlage Suite","article_publisher":"https:\/\/www.facebook.com\/chiarabassiperlagesuite","article_published_time":"2021-02-26T14:29:32+00:00","article_modified_time":"2021-03-05T17:25:34+00:00","og_image":[{"width":1080,"height":720,"url":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/02\/derthona-timorasso-aroma-wine-bar-enoteca-tortona-2.jpg","type":"image\/jpeg"}],"author":"Chiara Bassi","twitter_card":"summary_large_image","twitter_creator":"@perlagesuite","twitter_site":"@perlagesuite","twitter_misc":{"Written by":"Chiara Bassi","Estimated reading time":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/perlagesuite.com\/timorasso-derthona-vitigno-vino\/#article","isPartOf":{"@id":"https:\/\/perlagesuite.com\/timorasso-derthona-vitigno-vino\/"},"author":{"name":"Chiara Bassi","@id":"https:\/\/perlagesuite.com\/#\/schema\/person\/81b257517a1007c1a823318ac86c6013"},"headline":"Timorasso: dal vitigno al vino, degustando Derthona","datePublished":"2021-02-26T14:29:32+00:00","dateModified":"2021-03-05T17:25:34+00:00","mainEntityOfPage":{"@id":"https:\/\/perlagesuite.com\/timorasso-derthona-vitigno-vino\/"},"wordCount":2466,"commentCount":0,"publisher":{"@id":"https:\/\/perlagesuite.com\/#organization"},"image":{"@id":"https:\/\/perlagesuite.com\/timorasso-derthona-vitigno-vino\/#primaryimage"},"thumbnailUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/02\/derthona-timorasso-aroma-wine-bar-enoteca-tortona-2.jpg","articleSection":["Degustazioni"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/perlagesuite.com\/timorasso-derthona-vitigno-vino\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/perlagesuite.com\/timorasso-derthona-vitigno-vino\/","url":"https:\/\/perlagesuite.com\/timorasso-derthona-vitigno-vino\/","name":"Timorasso: from vine to wine, tasting Derthona - Perlage Suite","isPartOf":{"@id":"https:\/\/perlagesuite.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/perlagesuite.com\/timorasso-derthona-vitigno-vino\/#primaryimage"},"image":{"@id":"https:\/\/perlagesuite.com\/timorasso-derthona-vitigno-vino\/#primaryimage"},"thumbnailUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/02\/derthona-timorasso-aroma-wine-bar-enoteca-tortona-2.jpg","datePublished":"2021-02-26T14:29:32+00:00","dateModified":"2021-03-05T17:25:34+00:00","description":"Thanks to Aroma Wine Bar, an Enoteca in Tortona, I had the opportunity to taste some interpretations of Derthona Timorasso and more!","breadcrumb":{"@id":"https:\/\/perlagesuite.com\/timorasso-derthona-vitigno-vino\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/perlagesuite.com\/timorasso-derthona-vitigno-vino\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/perlagesuite.com\/timorasso-derthona-vitigno-vino\/#primaryimage","url":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/02\/derthona-timorasso-aroma-wine-bar-enoteca-tortona-2.jpg","contentUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/02\/derthona-timorasso-aroma-wine-bar-enoteca-tortona-2.jpg","width":1080,"height":720,"caption":"derthona timorasso aroma wine bar vino piemontese"},{"@type":"BreadcrumbList","@id":"https:\/\/perlagesuite.com\/timorasso-derthona-vitigno-vino\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/perlagesuite.com\/"},{"@type":"ListItem","position":2,"name":"Timorasso: dal vitigno al vino, degustando Derthona"}]},{"@type":"WebSite","@id":"https:\/\/perlagesuite.com\/#website","url":"https:\/\/perlagesuite.com\/","name":"Perlage Suite","description":"Chiara Bassi's Wine Blog","publisher":{"@id":"https:\/\/perlagesuite.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/perlagesuite.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/perlagesuite.com\/#organization","name":"Chiara Bassi","url":"https:\/\/perlagesuite.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/perlagesuite.com\/#\/schema\/logo\/image\/","url":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2022\/03\/Chiara-Bassi-sommelier-wine-blogger-logo.png","contentUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2022\/03\/Chiara-Bassi-sommelier-wine-blogger-logo.png","width":512,"height":512,"caption":"Chiara Bassi"},"image":{"@id":"https:\/\/perlagesuite.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/chiarabassiperlagesuite","https:\/\/x.com\/perlagesuite","https:\/\/www.instagram.com\/perlagesuite\/"]},{"@type":"Person","@id":"https:\/\/perlagesuite.com\/#\/schema\/person\/81b257517a1007c1a823318ac86c6013","name":"Chiara Bassi","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g","caption":"Chiara Bassi"},"sameAs":["https:\/\/perlagesuite.com"]}]}},"_links":{"self":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/posts\/28180","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/comments?post=28180"}],"version-history":[{"count":0,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/posts\/28180\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/media\/28201"}],"wp:attachment":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/media?parent=28180"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/categories?post=28180"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/tags?post=28180"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}