{"id":283562,"date":"2022-12-22T13:22:49","date_gmt":"2022-12-22T12:22:49","guid":{"rendered":"https:\/\/perlagesuite.com\/?p=283562"},"modified":"2022-12-22T13:54:18","modified_gmt":"2022-12-22T12:54:18","slug":"genuino-del-duca","status":"publish","type":"post","link":"https:\/\/perlagesuite.com\/en\/genuino-del-duca\/","title":{"rendered":"Genuino Del Duca: my letter to your daughter Claudia"},"content":{"rendered":"\n[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||30px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.19.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<p>Cara <strong>Claudia Del Duca<\/strong>, ti scrivo perch\u00e8 non posso farne a meno e questa lettera non \u00e8 solo per te, ma per tutte quelle figlie innamorate dei loro pap\u00e0 che li hanno persi troppo presto come noi. Cara Claudia, ti scrivo perch\u00e8 non mi serve essere la tua migliore amica per sapere che adoravi tuo padre, come io adoravo il mio. Cara Claudia ti scrivo perch\u00e8, anche se sono passati 4 anni, non riesco ancora a parlare di mio padre senza piangere e alla quarta riga di questa lettera non ancora iniziata ho gi\u00e0 gli occhi lucidi. Se ti chiamassi non sarei affatto d&#8217;aiuto per te. Infine, cara Claudia, ti scrivo perch\u00e8 ho visto te e <strong>Genuino Del Duca<\/strong>\u00a0circa un paio di settimane fa, in occasione della presentazione della <a href=\"https:\/\/perlagesuite.com\/ristoranti-buon-ricordo\/\"><span style=\"text-decoration: underline;\"><strong>guida ristoranti Buon Ricordo 2023<\/strong><\/span><\/a>, e abbiamo scambiato qualche parola, e tuo pap\u00e0 non \u00e8 mancato di dirmi di venirvi a trovare ancora. Quando ho saputo che era morto stavo guardando i mondiali, l&#8217;Argentina stava battendo la Francia 2-0 e era l&#8217;anniversario della morte di mio padre: il 18 dicembre.<\/p>\n<p>Non stento a pensare che in questi giorni ti cercheranno un po&#8217; tutti e tu li cercherai a tua volta o li odierai, uno a uno. Saranno fasi diverse del tuo umore, stati d&#8217;animo che non potrai controllare. Non avere paura di viverli e mostrarli: solo un idiota non capirebbe. Quando mio padre \u00e8 morto ho passato giorni in cui ero assente. Erano giorni in cui il mio cervello era totalmente scollegato dal mio agire e facevo le cose in automatico. In quei giorni ho perso clienti (all&#8217;epoca lavoravo ancora come web designer), ho fatto cazzate di ogni sorta e mi sono pure fidanzata con il peggiore degli stronzi (fortunatamente sono rinsavita nel giro di pochi mesi). Puoi solo fare meglio.<\/p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.19.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<p>Non so di cosa \u00e8 morto Genuino Del Duca. Non so se stava lottando con una lunga malattia o si \u00e8 trattato di un malore improvviso. Mio pap\u00e0 \u00e8 morto dopo un anno e mezzo di indicibili sofferenze, dopo cicli di chemioterapia, immunoterapia, radioterapia e una gamba amputata. Mio pap\u00e0 \u00e8 morto dopo aver lottato come un leone, quando ormai la malattia lo aveva cos\u00ec cambiato di aspetto e carattere che quasi io e mamma non lo riconoscevamo pi\u00f9. Ma riconoscevamo la sua voglia di vivere e la dignit\u00e0 con cui affrontava la malattia. E soprattutto io ero la figlia che amava pi\u00f9 di s\u00e9 stesso e mi commuovo ancora a pensarlo lavorare per me con il tablet perfino durante la seduta di chemio. Per cercare di aiutarmi quanto pi\u00f9 possibile finch\u00e8 c\u2019era e per sentirsi vivo fino all\u2019ultimo. Anche io negli ultimi anni avevo cominciato a lavorare con il mio pap\u00e0 come te.<\/p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.19.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<p style=\"text-align: left;\"><span><strong>Mio pap\u00e0 mi ha lasciato in eredit\u00e0 la ricchezza pi\u00f9 grande: credere che non ci siano sogni impossibili<\/strong>. Credo che tuo pap\u00e0 abbia lasciato a te altrettanto: non era lui che aveva abbandonato l&#8217;arma dei carabinieri per inseguire il suo amore per il buon cibo e il buon vino? Non \u00e8 nato cos\u00ec <a href=\"https:\/\/perlagesuite.com\/podere-marcampo-degustazione-vini-e-ristorante-a-volterra\/\"><span style=\"text-decoration: underline;\"><strong>Podere Marcampo<\/strong><\/span><\/a> o il ristorante dove abbiamo festeggiato insieme il suo 63esimo compleanno? All&#8217;Enoteca Del Duca, che non mi stupisce affatto fosse sulla Guida Michelin, ho mangiato una carbonara al tartufo e un piccione indimenticabili di ritorno dalla mia luna di miele, quando mi sono fermata a Volterra &#8220;a far finta di vendemmiare duro&#8221; come ogni bravo wine influencer fa almeno una volta nella vita.<\/span><\/p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.19.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<p style=\"text-align: left;\">Oggi sono passati 4 anni. Quattro anni in cui sono successe tante cose e lui non c&#8217;era. Quattro anni in cui mi sono sposata, laureata, ho fatto un master e ho avuto una costellazione di successi lavorativi che lo avrebbero reso fiero ancora di pi\u00f9 di quello che gi\u00e0 era. Quattro anni in cui mi sono concentrata sul lavoro con una dedizione inconcepibile per chiunque non abbia provato quello che io ho provato e quello che tu, molto probabilmente, stai provando. E qui ho una buona notizia per te: fare un lavoro che si ama con tutto il cuore \u00e8 il pi\u00f9 prezioso degli alleati per cacciare le lacrime in un cassettino e dimenticare il dolore. Lo so, questo non \u00e8 sufficiente per stare meglio, ma \u00e8 comunque un grandissimo aiuto per vivere con una parvenza di normalit\u00e0 e serenit\u00e0 la vita di ogni giorno. Uno psicologo mi direbbe che a distanza di 4 anni non ho elaborato il lutto. Probabilmente gli risponderei che non voglio nemmeno elaborarlo, e pazienza se qualcuno mi considerer\u00e0 matta o depressa: al netto di comportarmi con la pi\u00f9 grande correttezza possibile verso tutti, non me ne \u00e8 mai fregato nulla di cosa pensano gli altri di me e non inizier\u00f2 a preoccuparmene oggi a 37 anni.<\/p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.19.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<p style=\"text-align: left;\"><span>Cara Claudia, ti scrivo ancora poche righe perch\u00e8 ormai le lacrime scendono cos\u00ec copiose che non riesco pi\u00f9 a sopportarle. Credo che manger\u00f2 un cioccolatino. S\u00ec, anche il cioccolato aiuta l&#8217;umore, ma non fare come me e non mangiarne troppo: sei cos\u00ec bella! Approfitta del tuo lavoro che ti obbliga a relazionarti con l&#8217;esterno &#8211; \u00e8 una fortuna anche se oggi ti sembra una condanna &#8211; per uscire, uscire tantissimo. Il sole, cos\u00ec come passeggiare, aiutano tanto la mente. Ascolta la musica che ti piace. Goditi il vino, il cibo e qualunque cosa ti dia piacere. E accogli l&#8217;unica nota positiva di questa cosa orribile che ci \u00e8 capitata: ora sai quanto \u00e8 fragile la vita. Tutti diciamo che <\/span><span>perdere la vita \u00e8 un attimo, ma capiamo che \u00e8 un attimo davvero solo quando viviamo cose come questa. Essere consapevoli che non ci \u00e8 dato sapere quanto evolveremo ancora prima di cominciare a decadere, se sar\u00e0 un invecchiamento graduale o ci spaccheremo all&#8217;improvviso come una bottiglia che cade, ci aiuta a mettere prima noi al centro della nostra vita. E non \u00e8 affatto scontato o facile.<\/span><\/p>\n<p style=\"text-align: left;\"><span>Chi dice che pensare prima a s\u00e9 stessi \u00e8 da egoisti \u00e8 pi\u00f9 idiota di chi non capir\u00e0 i tuoi sbalzi d&#8217;umore o gli errori che inevitabilmente farai in questo periodo. Non avere paura di allontanare le persone tossiche per te, qualunque ruolo abbiano nella tua vita. Fare il possibile per vivere il tempo che si ha a disposizione come si desidera e non come gli altri si aspettano \u00e8 un diritto fondamentale di ogni individuo. Anche tuo e mio. Quindi non dimenticare mai che la vita \u00e8 imprevedibile e il nostro corpo \u00e8 una macchina meravigliosa, ma delicatissima: insegui i tuoi sogni e vivi come credi questa vita che ci \u00e8 stata donata dai nostri genitori. E ricorda che anche se il tempo con tuo pap\u00e0 non ti \u00e8 bastato, tu, come me, un pap\u00e0 che ti amava lo hai avuto.<\/span><span><\/span><\/p>\n<p style=\"text-align: left;\">Io me lo ripeto ogni giorno, quando cala la sera, e la sua voce rassicurante e bellissima mi manca da fermarmi il cuore.<span><\/span><\/p>\n<p style=\"text-align: justify;\"><span>Un abbraccio grande\ud83c\udf77<\/span><\/p>\n<p style=\"text-align: justify;\"><span>Chiara<\/span><\/p>[\/et_pb_text][et_pb_divider _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section]\n","protected":false},"excerpt":{"rendered":"<p>Cara Claudia Del Duca, ti scrivo perch\u00e8 non posso farne a meno e questa lettera non \u00e8 solo per te, ma per tutte quelle figlie innamorate dei loro pap\u00e0 che li hanno persi troppo presto come noi. Cara Claudia, ti scrivo perch\u00e8 non mi serve essere la tua migliore amica per sapere che adoravi tuo [&hellip;]<\/p>\n","protected":false},"author":49,"featured_media":283576,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"2880","footnotes":""},"categories":[516],"tags":[],"class_list":["post-283562","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-riflessioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.0 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Genuino Del Duca: la mia lettera a tua figlia Claudia | Perlage Suite<\/title>\n<meta name=\"description\" content=\"Genuino Del Duca: una morte che mi ha turbato, prima perch\u00e8 lo avevo visto solo pochi giorni fa, poi perch\u00e8 mi ha ricordato mio padre.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/perlagesuite.com\/en\/genuino-del-duca\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Genuino Del Duca: la mia lettera a tua figlia Claudia\" \/>\n<meta property=\"og:description\" content=\"Genuino Del Duca: una morte che mi ha turbato, prima perch\u00e8 lo avevo visto solo pochi giorni fa, poi perch\u00e8 mi ha ricordato mio padre.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/perlagesuite.com\/en\/genuino-del-duca\/\" \/>\n<meta property=\"og:site_name\" content=\"Perlage Suite\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/chiarabassiperlagesuite\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-22T12:22:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-22T12:54:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/perlagesuite.com\/wp-content\/uploads\/2022\/12\/Claudia-Genuino-Del-Duca.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Chiara Bassi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@perlagesuite\" \/>\n<meta name=\"twitter:site\" content=\"@perlagesuite\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Chiara Bassi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/genuino-del-duca\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/genuino-del-duca\\\/\"},\"author\":{\"name\":\"Chiara Bassi\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/person\\\/81b257517a1007c1a823318ac86c6013\"},\"headline\":\"Genuino Del Duca: la mia lettera a tua figlia Claudia\",\"datePublished\":\"2022-12-22T12:22:49+00:00\",\"dateModified\":\"2022-12-22T12:54:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/genuino-del-duca\\\/\"},\"wordCount\":1294,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/genuino-del-duca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Claudia-Genuino-Del-Duca.jpeg\",\"articleSection\":[\"Riflessioni\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/perlagesuite.com\\\/genuino-del-duca\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/genuino-del-duca\\\/\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/genuino-del-duca\\\/\",\"name\":\"Genuino Del Duca: la mia lettera a tua figlia Claudia | Perlage Suite\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/genuino-del-duca\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/genuino-del-duca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Claudia-Genuino-Del-Duca.jpeg\",\"datePublished\":\"2022-12-22T12:22:49+00:00\",\"dateModified\":\"2022-12-22T12:54:18+00:00\",\"description\":\"Genuino Del Duca: una morte che mi ha turbato, prima perch\u00e8 lo avevo visto solo pochi giorni fa, poi perch\u00e8 mi ha ricordato mio padre.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/genuino-del-duca\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/perlagesuite.com\\\/genuino-del-duca\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/genuino-del-duca\\\/#primaryimage\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Claudia-Genuino-Del-Duca.jpeg\",\"contentUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Claudia-Genuino-Del-Duca.jpeg\",\"width\":1080,\"height\":720,\"caption\":\"Claudia Genuino Del Duca\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/genuino-del-duca\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/perlagesuite.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Genuino Del Duca: la mia lettera a tua figlia Claudia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#website\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/\",\"name\":\"Perlage Suite\",\"description\":\"Il Wine Blog di Chiara Bassi\",\"publisher\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/perlagesuite.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#organization\",\"name\":\"Chiara Bassi\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Chiara-Bassi-sommelier-wine-blogger-logo.png\",\"contentUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Chiara-Bassi-sommelier-wine-blogger-logo.png\",\"width\":512,\"height\":512,\"caption\":\"Chiara Bassi\"},\"image\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/chiarabassiperlagesuite\",\"https:\\\/\\\/x.com\\\/perlagesuite\",\"https:\\\/\\\/www.instagram.com\\\/perlagesuite\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/person\\\/81b257517a1007c1a823318ac86c6013\",\"name\":\"Chiara Bassi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g\",\"caption\":\"Chiara Bassi\"},\"sameAs\":[\"https:\\\/\\\/perlagesuite.com\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Genuino Del Duca: my letter to your daughter Claudia | Perlage Suite","description":"Genuino Del Duca: a death that disturbed me, first because I had seen him only a few days ago, then because he reminded me of my father.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/perlagesuite.com\/en\/genuino-del-duca\/","og_locale":"en_GB","og_type":"article","og_title":"Genuino Del Duca: la mia lettera a tua figlia Claudia","og_description":"Genuino Del Duca: una morte che mi ha turbato, prima perch\u00e8 lo avevo visto solo pochi giorni fa, poi perch\u00e8 mi ha ricordato mio padre.","og_url":"https:\/\/perlagesuite.com\/en\/genuino-del-duca\/","og_site_name":"Perlage Suite","article_publisher":"https:\/\/www.facebook.com\/chiarabassiperlagesuite","article_published_time":"2022-12-22T12:22:49+00:00","article_modified_time":"2022-12-22T12:54:18+00:00","og_image":[{"width":1080,"height":720,"url":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2022\/12\/Claudia-Genuino-Del-Duca.jpeg","type":"image\/jpeg"}],"author":"Chiara Bassi","twitter_card":"summary_large_image","twitter_creator":"@perlagesuite","twitter_site":"@perlagesuite","twitter_misc":{"Written by":"Chiara Bassi","Estimated reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/perlagesuite.com\/genuino-del-duca\/#article","isPartOf":{"@id":"https:\/\/perlagesuite.com\/genuino-del-duca\/"},"author":{"name":"Chiara Bassi","@id":"https:\/\/perlagesuite.com\/#\/schema\/person\/81b257517a1007c1a823318ac86c6013"},"headline":"Genuino Del Duca: la mia lettera a tua figlia Claudia","datePublished":"2022-12-22T12:22:49+00:00","dateModified":"2022-12-22T12:54:18+00:00","mainEntityOfPage":{"@id":"https:\/\/perlagesuite.com\/genuino-del-duca\/"},"wordCount":1294,"commentCount":0,"publisher":{"@id":"https:\/\/perlagesuite.com\/#organization"},"image":{"@id":"https:\/\/perlagesuite.com\/genuino-del-duca\/#primaryimage"},"thumbnailUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2022\/12\/Claudia-Genuino-Del-Duca.jpeg","articleSection":["Riflessioni"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/perlagesuite.com\/genuino-del-duca\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/perlagesuite.com\/genuino-del-duca\/","url":"https:\/\/perlagesuite.com\/genuino-del-duca\/","name":"Genuino Del Duca: my letter to your daughter Claudia | Perlage Suite","isPartOf":{"@id":"https:\/\/perlagesuite.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/perlagesuite.com\/genuino-del-duca\/#primaryimage"},"image":{"@id":"https:\/\/perlagesuite.com\/genuino-del-duca\/#primaryimage"},"thumbnailUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2022\/12\/Claudia-Genuino-Del-Duca.jpeg","datePublished":"2022-12-22T12:22:49+00:00","dateModified":"2022-12-22T12:54:18+00:00","description":"Genuino Del Duca: a death that disturbed me, first because I had seen him only a few days ago, then because he reminded me of my father.","breadcrumb":{"@id":"https:\/\/perlagesuite.com\/genuino-del-duca\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/perlagesuite.com\/genuino-del-duca\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/perlagesuite.com\/genuino-del-duca\/#primaryimage","url":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2022\/12\/Claudia-Genuino-Del-Duca.jpeg","contentUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2022\/12\/Claudia-Genuino-Del-Duca.jpeg","width":1080,"height":720,"caption":"Claudia Genuino Del Duca"},{"@type":"BreadcrumbList","@id":"https:\/\/perlagesuite.com\/genuino-del-duca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/perlagesuite.com\/"},{"@type":"ListItem","position":2,"name":"Genuino Del Duca: la mia lettera a tua figlia Claudia"}]},{"@type":"WebSite","@id":"https:\/\/perlagesuite.com\/#website","url":"https:\/\/perlagesuite.com\/","name":"Perlage Suite","description":"Chiara Bassi's Wine Blog","publisher":{"@id":"https:\/\/perlagesuite.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/perlagesuite.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/perlagesuite.com\/#organization","name":"Chiara Bassi","url":"https:\/\/perlagesuite.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/perlagesuite.com\/#\/schema\/logo\/image\/","url":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2022\/03\/Chiara-Bassi-sommelier-wine-blogger-logo.png","contentUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2022\/03\/Chiara-Bassi-sommelier-wine-blogger-logo.png","width":512,"height":512,"caption":"Chiara Bassi"},"image":{"@id":"https:\/\/perlagesuite.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/chiarabassiperlagesuite","https:\/\/x.com\/perlagesuite","https:\/\/www.instagram.com\/perlagesuite\/"]},{"@type":"Person","@id":"https:\/\/perlagesuite.com\/#\/schema\/person\/81b257517a1007c1a823318ac86c6013","name":"Chiara Bassi","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g","caption":"Chiara Bassi"},"sameAs":["https:\/\/perlagesuite.com"]}]}},"_links":{"self":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/posts\/283562","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/comments?post=283562"}],"version-history":[{"count":0,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/posts\/283562\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/media\/283576"}],"wp:attachment":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/media?parent=283562"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/categories?post=283562"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/tags?post=283562"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}