{"id":29310,"date":"2021-05-30T00:29:34","date_gmt":"2021-05-29T23:29:34","guid":{"rendered":"https:\/\/perlagesuite.com\/?p=29310"},"modified":"2021-06-02T21:20:13","modified_gmt":"2021-06-02T20:20:13","slug":"bolgheri-un-gioiello-di-vino-scopri-podere-conca","status":"publish","type":"post","link":"https:\/\/perlagesuite.com\/en\/bolgheri-un-gioiello-di-vino-scopri-podere-conca\/","title":{"rendered":"Bolgheri: a jewel of a wine? Discover Podere Conca!"},"content":{"rendered":"\n[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||28px|||&#8221;][et_pb_row _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;]<p style=\"text-align: justify;\"><span>Avrei voluto raccontarti prima questa bellissima esperienza, ma sono stati davvero giorni di fuoco tra il lavoro e l&#8217;universit\u00e0! Eccomi finalmente a parlarti della seconda tappa del mio week end toscano e dell&#8217;azienda che forse mi ha fatto innamorare di pi\u00f9. Forse, non lo so, perch\u00e8 \u00e8 stata davvero tutta un&#8217;esperienza bellissima e ringrazio Maddalena Mazzeschi per questo. <strong>Podere Conca \u00e8 un gioiello incastonato in quel museo a cielo aperto che \u00e8 Bolgheri<\/strong>, un luogo che merita il rispetto di ogni winelovers. Altro che foto di culi all&#8217;aria, anche se di un certo spessore. Siamo in un&#8217;era dove la provocazione \u00e8 tornata di moda e certi miei colleghi osano mettere merda nei social a mo di Manzoni. No, non parlo di quello dei Promessi Sposi, piuttosto di quell&#8217;artista-fenomeno che nel 1961 sigill\u00f2 90 barattoli e li etichett\u00f2 con la scritta &#8220;<a href=\"https:\/\/it.wikipedia.org\/wiki\/Merda_d%27artista\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\"><strong>Merda d&#8217;artista<\/strong><\/span><\/a>. 30g&#8221; e poco pi\u00f9. Li battezz\u00f2 a 300g d&#8217;oro e voilat, l&#8217;opera d&#8217;arte \u00e8 servita. E nel 2016 un collezionista ha pagato il barattolo numero 69 la bellezza di una volta e mezzo casa mia. Comunque la loro merda fotografata piace, quindi per me hanno ragione loro, esattamente come aveva ragione Manzoni.<\/span><\/p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/05\/podere-conca-vino-bolgheri-vini-toscani-6.jpg&#8221; alt=&#8221;podere conca vino bolgheri vini toscani &#8221; title_text=&#8221;podere-conca-vino-bolgheri-vini-toscani-6&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; border_width_all=&#8221;3px&#8221; border_color_all=&#8221;gcid-65af285e-4bd3-4ea9-81b6-b2c2b9f89915&#8243; box_shadow_style=&#8221;preset3&#8243; box_shadow_color=&#8221;#000000&#8243; global_colors_info=&#8221;{%22gcid-65af285e-4bd3-4ea9-81b6-b2c2b9f89915%22:%91%22border_color_all%22%93}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;]<p style=\"text-align: justify;\"><span>Torniamo per\u00f2 a parlare di cose pi\u00f9 piacevoli e profumate come il vigneto giardino di Podere Conca. <strong>Podere Conca \u00e8 un casolare incantato con quelle tre finestre rosse cos\u00ec espressive e uniche da diventare un logo che mi \u00e8 piaciuto tantissimo<\/strong>. Non avevo mai visto un vigneto cos\u00ec bello come quello che circonda il casolare. Quanta cura e perfezione, quanta armonia tra natura e costruito!<\/span><span><\/span><\/p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/05\/podere-conca-vino-bolgheri-vini-toscani-4-1.jpg&#8221; alt=&#8221;podere conca vino bolgheri vini toscani &#8221; title_text=&#8221;podere-conca-vino-bolgheri-vini-toscani-4&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; border_width_all=&#8221;3px&#8221; border_color_all=&#8221;gcid-65af285e-4bd3-4ea9-81b6-b2c2b9f89915&#8243; box_shadow_style=&#8221;preset3&#8243; box_shadow_color=&#8221;#000000&#8243; global_colors_info=&#8221;{%22gcid-65af285e-4bd3-4ea9-81b6-b2c2b9f89915%22:%91%22border_color_all%22%93}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;]<blockquote>\n<p style=\"text-align: justify;\"><em>Un\u2019amicizia leg\u00f2 mia nonna materna, Graziella Cedraschi, donna prodigiosa e lungimirante, a Luciana Aloisi, madre di Livio e di Giulia, quest\u2019ultima sposa di Nicol\u00f2 Incisa della Rocchetta. Da l\u00ec inizi\u00f2 uno scambio di amore affettuoso che continua oggi con altri volti, altri nomi. Fu quindi quell\u2019amore, per primo, a indirizzare i miei nonni verso questa terra che in alcuni luoghi si lega all\u2019Africa che tanto rappresent\u00f2 le fortune e le tragedie dei primi protagonisti di Bolgheri.<\/em><\/p>\n<\/blockquote>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/05\/podere-conca-vino-bolgheri-vini-toscani-3.jpg&#8221; alt=&#8221;podere conca vino bolgheri vini toscani &#8221; title_text=&#8221;podere-conca-vino-bolgheri-vini-toscani-3&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; border_width_all=&#8221;3px&#8221; border_color_all=&#8221;gcid-65af285e-4bd3-4ea9-81b6-b2c2b9f89915&#8243; box_shadow_style=&#8221;preset3&#8243; global_colors_info=&#8221;{%22gcid-65af285e-4bd3-4ea9-81b6-b2c2b9f89915%22:%91%22border_color_all%22%93}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;]<blockquote>\n<p style=\"text-align: justify;\"><span><em>Ma inizi\u00f2 soprattutto l\u2019attaccamento a quei reami magici fatti di ulivi santificati e di vigneti divenuti sacri: quasi immortali. L\u2019amore suggell\u00f2 contratti di cessione e prolung\u00f2 il nostro vivere in Toscana. La casa di Bolgheri divenne il gioco delle nostre estati di bambini, divent\u00f2 la meta dei viaggi di noi adolescenti e il luogo preferito dove vivere il sole che da maremmano si fa globo di tutti i mondi\u2026 soprattutto fu teatro senza sipario delle amicizie pi\u00f9 franche.<\/em><\/span><\/p>\n<p style=\"text-align: right;\"><span><em><strong>Giovanni Gastel Jr<\/strong><\/em><\/span><\/p>\n<\/blockquote>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/05\/podere-conca-vino-bolgheri-vini-toscani-8.jpg&#8221; alt=&#8221;podere conca vino bolgheri vini toscani &#8221; title_text=&#8221;podere-conca-vino-bolgheri-vini-toscani-8&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; border_width_all=&#8221;3px&#8221; border_color_all=&#8221;gcid-65af285e-4bd3-4ea9-81b6-b2c2b9f89915&#8243; box_shadow_style=&#8221;preset3&#8243; global_colors_info=&#8221;{%22gcid-65af285e-4bd3-4ea9-81b6-b2c2b9f89915%22:%91%22border_color_all%22%93}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;]<p style=\"text-align: justify;\"><span>Ci sono piante che sembrano sculture, sacre anch&#8217;esse in queste terre che raccontano la storia di un luogo divenuto immortale grazie al lavoro di queste donne e questi uomini cos\u00ec speciali. S\u00ec, speciali, perch\u00e8 custodire un gioiello \u00e8 normale, ma crearlo e renderlo cos\u00ec prezioso \u00e8 proprio solo di menti illuminate. E io mi auguro nel tempo di essere all&#8217;altezza di fare la stessa cosa con le mie parole e la mia volont\u00e0 di farle riecheggiare nel cuore di chi sa amare il vino e il cibo profondamente.<\/span><\/p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/05\/podere-conca-vino-bolgheri-vini-toscani-7.jpg&#8221; alt=&#8221;podere conca vino bolgheri vini toscani &#8221; title_text=&#8221;podere-conca-vino-bolgheri-vini-toscani-7&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; border_width_all=&#8221;3px&#8221; border_color_all=&#8221;gcid-65af285e-4bd3-4ea9-81b6-b2c2b9f89915&#8243; box_shadow_style=&#8221;preset3&#8243; global_colors_info=&#8221;{%22gcid-65af285e-4bd3-4ea9-81b6-b2c2b9f89915%22:%91%22border_color_all%22%93}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;]<p style=\"text-align: justify;\"><span>Dopo aver visitato i vigneti siamo giunti in cantina, dove ho trovato queste splendide botti in cemento tulip rosse. Ricordo di averle viste in tantissime cantine di Bordeaux, da Ch\u00e2teau Beychevelle a Ch\u00e2teau Kirwan, ma in entrambi erano di colore grigio. Le adoro, come adoro i vini che fanno un passaggio in cemento.<\/span><\/p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/05\/podere-conca-vino-bolgheri-vini-toscani-9.jpg&#8221; alt=&#8221;podere conca vino bolgheri vini toscani &#8221; title_text=&#8221;podere-conca-vino-bolgheri-vini-toscani-9&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; border_width_all=&#8221;3px&#8221; border_color_all=&#8221;gcid-65af285e-4bd3-4ea9-81b6-b2c2b9f89915&#8243; box_shadow_style=&#8221;preset3&#8243; global_colors_info=&#8221;{%22gcid-65af285e-4bd3-4ea9-81b6-b2c2b9f89915%22:%91%22border_color_all%22%93}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;]<p style=\"text-align: justify;\"><span>Podere Conca conduce i vigneti e l&#8217;uliveta secondo le antiche tradizioni e l&#8217;agricoltura biologica. C&#8217;\u00e8 tanto amore e tanta cura in ogni dettaglio e l&#8217;approccio scientifico di Silvia Cirri, CEO di Podere Conca, si vede anche e soprattutto nelle scelte fatte in cantina.<\/span><\/p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/05\/podere-conca-vino-bolgheri-vini-toscani-10.jpg&#8221; alt=&#8221;podere conca vino bolgheri vini toscani &#8221; title_text=&#8221;podere-conca-vino-bolgheri-vini-toscani-10&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; border_width_all=&#8221;3px&#8221; border_color_all=&#8221;gcid-65af285e-4bd3-4ea9-81b6-b2c2b9f89915&#8243; box_shadow_style=&#8221;preset3&#8243; global_colors_info=&#8221;{%22gcid-65af285e-4bd3-4ea9-81b6-b2c2b9f89915%22:%91%22border_color_all%22%93}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;]<p style=\"text-align: justify;\"><span>Questa perfezione non pu\u00f2 essere casuale. E infatti <strong>il cuore \u00e8 lei,<\/strong> <strong>Silvia Cirri<\/strong>, CEO e socio di maggioranza di questo gioiellino di Bolgheri nel fine settimana e primario di Anestesia, Rianimazione e Terapia Intensiva dell\u2019Istituto Clinico Sant\u2019Ambrogio del Gruppo San Donato di Milano durante la settimana. Nel frattempo \u00e8 riuscita anche a fondare una Onlus per i bambini cardiopatici nel mondo. Io sono semplicemente ammirata. Silvia non \u00e8 sola: con lei c&#8217;\u00e8 un <strong>gentiluomo di campagna suo grande amico Livio Aloisi<\/strong>, che prima di abbracciare questa avventura ha lavorato a Bolgheri con il cognato Nicol\u00f2 Incisa della Rocchetta e suo padre Mario, produttori del famoso Sassicaia. E poi ci sono il nipote <strong>Giovanni Gastel Jr<\/strong>, nipote anche del celebre fotografo e del regista Luchino Visconti. La figlia di Silvia, <strong>Virginia Archinto Rocca Saporiti<\/strong> non ha solo un nome importante tra le famiglie della nobilt\u00e0 milanese, ma \u00e8 anche la Content Producer Manager di Bulgari e per Podere Conca cura l&#8217;immagine. E la figlia di Livio, <strong>Flavia Aloisi<\/strong>, una donna splendida che in questa foto \u00e8 tra Silvia e mio marito Francesco. Infine <strong>Manuela Gastel<\/strong>, moglie di Giovanni Gastel Jr, si occupa del commercio estero. Insomma, <strong>Podere Conca \u00e8 la storia di una grande amicizia, quella di Silvia Cirri e Livio Aloisi e delle loro famiglie che si intrecciano<\/strong>.<\/span><span><\/span><\/p>\n<p style=\"text-align: justify;\"><span>Poi ci sono i collaboratori, tra cui cito <strong>Linda Franceschi, agronoma<\/strong> e <strong>Simonetta Carboneschi, la chef<\/strong> che coccola Silvia quando scende in cantina&#8230; e ha coccolato anche noi!<\/span><span><\/span><\/p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/05\/podere-conca-vino-bolgheri-vini-toscani-11.jpg&#8221; alt=&#8221;podere conca vino bolgheri vini toscani &#8221; title_text=&#8221;podere-conca-vino-bolgheri-vini-toscani-11&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; border_width_all=&#8221;3px&#8221; border_color_all=&#8221;gcid-65af285e-4bd3-4ea9-81b6-b2c2b9f89915&#8243; box_shadow_style=&#8221;preset3&#8243; global_colors_info=&#8221;{%22gcid-65af285e-4bd3-4ea9-81b6-b2c2b9f89915%22:%91%22border_color_all%22%93}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;]<p style=\"text-align: justify;\">Dopo la visita in cantina siamo tornati al casolare per il pranzo e la piscina mi faceva una voglia&#8230; io ormai sono viziata, nel residence dove vivo abbiamo una piscina splendida vista lago e ormai ammetto di non poterci vivere senza. Attualmente si sta riempiendo perch\u00e8 abbiamo cambiato l&#8217;acqua e fino a marted\u00ec dovr\u00f2 resistere dal lanciarmici dentro!<\/p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/05\/podere-conca-vino-bolgheri-vini-toscani-2.jpg&#8221; alt=&#8221;podere conca vino bolgheri vini toscani&#8221; title_text=&#8221;podere-conca-vino-bolgheri-vini-toscani-2&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; border_width_all=&#8221;3px&#8221; border_color_all=&#8221;gcid-65af285e-4bd3-4ea9-81b6-b2c2b9f89915&#8243; box_shadow_style=&#8221;preset3&#8243; global_colors_info=&#8221;{%22gcid-65af285e-4bd3-4ea9-81b6-b2c2b9f89915%22:%91%22border_color_all%22%93}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;]<p>Iscriviti alla mia newsletter o scorri la pagina per continuare la lettura dell&#8217;articolo! <span>\ud83d\ude09<\/span><\/p>[\/et_pb_text][et_pb_signup provider=&#8221;mailpoet&#8221; mailpoet_list=&#8221;PEPEblu|49&#8243; success_message=&#8221;Controlla la tua e-mail: hai appena ricevuto un mio messaggio per confermare la tua iscrizione! Se non lo visualizzi controlla in spam o nella cartella %22promozioni%22 di Gmail. Grazie e a presto!&#8221; title=&#8221;Ti piace questo contenuto?&#8221; button_text=&#8221;Iscriviti subito!&#8221; description=&#8221;<p style=%22text-align: justify;%22>Iscriviti alla mia newsletter per non perderti nessun nuovo articolo del mio blog!<\/p>\n<p style=%22text-align: justify;%22>Non ti invier\u00f2 SPAM, ma solo la notifica dei nuovi articoli! Di tanto in tanto potrai ricevere anche qualche coupon per acquistare vino o partecipare ad eventi con condizioni speciali riservate ai lettori del mio blog!<\/p>\n<p style=%22text-align: justify;%22>Cheers \ud83e\udd29\ud83e\udd42<\/p>\n&#8221; footer_content=&#8221;Iscrivendoti accetti le condizioni della <a href=%22https:\/\/perlagesuite.com\/privacy-2\/%22 data-et-target-link=%22_blank%22 rel=%22noopener noreferrer%22><span style=%22text-decoration: underline;%22><strong>Privacy<\/strong><\/span><\/a> di Perlage Suite.&#8221; _builder_version=&#8221;4.7.7&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Delius Unicase|700|||||||&#8221; header_font_size=&#8221;22px&#8221; body_font=&#8221;Delius||||||||&#8221; background_color=&#8221;#008c96&#8243; box_shadow_style=&#8221;preset3&#8243; box_shadow_color=&#8221;rgba(0,140,150,0.6)&#8221; global_module=&#8221;27234&#8243;][\/et_pb_signup][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;]<p style=\"text-align: justify;\"><span>Ultimamente so di dirlo spesso, ma i vini bianchi che mi stanno convincendo di pi\u00f9 &#8211; salvo rare eccezioni &#8211; sono quelle che esulano dalle terre normalmente vocate a questa tipologia. Ed \u00e8 cos\u00ec che spicca la Toscana, nel firmamento del vino bianco italiano e regala perle inaspettate. Elleboro \u00e8 esattamente questo, con i suoi profumi decisi in cui le note agrumate ed &#8220;albicoccose&#8221; del viognier incontrano i profumi caratteristici del sauvignon per poi smussarsi nella burrosit\u00e0 dello chardonnay. Sapido al punto giusto, strutturato quanto basta per donargli grande versatilit\u00e0 di abbinamento. E come il Bolgheri rosso Agapanto costa troppo poco per quanto \u00e8 buono.<\/span><span><\/span><\/p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/05\/podere-conca-vino-bolgheri-vini-toscani-12.jpg&#8221; alt=&#8221;podere conca vino bolgheri vini toscani &#8221; title_text=&#8221;podere-conca-vino-bolgheri-vini-toscani-12&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; border_width_all=&#8221;3px&#8221; border_color_all=&#8221;gcid-65af285e-4bd3-4ea9-81b6-b2c2b9f89915&#8243; box_shadow_style=&#8221;preset3&#8243; global_colors_info=&#8221;{%22gcid-65af285e-4bd3-4ea9-81b6-b2c2b9f89915%22:%91%22border_color_all%22%93}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;]<p style=\"text-align: justify;\"><span><\/span>Agapanto \u00e8 un piccolo gioiello di vino Bolgheri e quando ho scoperto che costa 18 \u20ac non potevo crederci. Ti ho gi\u00e0 parlato di questo vino straordinario in <a href=\"https:\/\/perlagesuite.com\/bolgheri-podere-conca-il-rosso-non-sta-bene-con-tutto-podcast\/\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\"><strong>questo articolo<\/strong><\/span><\/a> un paio di mesi fa, quando l&#8217;ho abbinato a una bistecca meravigliosa. Mi piace tantissimo! Anche con questo secondo si \u00e8 abbinato magnificamente e in particolare le verdure erano deliziose!<span><\/span><\/p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/05\/podere-conca-vino-bolgheri-vini-toscani-13.jpg&#8221; alt=&#8221;podere conca vino bolgheri vini toscani &#8221; title_text=&#8221;podere-conca-vino-bolgheri-vini-toscani-13&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; border_width_all=&#8221;3px&#8221; border_color_all=&#8221;gcid-65af285e-4bd3-4ea9-81b6-b2c2b9f89915&#8243; box_shadow_style=&#8221;preset3&#8243; global_colors_info=&#8221;{%22gcid-65af285e-4bd3-4ea9-81b6-b2c2b9f89915%22:%91%22border_color_all%22%93}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;]<p style=\"text-align: justify;\"><span>Dopo un pranzo squisito vedere una cheese cake al cioccolato arrivare \u00e8 una grande gioia! Poi era davvero squisita e ne ho mangiate tre fette. E l&#8217;avrei sbranata letteralmente tutta! Fantastica! La panna freschissima e la ganache al cioccolato perfetta. Un dolce semplice eseguito a regola d&#8217;arte. A quando un vino passito da abbinarci? \ud83d\ude0d<\/span><\/p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/05\/podere-conca-vino-bolgheri-vini-toscani-5.jpg&#8221; alt=&#8221;podere conca vino bolgheri vini toscani &#8221; title_text=&#8221;podere-conca-vino-bolgheri-vini-toscani-5&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; border_width_all=&#8221;3px&#8221; border_color_all=&#8221;gcid-65af285e-4bd3-4ea9-81b6-b2c2b9f89915&#8243; box_shadow_style=&#8221;preset3&#8243; global_colors_info=&#8221;{%22gcid-65af285e-4bd3-4ea9-81b6-b2c2b9f89915%22:%91%22border_color_all%22%93}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;]<p style=\"text-align: justify;\"><span>Grazie di cuore a tutte queste splendide Donne per avermi regalato un compleanno meraviglioso, in un vigneto giardino, del mio colore preferito e con il mio dolce preferito. <a href=\"https:\/\/www.podereconcabolgheri.it\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\"><strong>Podere Conca<\/strong><\/span><\/a> \u00e8 davvero un gioiello nel cuore dei vini toscani che merita di essere scoperto da quanti pi\u00f9 winelovers possibili.<\/span><\/p>\n<p style=\"text-align: justify;\"><span>Cheers \ud83c\udf77<\/span><\/p>\n<p style=\"text-align: justify;\"><span>Chiara<\/span><\/p>[\/et_pb_text][et_pb_divider color=&#8221;gcid-65af285e-4bd3-4ea9-81b6-b2c2b9f89915&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{%22gcid-65af285e-4bd3-4ea9-81b6-b2c2b9f89915%22:%91%22color%22%93}&#8221;][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.0.6&#8243; global_module=&#8221;21425&#8243;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.0.6&#8243;][et_pb_wc_images product=&#8221;10582&#8243; show_product_gallery=&#8221;off&#8221; _builder_version=&#8221;4.9.4&#8243;][\/et_pb_wc_images][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.0.6&#8243;][et_pb_wc_title product=&#8221;10582&#8243; _builder_version=&#8221;4.0.6&#8243;][\/et_pb_wc_title][et_pb_text _builder_version=&#8221;4.9.4&#8243; text_font=&#8221;Delius Unicase||||||||&#8221;]<p style=\"text-align: justify;\"><span style=\"color: #ff0000;\"><span style=\"caret-color: #ff0000;\"><b>Tutti i miei appunti sul vino e sul cibo in un solo libro.<\/b><\/span><\/span><\/p>[\/et_pb_text][et_pb_wc_rating product=&#8221;10582&#8243; _builder_version=&#8221;4.0.6&#8243;][\/et_pb_wc_rating][et_pb_wc_price product=&#8221;10582&#8243; _builder_version=&#8221;4.0.6&#8243;][\/et_pb_wc_price][et_pb_wc_add_to_cart product=&#8221;10582&#8243; _builder_version=&#8221;4.0.6&#8243;][\/et_pb_wc_add_to_cart][et_pb_text _builder_version=&#8221;4.9.4&#8243; text_font=&#8221;Delius Unicase||||||||&#8221;]<p style=\"text-align: justify;\"><span style=\"color: #ff0000;\"><strong>IN OMAGGIO<\/strong><\/span>, solo per chi compra il mio libro su questo blog, una copia della <strong>Prima Edizione da Collezione della mia Guida Vini Spumanti &#8220;500 Bolle in 500&#8221;<\/strong>, prezzo di copertina 25,30 \u20ac. [Fino ad esaurimento scorte]<\/p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]\n","protected":false},"excerpt":{"rendered":"<p>Avrei voluto raccontarti prima questa bellissima esperienza, ma sono stati davvero giorni di fuoco tra il lavoro e l&#8217;universit\u00e0! Eccomi finalmente a parlarti della seconda tappa del mio week end toscano e dell&#8217;azienda che forse mi ha fatto innamorare di pi\u00f9. Forse, non lo so, perch\u00e8 \u00e8 stata davvero tutta un&#8217;esperienza bellissima e ringrazio Maddalena [&hellip;]<\/p>\n","protected":false},"author":49,"featured_media":29316,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"2880","footnotes":""},"categories":[501],"tags":[],"class_list":["post-29310","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ristoranti"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.0 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Bolgheri: un gioiello di vino? Scopri Podere Conca! - Perlage Suite<\/title>\n<meta name=\"description\" content=\"Il mio compleanno l&#039;ho festeggiato a Podere Conca una cantina speciale in un monumento alla storia enologica italiana: Bolgheri.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/perlagesuite.com\/en\/bolgheri-un-gioiello-di-vino-scopri-podere-conca\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bolgheri: un gioiello di vino? Scopri Podere Conca!\" \/>\n<meta property=\"og:description\" content=\"Il mio compleanno l&#039;ho festeggiato a Podere Conca una cantina speciale in un monumento alla storia enologica italiana: Bolgheri.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/perlagesuite.com\/en\/bolgheri-un-gioiello-di-vino-scopri-podere-conca\/\" \/>\n<meta property=\"og:site_name\" content=\"Perlage Suite\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/chiarabassiperlagesuite\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-29T23:29:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-02T20:20:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/05\/podere-conca-vino-bolgheri-vini-toscani-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Chiara Bassi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@perlagesuite\" \/>\n<meta name=\"twitter:site\" content=\"@perlagesuite\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Chiara Bassi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/bolgheri-un-gioiello-di-vino-scopri-podere-conca\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/bolgheri-un-gioiello-di-vino-scopri-podere-conca\\\/\"},\"author\":{\"name\":\"Chiara Bassi\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/person\\\/81b257517a1007c1a823318ac86c6013\"},\"headline\":\"Bolgheri: un gioiello di vino? Scopri Podere Conca!\",\"datePublished\":\"2021-05-29T23:29:34+00:00\",\"dateModified\":\"2021-06-02T20:20:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/bolgheri-un-gioiello-di-vino-scopri-podere-conca\\\/\"},\"wordCount\":2603,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/bolgheri-un-gioiello-di-vino-scopri-podere-conca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/podere-conca-vino-bolgheri-vini-toscani-1.jpg\",\"articleSection\":[\"Ristoranti\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/perlagesuite.com\\\/bolgheri-un-gioiello-di-vino-scopri-podere-conca\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/bolgheri-un-gioiello-di-vino-scopri-podere-conca\\\/\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/bolgheri-un-gioiello-di-vino-scopri-podere-conca\\\/\",\"name\":\"Bolgheri: un gioiello di vino? Scopri Podere Conca! - Perlage Suite\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/bolgheri-un-gioiello-di-vino-scopri-podere-conca\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/bolgheri-un-gioiello-di-vino-scopri-podere-conca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/podere-conca-vino-bolgheri-vini-toscani-1.jpg\",\"datePublished\":\"2021-05-29T23:29:34+00:00\",\"dateModified\":\"2021-06-02T20:20:13+00:00\",\"description\":\"Il mio compleanno l'ho festeggiato a Podere Conca una cantina speciale in un monumento alla storia enologica italiana: Bolgheri.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/bolgheri-un-gioiello-di-vino-scopri-podere-conca\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/perlagesuite.com\\\/bolgheri-un-gioiello-di-vino-scopri-podere-conca\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/bolgheri-un-gioiello-di-vino-scopri-podere-conca\\\/#primaryimage\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/podere-conca-vino-bolgheri-vini-toscani-1.jpg\",\"contentUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/podere-conca-vino-bolgheri-vini-toscani-1.jpg\",\"width\":1080,\"height\":720,\"caption\":\"podere conca vino bolgheri vini toscani\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/bolgheri-un-gioiello-di-vino-scopri-podere-conca\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/perlagesuite.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bolgheri: un gioiello di vino? Scopri Podere Conca!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#website\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/\",\"name\":\"Perlage Suite\",\"description\":\"Il Wine Blog di Chiara Bassi\",\"publisher\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/perlagesuite.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#organization\",\"name\":\"Chiara Bassi\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Chiara-Bassi-sommelier-wine-blogger-logo.png\",\"contentUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Chiara-Bassi-sommelier-wine-blogger-logo.png\",\"width\":512,\"height\":512,\"caption\":\"Chiara Bassi\"},\"image\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/chiarabassiperlagesuite\",\"https:\\\/\\\/x.com\\\/perlagesuite\",\"https:\\\/\\\/www.instagram.com\\\/perlagesuite\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/person\\\/81b257517a1007c1a823318ac86c6013\",\"name\":\"Chiara Bassi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g\",\"caption\":\"Chiara Bassi\"},\"sameAs\":[\"https:\\\/\\\/perlagesuite.com\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Bolgheri: a jewel of a wine? Discover Podere Conca! - Perlage Suite","description":"I celebrated my birthday at Podere Conca a special winery in a monument to Italian wine history: Bolgheri.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/perlagesuite.com\/en\/bolgheri-un-gioiello-di-vino-scopri-podere-conca\/","og_locale":"en_GB","og_type":"article","og_title":"Bolgheri: un gioiello di vino? Scopri Podere Conca!","og_description":"Il mio compleanno l'ho festeggiato a Podere Conca una cantina speciale in un monumento alla storia enologica italiana: Bolgheri.","og_url":"https:\/\/perlagesuite.com\/en\/bolgheri-un-gioiello-di-vino-scopri-podere-conca\/","og_site_name":"Perlage Suite","article_publisher":"https:\/\/www.facebook.com\/chiarabassiperlagesuite","article_published_time":"2021-05-29T23:29:34+00:00","article_modified_time":"2021-06-02T20:20:13+00:00","og_image":[{"width":1080,"height":720,"url":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/05\/podere-conca-vino-bolgheri-vini-toscani-1.jpg","type":"image\/jpeg"}],"author":"Chiara Bassi","twitter_card":"summary_large_image","twitter_creator":"@perlagesuite","twitter_site":"@perlagesuite","twitter_misc":{"Written by":"Chiara Bassi","Estimated reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/perlagesuite.com\/bolgheri-un-gioiello-di-vino-scopri-podere-conca\/#article","isPartOf":{"@id":"https:\/\/perlagesuite.com\/bolgheri-un-gioiello-di-vino-scopri-podere-conca\/"},"author":{"name":"Chiara Bassi","@id":"https:\/\/perlagesuite.com\/#\/schema\/person\/81b257517a1007c1a823318ac86c6013"},"headline":"Bolgheri: un gioiello di vino? Scopri Podere Conca!","datePublished":"2021-05-29T23:29:34+00:00","dateModified":"2021-06-02T20:20:13+00:00","mainEntityOfPage":{"@id":"https:\/\/perlagesuite.com\/bolgheri-un-gioiello-di-vino-scopri-podere-conca\/"},"wordCount":2603,"commentCount":0,"publisher":{"@id":"https:\/\/perlagesuite.com\/#organization"},"image":{"@id":"https:\/\/perlagesuite.com\/bolgheri-un-gioiello-di-vino-scopri-podere-conca\/#primaryimage"},"thumbnailUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/05\/podere-conca-vino-bolgheri-vini-toscani-1.jpg","articleSection":["Ristoranti"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/perlagesuite.com\/bolgheri-un-gioiello-di-vino-scopri-podere-conca\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/perlagesuite.com\/bolgheri-un-gioiello-di-vino-scopri-podere-conca\/","url":"https:\/\/perlagesuite.com\/bolgheri-un-gioiello-di-vino-scopri-podere-conca\/","name":"Bolgheri: a jewel of a wine? Discover Podere Conca! - Perlage Suite","isPartOf":{"@id":"https:\/\/perlagesuite.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/perlagesuite.com\/bolgheri-un-gioiello-di-vino-scopri-podere-conca\/#primaryimage"},"image":{"@id":"https:\/\/perlagesuite.com\/bolgheri-un-gioiello-di-vino-scopri-podere-conca\/#primaryimage"},"thumbnailUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/05\/podere-conca-vino-bolgheri-vini-toscani-1.jpg","datePublished":"2021-05-29T23:29:34+00:00","dateModified":"2021-06-02T20:20:13+00:00","description":"I celebrated my birthday at Podere Conca a special winery in a monument to Italian wine history: Bolgheri.","breadcrumb":{"@id":"https:\/\/perlagesuite.com\/bolgheri-un-gioiello-di-vino-scopri-podere-conca\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/perlagesuite.com\/bolgheri-un-gioiello-di-vino-scopri-podere-conca\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/perlagesuite.com\/bolgheri-un-gioiello-di-vino-scopri-podere-conca\/#primaryimage","url":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/05\/podere-conca-vino-bolgheri-vini-toscani-1.jpg","contentUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/05\/podere-conca-vino-bolgheri-vini-toscani-1.jpg","width":1080,"height":720,"caption":"podere conca vino bolgheri vini toscani"},{"@type":"BreadcrumbList","@id":"https:\/\/perlagesuite.com\/bolgheri-un-gioiello-di-vino-scopri-podere-conca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/perlagesuite.com\/"},{"@type":"ListItem","position":2,"name":"Bolgheri: un gioiello di vino? Scopri Podere Conca!"}]},{"@type":"WebSite","@id":"https:\/\/perlagesuite.com\/#website","url":"https:\/\/perlagesuite.com\/","name":"Perlage Suite","description":"Chiara Bassi's Wine Blog","publisher":{"@id":"https:\/\/perlagesuite.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/perlagesuite.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/perlagesuite.com\/#organization","name":"Chiara Bassi","url":"https:\/\/perlagesuite.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/perlagesuite.com\/#\/schema\/logo\/image\/","url":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2022\/03\/Chiara-Bassi-sommelier-wine-blogger-logo.png","contentUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2022\/03\/Chiara-Bassi-sommelier-wine-blogger-logo.png","width":512,"height":512,"caption":"Chiara Bassi"},"image":{"@id":"https:\/\/perlagesuite.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/chiarabassiperlagesuite","https:\/\/x.com\/perlagesuite","https:\/\/www.instagram.com\/perlagesuite\/"]},{"@type":"Person","@id":"https:\/\/perlagesuite.com\/#\/schema\/person\/81b257517a1007c1a823318ac86c6013","name":"Chiara Bassi","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g","caption":"Chiara Bassi"},"sameAs":["https:\/\/perlagesuite.com"]}]}},"_links":{"self":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/posts\/29310","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/comments?post=29310"}],"version-history":[{"count":0,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/posts\/29310\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/media\/29316"}],"wp:attachment":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/media?parent=29310"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/categories?post=29310"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/tags?post=29310"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}