{"id":29647,"date":"2021-06-24T16:11:18","date_gmt":"2021-06-24T15:11:18","guid":{"rendered":"https:\/\/perlagesuite.com\/?p=29647"},"modified":"2021-07-26T13:41:57","modified_gmt":"2021-07-26T12:41:57","slug":"autoctono-si-nasce-2021-i-10-vini-bianchi-che-mi-sono-piaciuti-di-piu","status":"publish","type":"post","link":"https:\/\/perlagesuite.com\/en\/autoctono-si-nasce-2021-i-10-vini-bianchi-che-mi-sono-piaciuti-di-piu\/","title":{"rendered":"Autoctono si nasce 2021: the 10 white wines I liked best"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.9.7&#8243; _module_preset=&#8221;default&#8221;][et_pb_row _builder_version=&#8221;4.9.7&#8243; _module_preset=&#8221;default&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.9.7&#8243; _module_preset=&#8221;default&#8221;][et_pb_text _builder_version=&#8221;4.9.7&#8243; _module_preset=&#8221;default&#8221;]<\/p>\n<p style=\"text-align: justify;\"><strong>Autoctono si nasce 2021 di Go Wine<\/strong> \u00e8 uno degli eventi che da sempre mi piace di pi\u00f9. Ci sono tante chicche interessanti e l&#8217;anteprima per la stampa \u00e8 sempre &#8220;a misura&#8221; di degustatore, ovvero riesco a prendere tutti i miei appunti serenamente. Purtroppo la degustazione su turni non mi permetteva di assaggiare tutto pertanto, visto che normalmente d\u00f2 sempre pi\u00f9 spazio alle bollicine soprattutto metodo classico, per questa <strong>edizione 2021 a Milano<\/strong> ho deciso di prediligere i vini bianchi. E li ho assaggiati tutti, davvero tutti! Ho sforato di qualche minuto nel tempo massimo consentito ma orgogliosamente ci sono riuscita! Non solo, ho stilato una vera classifica di degustazione dei vini che mi sono piaciuti di pi\u00f9. Ti chiedo di leggerla con uno sguardo emozionale perch\u00e8, essendo vini diversi di regioni diverse ed elaborati con vitigni autoctoni diversi non posso certo fare paragoni. Considerala quindi puro piacere soggettivo del mio palato!<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.9.7&#8243; _module_preset=&#8221;default&#8221; header_3_font=&#8221;Delius Unicase|700|||||||&#8221; header_3_font_size=&#8221;18px&#8221;]<\/p>\n<h3 style=\"text-align: justify;\">#1 Autoctono si nasce 2021: &#8220;Ensemblao&#8221; 2017, La source<\/h3>\n<p style=\"text-align: justify;\"><strong>Appunti di degustazione<\/strong>. Si presenta di un bellissimo colore giallo oro intenso e brillante. Al naso ricorda un gewurztraminer alsaziano ed \u00e8 semplicemente pazzesco. Si abbina magnificamente con le ostriche e i formaggi erborinati.<\/p>\n<p style=\"text-align: justify;\"><strong>Vitigno autoctono<\/strong>. <strong>Moscato<\/strong>, <strong>gew\u00fcrztraminer<\/strong> e <strong>m\u00fcller-thurgau<\/strong> si incontrano per creare un capolavoro. Non sono proprio vitigni autoctoni della Valle d&#8217;Aosta, ma il moscato bianco e il m\u00fcller-thurgau sono cos\u00ec radicati da lungo tempo nella regione da potersi ormai definire quasi autoctoni.<\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/06\/autoctono-si-nasce-go-wine-la-source.jpg&#8221; alt=&#8221;autoctono si nasce go wine la source&#8221; title_text=&#8221;autoctono-si-nasce-go-wine-la-source&#8221; _builder_version=&#8221;4.9.7&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|8px|8px|8px|8px&#8221; border_width_all=&#8221;3px&#8221; border_color_all=&#8221;gcid-65af285e-4bd3-4ea9-81b6-b2c2b9f89915&#8243; box_shadow_style=&#8221;preset3&#8243; global_colors_info=&#8221;{%22gcid-65af285e-4bd3-4ea9-81b6-b2c2b9f89915%22:%91%22border_color_all%22%93}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.9.7&#8243; _module_preset=&#8221;default&#8221; header_3_font=&#8221;Delius Unicase|700|||||||&#8221; header_3_font_size=&#8221;18px&#8221;]<\/p>\n<h3 style=\"text-align: justify;\">#2 Autoctono si nasce 2021: &#8220;Incompreso&#8221; 2020, Ca ed Curen<\/h3>\n<p style=\"text-align: justify;\"><strong>Appunti di degustazione<\/strong>.\u00a0Giallo paglierino scarico e brillante. Al naso ha note pi\u00f9 da sauvignon che da moscato. Si arricchisce di pesca sciroppata, pera e cioccolato bianco. In bocca \u00e8 equilibrato coerente fresco e piuttosto sapido.<\/p>\n<p style=\"text-align: justify;\"><strong>Vitigno autoctono<\/strong>. Il <strong>moscato<\/strong> \u00e8 un vitigno aromatico a bacca bianca autoctono del Piemonte.<\/p>\n<p style=\"text-align: justify;\">N.B Il 23 gennaio 2020 a Autoctono si nasce avevo scelto questo vino tra i 5 che mi erano piaciuti di pi\u00f9. Scopri le altre chicche <a href=\"https:\/\/perlagesuite.com\/autoctono-si-nasce-2020-gowine\/\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\"><strong>QUI<\/strong><\/span><\/a>.<\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/06\/autoctono-si-nasce-go-wine-ca-ed-curen.jpg&#8221; alt=&#8221;autoctono si nasce go wine ca ed curen&#8221; title_text=&#8221;autoctono-si-nasce-go-wine-ca-ed-curen&#8221; _builder_version=&#8221;4.9.7&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|8px|8px|8px|8px&#8221; border_width_all=&#8221;3px&#8221; border_color_all=&#8221;gcid-65af285e-4bd3-4ea9-81b6-b2c2b9f89915&#8243; box_shadow_style=&#8221;preset3&#8243; global_colors_info=&#8221;{%22gcid-65af285e-4bd3-4ea9-81b6-b2c2b9f89915%22:%91%22border_color_all%22%93}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.9.7&#8243; _module_preset=&#8221;default&#8221; header_3_font=&#8221;Delius Unicase|700|||||||&#8221; header_3_font_size=&#8221;18px&#8221;]<\/p>\n<h3 style=\"text-align: justify;\">#3 Autoctono si nasce 2021: &#8220;Telos Bianco&#8221; 2019, Tenuta Sant&#8217;Antonio<\/h3>\n<p style=\"text-align: justify;\"><strong>Appunti di degustazione<\/strong>. Giallo paglierino con riflessi dorati, brillante e consistente. Al naso \u00e8 intenso, profumatissimo e molto elegante. Note di frutto della passione, arancia rossa, cioccolato bianco e basilico greco. In bocca \u00e8 coerente, con una grande spalla acida, sapidit\u00e0 e tanta struttura. Lungo finale agrumato.<\/p>\n<p style=\"text-align: justify;\"><strong>Vitigno autoctono<\/strong>. La <strong>garganega<\/strong> \u00e8 il vitigno a bacca bianca autoctono delle province di Verona e Vicenza. Una curiosit\u00e0? Studi del DNA hanno evidenziato che un suo clone \u00e8 identico alla Malvasia de Manresa, un vitigno spagnolo praticamente estinto.<\/p>\n<p style=\"text-align: justify;\">N.B. Il 31 maggio 2019 ho fatto una <a href=\"https:\/\/perlagesuite.com\/tenuta-santantonio-una-verticale-di-telos-spettacolare\/\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\"><strong>verticale di Telos spettacolare<\/strong><\/span><\/a>, dall&#8217;annata 2018 all&#8217;annata 2012.<\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/06\/autoctono-si-nasce-go-wine-telos-bianco-tenuta-sant-antonio.jpg&#8221; alt=&#8221;autoctono si nasce tenuta Sant\u2019Antonio telos bianco&#8221; title_text=&#8221;autoctono-si-nasce-go-wine-telos-bianco-tenuta-sant-antonio&#8221; _builder_version=&#8221;4.9.7&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|8px|8px|8px|8px&#8221; border_width_all=&#8221;3px&#8221; border_color_all=&#8221;gcid-65af285e-4bd3-4ea9-81b6-b2c2b9f89915&#8243; box_shadow_style=&#8221;preset3&#8243; global_colors_info=&#8221;{%22gcid-65af285e-4bd3-4ea9-81b6-b2c2b9f89915%22:%91%22border_color_all%22%93}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.9.7&#8243; _module_preset=&#8221;default&#8221; header_3_font=&#8221;Delius Unicase|700|||||||&#8221; header_3_font_size=&#8221;18px&#8221;]<\/p>\n<h3 style=\"text-align: justify;\">#4 Autoctono si nasce 2021: &#8220;Giganti Bianco&#8221; 2019, Contini<\/h3>\n<p style=\"text-align: justify;\"><strong>Appunti di degustazione<\/strong>.\u00a0Giallo paglierino brillante e consistente. Naso pazzesco si sente la botte, ma non \u00e8 invadente. Naso intenso con note di cioccolato bianco, banana, noci di macadamia, aneto. In bocca \u00e8 coerente, croccante, fresco, caldo sapido e con un lungo finale di mousse di mascarpone.<\/p>\n<p style=\"text-align: justify;\"><strong>Vitigno autoctono<\/strong>. <strong>Vernaccia<\/strong> e <strong>Vermentino<\/strong> si uniscono nella loro terra autoctona: la Sardegna.<\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/06\/autoctono-si-nasce-go-wine-giganti-bianco-contini.jpg&#8221; alt=&#8221;autoctono si nasce go wine contini giganti bianco&#8221; title_text=&#8221;autoctono-si-nasce-go-wine-giganti-bianco-contini&#8221; _builder_version=&#8221;4.9.7&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|8px|8px|8px|8px&#8221; border_width_all=&#8221;3px&#8221; border_color_all=&#8221;gcid-65af285e-4bd3-4ea9-81b6-b2c2b9f89915&#8243; box_shadow_style=&#8221;preset3&#8243; global_colors_info=&#8221;{%22gcid-65af285e-4bd3-4ea9-81b6-b2c2b9f89915%22:%91%22border_color_all%22%93}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.9.7&#8243; _module_preset=&#8221;default&#8221; header_3_font=&#8221;Delius Unicase|700|||||||&#8221; header_3_font_size=&#8221;18px&#8221;]<\/p>\n<h3 style=\"text-align: justify;\">#5 Autoctono si nasce 2021: &#8220;Ti Esti'&#8221; Fiano 2019, Domus Hortae<\/h3>\n<p style=\"text-align: justify;\"><strong>Appunti di degustazione<\/strong>.\u00a0Naso meraviglioso citrino con note di pera candita, cedro candito, essenza di citronella, lavanda, camomilla, te nero (tanto). In bocca \u00e8 coerente con note di te al limone, molto sapido e freschissimo. Lungo finale di te nero non zuccherato.<\/p>\n<p style=\"text-align: justify;\"><strong>Vitigno autoctono<\/strong>. Il <strong>minutolo<\/strong> \u00e8 un vitigno aromatico a bacca bianca autoctono della Puglia che da sempre vive all&#8217;ombra del ben pi\u00f9 famoso fiano di Avellino. In realt\u00e0 sono due vitigni diversi che per lungo tempo si sono chiamati entrambi <em>fiano<\/em>, in Valle d&#8217;Itria talvolta si chiamava <em>fiano minutolo<\/em> poi dal 2011 finalmente nel Registro delle Politiche Agricole fa la sua comparsa ufficiale solo con il nome <em>minutolo<\/em>. La coltivazione \u00e8 attualmente in osservazione in Basilicata.<\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/06\/autoctono-si-nasce-go-wine-fiano-domus-hortae-1.jpg&#8221; alt=&#8221;autoctono si nasce go wine fiano domus hortae&#8221; title_text=&#8221;autoctono-si-nasce-go-wine-fiano-domus-hortae&#8221; _builder_version=&#8221;4.9.7&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|8px|8px|8px|8px&#8221; border_width_all=&#8221;3px&#8221; border_color_all=&#8221;gcid-65af285e-4bd3-4ea9-81b6-b2c2b9f89915&#8243; box_shadow_style=&#8221;preset3&#8243; global_colors_info=&#8221;{%22gcid-65af285e-4bd3-4ea9-81b6-b2c2b9f89915%22:%91%22border_color_all%22%93}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.9.7&#8243; _module_preset=&#8221;default&#8221; header_3_font=&#8221;Delius Unicase|700|||||||&#8221; header_3_font_size=&#8221;18px&#8221;]<\/p>\n<h3 style=\"text-align: justify;\">#6 Autoctono si nasce 2021:\u00a0Grechetto 2019, Colle Ciocco<\/h3>\n<p style=\"text-align: justify;\"><strong>Appunti di degustazione<\/strong>.\u00a0Giallo paglierino brillante con sfumature dorate. Al naso \u00e8 delizioso con note citrine di cacao con limone candito e zenzero, viola, spremuta d\u2019arancia rossa. In bocca \u00e8 coerente e molto equilibrato, particolarmente beverino e con un lungo finale di arancia rossa.<\/p>\n<p style=\"text-align: justify;\"><strong>Vitigno autoctono<\/strong>. Il <strong>grechetto<\/strong> \u00e8 un vitigno diffuso in Umbria e in tutta la fascia dell&#8217;Italia Centrale. Viene coltivato anche in Emilia dove si elabora il Pignoletto DOCG, ma io preferisco le sue espressioni ferme.<\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/06\/autoctono-si-nasce-go-wine-colle-ciocco-grechetto.jpg&#8221; alt=&#8221;autoctono si nasce go wine colle ciocco grechetto&#8221; title_text=&#8221;autoctono-si-nasce-go-wine-colle-ciocco-grechetto&#8221; _builder_version=&#8221;4.9.7&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|8px|8px|8px|8px&#8221; border_width_all=&#8221;3px&#8221; border_color_all=&#8221;gcid-65af285e-4bd3-4ea9-81b6-b2c2b9f89915&#8243; box_shadow_style=&#8221;preset3&#8243; global_colors_info=&#8221;{%22gcid-65af285e-4bd3-4ea9-81b6-b2c2b9f89915%22:%91%22border_color_all%22%93}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.9.7&#8243; _module_preset=&#8221;default&#8221; header_3_font=&#8221;Delius Unicase|700|||||||&#8221; header_3_font_size=&#8221;18px&#8221;]<\/p>\n<h3 style=\"text-align: justify;\">#7 Autoctono si nasce 2021: &#8220;Vigne Alte&#8221; Lugana 2020, Zeni 1870<\/h3>\n<p style=\"text-align: justify;\"><strong>Appunti di degustazione<\/strong>.\u00a0Stile classico della Lugana. molto grasso, coerente, naso della turbina con una nota di albicocca. In bocca \u00e8 fresco e molto sapido, piacevolissimo.<\/p>\n<p style=\"text-align: justify;\"><strong>Vitigno autoctono<\/strong>. Il trebbiano di Soave \u00e8 conosciuto anche come trebbiano di Lugana, turbiana, verdicchio bianco.<\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/06\/autoctono-si-nasce-go-wine-vigne-alte-lugana-zeni-1870.jpg&#8221; alt=&#8221;autoctono si nasce go wine lugana zeni 1870&#8243; title_text=&#8221;autoctono-si-nasce-go-wine-vigne-alte-lugana-zeni-1870&#8243; _builder_version=&#8221;4.9.7&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|8px|8px|8px|8px&#8221; border_width_all=&#8221;3px&#8221; border_color_all=&#8221;gcid-65af285e-4bd3-4ea9-81b6-b2c2b9f89915&#8243; box_shadow_style=&#8221;preset3&#8243; global_colors_info=&#8221;{%22gcid-65af285e-4bd3-4ea9-81b6-b2c2b9f89915%22:%91%22border_color_all%22%93}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.9.7&#8243; _module_preset=&#8221;default&#8221; header_3_font=&#8221;Delius Unicase|700|||||||&#8221; header_3_font_size=&#8221;18px&#8221;]<\/p>\n<h3 style=\"text-align: justify;\">#8 Autoctono si nasce 2021: &#8220;Torcoli&#8221; Vermentino 2019, Lombardi<\/h3>\n<p style=\"text-align: justify;\"><strong>Appunti di degustazione<\/strong>.\u00a0Giallo paglierino brillante e consistente. Al naso \u00e8 minerale con note di idrocarburi particolarmente interessanti. Note di pera, miele, mon cheri, burro fuso. In bocca \u00e8 fresco, molto sapido, strutturato e caldo. Lungo finale mielato.<\/p>\n<p style=\"text-align: justify;\"><strong>Vitigno autoctono<\/strong>. Il <strong>vermentino<\/strong> \u00e8 un vitigno famosissimo coltivato soprattutto in Sardegna, Liguria, Toscana e Piemonte (con il nome Favorita), dove pu\u00f2 definirsi autoctono. Per esprimersi al meglio chiede di essere allevato lungo la costa, meglio ancora se in altitudine.<\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/06\/autoctono-si-nasce-go-wine-lombardi-vermentino-ligure.jpg&#8221; alt=&#8221;autoctono si nasce go wine lombardi vermentino&#8221; title_text=&#8221;autoctono-si-nasce-go-wine-lombardi-vermentino-ligure&#8221; _builder_version=&#8221;4.9.7&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|8px|8px|8px|8px&#8221; border_width_all=&#8221;3px&#8221; border_color_all=&#8221;gcid-65af285e-4bd3-4ea9-81b6-b2c2b9f89915&#8243; box_shadow_style=&#8221;preset3&#8243; global_colors_info=&#8221;{%22gcid-65af285e-4bd3-4ea9-81b6-b2c2b9f89915%22:%91%22border_color_all%22%93}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.9.7&#8243; _module_preset=&#8221;default&#8221; header_3_font=&#8221;Delius Unicase|700|||||||&#8221; header_3_font_size=&#8221;18px&#8221;]<\/p>\n<h3 style=\"text-align: justify;\">#9 Autoctono si nasce 2021: Pigato 2020, Claudio Vio<\/h3>\n<p style=\"text-align: justify;\"><strong>Appunti di degustazione<\/strong>.\u00a0Giallo paglierino brillante, consistente. Al naso caratteristico del pigato, senza sbavature. Naso floreale e burroso, con note di miele, confetto e gelsomino. In bocca \u00e8 coerente, fresco, molto sapido e lungo.<\/p>\n<p style=\"text-align: justify;\"><strong>Vitigno autoctono<\/strong>. Il <strong>pigato<\/strong> \u00e8 un vitigno a bacca bianca di origine greca arrivato in Liguria durante il Medioevo.<\/p>\n<p style=\"text-align: justify;\">N.B. Ho avuto il piacere di soggiornare nel delizioso agriturismo della famiglia Vio durante una splendida serata di <a href=\"https:\/\/perlagesuite.com\/stelle-calici-1-tappa-vini-liguri-chef-stellati-liguria\/\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\"><strong>Stelle &amp; Calici con chef Tommaso Arrigoni organizzata da Vite in Riviera<\/strong><\/span><\/a>. Mi piacerebbe proprio tornarci! <span>\ud83d\ude0d<\/span><\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/06\/autoctono-si-nasce-go-wine-pigato-claudio-vio.jpg&#8221; alt=&#8221;autoctono si nasce go wine pigato claudio vio&#8221; title_text=&#8221;autoctono-si-nasce-go-wine-pigato-claudio-vio&#8221; _builder_version=&#8221;4.9.7&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|8px|8px|8px|8px&#8221; border_width_all=&#8221;3px&#8221; border_color_all=&#8221;gcid-65af285e-4bd3-4ea9-81b6-b2c2b9f89915&#8243; box_shadow_style=&#8221;preset3&#8243; global_colors_info=&#8221;{%22gcid-65af285e-4bd3-4ea9-81b6-b2c2b9f89915%22:%91%22border_color_all%22%93}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.9.7&#8243; _module_preset=&#8221;default&#8221; header_3_font=&#8221;Delius Unicase|700|||||||&#8221; header_3_font_size=&#8221;18px&#8221;]<\/p>\n<h3 style=\"text-align: justify;\">#10 Autoctono si nasce 2021: Vigneto Storico Friulano 2019, Gigante<\/h3>\n<p style=\"text-align: justify;\"><strong>Appunti di degustazione<\/strong>.\u00a0Giallo paglierino brillante un friulano eccellente e particolarmente minerale. Al naso pesca, pera, viola, albicocca, amarena sfumano in un finale di salsedine. In bocca \u00e8 freschissimo e sapido. Lungo finale ammandorlato. Si abbina bene con i crostacei e i pesci di lago, meglio crudi.<\/p>\n<p style=\"text-align: justify;\"><strong>Vitigno autoctono<\/strong>. Un tempo si chiamava tocai, oggi si chiama semplicemente <strong>friulano<\/strong> a seguito di una disputa legale con il blasonato vino ungherese <span>Tokaji prodotto con il vitigno furmint<\/span>. Curiosamente poi sembra che sia in realt\u00e0 tocai italiano, portato in Ungheria come dote matrimoniale dalla nobile friulana Aurora Formentini nel 1632. Quindi, se non \u00e8 chiaro, sembra che noi non possiamo pi\u00f9 chiamare il nostro vitigno e il relativo vino prodotto Tocai perch\u00e8 in assonanza con il <span>Tokaji ungherese che sarebbe in realt\u00e0 prodotto con il tocai italiano. Aiuto\u00a0\ud83d\ude05<\/span>\u00a0Questo vitigno a bacca bianca si coltiva in Friuli-Venezia Giulia e Slovenia.<\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/06\/autoctono-si-nasce-go-wine-giganti-friulano-vigneto-storico.jpg&#8221; alt=&#8221;autoctono si nasce go wine friulano vigneto storico giganti&#8221; title_text=&#8221;autoctono-si-nasce-go-wine-giganti-friulano-vigneto-storico&#8221; _builder_version=&#8221;4.9.7&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|8px|8px|8px|8px&#8221; border_width_all=&#8221;3px&#8221; border_color_all=&#8221;gcid-65af285e-4bd3-4ea9-81b6-b2c2b9f89915&#8243; box_shadow_style=&#8221;preset3&#8243; global_colors_info=&#8221;{%22gcid-65af285e-4bd3-4ea9-81b6-b2c2b9f89915%22:%91%22border_color_all%22%93}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.9.7&#8243; _module_preset=&#8221;default&#8221; header_3_font=&#8221;Delius Unicase|700|||||||&#8221; header_3_font_size=&#8221;18px&#8221;]<\/p>\n<h3 style=\"text-align: justify;\">Bonus: Ti piace il giapponese? Prova Sushi Kobbo a Milano!<\/h3>\n<p style=\"text-align: justify;\">Quanto mi piace il sushi&#8230; e quanto mi piace la formula ACE! Tuttavia trovare un sushi all can you eat di qualit\u00e0 \u00e8 pi\u00f9 difficile che trovare un Sassicaia dell&#8217;85 in cantina. Ho il mio punto di riferimento a Milano che \u00e8 <strong>Jin Sushi<\/strong>, per\u00f2 il luned\u00ec \u00e8 chiuso e mi sono ritrovata allo sbando con una fame chimica assurda. Cos\u00ec curiosando tra le varie proposte ho scovato <strong>Sushi Kobbo<\/strong>&#8230; e devo dire che alla fine mi \u00e8 piaciuto almeno quanto Jin Sushi. Una qualit\u00e0 incredibile tra tipico e fusion in un ambiente curatissimo e con poltrone comodissime. Considera 60\u20ac in 2 vino escluso per gustare una vagonata di sushi e sashimi deliziosi. Ti segnalo gli uramaki all&#8217;astice, il nigiri all&#8217;anguilla e tutto il sashimi. Non vedo l&#8217;ora di tornarci!<\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/06\/sushi-kobbo-milano.jpg&#8221; alt=&#8221;sushi kobbo milano ristorante giapponese&#8221; title_text=&#8221;sushi-kobbo-milano&#8221; _builder_version=&#8221;4.9.7&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|8px|8px|8px|8px&#8221; border_width_all=&#8221;3px&#8221; border_color_all=&#8221;gcid-65af285e-4bd3-4ea9-81b6-b2c2b9f89915&#8243; box_shadow_style=&#8221;preset3&#8243; global_colors_info=&#8221;{%22gcid-65af285e-4bd3-4ea9-81b6-b2c2b9f89915%22:%91%22border_color_all%22%93}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.9.10&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p style=\"text-align: justify;\">Spero proprio che assaggerai questi vini&#8230; lato mio mi riprometto al pi\u00f9 presto di visitare qualcuna di queste cantine perch\u00e8 sono convinta che c&#8217;\u00e8 molto altro di buono da assaggiare!<\/p>\n<p style=\"text-align: justify;\">Conosci qualcuna di queste cantine? Se s\u00ec scorri la pagina e scrivimelo in un commento! <span>\ud83e\udd29 <\/span><\/p>\n<p>Cheers<span>\ud83c\udf77<\/span><\/p>\n<p>Chiara<\/p>\n<p>P.S. Scopri i vini che mi erano piaciuti di pi\u00f9 ad <a href=\"https:\/\/perlagesuite.com\/autoctono-si-nasce-2020-gowine\/\"><span style=\"text-decoration: underline;\"><strong>Autoctono si nasce 2020<\/strong><\/span><\/a>!<\/p>\n<p>[\/et_pb_text][et_pb_divider color=&#8221;gcid-65af285e-4bd3-4ea9-81b6-b2c2b9f89915&#8243; _builder_version=&#8221;4.9.7&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{%22gcid-65af285e-4bd3-4ea9-81b6-b2c2b9f89915%22:%91%22color%22%93}&#8221;][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.0.6&#8243; global_module=&#8221;21425&#8243;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.0.6&#8243;][et_pb_wc_images product=&#8221;10582&#8243; show_product_gallery=&#8221;off&#8221; _builder_version=&#8221;4.9.4&#8243;][\/et_pb_wc_images][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.0.6&#8243;][et_pb_wc_title product=&#8221;10582&#8243; _builder_version=&#8221;4.0.6&#8243;][\/et_pb_wc_title][et_pb_text _builder_version=&#8221;4.9.4&#8243; text_font=&#8221;Delius Unicase||||||||&#8221;]<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ff0000;\"><span style=\"caret-color: #ff0000;\"><b>Tutti i miei appunti sul vino e sul cibo in un solo libro.<\/b><\/span><\/span><\/p>\n<p>[\/et_pb_text][et_pb_wc_rating product=&#8221;10582&#8243; _builder_version=&#8221;4.0.6&#8243;][\/et_pb_wc_rating][et_pb_wc_price product=&#8221;10582&#8243; _builder_version=&#8221;4.0.6&#8243;][\/et_pb_wc_price][et_pb_wc_add_to_cart product=&#8221;10582&#8243; _builder_version=&#8221;4.0.6&#8243;][\/et_pb_wc_add_to_cart][et_pb_text _builder_version=&#8221;4.9.4&#8243; text_font=&#8221;Delius Unicase||||||||&#8221;]<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ff0000;\"><strong>IN OMAGGIO<\/strong><\/span>, solo per chi compra il mio libro su questo blog, una copia della <strong>Prima Edizione da Collezione della mia Guida Vini Spumanti &#8220;500 Bolle in 500&#8221;<\/strong>, prezzo di copertina 25,30 \u20ac. [Fino ad esaurimento scorte]<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Autoctono si nasce 2021 di Go Wine \u00e8 uno degli eventi che da sempre mi piace di pi\u00f9. Ci sono tante chicche interessanti e l&#8217;anteprima per la stampa \u00e8 sempre &#8220;a misura&#8221; di degustatore, ovvero riesco a prendere tutti i miei appunti serenamente. Purtroppo la degustazione su turni non mi permetteva di assaggiare tutto pertanto, [&hellip;]<\/p>\n","protected":false},"author":49,"featured_media":29693,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"2880","footnotes":""},"categories":[298],"tags":[],"class_list":["post-29647","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-degustazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.0 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Autoctono si nasce 2021: i miei appunti di degustazione - Perlage Suite<\/title>\n<meta name=\"description\" content=\"&quot;Autoctono si nasce&quot; 2021, Go Wine a Milano: appunti di degustazione dei 10 vini bianchi che mi sono piaciuti di pi\u00f9. Ne conosci qualcuno?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/perlagesuite.com\/en\/autoctono-si-nasce-2021-i-10-vini-bianchi-che-mi-sono-piaciuti-di-piu\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Autoctono si nasce 2021: i 10 vini bianchi che mi sono piaciuti di pi\u00f9\" \/>\n<meta property=\"og:description\" content=\"&quot;Autoctono si nasce&quot; 2021, Go Wine a Milano: appunti di degustazione dei 10 vini bianchi che mi sono piaciuti di pi\u00f9. Ne conosci qualcuno?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/perlagesuite.com\/en\/autoctono-si-nasce-2021-i-10-vini-bianchi-che-mi-sono-piaciuti-di-piu\/\" \/>\n<meta property=\"og:site_name\" content=\"Perlage Suite\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/chiarabassiperlagesuite\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-24T15:11:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-26T12:41:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/06\/autoctono-si-nasce-2021-milano-go-wine.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Chiara Bassi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@perlagesuite\" \/>\n<meta name=\"twitter:site\" content=\"@perlagesuite\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Chiara Bassi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/autoctono-si-nasce-2021-i-10-vini-bianchi-che-mi-sono-piaciuti-di-piu\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/autoctono-si-nasce-2021-i-10-vini-bianchi-che-mi-sono-piaciuti-di-piu\\\/\"},\"author\":{\"name\":\"Chiara Bassi\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/person\\\/81b257517a1007c1a823318ac86c6013\"},\"headline\":\"Autoctono si nasce 2021: i 10 vini bianchi che mi sono piaciuti di pi\u00f9\",\"datePublished\":\"2021-06-24T15:11:18+00:00\",\"dateModified\":\"2021-07-26T12:41:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/autoctono-si-nasce-2021-i-10-vini-bianchi-che-mi-sono-piaciuti-di-piu\\\/\"},\"wordCount\":2611,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/autoctono-si-nasce-2021-i-10-vini-bianchi-che-mi-sono-piaciuti-di-piu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/autoctono-si-nasce-2021-milano-go-wine.jpg\",\"articleSection\":[\"Degustazioni\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/perlagesuite.com\\\/autoctono-si-nasce-2021-i-10-vini-bianchi-che-mi-sono-piaciuti-di-piu\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/autoctono-si-nasce-2021-i-10-vini-bianchi-che-mi-sono-piaciuti-di-piu\\\/\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/autoctono-si-nasce-2021-i-10-vini-bianchi-che-mi-sono-piaciuti-di-piu\\\/\",\"name\":\"Autoctono si nasce 2021: i miei appunti di degustazione - Perlage Suite\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/autoctono-si-nasce-2021-i-10-vini-bianchi-che-mi-sono-piaciuti-di-piu\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/autoctono-si-nasce-2021-i-10-vini-bianchi-che-mi-sono-piaciuti-di-piu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/autoctono-si-nasce-2021-milano-go-wine.jpg\",\"datePublished\":\"2021-06-24T15:11:18+00:00\",\"dateModified\":\"2021-07-26T12:41:57+00:00\",\"description\":\"\\\"Autoctono si nasce\\\" 2021, Go Wine a Milano: appunti di degustazione dei 10 vini bianchi che mi sono piaciuti di pi\u00f9. Ne conosci qualcuno?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/autoctono-si-nasce-2021-i-10-vini-bianchi-che-mi-sono-piaciuti-di-piu\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/perlagesuite.com\\\/autoctono-si-nasce-2021-i-10-vini-bianchi-che-mi-sono-piaciuti-di-piu\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/autoctono-si-nasce-2021-i-10-vini-bianchi-che-mi-sono-piaciuti-di-piu\\\/#primaryimage\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/autoctono-si-nasce-2021-milano-go-wine.jpg\",\"contentUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/autoctono-si-nasce-2021-milano-go-wine.jpg\",\"width\":1080,\"height\":720,\"caption\":\"autoctono si nasce 2021 go wine milano\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/autoctono-si-nasce-2021-i-10-vini-bianchi-che-mi-sono-piaciuti-di-piu\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/perlagesuite.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Autoctono si nasce 2021: i 10 vini bianchi che mi sono piaciuti di pi\u00f9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#website\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/\",\"name\":\"Perlage Suite\",\"description\":\"Il Wine Blog di Chiara Bassi\",\"publisher\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/perlagesuite.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#organization\",\"name\":\"Chiara Bassi\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Chiara-Bassi-sommelier-wine-blogger-logo.png\",\"contentUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Chiara-Bassi-sommelier-wine-blogger-logo.png\",\"width\":512,\"height\":512,\"caption\":\"Chiara Bassi\"},\"image\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/chiarabassiperlagesuite\",\"https:\\\/\\\/x.com\\\/perlagesuite\",\"https:\\\/\\\/www.instagram.com\\\/perlagesuite\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/person\\\/81b257517a1007c1a823318ac86c6013\",\"name\":\"Chiara Bassi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g\",\"caption\":\"Chiara Bassi\"},\"sameAs\":[\"https:\\\/\\\/perlagesuite.com\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Autoctono si nasce 2021: my tasting notes - Perlage Suite","description":"\"Autoctono si nasce\" 2021, Go Wine in Milan: tasting notes of the 10 white wines I liked best. Do you know any of them?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/perlagesuite.com\/en\/autoctono-si-nasce-2021-i-10-vini-bianchi-che-mi-sono-piaciuti-di-piu\/","og_locale":"en_GB","og_type":"article","og_title":"Autoctono si nasce 2021: i 10 vini bianchi che mi sono piaciuti di pi\u00f9","og_description":"\"Autoctono si nasce\" 2021, Go Wine a Milano: appunti di degustazione dei 10 vini bianchi che mi sono piaciuti di pi\u00f9. Ne conosci qualcuno?","og_url":"https:\/\/perlagesuite.com\/en\/autoctono-si-nasce-2021-i-10-vini-bianchi-che-mi-sono-piaciuti-di-piu\/","og_site_name":"Perlage Suite","article_publisher":"https:\/\/www.facebook.com\/chiarabassiperlagesuite","article_published_time":"2021-06-24T15:11:18+00:00","article_modified_time":"2021-07-26T12:41:57+00:00","og_image":[{"width":1080,"height":720,"url":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/06\/autoctono-si-nasce-2021-milano-go-wine.jpg","type":"image\/jpeg"}],"author":"Chiara Bassi","twitter_card":"summary_large_image","twitter_creator":"@perlagesuite","twitter_site":"@perlagesuite","twitter_misc":{"Written by":"Chiara Bassi","Estimated reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/perlagesuite.com\/autoctono-si-nasce-2021-i-10-vini-bianchi-che-mi-sono-piaciuti-di-piu\/#article","isPartOf":{"@id":"https:\/\/perlagesuite.com\/autoctono-si-nasce-2021-i-10-vini-bianchi-che-mi-sono-piaciuti-di-piu\/"},"author":{"name":"Chiara Bassi","@id":"https:\/\/perlagesuite.com\/#\/schema\/person\/81b257517a1007c1a823318ac86c6013"},"headline":"Autoctono si nasce 2021: i 10 vini bianchi che mi sono piaciuti di pi\u00f9","datePublished":"2021-06-24T15:11:18+00:00","dateModified":"2021-07-26T12:41:57+00:00","mainEntityOfPage":{"@id":"https:\/\/perlagesuite.com\/autoctono-si-nasce-2021-i-10-vini-bianchi-che-mi-sono-piaciuti-di-piu\/"},"wordCount":2611,"commentCount":0,"publisher":{"@id":"https:\/\/perlagesuite.com\/#organization"},"image":{"@id":"https:\/\/perlagesuite.com\/autoctono-si-nasce-2021-i-10-vini-bianchi-che-mi-sono-piaciuti-di-piu\/#primaryimage"},"thumbnailUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/06\/autoctono-si-nasce-2021-milano-go-wine.jpg","articleSection":["Degustazioni"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/perlagesuite.com\/autoctono-si-nasce-2021-i-10-vini-bianchi-che-mi-sono-piaciuti-di-piu\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/perlagesuite.com\/autoctono-si-nasce-2021-i-10-vini-bianchi-che-mi-sono-piaciuti-di-piu\/","url":"https:\/\/perlagesuite.com\/autoctono-si-nasce-2021-i-10-vini-bianchi-che-mi-sono-piaciuti-di-piu\/","name":"Autoctono si nasce 2021: my tasting notes - Perlage Suite","isPartOf":{"@id":"https:\/\/perlagesuite.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/perlagesuite.com\/autoctono-si-nasce-2021-i-10-vini-bianchi-che-mi-sono-piaciuti-di-piu\/#primaryimage"},"image":{"@id":"https:\/\/perlagesuite.com\/autoctono-si-nasce-2021-i-10-vini-bianchi-che-mi-sono-piaciuti-di-piu\/#primaryimage"},"thumbnailUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/06\/autoctono-si-nasce-2021-milano-go-wine.jpg","datePublished":"2021-06-24T15:11:18+00:00","dateModified":"2021-07-26T12:41:57+00:00","description":"\"Autoctono si nasce\" 2021, Go Wine in Milan: tasting notes of the 10 white wines I liked best. Do you know any of them?","breadcrumb":{"@id":"https:\/\/perlagesuite.com\/autoctono-si-nasce-2021-i-10-vini-bianchi-che-mi-sono-piaciuti-di-piu\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/perlagesuite.com\/autoctono-si-nasce-2021-i-10-vini-bianchi-che-mi-sono-piaciuti-di-piu\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/perlagesuite.com\/autoctono-si-nasce-2021-i-10-vini-bianchi-che-mi-sono-piaciuti-di-piu\/#primaryimage","url":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/06\/autoctono-si-nasce-2021-milano-go-wine.jpg","contentUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/06\/autoctono-si-nasce-2021-milano-go-wine.jpg","width":1080,"height":720,"caption":"autoctono si nasce 2021 go wine milano"},{"@type":"BreadcrumbList","@id":"https:\/\/perlagesuite.com\/autoctono-si-nasce-2021-i-10-vini-bianchi-che-mi-sono-piaciuti-di-piu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/perlagesuite.com\/"},{"@type":"ListItem","position":2,"name":"Autoctono si nasce 2021: i 10 vini bianchi che mi sono piaciuti di pi\u00f9"}]},{"@type":"WebSite","@id":"https:\/\/perlagesuite.com\/#website","url":"https:\/\/perlagesuite.com\/","name":"Perlage Suite","description":"Chiara Bassi's Wine Blog","publisher":{"@id":"https:\/\/perlagesuite.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/perlagesuite.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/perlagesuite.com\/#organization","name":"Chiara Bassi","url":"https:\/\/perlagesuite.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/perlagesuite.com\/#\/schema\/logo\/image\/","url":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2022\/03\/Chiara-Bassi-sommelier-wine-blogger-logo.png","contentUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2022\/03\/Chiara-Bassi-sommelier-wine-blogger-logo.png","width":512,"height":512,"caption":"Chiara Bassi"},"image":{"@id":"https:\/\/perlagesuite.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/chiarabassiperlagesuite","https:\/\/x.com\/perlagesuite","https:\/\/www.instagram.com\/perlagesuite\/"]},{"@type":"Person","@id":"https:\/\/perlagesuite.com\/#\/schema\/person\/81b257517a1007c1a823318ac86c6013","name":"Chiara Bassi","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g","caption":"Chiara Bassi"},"sameAs":["https:\/\/perlagesuite.com"]}]}},"_links":{"self":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/posts\/29647","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/comments?post=29647"}],"version-history":[{"count":0,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/posts\/29647\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/media\/29693"}],"wp:attachment":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/media?parent=29647"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/categories?post=29647"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/tags?post=29647"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}