{"id":30340,"date":"2021-09-20T17:41:03","date_gmt":"2021-09-20T16:41:03","guid":{"rendered":"https:\/\/perlagesuite.com\/?p=30340"},"modified":"2022-06-14T01:17:04","modified_gmt":"2022-06-14T00:17:04","slug":"guida-michelin-riflessioni-dopo-cena","status":"publish","type":"post","link":"https:\/\/perlagesuite.com\/en\/guida-michelin-riflessioni-dopo-cena\/","title":{"rendered":"Michelin Guide: 'after dinner' reflections"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.17.4&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p style=\"text-align: left;\">Venerd\u00ec sera, dopo mesi di clausura per la stesura della <a href=\"https:\/\/perlagesuite.com\/prodotto\/come-diventare-sommelier-esame-ais-corso-sommelier\/\"><span style=\"text-decoration: underline;\"><strong>nuova edizione del mio libro<\/strong><\/span><\/a>, ho deciso di passare con mio marito una serata speciale per festeggiare la fine di questo lavoro cos\u00ec immenso. Cos\u00ec sono andata nel mio ristorante preferito, nell&#8217;unico ristorante capace di superare le mie sempre alte aspettative: <strong>Tentazioni Ristorante di Costa Volpino (BG)<\/strong>. Dopo una cena perfetta mi \u00e8 venuta spontanea una riflessione, che ora cercher\u00f2 di mettere &#8220;nero su bianco&#8221; per condividerla con te, con l&#8217;augurio di scatenare un interessante dibattito (il meno possibile polemico) sulla <strong>Guida Michelin<\/strong> e sui ristoranti stellati.<\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/09\/guida-michelin-ristorante-tentazioni-costa-volpino-10.jpg&#8221; alt=&#8221;guida michelin ristorante tentazioni costa volpino&#8221; title_text=&#8221;guida-michelin-ristorante-tentazioni-costa-volpino-10&#8243; _builder_version=&#8221;4.17.4&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; border_radii=&#8221;on|8px|8px|8px|8px&#8221; border_width_all=&#8221;3px&#8221; border_color_all=&#8221;gcid-21fbec71-877e-4169-81a6-b6b5df6aa348&#8243; box_shadow_style=&#8221;preset3&#8243; global_colors_info=&#8221;{%22gcid-21fbec71-877e-4169-81a6-b6b5df6aa348%22:%91%22border_color_all%22%93}&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.17.4&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p style=\"text-align: left;\">Complice il mio lavoro da wine blogger ho avuto il privilegio di assaggiare piatti di Gordon Ramsay**, Antonino Cannavacciuolo**, Carlo Cracco*, Heinz Beck***, Davide Oldani*, Igles Corelli*, Tommaso Arrigoni*, Marco Sacco**, Alessandro Gavagna*, Isa Mazzocchi*, Herbert Hintner*, Gian Piero Vivalda**, Luigi Pomata*, Christian Costardi*, Chicco Cerea***, Enrico Crippa***, Enrico Bartolini**, Niko Romito***&#8230; e tutta una sfilza di ristoranti segnalati sulla Guida Michelin in tutta Italia. <strong>Cos\u00ec, quando venerd\u00ec sera ho vissuto un&#8217;altra serata perfetta in un ristorante che, nonostante \u00e8 aperto gi\u00e0 da alcuni anni, non \u00e8 presente sulla Guida Michelin manco tra i segnalati, qualche domanda me la sono posta.<\/strong><\/p>\n<p style=\"text-align: left;\">S\u00ec, perch\u00e8 tra i nomi che ho fatto &#8211; e sono certa me ne \u00e8 sfuggito qualcuno &#8211; ci sono cuochi che mi hanno emozionato e altri che non mi hanno entusiasmato, anzi: confesso che <strong>se avessi pagato la cena mi sarei pure incazzata<\/strong>.<\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/09\/guida-michelin-ristorante-tentazioni-costa-volpino-8.jpg&#8221; alt=&#8221;guida michelin ristorante tentazioni costa volpino&#8221; title_text=&#8221;guida-michelin-ristorante-tentazioni-costa-volpino-8&#8243; _builder_version=&#8221;4.17.4&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; border_radii=&#8221;on|8px|8px|8px|8px&#8221; border_width_all=&#8221;3px&#8221; border_color_all=&#8221;gcid-21fbec71-877e-4169-81a6-b6b5df6aa348&#8243; box_shadow_style=&#8221;preset3&#8243; global_colors_info=&#8221;{%22gcid-21fbec71-877e-4169-81a6-b6b5df6aa348%22:%91%22border_color_all%22%93}&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.17.4&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p style=\"text-align: left;\"><strong>La Michelin assegna le stelle in base alla qualit\u00e0 degli ingredienti usati, alla maestria del controllo dei sapori e delle tecniche di cottura, alla personalit\u00e0 dello Chef all&#8217;interno della sua cucina, al valore e alla coerenza delle proposte dei piatti<\/strong>. Non posso quindi, dopo l&#8217;ennesima cena capace di farmi ubriacare di piacere e felicit\u00e0, non chiedermi quale sia il problema. Sicuramente dietro la Guida Michelin c&#8217;\u00e8 un alone di mistero che i vari tentativi di presunta trasparenza non sono mai riusciti a sfumare. Sono certa che anche tu hai un ristorante del cuore, che merita il viaggio e che non \u00e8 presente sulla Guida Michelin. Perch\u00e8?<\/p>\n<p style=\"text-align: left;\">Si dice che i sistemi di punteggio utilizzati dagli ispettori sono un segreto gelosamente custodito. A me questo onestamente non solo non piace, ma fa anche paura. Quando una fonte \u00e8 autorevole DEVE essere trasparente. La mancanza di trasparenza mi fa sorgere dubbi sull&#8217;autorevolezza della fonte stessa. Ad esempio se si degusta un vino per attribuire un punteggio, la scheda punti AIS ha criteri ben definiti di valutazione accessibili a chiunque. Per prima cosa questo d\u00e0 la possibilit\u00e0 a chi produce vino di avere una check list da utilizzare per crescere, poi rassicura il consumatore finale sul come vengono attribuiti i punteggi.<\/p>\n<p style=\"text-align: left;\"><strong>Noi fedeli consultatori della Guida Michelin invece abbiamo in mano solo la fede cieca verso una Guida nata oltre 100 anni fa che, nella stragrande maggioranza dei casi, ci fa vivere esperienze straordinarie.\u00a0<\/strong><\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/09\/guida-michelin-ristorante-tentazioni-costa-volpino-7.jpg&#8221; alt=&#8221;guida michelin ristorante tentazioni costa volpino&#8221; title_text=&#8221;guida-michelin-ristorante-tentazioni-costa-volpino-7&#8243; _builder_version=&#8221;4.17.4&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; border_radii=&#8221;on|8px|8px|8px|8px&#8221; border_width_all=&#8221;3px&#8221; border_color_all=&#8221;gcid-21fbec71-877e-4169-81a6-b6b5df6aa348&#8243; box_shadow_style=&#8221;preset3&#8243; global_colors_info=&#8221;{%22gcid-21fbec71-877e-4169-81a6-b6b5df6aa348%22:%91%22border_color_all%22%93}&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.17.4&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p style=\"text-align: left;\"><span>La Guida Michelin sicuramente premia ristoranti di grande valore e io la consulto sempre se voglio concedermi una serata speciale. Tuttavia, dopo l&#8217;ennesima serata perfetta alle Tentazioni Ristorante mi chiedo&#8230; quanto sommerso c&#8217;\u00e8? Quanti ristoranti di valore ci sono in giro che non sono menzionati in nessuna guida e in particolare non sono sulla Michelin? Con che criterio si attribuiscono le stelle? Non sono un ispettore Michelin, ma per la mia umile esperienza Tentazioni Ristorante di Giacomo e Sandro Pittelli dovrebbe avere MINIMO una segnalazione, pi\u00f9 correttemente una stella Michelin. Non solo per premiare il loro talento, ma tutta la loro squadra dalla cucina alla sala.<\/span><\/p>\n<p style=\"text-align: left;\"><span>Ora per\u00f2 parliamo di cosa ho mangiato&#8230; cos\u00ec magari deciderai di fare una tappa (*), una deviazione (**) o addirittura penserai che questo ristorante sul Lago d&#8217;Iseo merita il viaggio (***)!<\/span><\/p>\n<p style=\"text-align: left;\"><span>Abbiamo preso il <a href=\"https:\/\/tentazioniristorante.it\/menu\/#category-9\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\"><strong>Menu Degustazione &#8220;La vostra mano libera&#8221;<\/strong><\/span><\/a> che, inspiegabilmente, costa solo 50 \u20ac con 3 portate scelte dal menu che devono essere uguali per tutto il tavolo, il dessert che ognuno pu\u00f2 scegliere liberamente, acqua e caff\u00e8. Il coperto costa incredibilmente poco (3 \u20ac) se si considera che include grissini, pane fatto in casa, cialde croccanti, pizzette di benvenuto, fingerfood.<\/span><\/p>\n<p style=\"text-align: left;\"><span>Il primo piatto che ho scelto mi aveva stuzzicato la settimana prima su Instagram, alla faccia di chi dice che questo canale non funziona: io praticamente scelgo tutto quello che mangio nel mio feed. Instagram sa cosa mi piace mangiare con pi\u00f9 precisione di mia madre. Ecco la <strong>tartare di fassona piemontese, colatura di alici, burro nocciola e tuorlo d\u2019 uovo fritto<\/strong>: la migliore della mia vita. Non serve aggiungere altro, credo che la foto parli da sola. Ingredienti apparentemente non semplici da combinare che hanno danzato per me in perfetta armonia.<\/span><\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/09\/guida-michelin-ristorante-tentazioni-costa-volpino-6.jpg&#8221; alt=&#8221;guida michelin ristorante tentazioni costa volpino&#8221; title_text=&#8221;guida-michelin-ristorante-tentazioni-costa-volpino-6&#8243; _builder_version=&#8221;4.17.4&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; border_radii=&#8221;on|8px|8px|8px|8px&#8221; border_width_all=&#8221;3px&#8221; border_color_all=&#8221;gcid-21fbec71-877e-4169-81a6-b6b5df6aa348&#8243; box_shadow_style=&#8221;preset3&#8243; global_colors_info=&#8221;{%22gcid-21fbec71-877e-4169-81a6-b6b5df6aa348%22:%91%22border_color_all%22%93}&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.17.4&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p style=\"text-align: left;\"><span>I prossimi due piatti sono stati un fuori menu di cui vale la pena parlare. In alto la <strong>Royal al parmigiano, nocciole, funghi porcini, estratto di mirtilli e tartufo nero<\/strong>. Credo la cosa pi\u00f9 incredibile che ho mangiato negli ultimi 9 mesi. Non avrei mai pensato che il mirtillo potesse abbinarsi cos\u00ec bene alla crema di parmigiano e al tartufo nero. La nocciola tritata ha dato un tocco di croccantezza a un piatto che nasce cremosissimo e fatico a inquadrare in una portata: io lo considero un momento di incredibile piacere. La salsa Royal si usa anche per preparare la famosa <a href=\"https:\/\/perlagesuite.com\/quiche-lorraine-ricetta-originale-direttamente-da-bordeaux\/\"><span style=\"text-decoration: underline;\"><strong>Quiche Lorraine, vuoi provare la mia ricetta?<\/strong><\/span><\/a><br \/><\/span><\/p>\n<p style=\"text-align: left;\">In basso il <strong>Risotto di riso carnaroli, funghi porcini, Fatul\u00ec della Val Saviore, polvere di verdure alla brace<\/strong>, altro piatto squisito. Come ti ho gi\u00e0 detto non sono un&#8217;amante dei risotti, ma quelli di Sandro Pittelli riescono sempre a stupirmi per maestria di esecuzione e connubio di sapori, anche se il mio preferito rester\u00e0 sempre il <a href=\"https:\/\/perlagesuite.com\/comitissa-gold-2002-lorenz-martini-tantissimi-auguri-papino\/\"><span style=\"text-decoration: underline;\"><strong>risotto con<\/strong> <strong>emulsione di pomodoro, burro acido e tartare di gamberi rossi, ricciola e tonno del Mediterraneo<\/strong><\/span><\/a> che mi ha rubato per sempre il cuore. A proposito, ne approfitto per fare a Sandro una richiesta speciale: la prossima volta che vengo me lo prepari? <span>\ud83d\ude0d<\/span><\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/09\/guida-michelin-ristorante-tentazioni-costa-volpino-5.jpg&#8221; alt=&#8221;guida michelin ristorante tentazioni costa volpino&#8221; title_text=&#8221;guida-michelin-ristorante-tentazioni-costa-volpino-5&#8243; _builder_version=&#8221;4.17.4&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; border_radii=&#8221;on|8px|8px|8px|8px&#8221; border_width_all=&#8221;3px&#8221; border_color_all=&#8221;gcid-21fbec71-877e-4169-81a6-b6b5df6aa348&#8243; box_shadow_style=&#8221;preset3&#8243; global_colors_info=&#8221;{%22gcid-21fbec71-877e-4169-81a6-b6b5df6aa348%22:%91%22border_color_all%22%93}&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: justify;\"><span>Ora puoi iscriverti alla mia Newsletter o scorrere la pagina per proseguire la lettura dell&#8217;articolo.\ud83d\ude09<\/span><\/p>\n<p>[\/et_pb_text][et_pb_signup provider=&#8221;mailpoet&#8221; mailpoet_list=&#8221;chiara@pepeblu.com|49&#8243; success_message=&#8221;Controlla la tua e-mail: hai appena ricevuto un mio messaggio per confermare la tua iscrizione! Se non lo visualizzi controlla in spam o nella cartella %22promozioni%22 di Gmail. Grazie e a presto!&#8221; title=&#8221;Ti piace questo contenuto?&#8221; button_text=&#8221;Iscriviti subito!&#8221; description=&#8221;<\/p>\n<p style=%22text-align: justify;%22>Iscriviti alla mia newsletter per non perderti nessun nuovo articolo del mio blog!<\/p>\n<p style=%22text-align: justify;%22>Non ti invier\u00f2 SPAM, ma solo la notifica dei nuovi articoli! Di tanto in tanto potrai ricevere anche qualche coupon per acquistare vino o partecipare ad eventi con condizioni speciali riservate ai lettori del mio blog!<\/p>\n<p style=%22text-align: justify;%22>Cheers \ud83e\udd29\ud83e\udd42<\/p>\n<p>&#8221; footer_content=&#8221;<\/p>\n<p>Iscrivendoti accetti le condizioni della <a href=%22https:\/\/perlagesuite.com\/privacy-2\/%22 data-et-target-link=%22_blank%22 rel=%22noopener noreferrer%22><span style=%22text-decoration: underline;%22><strong><span style=%22color: #000000; text-decoration: underline;%22>Privacy<\/span><\/strong><\/span><\/a> di Perlage Suite.<\/p>\n<p>&#8221; _builder_version=&#8221;4.14.8&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;|700|||||||&#8221; header_font_size=&#8221;22px&#8221; body_font=&#8221;||||||||&#8221; background_color=&#8221;gcid-21fbec71-877e-4169-81a6-b6b5df6aa348&#8243; box_shadow_style=&#8221;preset3&#8243; box_shadow_color=&#8221;rgba(0,140,150,0.6)&#8221; global_module=&#8221;27234&#8243; global_colors_info=&#8221;{%22gcid-21fbec71-877e-4169-81a6-b6b5df6aa348%22:%91%22background_color%22%93}&#8221;][\/et_pb_signup][et_pb_text _builder_version=&#8221;4.17.4&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p style=\"text-align: left;\"><span>Sia chiaro, io non voglio mettere in discussione l&#8217;operato degli ispettori, n\u00e9 dubitare del fatto che un ristorante venga visitato pi\u00f9 volte prima di ricevere una stella. Quello che vorrei sinceramente capire \u00e8 se questi ispettori sono mai stati al Ristorante Tentazioni di Costa Volpino e se s\u00ec quante volte ci sono stati e se no perch\u00e8 non ci mettono piede. So perfettamente che di ristoranti in Italia ce ne sono tantissimi, ma la Guida Michelin \u00e8 cos\u00ec prestigiosa e ruotano cos\u00ec tanti soldi intorno ad essa che non dubito che pu\u00f2 pagarse eventuali ispettori in pi\u00f9, laddove servissero. <strong>La pandemia ha tenuto chiusi i ristoranti per mesi creando un danno incredibile al settore che i ristori non potranno mai compensare.<\/strong> Questo perch\u00e8, anche laddove fossero sufficienti per coprire le spese, non riuscirebbero a far fronte al danno causato al cambio di abitudini delle persone. Certo, ci sono locali come quello di Sandro e Giacomo Pittelli che sono cos\u00ec eccellenti da essere comunque sempre pieni, ma il focus rimane. Credo che il lavoro della Guida Michelin oggi sia far entrare ristoranti nuovi per dar loro la possibilit\u00e0 di promuoversi davanti a un pi\u00f9 ampio gruppo di potenziali clienti, clienti oltretutto capaci di dare davvero soddisfazione a uno chef talentuoso.<\/span><\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/09\/guida-michelin-ristorante-tentazioni-costa-volpino-4.jpg&#8221; alt=&#8221;guida michelin ristorante tentazioni costa volpino&#8221; title_text=&#8221;guida-michelin-ristorante-tentazioni-costa-volpino-4&#8243; _builder_version=&#8221;4.17.4&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; border_radii=&#8221;on|8px|8px|8px|8px&#8221; border_width_all=&#8221;3px&#8221; border_color_all=&#8221;gcid-21fbec71-877e-4169-81a6-b6b5df6aa348&#8243; box_shadow_style=&#8221;preset3&#8243; global_colors_info=&#8221;{%22gcid-21fbec71-877e-4169-81a6-b6b5df6aa348%22:%91%22border_color_all%22%93}&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.17.4&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p style=\"text-align: left;\"><span>Ma ora torniamo alla cena&#8230;<\/span><\/p>\n<p style=\"text-align: left;\"><span>Tra tutte le proposte, gli <strong>spaghetti, olio al cardamomo nero, astice marinato e brodetto di crostacei<\/strong> \u00e8 stata quella che ho preferito. Il burro giustamente salato, il brodetto di crostacei denso come una bisque che ha dato un tocco amaro ed equilibrato la tendenza dolce del burro e l&#8217;astice marinato in modo magnifico sono stati un orgasmo culinario. Con questo piatto poi il riesling \u00e8 stato perfetto.<\/span><\/p>\n<p style=\"text-align: left;\"><span>A proposito del Riesling, hanno cambiato cantina e devo ammettere che questo mi piace meno. Non perch\u00e8 non sia buono, ma perch\u00e8 ha uno stile tutto spostato sugli agrumi e sul pompelmo in particolare. Io invece amo i Riesling carichi di idrocarburi. Vorr\u00e0 dire che prossima volta mi dar\u00f2 a un certo Chardonnay della Borgogna&#8230;<\/span><\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/09\/guida-michelin-ristorante-tentazioni-costa-volpino-3.jpg&#8221; alt=&#8221;guida michelin ristorante tentazioni costa volpino&#8221; title_text=&#8221;guida-michelin-ristorante-tentazioni-costa-volpino-3&#8243; _builder_version=&#8221;4.17.4&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; border_radii=&#8221;on|8px|8px|8px|8px&#8221; border_width_all=&#8221;3px&#8221; border_color_all=&#8221;gcid-21fbec71-877e-4169-81a6-b6b5df6aa348&#8243; box_shadow_style=&#8221;preset3&#8243; global_colors_info=&#8221;{%22gcid-21fbec71-877e-4169-81a6-b6b5df6aa348%22:%91%22border_color_all%22%93}&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.17.4&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p style=\"text-align: left;\"><span><strong>Manzo Rib-eye argentino e lattuga alla brace, mostarda di clementine<\/strong> \u00e8 un piatto delizioso. Io sono profondamente carnivora e amo la carne blu. Il manzo argentino \u00e8 delizioso e il taglio Rib-eye \u00e8 la costata, cos\u00ec chiamata per un pezzo di grasso che sembra formare un occhio. Non \u00e8 affatto banale trovarla cos\u00ec tenera: a differenza del filetto contiene una parte di muscolo che potrebbe risultare duro in cottura. Questa era perfetta, cotta alla perfezione e con una Reazione di Maillard perfettamente svolta nonostante la brevissima cottura che aveva conferito tutti quei deliziosi profumi di pane appena sfornato, nocciole e caff\u00e8 tostato. Mi \u00e8 piaciuta molto anche la scelta della soia, ma era la mostarda di clementine il vero lavoro. Credo contenesse rafano e non senape perch\u00e8 mi ha ricordato il wasabi, in ogni caso era magnifica. Ne avrei mangiata una quintalata!<\/span><span><\/span><\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/09\/guida-michelin-ristorante-tentazioni-costa-volpino-2.jpg&#8221; alt=&#8221;guida michelin ristorante tentazioni costa volpino&#8221; title_text=&#8221;guida-michelin-ristorante-tentazioni-costa-volpino-2&#8243; _builder_version=&#8221;4.17.4&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; border_radii=&#8221;on|8px|8px|8px|8px&#8221; border_width_all=&#8221;3px&#8221; border_color_all=&#8221;gcid-21fbec71-877e-4169-81a6-b6b5df6aa348&#8243; box_shadow_style=&#8221;preset3&#8243; global_colors_info=&#8221;{%22gcid-21fbec71-877e-4169-81a6-b6b5df6aa348%22:%91%22border_color_all%22%93}&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.17.4&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;]<\/p>\n<blockquote>\n<p style=\"text-align: left;\">Ora puoi comprare il mio libro cartaceo &#8220;Sommelier: il manuale illustrato&#8221; o scorrere la pagina per continuare la lettura dell&#8217;articolo!<\/p>\n<\/blockquote>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221; global_module=&#8221;21425&#8243; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_wc_images product=&#8221;10582&#8243; show_product_gallery=&#8221;off&#8221; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_wc_images][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_wc_title product=&#8221;10582&#8243; _builder_version=&#8221;4.16&#8243; header_level=&#8221;h2&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_wc_title][et_pb_text _builder_version=&#8221;4.16&#8243; text_font=&#8221;Crushed||||||||&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<h4 style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"caret-color: #ff0000;\"><b>Tutti i miei appunti sul vino e sul cibo in un solo libro.<\/b><\/span><\/span><\/h4>\n<p>[\/et_pb_text][et_pb_wc_rating product=&#8221;10582&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_wc_rating][et_pb_wc_price product=&#8221;10582&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_wc_price][et_pb_wc_add_to_cart product=&#8221;10582&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_wc_add_to_cart][et_pb_text _builder_version=&#8221;4.16&#8243; text_font=&#8221;Crushed||||||||&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #86A293;\"><strong>IN OMAGGIO<\/strong><\/span>, solo per chi compra il mio libro su questo blog, una copia della <strong>Prima Edizione da Collezione della mia Guida Vini Spumanti &#8220;500 Bolle in 500&#8221;<\/strong>, prezzo di copertina 25,30 \u20ac. [Fino ad esaurimento scorte]<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.17.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_column _builder_version=&#8221;4.17.4&#8243; _module_preset=&#8221;default&#8221; type=&#8221;4_4&#8243;][et_pb_text _builder_version=&#8221;4.17.4&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p style=\"text-align: left;\"><span>Il dolce mi ha davvero emozionato: una <strong>cassata siciliana<\/strong> rivisitata (il mio dessert preferito in assoluto!) con una crema alla ricotta di bufala giocata su due consistenze. La prima, interna, pi\u00f9 simile a un semifreddo, ha la classica consistenza della crema del ripieno della cassata. La seconda, il topper della monoporzione, \u00e8 molto soffice, quasi setosa. Delizioso anche il croccante. Molto carina la presentazione, chiede solo un po&#8217; pi\u00f9 di precisione nella stesura sopra per essere assolutamente perfetta. L&#8217;abbinamento che mi ha suggerito il cameriere Giovanni, che mi conosce bene, \u00e8 stato il <strong>Riesling Passito Benaco Bresciano IGT Cascina San Giovanni di un&#8217;azienda (quasi) locale: Pasini<\/strong>. Beh, mi \u00e8 piaciuto cos\u00ec tanto che andr\u00f2 a trovarli al pi\u00f9 presto!<\/span><\/p>\n<p style=\"text-align: left;\"><span>Il caff\u00e8 \u00e8 buono, cosa assolutamente rara, in un ristorante di qualsiasi livello. E la piccola pasticceria che l&#8217;accompagna \u00e8 semplicemente divina: il cannoncino \u00e8 stato il pi\u00f9 buono della mia vita! Appena riempito, sfogliato bene e molto caramellato, ha creato uno splendido contrasto dolce e amaro con la crema.<\/span><\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/09\/guida-michelin-ristorante-tentazioni-costa-volpino-1.jpg&#8221; alt=&#8221;guida michelin ristorante tentazioni costa volpino&#8221; title_text=&#8221;guida-michelin-ristorante-tentazioni-costa-volpino-1&#8243; _builder_version=&#8221;4.17.4&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; border_radii=&#8221;on|8px|8px|8px|8px&#8221; border_width_all=&#8221;3px&#8221; border_color_all=&#8221;gcid-21fbec71-877e-4169-81a6-b6b5df6aa348&#8243; box_shadow_style=&#8221;preset3&#8243; global_colors_info=&#8221;{%22gcid-21fbec71-877e-4169-81a6-b6b5df6aa348%22:%91%22border_color_all%22%93}&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.17.4&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p style=\"text-align: left;\"><span><strong>Ho segnalato Sandro e Giacomo Pittelli gi\u00e0 una volta alla Michelin anni fa<\/strong>, e ho intenzione di mandare loro anche questo articolo per vedere se inviano un ispettore. Mi aspetto di vedere Tentazioni Ristorante massimo nella Guida 2023 e almeno con una forchetta, se non con una stella: il locale oltretutto \u00e8 di una bellezza e una cura disarmanti, mille volte meglio di tanti altri ristoranti che ho visto in guida, talvolta con arredi molto datati.\u00a0<\/span><\/p>\n<p style=\"text-align: left;\"><span>La Michelin \u00e8 diventata ormai la consacrazione di uno Chef.\u00a0<\/span><span>Per me, tuttavia,<strong> la vera consacrazione \u00e8 un ristorante pieno di clienti felici e ansiosi di ritornare, come eravamo io e Francesco venerd\u00ec sera<\/strong>.<\/span><\/p>\n<p style=\"text-align: left;\"><span>Cheers \ud83c\udf77<\/span><\/p>\n<p style=\"text-align: left;\"><span>Chiara<\/span><\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/09\/guida-michelin-ristorante-tentazioni-costa-volpino-9.jpg&#8221; alt=&#8221;guida michelin ristorante tentazioni costa volpino&#8221; title_text=&#8221;guida-michelin-ristorante-tentazioni-costa-volpino-9&#8243; _builder_version=&#8221;4.17.4&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; border_radii=&#8221;on|8px|8px|8px|8px&#8221; border_width_all=&#8221;3px&#8221; border_color_all=&#8221;gcid-21fbec71-877e-4169-81a6-b6b5df6aa348&#8243; box_shadow_style=&#8221;preset3&#8243; global_colors_info=&#8221;{%22gcid-21fbec71-877e-4169-81a6-b6b5df6aa348%22:%91%22border_color_all%22%93}&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Venerd\u00ec sera, dopo mesi di clausura per la stesura della nuova edizione del mio libro, ho deciso di passare con mio marito una serata speciale per festeggiare la fine di questo lavoro cos\u00ec immenso. Cos\u00ec sono andata nel mio ristorante preferito, nell&#8217;unico ristorante capace di superare le mie sempre alte aspettative: Tentazioni Ristorante di Costa [&hellip;]<\/p>\n","protected":false},"author":49,"featured_media":30407,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"2880","footnotes":""},"categories":[501],"tags":[],"class_list":["post-30340","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ristoranti"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.0 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Guida Michelin: riflessioni &quot;dopo cena&quot; - Perlage Suite<\/title>\n<meta name=\"description\" content=\"Guida Michelin: un articolo &quot;scomodo&quot; dopo una cena perfetta nato (giuro) non per fare polemica ma per riflettere insieme sulle guide nella ristorazione.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/perlagesuite.com\/en\/guida-michelin-riflessioni-dopo-cena\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Guida Michelin: riflessioni &quot;dopo cena&quot;\" \/>\n<meta property=\"og:description\" content=\"Guida Michelin: un articolo &quot;scomodo&quot; dopo una cena perfetta nato (giuro) non per fare polemica ma per riflettere insieme sulle guide nella ristorazione.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/perlagesuite.com\/en\/guida-michelin-riflessioni-dopo-cena\/\" \/>\n<meta property=\"og:site_name\" content=\"Perlage Suite\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/chiarabassiperlagesuite\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-20T16:41:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-14T00:17:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/09\/guida-michelin-ristorante-tentazioni-costa-volpino.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Chiara Bassi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@perlagesuite\" \/>\n<meta name=\"twitter:site\" content=\"@perlagesuite\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Chiara Bassi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/guida-michelin-riflessioni-dopo-cena\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/guida-michelin-riflessioni-dopo-cena\\\/\"},\"author\":{\"name\":\"Chiara Bassi\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/person\\\/81b257517a1007c1a823318ac86c6013\"},\"headline\":\"Guida Michelin: riflessioni &#8220;dopo cena&#8221;\",\"datePublished\":\"2021-09-20T16:41:03+00:00\",\"dateModified\":\"2022-06-14T00:17:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/guida-michelin-riflessioni-dopo-cena\\\/\"},\"wordCount\":3221,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/guida-michelin-riflessioni-dopo-cena\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/guida-michelin-ristorante-tentazioni-costa-volpino.jpg\",\"articleSection\":[\"Ristoranti\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/perlagesuite.com\\\/guida-michelin-riflessioni-dopo-cena\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/guida-michelin-riflessioni-dopo-cena\\\/\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/guida-michelin-riflessioni-dopo-cena\\\/\",\"name\":\"Guida Michelin: riflessioni \\\"dopo cena\\\" - Perlage Suite\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/guida-michelin-riflessioni-dopo-cena\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/guida-michelin-riflessioni-dopo-cena\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/guida-michelin-ristorante-tentazioni-costa-volpino.jpg\",\"datePublished\":\"2021-09-20T16:41:03+00:00\",\"dateModified\":\"2022-06-14T00:17:04+00:00\",\"description\":\"Guida Michelin: un articolo \\\"scomodo\\\" dopo una cena perfetta nato (giuro) non per fare polemica ma per riflettere insieme sulle guide nella ristorazione.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/guida-michelin-riflessioni-dopo-cena\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/perlagesuite.com\\\/guida-michelin-riflessioni-dopo-cena\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/guida-michelin-riflessioni-dopo-cena\\\/#primaryimage\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/guida-michelin-ristorante-tentazioni-costa-volpino.jpg\",\"contentUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/guida-michelin-ristorante-tentazioni-costa-volpino.jpg\",\"width\":1080,\"height\":720,\"caption\":\"guida michelin ristorante tentazioni costa volpino\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/guida-michelin-riflessioni-dopo-cena\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/perlagesuite.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Guida Michelin: riflessioni &#8220;dopo cena&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#website\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/\",\"name\":\"Perlage Suite\",\"description\":\"Il Wine Blog di Chiara Bassi\",\"publisher\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/perlagesuite.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#organization\",\"name\":\"Chiara Bassi\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Chiara-Bassi-sommelier-wine-blogger-logo.png\",\"contentUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Chiara-Bassi-sommelier-wine-blogger-logo.png\",\"width\":512,\"height\":512,\"caption\":\"Chiara Bassi\"},\"image\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/chiarabassiperlagesuite\",\"https:\\\/\\\/x.com\\\/perlagesuite\",\"https:\\\/\\\/www.instagram.com\\\/perlagesuite\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/person\\\/81b257517a1007c1a823318ac86c6013\",\"name\":\"Chiara Bassi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g\",\"caption\":\"Chiara Bassi\"},\"sameAs\":[\"https:\\\/\\\/perlagesuite.com\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Michelin Guide: 'after dinner' reflections - Perlage Suite","description":"Michelin Guide: an 'uncomfortable' article after a perfect dinner born (I swear) not to be controversial but to reflect together on guides in the restaurant industry.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/perlagesuite.com\/en\/guida-michelin-riflessioni-dopo-cena\/","og_locale":"en_GB","og_type":"article","og_title":"Guida Michelin: riflessioni \"dopo cena\"","og_description":"Guida Michelin: un articolo \"scomodo\" dopo una cena perfetta nato (giuro) non per fare polemica ma per riflettere insieme sulle guide nella ristorazione.","og_url":"https:\/\/perlagesuite.com\/en\/guida-michelin-riflessioni-dopo-cena\/","og_site_name":"Perlage Suite","article_publisher":"https:\/\/www.facebook.com\/chiarabassiperlagesuite","article_published_time":"2021-09-20T16:41:03+00:00","article_modified_time":"2022-06-14T00:17:04+00:00","og_image":[{"width":1080,"height":720,"url":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/09\/guida-michelin-ristorante-tentazioni-costa-volpino.jpg","type":"image\/jpeg"}],"author":"Chiara Bassi","twitter_card":"summary_large_image","twitter_creator":"@perlagesuite","twitter_site":"@perlagesuite","twitter_misc":{"Written by":"Chiara Bassi","Estimated reading time":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/perlagesuite.com\/guida-michelin-riflessioni-dopo-cena\/#article","isPartOf":{"@id":"https:\/\/perlagesuite.com\/guida-michelin-riflessioni-dopo-cena\/"},"author":{"name":"Chiara Bassi","@id":"https:\/\/perlagesuite.com\/#\/schema\/person\/81b257517a1007c1a823318ac86c6013"},"headline":"Guida Michelin: riflessioni &#8220;dopo cena&#8221;","datePublished":"2021-09-20T16:41:03+00:00","dateModified":"2022-06-14T00:17:04+00:00","mainEntityOfPage":{"@id":"https:\/\/perlagesuite.com\/guida-michelin-riflessioni-dopo-cena\/"},"wordCount":3221,"commentCount":0,"publisher":{"@id":"https:\/\/perlagesuite.com\/#organization"},"image":{"@id":"https:\/\/perlagesuite.com\/guida-michelin-riflessioni-dopo-cena\/#primaryimage"},"thumbnailUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/09\/guida-michelin-ristorante-tentazioni-costa-volpino.jpg","articleSection":["Ristoranti"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/perlagesuite.com\/guida-michelin-riflessioni-dopo-cena\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/perlagesuite.com\/guida-michelin-riflessioni-dopo-cena\/","url":"https:\/\/perlagesuite.com\/guida-michelin-riflessioni-dopo-cena\/","name":"Michelin Guide: 'after dinner' reflections - Perlage Suite","isPartOf":{"@id":"https:\/\/perlagesuite.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/perlagesuite.com\/guida-michelin-riflessioni-dopo-cena\/#primaryimage"},"image":{"@id":"https:\/\/perlagesuite.com\/guida-michelin-riflessioni-dopo-cena\/#primaryimage"},"thumbnailUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/09\/guida-michelin-ristorante-tentazioni-costa-volpino.jpg","datePublished":"2021-09-20T16:41:03+00:00","dateModified":"2022-06-14T00:17:04+00:00","description":"Michelin Guide: an 'uncomfortable' article after a perfect dinner born (I swear) not to be controversial but to reflect together on guides in the restaurant industry.","breadcrumb":{"@id":"https:\/\/perlagesuite.com\/guida-michelin-riflessioni-dopo-cena\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/perlagesuite.com\/guida-michelin-riflessioni-dopo-cena\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/perlagesuite.com\/guida-michelin-riflessioni-dopo-cena\/#primaryimage","url":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/09\/guida-michelin-ristorante-tentazioni-costa-volpino.jpg","contentUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/09\/guida-michelin-ristorante-tentazioni-costa-volpino.jpg","width":1080,"height":720,"caption":"guida michelin ristorante tentazioni costa volpino"},{"@type":"BreadcrumbList","@id":"https:\/\/perlagesuite.com\/guida-michelin-riflessioni-dopo-cena\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/perlagesuite.com\/"},{"@type":"ListItem","position":2,"name":"Guida Michelin: riflessioni &#8220;dopo cena&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/perlagesuite.com\/#website","url":"https:\/\/perlagesuite.com\/","name":"Perlage Suite","description":"Chiara Bassi's Wine Blog","publisher":{"@id":"https:\/\/perlagesuite.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/perlagesuite.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/perlagesuite.com\/#organization","name":"Chiara Bassi","url":"https:\/\/perlagesuite.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/perlagesuite.com\/#\/schema\/logo\/image\/","url":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2022\/03\/Chiara-Bassi-sommelier-wine-blogger-logo.png","contentUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2022\/03\/Chiara-Bassi-sommelier-wine-blogger-logo.png","width":512,"height":512,"caption":"Chiara Bassi"},"image":{"@id":"https:\/\/perlagesuite.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/chiarabassiperlagesuite","https:\/\/x.com\/perlagesuite","https:\/\/www.instagram.com\/perlagesuite\/"]},{"@type":"Person","@id":"https:\/\/perlagesuite.com\/#\/schema\/person\/81b257517a1007c1a823318ac86c6013","name":"Chiara Bassi","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g","caption":"Chiara Bassi"},"sameAs":["https:\/\/perlagesuite.com"]}]}},"_links":{"self":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/posts\/30340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/comments?post=30340"}],"version-history":[{"count":0,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/posts\/30340\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/media\/30407"}],"wp:attachment":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/media?parent=30340"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/categories?post=30340"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/tags?post=30340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}