{"id":30949,"date":"2021-10-22T00:41:31","date_gmt":"2021-10-21T23:41:31","guid":{"rendered":"https:\/\/perlagesuite.com\/?p=30949"},"modified":"2022-10-04T21:50:26","modified_gmt":"2022-10-04T20:50:26","slug":"tortelli-e-vermentino-toscano-ricetta-e","status":"publish","type":"post","link":"https:\/\/perlagesuite.com\/en\/tortelli-e-vermentino-toscano-ricetta-e\/","title":{"rendered":"Tortelli and Tuscan Vermentino: recipe and..."},"content":{"rendered":"\n[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.9.10&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.9.10&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.9.10&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.11.3&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<p style=\"text-align: justify;\">Stasera volevo coccolare mio marito con un piatto delizioso e, dopo i <strong>tortelli di zucca<\/strong> di ieri sera, ho pensato di inventarmi un ripieno speciale. Ammetto anche un po&#8217; svuotafrigo, dato che ho usato una melanzana che era l\u00ec da un po&#8217;, il mezzo pomodoro cuore di bue che avevo avanzato dal pranzo e poco altro! Questi <strong>tortelli ripieni di verdure<\/strong> non sono solo gustosi, ma sono anche facili, economici e veloci. Li ho abbinati a un <strong>vino vermentino toscano Villa Acquaviva<\/strong>, in fondo all&#8217;articolo troverai la <strong>degustazione<\/strong> e perch\u00e8 ho scelto questo <strong>vino bianco<\/strong> con questo piatto.<\/p>\n<p style=\"text-align: justify;\">I tortelli sono una pasta ripiena tipica dell&#8217;Emilia-Romagna, della Lombardia e della Toscana che pu\u00f2 essere chiusa in vari modi. Per praticit\u00e0 io taglio la sfoglia con un coppapasta tondo di 8 cm di diamentro, metto il ripieno, chiudo a mezzaluna e chiudo ancora sovrapponendo i bordi tipo tortellino o cappelletto. Se vuoi essere pi\u00f9 veloce puoi chiuderli anche &#8220;solo&#8221; a mezzaluna: saranno comunque buonissimi! <span>\ud83e\udd29<\/span><\/p>\n<p style=\"text-align: justify;\">NB: in questa ricetta non mi sono preoccupata di chiuderli con precisione maniacale perch\u00e8 \u00e8 un piatto della nostra cucina quotidiana. <span>\ud83d\ude4f<\/span><\/p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/10\/tortelli-ricetta-vermentino-toscano-3.jpg&#8221; alt=&#8221;tortelli ricetta vermentino toscano&#8221; title_text=&#8221;tortelli-ricetta-vermentino-toscano-3&#8243; _builder_version=&#8221;4.11.3&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|8px|8px|8px|8px&#8221; border_width_all=&#8221;3px&#8221; border_color_all=&#8221;#da413d&#8221; box_shadow_style=&#8221;preset3&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.11.3&#8243; _module_preset=&#8221;default&#8221; header_2_font=&#8221;Delius Unicase|700|||||||&#8221; header_2_font_size=&#8221;20px&#8221; header_3_font=&#8221;Delius Unicase|700|||||||&#8221; header_3_font_size=&#8221;15px&#8221; custom_margin=&#8221;||9px|||&#8221; global_colors_info=&#8221;{}&#8221;]<h2 style=\"text-align: justify;\"><span>Tortelli ricetta: ingredienti per 30 tortelloni<\/span><\/h2>\n<h3><span>Per la pasta fresca fatta in casa:<\/span><\/h3>\n<ul>\n<li><span>2 uova grandi extra fresche, meglio scegliere quelle giallo pasta<\/span><\/li>\n<li><span>190 g di farina di semola rimacinata<\/span><\/li>\n<\/ul>\n<h3><span>Per il ripieno:<\/span><\/h3>\n<ul>\n<li><span>1 melanzana piccola<\/span><\/li>\n<li><span>1 pomodoro cuore di bue<\/span><\/li>\n<li><span>50 g di tonno<\/span><\/li>\n<li><span>50 g di pangrattato<\/span><\/li>\n<li><span>50 g di formaggio grana grattuggiato<\/span><\/li>\n<li><span>1 cucchiaio d&#8217;olio extravergine di oliva<\/span><\/li>\n<li><span>un pizzico di sale<\/span><\/li>\n<li><span>un pizzico di noce moscata (facoltativo)<\/span><\/li>\n<li><span>semi di aneto (facoltativo)<\/span><\/li>\n<\/ul>\n<p><span><\/span><\/p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.11.3&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<p style=\"text-align: justify;\"><span>Se questa ricetta ti piace iscriviti alla mia newsletter oppure scorri la pagina per scoprire il procedimento! \ud83d\ude09<\/span><\/p>[\/et_pb_text][et_pb_signup provider=&#8221;mailpoet&#8221; mailpoet_list=&#8221;PEPEblu|49&#8243; success_message=&#8221;Controlla la tua e-mail: hai appena ricevuto un mio messaggio per confermare la tua iscrizione! Se non lo visualizzi controlla in spam o nella cartella %22promozioni%22 di Gmail. Grazie e a presto!&#8221; title=&#8221;Ti piace questo contenuto?&#8221; button_text=&#8221;Iscriviti subito!&#8221; description=&#8221;<p style=%22text-align: justify;%22>Iscriviti alla mia newsletter per non perderti nessun nuovo articolo del mio blog!<\/p>\n<p style=%22text-align: justify;%22>Non ti invier\u00f2 SPAM, ma solo la notifica dei nuovi articoli! Di tanto in tanto potrai ricevere anche qualche coupon per acquistare vino o partecipare ad eventi con condizioni speciali riservate ai lettori del mio blog!<\/p>\n<p style=%22text-align: justify;%22>Cheers \ud83e\udd29\ud83e\udd42<\/p>\n&#8221; footer_content=&#8221;Iscrivendoti accetti le condizioni della <a href=%22https:\/\/perlagesuite.com\/privacy-2\/%22 data-et-target-link=%22_blank%22 rel=%22noopener noreferrer%22><span style=%22text-decoration: underline;%22><strong>Privacy<\/strong><\/span><\/a> di Perlage Suite.&#8221; _builder_version=&#8221;4.7.7&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Delius Unicase|700|||||||&#8221; header_font_size=&#8221;22px&#8221; body_font=&#8221;Delius||||||||&#8221; background_color=&#8221;#008c96&#8243; box_shadow_style=&#8221;preset3&#8243; box_shadow_color=&#8221;rgba(0,140,150,0.6)&#8221; global_module=&#8221;27234&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_signup][et_pb_text _builder_version=&#8221;4.11.3&#8243; _module_preset=&#8221;default&#8221; header_2_font=&#8221;Delius Unicase|700|||||||&#8221; header_2_font_size=&#8221;20px&#8221; header_3_font=&#8221;Delius Unicase|700|||||||&#8221; header_3_font_size=&#8221;15px&#8221; custom_margin=&#8221;||9px|||&#8221; global_colors_info=&#8221;{}&#8221;]<h2 style=\"text-align: justify;\"><span>Ricetta tortelli: preparazione<\/span><\/h2>\n<h3><span>Per la pasta fresca all&#8217;uovo fatta in casa, fase 1:<\/span><\/h3>\n<p style=\"text-align: justify;\"><strong>Passo 1.<\/strong> In un recipiente metti le uova e sbattile qualche secondo con la forchetta. Aggiungi la farina e mescola con la stessa forchetta.<\/p>\n<p style=\"text-align: justify;\"><strong>Passo 2.\u00a0<\/strong>Trasferisci il composto su un piano pulito con acqua o aceto (no detersivi). Visto che la quantit\u00e0 \u00e8 poca, puoi impastarla a mano fin tanto che non ottieni un panetto uniforme, liscio ed elastico. Ci vorranno circa 5 minuti.<\/p>\n<p style=\"text-align: justify;\"><strong>Passo 3.\u00a0<\/strong>Copri con la stessa ciotola e lascia riposare il tempo di tagliare e mettere a cuocere le verdure per il ripieno.<\/p>\n<h3><span>Per il ripieno, fase 1:<\/span><\/h3>\n<p style=\"text-align: justify;\"><strong>Passo 4. <\/strong>Scalda un cucchiaio d&#8217;olio in un wok o in una padella antiaderente mentre tagli a cubetti regolari il pomodoro e la melanzana. Considera che non c&#8217;\u00e8 una regola per le dimensioni dei cubetti (tanto dopo frulliamo tutto), semplicemente ti cambieranno i tempi di cottura.<\/p>\n<p style=\"text-align: justify;\"><strong>Passo 5. <\/strong>Cuoci per circa 15 minuti a fuoco medio le verdure mescolando all&#8217;occorrenza. Se si sta asciugando troppo, aggiungi un mestolo d&#8217;acqua calda o di brodo di verdure<span><\/span><\/p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.11.3&#8243; _module_preset=&#8221;default&#8221; header_2_font=&#8221;Delius Unicase|700|||||||&#8221; header_2_font_size=&#8221;20px&#8221; header_3_font=&#8221;Delius Unicase|700|||||||&#8221; header_3_font_size=&#8221;15px&#8221; custom_margin=&#8221;||9px|||&#8221; global_colors_info=&#8221;{}&#8221;]<h3><span>Per la pasta fresca all&#8217;uovo fatta in casa, fase 2:<\/span><\/h3>\n<p style=\"text-align: justify;\"><strong>Passo 6.<\/strong> Appiattisci la pasta con le mani o con un mattarello e appena \u00e8 circa un cm passala tra i rulli configurati nel modo pi\u00f9 largo di una macchina per la pasta (io utilizzo <a href=\"https:\/\/amzn.to\/30Fym4k\" target=\"_blank\" rel=\"noopener\"><strong>questa macchina della pasta di Marcato<\/strong><\/a> dal lontano 2006!) che c&#8217;\u00e8 tempo per diventare delle casalinghe disperate. E poi sar\u00e0 che io utilizzo solo il mattarello in silicone per motivi igienici, la ruvidit\u00e0 ottenuta \u00e8 praticamente identica. Anzi, per la mia esperienza la ruvidit\u00e0 della pasta fresca veloce o tradizionale \u00e8 condizionata di pi\u00f9 dall&#8217;utilizzo sapiente della semola! Arriva fino al numero 5 della macchinetta, stringendo ad ogni passaggio e compi un passaggio alla volta e senza infarinarla troppo perch\u00e8 per chiudere pi\u00f9 agevolmente i tortelli ci serve una sfoglia umida. Considera che io infarino solo un po&#8217; il piano di lavoro e basta. Sul web troverai scritto di ripiegare la pasta&#8230; boh, a me ha insegnato a farla mia nonna cos\u00ec, noi non abbiamo mai piegato niente e la pasta ci \u00e8 sempre uscita eccezionale!<\/p>\n<p style=\"text-align: justify;\"><strong>Passo 7.\u00a0<\/strong>Con il coppapasta tondo da circa 8 cm di diametro (come <a href=\"https:\/\/amzn.to\/3jlXF1J\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\"><strong>questo set di coppapasta di kaiser<\/strong><\/span><\/a>, ma se non ce l&#8217;hai puoi aiutarti con un bicchiere!) ricava dei dischetti. Impasta e stendi anche i ritagli, fino ad ottenere circa 30 dischetti.<\/p>\n<h3><span>Per il ripieno, fase 2:<\/span><\/h3>\n<p style=\"text-align: justify;\"><strong>Passo 8. <\/strong>Frulla le verdure (io utilizzo il minipimer ad immersione nel suo bicchiere) in modo grossolano.<\/p>\n<p style=\"text-align: justify;\"><strong>Passo 9. <\/strong>Trasferisci 200g di verdure frullate in una ciotola e aggiungi il resto degli ingredienti. Mescola con una forchetta.<span><\/span><\/p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/10\/tortelli-ricetta-vermentino-toscano-1.jpg&#8221; alt=&#8221;tortelli ricetta vermentino toscano&#8221; title_text=&#8221;tortelli-ricetta-vermentino-toscano-1&#8243; _builder_version=&#8221;4.11.3&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|8px|8px|8px|8px&#8221; border_width_all=&#8221;3px&#8221; border_color_all=&#8221;#da413d&#8221; box_shadow_style=&#8221;preset3&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.11.3&#8243; _module_preset=&#8221;default&#8221; header_2_font=&#8221;Delius Unicase|700|||||||&#8221; header_2_font_size=&#8221;20px&#8221; header_3_font=&#8221;Delius Unicase|700|||||||&#8221; header_3_font_size=&#8221;15px&#8221; custom_margin=&#8221;||9px|||&#8221; global_colors_info=&#8221;{}&#8221;]<h3><span>Per la pasta fresca all&#8217;uovo ripiena, fase 3:<\/span><\/h3>\n<p style=\"text-align: justify;\"><strong>Passo 10.<\/strong>\u00a0In ogni dischetto poni al centro un bel cucchiaino abbondante di ripieno.<\/p>\n<p style=\"text-align: justify;\"><strong>Passo 11.\u00a0<\/strong>Piega il dischetto a mezzaluna e schiaccia bene il bordo con le dita. Eventualmente fai ancora una piega unendo i bordi uno sopra all&#8217;altro e schiaccia per dare la forma al tortellone.<\/p>\n<h3><span>Per la cottura, fase 4:<\/span><\/h3>\n<p style=\"text-align: justify;\"><strong>Passo 12. <\/strong>Cuoci i tortelli in acqua bollente salata e aspetta che vengano a galla. Dopo circa un minuto trasferiscili nella padella dove hai cotto le verdure con eventualmente un cucchiaio delle verdure frullate che dovresti avere avanzato e un mezzo mestolo d&#8217;acqua di cottura e lasciali andare a fuoco minimo per qualche minuto finch\u00e8 non hanno un aspetto simile alla foto sopra. Trasferiscili nel piatto e completa con qualche seme di aneto.<\/p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.11.3&#8243; _module_preset=&#8221;default&#8221; header_2_font=&#8221;Delius Unicase|700|||||||&#8221; header_2_font_size=&#8221;20px&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<h2 style=\"text-align: justify;\"><span>Vermentino Maremma Toscana DOC 2020, Villa Acquaviva<\/span><\/h2>\n<p style=\"text-align: justify;\"><span>Si presenta giallo paglierino intenso e brillante. Al naso \u00e8 profumato, caratteristico, elegante e piacevole. Si riconoscono note di fiori di origano, frutti del cappero, iodio e pera candita, con un finale quasi mielato. In bocca \u00e8 coerente, strutturato e caratterizzato da una grande sapidit\u00e0 e una buona lunghezza di bocca.<\/span><\/p>\n<p style=\"text-align: justify;\"><span>Le uve di vermentino sono raccolte a mano in piccole cassette e, dopo una pressatura soffice, viene vinificato in acciaio per circa sei mesi per mantenere le tipicit\u00e0 del vitigno alla sua perfetta maturazione. Prima della messa in commercio trascorre ancora qualche mese in bottiglia per equilibrarsi.<\/span><\/p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/10\/tortelli-ricetta-vermentino-toscano-2.jpg&#8221; alt=&#8221;tortelli ricetta vermentino toscano&#8221; title_text=&#8221;tortelli-ricetta-vermentino-toscano-2&#8243; _builder_version=&#8221;4.11.3&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|8px|8px|8px|8px&#8221; border_width_all=&#8221;3px&#8221; border_color_all=&#8221;#da413d&#8221; box_shadow_style=&#8221;preset3&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.11.3&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<p style=\"text-align: justify;\"><span>Adoro sperimentare <strong>tortelloni ripieni<\/strong> di qualsiasi cosa mi viene in mente! Se cerchi una <strong>ricetta per tortelli<\/strong> originale ti consiglio di provarla. Se ti serve un consiglio, vuoi suggerirmi una variante o farmi sapere se questo <strong>vermentino Villa Acquaviva<\/strong> ti \u00e8 piaciuto puoi scorrere la pagina e lasciarmi un commento!<\/span><\/p>\n<p style=\"text-align: justify;\"><span>Cheers \ud83c\udf77<\/span><\/p>\n<p style=\"text-align: justify;\"><span>Chiara<\/span><\/p>\n<p style=\"text-align: justify;\"><span>P.S. Il piatto nella foto mi \u00e8 servito a capire che i tortelloni erano cotti e per fare la degustazione e l&#8217;abbinamento. Ha seguito la cena con la porzione reale di 12 tortelli per me e 15 per mio marito, ovviamente!<\/span><\/p>[\/et_pb_text][et_pb_divider color=&#8221;#da413d&#8221; _builder_version=&#8221;4.9.10&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.0.6&#8243; global_module=&#8221;21425&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.0.6&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_wc_images product=&#8221;10582&#8243; show_product_gallery=&#8221;off&#8221; _builder_version=&#8221;4.9.4&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_wc_images][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.0.6&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_wc_title product=&#8221;10582&#8243; _builder_version=&#8221;4.0.6&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_wc_title][et_pb_text _builder_version=&#8221;4.9.4&#8243; text_font=&#8221;Delius Unicase||||||||&#8221; global_colors_info=&#8221;{}&#8221;]<p style=\"text-align: justify;\"><span style=\"color: #ff0000;\"><span style=\"caret-color: #ff0000;\"><b>Tutti i miei appunti sul vino e sul cibo in un solo libro.<\/b><\/span><\/span><\/p>[\/et_pb_text][et_pb_wc_rating product=&#8221;10582&#8243; _builder_version=&#8221;4.0.6&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_wc_rating][et_pb_wc_price product=&#8221;10582&#8243; _builder_version=&#8221;4.0.6&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_wc_price][et_pb_wc_add_to_cart product=&#8221;10582&#8243; _builder_version=&#8221;4.0.6&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_wc_add_to_cart][et_pb_text _builder_version=&#8221;4.9.4&#8243; text_font=&#8221;Delius Unicase||||||||&#8221; global_colors_info=&#8221;{}&#8221;]<p style=\"text-align: justify;\"><span style=\"color: #ff0000;\"><strong>IN OMAGGIO<\/strong><\/span>, solo per chi compra il mio libro su questo blog, una copia della <strong>Prima Edizione da Collezione della mia Guida Vini Spumanti &#8220;500 Bolle in 500&#8221;<\/strong>, prezzo di copertina 25,30 \u20ac. [Fino ad esaurimento scorte]<\/p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]\n","protected":false},"excerpt":{"rendered":"<p>Stasera volevo coccolare mio marito con un piatto delizioso e, dopo i tortelli di zucca di ieri sera, ho pensato di inventarmi un ripieno speciale. Ammetto anche un po&#8217; svuotafrigo, dato che ho usato una melanzana che era l\u00ec da un po&#8217;, il mezzo pomodoro cuore di bue che avevo avanzato dal pranzo e poco [&hellip;]<\/p>\n","protected":false},"author":49,"featured_media":30986,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"2880","footnotes":""},"categories":[537,299],"tags":[],"class_list":["post-30949","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primi-piatti","category-ricette"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.0 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Tortelli e vermentino toscano: ricetta e abbinamento | Perlage Suite<\/title>\n<meta name=\"description\" content=\"Tortelli: una ricetta facile e particolare da fare a casa in abbinamento a vino vermentino toscano di Villa Acquaviva per stupire!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/perlagesuite.com\/en\/tortelli-e-vermentino-toscano-ricetta-e\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tortelli e vermentino toscano: ricetta e...\" \/>\n<meta property=\"og:description\" content=\"Tortelli: una ricetta facile e particolare da fare a casa in abbinamento a vino vermentino toscano di Villa Acquaviva per stupire!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/perlagesuite.com\/en\/tortelli-e-vermentino-toscano-ricetta-e\/\" \/>\n<meta property=\"og:site_name\" content=\"Perlage Suite\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/chiarabassiperlagesuite\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-21T23:41:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-04T20:50:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/10\/tortelli-vermentino-toscano.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Chiara Bassi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@perlagesuite\" \/>\n<meta name=\"twitter:site\" content=\"@perlagesuite\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Chiara Bassi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/tortelli-e-vermentino-toscano-ricetta-e\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/tortelli-e-vermentino-toscano-ricetta-e\\\/\"},\"author\":{\"name\":\"Chiara Bassi\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/person\\\/81b257517a1007c1a823318ac86c6013\"},\"headline\":\"Tortelli e vermentino toscano: ricetta e&#8230;\",\"datePublished\":\"2021-10-21T23:41:31+00:00\",\"dateModified\":\"2022-10-04T20:50:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/tortelli-e-vermentino-toscano-ricetta-e\\\/\"},\"wordCount\":1783,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/tortelli-e-vermentino-toscano-ricetta-e\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/tortelli-vermentino-toscano.jpg\",\"articleSection\":[\"Primi Piatti\",\"Ricette &amp; Abbinamenti\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/perlagesuite.com\\\/tortelli-e-vermentino-toscano-ricetta-e\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/tortelli-e-vermentino-toscano-ricetta-e\\\/\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/tortelli-e-vermentino-toscano-ricetta-e\\\/\",\"name\":\"Tortelli e vermentino toscano: ricetta e abbinamento | Perlage Suite\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/tortelli-e-vermentino-toscano-ricetta-e\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/tortelli-e-vermentino-toscano-ricetta-e\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/tortelli-vermentino-toscano.jpg\",\"datePublished\":\"2021-10-21T23:41:31+00:00\",\"dateModified\":\"2022-10-04T20:50:26+00:00\",\"description\":\"Tortelli: una ricetta facile e particolare da fare a casa in abbinamento a vino vermentino toscano di Villa Acquaviva per stupire!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/tortelli-e-vermentino-toscano-ricetta-e\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/perlagesuite.com\\\/tortelli-e-vermentino-toscano-ricetta-e\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/tortelli-e-vermentino-toscano-ricetta-e\\\/#primaryimage\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/tortelli-vermentino-toscano.jpg\",\"contentUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/tortelli-vermentino-toscano.jpg\",\"width\":1080,\"height\":720,\"caption\":\"tortelli vermentino toscano\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/tortelli-e-vermentino-toscano-ricetta-e\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/perlagesuite.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tortelli e vermentino toscano: ricetta e&#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#website\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/\",\"name\":\"Perlage Suite\",\"description\":\"Il Wine Blog di Chiara Bassi\",\"publisher\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/perlagesuite.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#organization\",\"name\":\"Chiara Bassi\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Chiara-Bassi-sommelier-wine-blogger-logo.png\",\"contentUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Chiara-Bassi-sommelier-wine-blogger-logo.png\",\"width\":512,\"height\":512,\"caption\":\"Chiara Bassi\"},\"image\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/chiarabassiperlagesuite\",\"https:\\\/\\\/x.com\\\/perlagesuite\",\"https:\\\/\\\/www.instagram.com\\\/perlagesuite\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/person\\\/81b257517a1007c1a823318ac86c6013\",\"name\":\"Chiara Bassi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g\",\"caption\":\"Chiara Bassi\"},\"sameAs\":[\"https:\\\/\\\/perlagesuite.com\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tortelli and Tuscan vermentino: recipe and pairing | Perlage Suite","description":"Tortelli: an easy and special recipe to make at home in combination with Tuscan vermentino wine from Villa Acquaviva to amaze!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/perlagesuite.com\/en\/tortelli-e-vermentino-toscano-ricetta-e\/","og_locale":"en_GB","og_type":"article","og_title":"Tortelli e vermentino toscano: ricetta e...","og_description":"Tortelli: una ricetta facile e particolare da fare a casa in abbinamento a vino vermentino toscano di Villa Acquaviva per stupire!","og_url":"https:\/\/perlagesuite.com\/en\/tortelli-e-vermentino-toscano-ricetta-e\/","og_site_name":"Perlage Suite","article_publisher":"https:\/\/www.facebook.com\/chiarabassiperlagesuite","article_published_time":"2021-10-21T23:41:31+00:00","article_modified_time":"2022-10-04T20:50:26+00:00","og_image":[{"width":1080,"height":720,"url":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/10\/tortelli-vermentino-toscano.jpg","type":"image\/jpeg"}],"author":"Chiara Bassi","twitter_card":"summary_large_image","twitter_creator":"@perlagesuite","twitter_site":"@perlagesuite","twitter_misc":{"Written by":"Chiara Bassi","Estimated reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/perlagesuite.com\/tortelli-e-vermentino-toscano-ricetta-e\/#article","isPartOf":{"@id":"https:\/\/perlagesuite.com\/tortelli-e-vermentino-toscano-ricetta-e\/"},"author":{"name":"Chiara Bassi","@id":"https:\/\/perlagesuite.com\/#\/schema\/person\/81b257517a1007c1a823318ac86c6013"},"headline":"Tortelli e vermentino toscano: ricetta e&#8230;","datePublished":"2021-10-21T23:41:31+00:00","dateModified":"2022-10-04T20:50:26+00:00","mainEntityOfPage":{"@id":"https:\/\/perlagesuite.com\/tortelli-e-vermentino-toscano-ricetta-e\/"},"wordCount":1783,"commentCount":0,"publisher":{"@id":"https:\/\/perlagesuite.com\/#organization"},"image":{"@id":"https:\/\/perlagesuite.com\/tortelli-e-vermentino-toscano-ricetta-e\/#primaryimage"},"thumbnailUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/10\/tortelli-vermentino-toscano.jpg","articleSection":["Primi Piatti","Ricette &amp; Abbinamenti"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/perlagesuite.com\/tortelli-e-vermentino-toscano-ricetta-e\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/perlagesuite.com\/tortelli-e-vermentino-toscano-ricetta-e\/","url":"https:\/\/perlagesuite.com\/tortelli-e-vermentino-toscano-ricetta-e\/","name":"Tortelli and Tuscan vermentino: recipe and pairing | Perlage Suite","isPartOf":{"@id":"https:\/\/perlagesuite.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/perlagesuite.com\/tortelli-e-vermentino-toscano-ricetta-e\/#primaryimage"},"image":{"@id":"https:\/\/perlagesuite.com\/tortelli-e-vermentino-toscano-ricetta-e\/#primaryimage"},"thumbnailUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/10\/tortelli-vermentino-toscano.jpg","datePublished":"2021-10-21T23:41:31+00:00","dateModified":"2022-10-04T20:50:26+00:00","description":"Tortelli: an easy and special recipe to make at home in combination with Tuscan vermentino wine from Villa Acquaviva to amaze!","breadcrumb":{"@id":"https:\/\/perlagesuite.com\/tortelli-e-vermentino-toscano-ricetta-e\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/perlagesuite.com\/tortelli-e-vermentino-toscano-ricetta-e\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/perlagesuite.com\/tortelli-e-vermentino-toscano-ricetta-e\/#primaryimage","url":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/10\/tortelli-vermentino-toscano.jpg","contentUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/10\/tortelli-vermentino-toscano.jpg","width":1080,"height":720,"caption":"tortelli vermentino toscano"},{"@type":"BreadcrumbList","@id":"https:\/\/perlagesuite.com\/tortelli-e-vermentino-toscano-ricetta-e\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/perlagesuite.com\/"},{"@type":"ListItem","position":2,"name":"Tortelli e vermentino toscano: ricetta e&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/perlagesuite.com\/#website","url":"https:\/\/perlagesuite.com\/","name":"Perlage Suite","description":"Chiara Bassi's Wine Blog","publisher":{"@id":"https:\/\/perlagesuite.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/perlagesuite.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/perlagesuite.com\/#organization","name":"Chiara Bassi","url":"https:\/\/perlagesuite.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/perlagesuite.com\/#\/schema\/logo\/image\/","url":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2022\/03\/Chiara-Bassi-sommelier-wine-blogger-logo.png","contentUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2022\/03\/Chiara-Bassi-sommelier-wine-blogger-logo.png","width":512,"height":512,"caption":"Chiara Bassi"},"image":{"@id":"https:\/\/perlagesuite.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/chiarabassiperlagesuite","https:\/\/x.com\/perlagesuite","https:\/\/www.instagram.com\/perlagesuite\/"]},{"@type":"Person","@id":"https:\/\/perlagesuite.com\/#\/schema\/person\/81b257517a1007c1a823318ac86c6013","name":"Chiara Bassi","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g","caption":"Chiara Bassi"},"sameAs":["https:\/\/perlagesuite.com"]}]}},"_links":{"self":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/posts\/30949","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/comments?post=30949"}],"version-history":[{"count":0,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/posts\/30949\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/media\/30986"}],"wp:attachment":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/media?parent=30949"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/categories?post=30949"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/tags?post=30949"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}