{"id":32361,"date":"2021-12-14T19:48:45","date_gmt":"2021-12-14T18:48:45","guid":{"rendered":"https:\/\/perlagesuite.com\/?p=32361"},"modified":"2022-02-28T20:25:32","modified_gmt":"2022-02-28T19:25:32","slug":"lugana-di-sirmione-vino-cibo-e-territorio","status":"publish","type":"post","link":"https:\/\/perlagesuite.com\/en\/lugana-di-sirmione-vino-cibo-e-territorio\/","title":{"rendered":"Lugana di sirmione: wine, food and territory"},"content":{"rendered":"\n\n\n[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.9.10&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.9.10&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.9.10&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.14.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<p style=\"text-align: justify;\">Il <strong>vino<\/strong> <strong>Lugana DOC<\/strong> deve il suo successo anche alla sua incredibile posizione geografica: \u00e8 prodotto in quel di <strong>Sirmione<\/strong> sul <strong>Lago di Garda<\/strong>. Elaborato da <strong>uve turbiana<\/strong>, chiamate anche <strong>trebbiano di Lugana<\/strong>, \u00e8 un vino bianco adatto a una lunga evoluzione in bottiglia. Per la mia esperienza esistono due stili di Lugana: uno pi\u00f9 verticale e acido &#8211; talvolta ricorda certi riesling tedeschi &#8211; e uno pi\u00f9 grasso e voluminoso. A questo proposito ti invito a leggere <a href=\"https:\/\/perlagesuite.com\/milano-wine-week-2020-masterclass-lugana\/\"><span style=\"text-decoration: underline;\"><strong>questo articolo di una bellissima Masterclass di Lugan<\/strong><strong>a<\/strong><\/span><\/a> a cui ho partecipato, dove hanno spiccato quello &#8220;stile riesling austriaco&#8221; di Cascina Maddalena e quello stile riesling tedesco di Marangona.<\/p>\n<p style=\"text-align: justify;\">Sul sito del <a href=\"https:\/\/www.consorziolugana.it\/consorzio-presentazione\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\"><strong>Consorzio Tutela Lugana DOC<\/strong><\/span><\/a> puoi trovare tantissime informazioni su questo vino e ti invito a consultarlo.\u00a0Per noi appassionati di vino \u00e8 interessante sapere che questo splendido territorio \u00e8 diviso in due zone:<\/p>\n<ol>\n<li style=\"text-align: justify;\">La prima \u00e8 ampia e pianeggiante e si estende orizzontalmente lungo l\u2019entroterra compreso tra Desenzano, Sirmione, una parte del comune di Pozzolengo e Peschiera. Cuore pulsante della denominazione, tra Rovizza e Lugana di Sirmione, frazioni depositarie dello stile pi\u00f9 \u201clacustre\u201d e minerale del Lugana, trova le sue zone storiche ed elettive.\u00a0Nella parte veneta del Lugana, nell&#8217;unico comune di Peschiera del Garda, si trova una delle sottozone pi\u00f9 interessanti, quella di <strong>San Benedetto di Lugana<\/strong>, vero e proprio \u201ccru\u201d della denominazione.<\/li>\n<li style=\"text-align: justify;\"><span>La seconda \u00e8 collinare e si allunga dalla celebre Torre Monumentale di <strong>San Martino della Battaglia<\/strong> lungo le direttrici di Pozzolengo e di Lonato. Qui le dolci colline &#8211; che non superano i 130 m s.l.m. &#8211; presentano terreni morenici con argille pi\u00f9 sabbiose e ghiaia sciolta. Ne derivano vini meno minerali, con una spalla acida pi\u00f9 potente e tanto &#8220;volume&#8221;.<\/span><\/li>\n<\/ol>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/12\/sirmione-lago-di-garda-brescia.jpg&#8221; alt=&#8221;lugana di sirmione lago di garda&#8221; title_text=&#8221;sirmione-lago-di-garda-brescia&#8221; _builder_version=&#8221;4.14.2&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|8px|8px|8px|8px&#8221; border_width_all=&#8221;3px&#8221; border_color_all=&#8221;#da413d&#8221; box_shadow_style=&#8221;preset3&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.14.2&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<h3 style=\"text-align: justify;\"><span>Una wine box come regalo per le feste?<\/span><\/h3>\n<p style=\"text-align: justify;\"><span>Con grande lungimiranza, il <strong>Consorzio Lugana<\/strong> propone delle bellissime <strong>wine box<\/strong> per fare i <strong>regali di Natale<\/strong> e delle feste in generale (io le apprezzo anche se me le regalate per la Befana, eh!\ud83d\ude04). Le <strong>Lugana CheersBox<\/strong> sono 13 e ognuna comprende due bottiglie di vino e una selezione di <strong>prodotti tipici del Lago di Garda<\/strong>, con un prezzo che oscilla tra i 35 \u20ac e gli 85 \u20ac comprensivo di spese di spedizione. Secondo me sono perfette come regalo per il padrone di casa quando ci si presenta come ospiti a un pranzo o una cena. Ogni box contiene un &#8220;<strong>Lugana Gift<\/strong>&#8221; che pu\u00f2 essere una selezione di articoli per sommelier e appassionati (tappi, antigoccia, cavatappi&#8230;) o la fascia per mantenere la temperatura, utilissima se la conservi in freezer come faccio io perch\u00e8 non bagna e non rovina l&#8217;etichetta.<\/span><span><\/span><\/p>\n<p style=\"text-align: justify;\">[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/12\/lugana-gift.jpg&#8221; alt=&#8221;lugana gift&#8221; title_text=&#8221;lugana-gift&#8221; _builder_version=&#8221;4.14.2&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; border_radii=&#8221;on|8px|8px|8px|8px&#8221; border_width_all=&#8221;3px&#8221; border_color_all=&#8221;#da413d&#8221; box_shadow_style=&#8221;preset3&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.14.2&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<h3 style=\"text-align: justify;\"><span>A questo punto ti voglio condividere le degustazioni di alcune delle box!<\/span><\/h3>\n<p><span>Iscriviti alla mia newsletter o scorri la pagina per leggere le degustazioni! \ud83d\ude09<\/span><\/p>\n<p style=\"text-align: justify;\">[\/et_pb_text][et_pb_signup provider=&#8221;mailpoet&#8221; mailpoet_list=&#8221;PEPEblu|49&#8243; success_message=&#8221;Controlla la tua e-mail: hai appena ricevuto un mio messaggio per confermare la tua iscrizione! Se non lo visualizzi controlla in spam o nella cartella %22promozioni%22 di Gmail. Grazie e a presto!&#8221; title=&#8221;Ti piace questo contenuto?&#8221; button_text=&#8221;Iscriviti subito!&#8221; description=&#8221;<p style=%22text-align: justify;%22>Iscriviti alla mia newsletter per non perderti nessun nuovo articolo del mio blog!<\/p>\n<p style=%22text-align: justify;%22>Non ti invier\u00f2 SPAM, ma solo la notifica dei nuovi articoli! Di tanto in tanto potrai ricevere anche qualche coupon per acquistare vino o partecipare ad eventi con condizioni speciali riservate ai lettori del mio blog!<\/p>\n<p style=%22text-align: justify;%22>Cheers \ud83e\udd29\ud83e\udd42<\/p>\n&#8221; footer_content=&#8221;Iscrivendoti accetti le condizioni della <a href=%22https:\/\/perlagesuite.com\/privacy-2\/%22 data-et-target-link=%22_blank%22 rel=%22noopener noreferrer%22><span style=%22text-decoration: underline;%22><strong>Privacy<\/strong><\/span><\/a> di Perlage Suite.&#8221; _builder_version=&#8221;4.7.7&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Delius Unicase|700|||||||&#8221; header_font_size=&#8221;22px&#8221; body_font=&#8221;Delius||||||||&#8221; background_color=&#8221;#008c96&#8243; box_shadow_style=&#8221;preset3&#8243; box_shadow_color=&#8221;rgba(0,140,150,0.6)&#8221; global_module=&#8221;27234&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_signup][et_pb_text _builder_version=&#8221;4.14.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<h3 style=\"text-align: justify;\"><span>Lugana DOC 2020, Valetti &#8211; Bardolino (BS)<\/span><\/h3>\n<p style=\"text-align: justify;\"><span>Si presenta di colore giallo paglierino brillante con riflessi verdolini ai bordi. Consistente. Al naso \u00e8 delicato, complesso e fine con note di miele d&#8217;acacia, fiori di ibisco, mandorle fresche e te bianco, un ricordo di canfora. In bocca \u00e8 coerente, con un gusto che si arricchisce di una nota di albicocca, fiori di rosa e scorza di limone, caldo, sapido e strutturato. Lungo finale floreale e ammandorlato.<\/span><\/p>\n<p style=\"text-align: justify;\"><span>Bellissima l&#8217;etichetta, \u00e8 un vino perfetto per fare bella figura. Se lo regali a un sommelier suggeriscigli di conservarlo ancora un paio d&#8217;anni prima di berlo: sar\u00e0 un piccolo gioiello che impreziosir\u00e0 la sua cantina. Bottiglia perfetta anche per un winelover impaziente: accompagner\u00e0 un aperitivo o una cena di pesce con raffinata discrezione!<\/span><\/p>\n<p style=\"text-align: justify;\"><span><a href=\"https:\/\/www.consorziolugana.it\/lugana-cheersbox\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\"><strong>Qui trovi maggiori informazioni sulla Lugana Cheers Box Valetti<\/strong><\/span><\/a>.<\/span><\/p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/12\/vino-lugana-valetti-olio-del-garda.jpg&#8221; alt=&#8221;vino lugana vasetti olio del garda&#8221; title_text=&#8221;vino-lugana-valetti-olio-del-garda&#8221; _builder_version=&#8221;4.14.2&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|8px|8px|8px|8px&#8221; border_width_all=&#8221;3px&#8221; border_color_all=&#8221;#da413d&#8221; box_shadow_style=&#8221;preset3&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.14.2&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<h3 style=\"text-align: justify;\"><span>Lugana D O C 2019 Etichetta Oro, Tognazzi &#8211; Peschiera del Garda (BS)<\/span><\/h3>\n<p style=\"text-align: justify;\"><span>Si presenta giallo paglierino brillante, abbastanza carico, con riflessi verdolini. Consistente. Si vede qualche piccola bollicina qua e l\u00e0 che scompare dopo circa una decina di minuti che \u00e8 nel bicchiere. Un piccolissimo difetto dell&#8217;esame visivo che non ne pregiudica le caratteristiche organolettiche. Al naso \u00e8 abbastanza complesso, con note di confetto, salvia e mela renetta. In bocca acquista note di pera, ma ha una pseudocalorica un po&#8217; abbondante per i miei gusti, nonostante il positivo effetto del glicerolo che conferisce una bella morbidezza al palato e una piacevolissima sapidit\u00e0. Lungo finale salino. Vino pronto, da bere a tutto pasto e abbinare principalmente a carni bianche.<\/span><\/p>\n<p style=\"text-align: justify;\"><span><a href=\"https:\/\/www.consorziolugana.it\/lugana-cheersbox\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\"><strong>Qui trovi maggiori informazioni sulla Lugana Cheers Box Tognazzi<\/strong><\/span><\/a>. PS&#8230; il limoncino \u00e8 uno spettacolo!<\/span><\/p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/12\/lugana-vino-tognazzi-distillerie-peroni-maddalena.jpg&#8221; alt=&#8221;lugana vino tognazzi distillerie peroni maddalena&#8221; title_text=&#8221;lugana-vino-tognazzi-distillerie-peroni-maddalena&#8221; _builder_version=&#8221;4.14.2&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|8px|8px|8px|8px&#8221; border_width_all=&#8221;3px&#8221; border_color_all=&#8221;#da413d&#8221; box_shadow_style=&#8221;preset3&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.14.2&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<h3 style=\"text-align: justify;\"><span>Lugana DOP 2019, Conti Ceresa &#8211; Pozzolengo (BS)<\/span><\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-size: 17px; color: #666666; font-family: Raleway, Helvetica, Arial, Lucida, sans-serif;\">Si presenta giallo verdolino brillante e consistente. [Si vede qualche piccola bollicina qua e l\u00e0 che scompare dopo circa una decina di minuti che \u00e8 nel bicchiere, sintomo di una piccola rifermentazione alcolica in bottiglia]. Al naso \u00e8 molto molto delicato, abbastanza complesso e piacevole con note di pesca bianca, miele d&#8217;acacia, scorza di limone e fiori di campo. In bocca \u00e8 un po&#8217; frizzante. Comunque fresco ed equilibrato, confido di riassaggiare una bottiglia intatta per apprezzarlo come merita.<\/span><span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 17px; color: #666666; font-family: Raleway, Helvetica, Arial, Lucida, sans-serif;\"><span><a href=\"https:\/\/www.consorziolugana.it\/lugana-cheersbox\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\"><strong>Qui trovi maggiori informazioni sulla Lugana Cheers Box Ceresa<\/strong><\/span><\/a>.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 17px; color: #666666; font-family: Raleway, Helvetica, Arial, Lucida, sans-serif;\"><\/span><\/p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/12\/ceresa-vino-lugana-consorzio-lugana.jpg&#8221; alt=&#8221;ceresa vino lugana consorzio lugana&#8221; title_text=&#8221;ceresa-vino-lugana-consorzio-lugana&#8221; _builder_version=&#8221;4.14.2&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|8px|8px|8px|8px&#8221; border_width_all=&#8221;3px&#8221; border_color_all=&#8221;#da413d&#8221; box_shadow_style=&#8221;preset3&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.14.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<h3 style=\"text-align: justify;\"><span>&#8220;Adele&#8221; Lugana Riserva DOC 2019, Sgreva &#8211; Sirmione (BS)<\/span><\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-size: 17px; color: #666666; font-family: Raleway, Helvetica, Arial, Lucida, sans-serif;\">Si presenta giallo paglierino con riflessi oro verde, brillante e consistente. Al naso \u00e8 fine, complesso e delicato con note di erbe aromatiche, spezie, buccia d&#8217;arancia e pesca gialla. In bocca \u00e8 caratteristico, coerente, ben equilibrato, con una pseudocalorica pronunciata, ma non invasiva e con buona struttura. Lungo finale di albicocca. Indubbiamente un vino da pasto, perfetto per accompagnare un&#8217;anatra all&#8217;arancia o la pasta fresca fatta in casa con sughi di animali da cortile.<\/span><span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 17px; color: #666666; font-family: Raleway, Helvetica, Arial, Lucida, sans-serif;\"><span><a href=\"https:\/\/www.consorziolugana.it\/lugana-cheersbox\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\"><strong>Qui trovi maggiori informazioni sulla Lugana Cheers Box Sgreva<\/strong><\/span><\/a>.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 17px; color: #666666; font-family: Raleway, Helvetica, Arial, Lucida, sans-serif;\"><\/span><\/p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/12\/sgreva-vino-lugana-riserva.jpg&#8221; alt=&#8221;sgreva vino lugana riserva&#8221; title_text=&#8221;sgreva-vino-lugana-riserva&#8221; _builder_version=&#8221;4.14.2&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|8px|8px|8px|8px&#8221; border_width_all=&#8221;3px&#8221; border_color_all=&#8221;#da413d&#8221; box_shadow_style=&#8221;preset3&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.14.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<h3 style=\"text-align: justify;\"><span>Lugana Spumante DOC, Malavasi &#8211; Sirmione (BS)<\/span><\/h3>\n<p style=\"text-align: justify;\"><span>Questa \u00e8 l&#8217;unica bottiglia che oggi non ho aperto. Questa <strong>bottiglia magnum<\/strong> di spumante mi ha chiesto di aprirla a Capodanno&#8230; e come darle torto? Quindi per conoscere la mia degustazione dovrai attendere il primo articolo del 2022&#8230; \ud83d\ude09<\/span><\/p>\n<p style=\"text-align: justify;\"><span><a href=\"https:\/\/www.consorziolugana.it\/lugana-cheersbox\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\"><strong>Qui trovi maggiori informazioni sulla Lugana Cheers Box Malavasi<\/strong><\/span><\/a>.<\/span><\/p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/12\/malavasi-lugana-spumante.jpg&#8221; alt=&#8221;lugana spumante malavasi&#8221; title_text=&#8221;malavasi-lugana-spumante&#8221; _builder_version=&#8221;4.14.2&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|8px|8px|8px|8px&#8221; border_width_all=&#8221;3px&#8221; border_color_all=&#8221;#da413d&#8221; box_shadow_style=&#8221;preset3&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.14.2&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<p style=\"text-align: justify;\"><span>La cosa per\u00f2 che mi \u00e8 piaciuta di pi\u00f9 \u00e8 l&#8217;idea delle Lugana CheersBox Dinner: 10 tappe in 10 ristoranti bresciani dove poter degustare deliziosi piatti preparati con alcuni ingredienti delle box e abbinati ai vini delle box con la possibilit\u00e0 di acquistarle direttamente in loco a un prezzo promozionale. <a href=\"https:\/\/www.consorziolugana.it\/lugana-cheersbox\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\"><strong>Puoi consultare qui i menu (scorri tutta la pagina, sono in fondo dopo le box)<\/strong><\/span><\/a>, a me tra tutte ispira tantissimo quella che si terr\u00e0 dopodomani al Ristorante Tavernetta Maria Callas + Cascina Maddalena e Ca&#8217; Lojera! <a href=\"https:\/\/perlagesuite.com\/gravlax-trota-marinata-ricetta-malvasia-lupinc\/\"><span style=\"text-decoration: underline;\"><strong>Io adoro la trota marinata agli agrumi, anzi ne approfitto per condividerti la mia ricetta<\/strong><\/span><\/a>!\ud83d\ude0b<\/span><\/p>\n<p style=\"text-align: justify;\"><span>Ti auguro delle feste spumeggianti, con tanto <strong>vino Lugana<\/strong> e mille sorrisi!<\/span><\/p>\n<p style=\"text-align: justify;\"><span>Cheers \ud83c\udf77<\/span><\/p>\n<p style=\"text-align: justify;\"><span>Chiara<\/span><\/p>[\/et_pb_text][et_pb_divider color=&#8221;#da413d&#8221; _builder_version=&#8221;4.9.10&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.0.6&#8243; global_module=&#8221;21425&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.0.6&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_wc_images product=&#8221;10582&#8243; show_product_gallery=&#8221;off&#8221; _builder_version=&#8221;4.9.4&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_wc_images][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.0.6&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_wc_title product=&#8221;10582&#8243; _builder_version=&#8221;4.14.1&#8243; header_level=&#8221;h2&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_wc_title][et_pb_text _builder_version=&#8221;4.14.2&#8243; text_font=&#8221;Crushed||||||||&#8221; global_colors_info=&#8221;{}&#8221;]<h4 style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"caret-color: #ff0000;\"><b>Tutti i miei appunti sul vino e sul cibo in un solo libro.<\/b><\/span><\/span><\/h4>[\/et_pb_text][et_pb_wc_rating product=&#8221;10582&#8243; _builder_version=&#8221;4.0.6&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_wc_rating][et_pb_wc_price product=&#8221;10582&#8243; _builder_version=&#8221;4.13.1&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_wc_price][et_pb_wc_add_to_cart product=&#8221;10582&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_wc_add_to_cart][et_pb_text _builder_version=&#8221;4.14.2&#8243; text_font=&#8221;Crushed||||||||&#8221; global_colors_info=&#8221;{}&#8221;]<p style=\"text-align: justify;\"><span style=\"color: #ff0000;\"><strong>IN OMAGGIO<\/strong><\/span>, solo per chi compra il mio libro su questo blog, una copia della <strong>Prima Edizione da Collezione della mia Guida Vini Spumanti &#8220;500 Bolle in 500&#8221;<\/strong>, prezzo di copertina 25,30 \u20ac. [Fino ad esaurimento scorte]<\/p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]\n\n\n","protected":false},"excerpt":{"rendered":"<p>Il vino Lugana DOC deve il suo successo anche alla sua incredibile posizione geografica: \u00e8 prodotto in quel di Sirmione sul Lago di Garda. Elaborato da uve turbiana, chiamate anche trebbiano di Lugana, \u00e8 un vino bianco adatto a una lunga evoluzione in bottiglia. Per la mia esperienza esistono due stili di Lugana: uno pi\u00f9 [&hellip;]<\/p>\n","protected":false},"author":49,"featured_media":32376,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"2880","footnotes":""},"categories":[298],"tags":[],"class_list":["post-32361","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-degustazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.0 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Lugana di sirmione: vino, cibo e territorio - Perlage Suite<\/title>\n<meta name=\"description\" content=\"Lugana CheersBox: una bella proposta del Consorzio per trascorrere i momenti speciali in compagnia dei vini Lugana DOC abbinati ai sapori del Lago di Garda.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/perlagesuite.com\/en\/lugana-di-sirmione-vino-cibo-e-territorio\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lugana di sirmione: vino, cibo e territorio\" \/>\n<meta property=\"og:description\" content=\"Lugana CheersBox: una bella proposta del Consorzio per trascorrere i momenti speciali in compagnia dei vini Lugana DOC abbinati ai sapori del Lago di Garda.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/perlagesuite.com\/en\/lugana-di-sirmione-vino-cibo-e-territorio\/\" \/>\n<meta property=\"og:site_name\" content=\"Perlage Suite\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/chiarabassiperlagesuite\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-14T18:48:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-28T19:25:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/12\/lugana-di-sirmione-vino.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Chiara Bassi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@perlagesuite\" \/>\n<meta name=\"twitter:site\" content=\"@perlagesuite\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Chiara Bassi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/lugana-di-sirmione-vino-cibo-e-territorio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/lugana-di-sirmione-vino-cibo-e-territorio\\\/\"},\"author\":{\"name\":\"Chiara Bassi\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/person\\\/81b257517a1007c1a823318ac86c6013\"},\"headline\":\"Lugana di sirmione: vino, cibo e territorio\",\"datePublished\":\"2021-12-14T18:48:45+00:00\",\"dateModified\":\"2022-02-28T19:25:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/lugana-di-sirmione-vino-cibo-e-territorio\\\/\"},\"wordCount\":1981,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/lugana-di-sirmione-vino-cibo-e-territorio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/lugana-di-sirmione-vino.jpg\",\"articleSection\":[\"Degustazioni\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/perlagesuite.com\\\/lugana-di-sirmione-vino-cibo-e-territorio\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/lugana-di-sirmione-vino-cibo-e-territorio\\\/\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/lugana-di-sirmione-vino-cibo-e-territorio\\\/\",\"name\":\"Lugana di sirmione: vino, cibo e territorio - Perlage Suite\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/lugana-di-sirmione-vino-cibo-e-territorio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/lugana-di-sirmione-vino-cibo-e-territorio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/lugana-di-sirmione-vino.jpg\",\"datePublished\":\"2021-12-14T18:48:45+00:00\",\"dateModified\":\"2022-02-28T19:25:32+00:00\",\"description\":\"Lugana CheersBox: una bella proposta del Consorzio per trascorrere i momenti speciali in compagnia dei vini Lugana DOC abbinati ai sapori del Lago di Garda.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/lugana-di-sirmione-vino-cibo-e-territorio\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/perlagesuite.com\\\/lugana-di-sirmione-vino-cibo-e-territorio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/lugana-di-sirmione-vino-cibo-e-territorio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/lugana-di-sirmione-vino.jpg\",\"contentUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/lugana-di-sirmione-vino.jpg\",\"width\":1080,\"height\":720,\"caption\":\"lugana di sirmione\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/lugana-di-sirmione-vino-cibo-e-territorio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/perlagesuite.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lugana di sirmione: vino, cibo e territorio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#website\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/\",\"name\":\"Perlage Suite\",\"description\":\"Il Wine Blog di Chiara Bassi\",\"publisher\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/perlagesuite.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#organization\",\"name\":\"Chiara Bassi\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Chiara-Bassi-sommelier-wine-blogger-logo.png\",\"contentUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Chiara-Bassi-sommelier-wine-blogger-logo.png\",\"width\":512,\"height\":512,\"caption\":\"Chiara Bassi\"},\"image\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/chiarabassiperlagesuite\",\"https:\\\/\\\/x.com\\\/perlagesuite\",\"https:\\\/\\\/www.instagram.com\\\/perlagesuite\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/person\\\/81b257517a1007c1a823318ac86c6013\",\"name\":\"Chiara Bassi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g\",\"caption\":\"Chiara Bassi\"},\"sameAs\":[\"https:\\\/\\\/perlagesuite.com\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Lugana di sirmione: wine, food and territory - Perlage Suite","description":"Lugana CheersBox: a beautiful proposal of the Consortium to spend special moments in the company of Lugana DOC wines combined with the flavours of Lake Garda.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/perlagesuite.com\/en\/lugana-di-sirmione-vino-cibo-e-territorio\/","og_locale":"en_GB","og_type":"article","og_title":"Lugana di sirmione: vino, cibo e territorio","og_description":"Lugana CheersBox: una bella proposta del Consorzio per trascorrere i momenti speciali in compagnia dei vini Lugana DOC abbinati ai sapori del Lago di Garda.","og_url":"https:\/\/perlagesuite.com\/en\/lugana-di-sirmione-vino-cibo-e-territorio\/","og_site_name":"Perlage Suite","article_publisher":"https:\/\/www.facebook.com\/chiarabassiperlagesuite","article_published_time":"2021-12-14T18:48:45+00:00","article_modified_time":"2022-02-28T19:25:32+00:00","og_image":[{"width":1080,"height":720,"url":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/12\/lugana-di-sirmione-vino.jpg","type":"image\/jpeg"}],"author":"Chiara Bassi","twitter_card":"summary_large_image","twitter_creator":"@perlagesuite","twitter_site":"@perlagesuite","twitter_misc":{"Written by":"Chiara Bassi","Estimated reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/perlagesuite.com\/lugana-di-sirmione-vino-cibo-e-territorio\/#article","isPartOf":{"@id":"https:\/\/perlagesuite.com\/lugana-di-sirmione-vino-cibo-e-territorio\/"},"author":{"name":"Chiara Bassi","@id":"https:\/\/perlagesuite.com\/#\/schema\/person\/81b257517a1007c1a823318ac86c6013"},"headline":"Lugana di sirmione: vino, cibo e territorio","datePublished":"2021-12-14T18:48:45+00:00","dateModified":"2022-02-28T19:25:32+00:00","mainEntityOfPage":{"@id":"https:\/\/perlagesuite.com\/lugana-di-sirmione-vino-cibo-e-territorio\/"},"wordCount":1981,"commentCount":0,"publisher":{"@id":"https:\/\/perlagesuite.com\/#organization"},"image":{"@id":"https:\/\/perlagesuite.com\/lugana-di-sirmione-vino-cibo-e-territorio\/#primaryimage"},"thumbnailUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/12\/lugana-di-sirmione-vino.jpg","articleSection":["Degustazioni"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/perlagesuite.com\/lugana-di-sirmione-vino-cibo-e-territorio\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/perlagesuite.com\/lugana-di-sirmione-vino-cibo-e-territorio\/","url":"https:\/\/perlagesuite.com\/lugana-di-sirmione-vino-cibo-e-territorio\/","name":"Lugana di sirmione: wine, food and territory - Perlage Suite","isPartOf":{"@id":"https:\/\/perlagesuite.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/perlagesuite.com\/lugana-di-sirmione-vino-cibo-e-territorio\/#primaryimage"},"image":{"@id":"https:\/\/perlagesuite.com\/lugana-di-sirmione-vino-cibo-e-territorio\/#primaryimage"},"thumbnailUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/12\/lugana-di-sirmione-vino.jpg","datePublished":"2021-12-14T18:48:45+00:00","dateModified":"2022-02-28T19:25:32+00:00","description":"Lugana CheersBox: a beautiful proposal of the Consortium to spend special moments in the company of Lugana DOC wines combined with the flavours of Lake Garda.","breadcrumb":{"@id":"https:\/\/perlagesuite.com\/lugana-di-sirmione-vino-cibo-e-territorio\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/perlagesuite.com\/lugana-di-sirmione-vino-cibo-e-territorio\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/perlagesuite.com\/lugana-di-sirmione-vino-cibo-e-territorio\/#primaryimage","url":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/12\/lugana-di-sirmione-vino.jpg","contentUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2021\/12\/lugana-di-sirmione-vino.jpg","width":1080,"height":720,"caption":"lugana di sirmione"},{"@type":"BreadcrumbList","@id":"https:\/\/perlagesuite.com\/lugana-di-sirmione-vino-cibo-e-territorio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/perlagesuite.com\/"},{"@type":"ListItem","position":2,"name":"Lugana di sirmione: vino, cibo e territorio"}]},{"@type":"WebSite","@id":"https:\/\/perlagesuite.com\/#website","url":"https:\/\/perlagesuite.com\/","name":"Perlage Suite","description":"Chiara Bassi's Wine Blog","publisher":{"@id":"https:\/\/perlagesuite.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/perlagesuite.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/perlagesuite.com\/#organization","name":"Chiara Bassi","url":"https:\/\/perlagesuite.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/perlagesuite.com\/#\/schema\/logo\/image\/","url":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2022\/03\/Chiara-Bassi-sommelier-wine-blogger-logo.png","contentUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2022\/03\/Chiara-Bassi-sommelier-wine-blogger-logo.png","width":512,"height":512,"caption":"Chiara Bassi"},"image":{"@id":"https:\/\/perlagesuite.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/chiarabassiperlagesuite","https:\/\/x.com\/perlagesuite","https:\/\/www.instagram.com\/perlagesuite\/"]},{"@type":"Person","@id":"https:\/\/perlagesuite.com\/#\/schema\/person\/81b257517a1007c1a823318ac86c6013","name":"Chiara Bassi","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g","caption":"Chiara Bassi"},"sameAs":["https:\/\/perlagesuite.com"]}]}},"_links":{"self":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/posts\/32361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/comments?post=32361"}],"version-history":[{"count":0,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/posts\/32361\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/media\/32376"}],"wp:attachment":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/media?parent=32361"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/categories?post=32361"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/tags?post=32361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}