{"id":4966,"date":"2016-11-08T11:06:17","date_gmt":"2016-11-08T10:06:17","guid":{"rendered":"http:\/\/perlagesuite.com\/?p=4966"},"modified":"2021-11-18T15:39:42","modified_gmt":"2021-11-18T14:39:42","slug":"tatu-alessia-berlusconi-fashion-no-victim","status":"publish","type":"post","link":"https:\/\/perlagesuite.com\/en\/tatu-alessia-berlusconi-fashion-no-victim\/","title":{"rendered":"Tat\u00f9 and Alessia Berlusconi present the brand new #FashionNoVictim Chilli Spray in Milan"},"content":{"rendered":"\n[et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;section&#8221; _builder_version=&#8221;3.22&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_row admin_label=&#8221;row&#8221; _builder_version=&#8221;3.25&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Text&#8221; _builder_version=&#8221;3.27.4&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; global_colors_info=&#8221;{}&#8221;]<p style=\"text-align: justify;\">Sono appena rientrata da Milano, dove sono stata alla presentazione del nuovissimo <strong>Spray al Peperoncino<\/strong> per autodifesa di <strong>Tat\u00f9<\/strong>, la start up piemontese che in poco pi\u00f9&nbsp;2 anni ha sfornato oggetti fashion di grande gusto e dall&#8217;animo solidale. <strong>Niente Paura<\/strong> S.r.l. \u00e8 l&#8217;azienda di <strong>Manuel Giannini<\/strong> e <strong>Luca Zafarana<\/strong>, un nuovo modo di fare impresa che ha come obiettivo di rendere pi\u00f9 umano il capitalismo destinando parte dell&#8217;utile netto per migliorare le condizioni di vita di chi si trova in difficolt\u00e0.<\/p>\n<p style=\"text-align: justify;\"><strong>Alessia Berlusconi \u00e8 stata un po&#8217; l&#8217;Angelo Custode dell&#8217;evento, e&nbsp;il suo 9.9 e la sua Rosa Mistica sono stati i vini con cui abbiamo brindato alla presentazione dello Spray al peperoncino per Autodifesa by Tat\u00f9<\/strong>. Che adoro il 9.9 ormai \u00e8 dichiarato (se ti va approfondisci <a href=\"http:\/\/perlagesuite.com\/la-contessa-alessia-berlusconi-sposa-la-riccafana-di-riccardo-fratus-a-milano\/\"><span style=\"text-decoration: underline;\"><strong>QUI il mio primo assaggio<\/strong><\/span><\/a>), quindi stasera voglio concentrarmi sulla bellezza di queste #donnechedifendonoledonne.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4973\" src=\"http:\/\/perlagesuite.com\/wp-content\/uploads\/2016\/11\/tatu-amore-scatenato-terrazza-duomo-milano.jpg\" alt=\"tatu terrazza duomo 21 milano\" width=\"1200\" height=\"1200\" srcset=\"https:\/\/perlagesuite.com\/wp-content\/uploads\/2016\/11\/tatu-amore-scatenato-terrazza-duomo-milano.jpg 1080w, https:\/\/perlagesuite.com\/wp-content\/uploads\/2016\/11\/tatu-amore-scatenato-terrazza-duomo-milano-400x400.jpg 400w, https:\/\/perlagesuite.com\/wp-content\/uploads\/2016\/11\/tatu-amore-scatenato-terrazza-duomo-milano-100x100.jpg 100w, https:\/\/perlagesuite.com\/wp-content\/uploads\/2016\/11\/tatu-amore-scatenato-terrazza-duomo-milano-600x600.jpg 600w, https:\/\/perlagesuite.com\/wp-content\/uploads\/2016\/11\/tatu-amore-scatenato-terrazza-duomo-milano-150x150.jpg 150w, https:\/\/perlagesuite.com\/wp-content\/uploads\/2016\/11\/tatu-amore-scatenato-terrazza-duomo-milano-300x300.jpg 300w, https:\/\/perlagesuite.com\/wp-content\/uploads\/2016\/11\/tatu-amore-scatenato-terrazza-duomo-milano-768x768.jpg 768w, https:\/\/perlagesuite.com\/wp-content\/uploads\/2016\/11\/tatu-amore-scatenato-terrazza-duomo-milano-1024x1024.jpg 1024w, https:\/\/perlagesuite.com\/wp-content\/uploads\/2016\/11\/tatu-amore-scatenato-terrazza-duomo-milano-610x610.jpg 610w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<p style=\"text-align: justify;\">L&#8217;evento di presentazione si \u00e8 tenuto alla <strong>Terrazza Duomo 21<\/strong>,&nbsp;uno splendido salotto affacciato sul Duomo di Milano. Mi piace sempre molto venire qui, \u00e8 un luogo esclusivo e perfetto per un&nbsp;incontro di lavoro (ma non solo). Tutto&nbsp;\u00e8 stato perfettamente organizzato, dal guardaroba alla galleria espositiva, dall&#8217;aperitivo alla presentazione vera e propria. I due titolari di Tat\u00f9, Manuel Giannini e Luca Zafarana, mi sono sembrati due ragazzi davvero in gamba, con&nbsp;un buon piglio imprenditoriale e un&#8217;etica fuori dal comune, ed \u00e8 stato bello ascoltarli.<\/p>\n<p style=\"text-align: justify;\">All&#8217;evento sono intervenute molte persone,&nbsp;volti del mondo dell&#8217;imprenditoria, tra cui&nbsp;il padre di Alessia, l&#8217;imprenditore Paolo Berlusconi e sua sorella, la produttrice televisiva Luna (Due-B Produzioni), e volti del mondo&nbsp;dello spettacolo tra cui l&#8217;attore Paolo Ruffini e il calciatore\/tronista Oscar Branzani, il web&nbsp;influencer Marco Ferrero (Iconize), la fashion influencer&nbsp;Rama Lila Giustina.<\/p>\n<p style=\"text-align: justify;\">Fin dalla nascita dell&#8217;azienda Niente Paura e del suo marchio Tat\u00f9, i due soci Manuel Giannini e Luca Zafarana avevano nella testa di creare uno strumento tecnologico per autodifesa. Quando hanno capito che produrre uno strumento tecnologico di questo tipo non era in linea con le esigenze di una fashion start up, hanno pensato di creare una partnership con la Defence Systems Srl di Modena, azienda leader nel settore della distribuzione di strumenti di protezione e difesa personale. Nasce cos\u00ec lo spray al peperoncino Tat\u00f9, con un vestito completamente ridisegnato dai due giovani imprenditori che l&#8217;hanno reso un vero e proprio oggetto del desiderio femminile e gli&nbsp;hashtag <strong>#NientePaura<\/strong> <strong>#PerLeDonneCheDifendonoLeDonne<\/strong>&nbsp;<strong>#FashionNoVictim<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Credo che sensibilizzare tutte le donne a reagire alla violenza e a camminare per strada pi\u00f9 sicure sia un qualcosa di bellissimo, che da donna non posso che accogliere a braccia aperte.<\/p>\n<p style=\"text-align: justify;\">Cito&nbsp;i ragazzi Tat\u00f9:<\/p>\n\n<blockquote>\n<p style=\"text-align: justify;\"><em>Non mi fermo dietro la montagna temendo di non essere in grado di superarla, non aspetto che dall\u2019altra parte qualcuno decida per me che cosa sono e che cosa devo volere, non immagino solo distruzione dall\u2019altra parte, o un mondo pi\u00f9 cupo del mio, n\u00e9 strade tortuose e piene di tranelli che \u00e8 meglio abbandonare.&nbsp;<\/em><strong>Non ci sono catene che io non possa spezzare!<\/strong><em>&nbsp;<\/em><em>Immagino invece una possibilit\u00e0 di potercela fare, perch\u00e9 se \u00e8 vero che \u201csolo uno su mille ce la fa\u201d, \u00e8 certo che \u00e8 colui che ha saputo osare, che non si \u00e8 fermato a piangersi addosso, che si \u00e8 rialzato dalla peggiore caduta, che ha guardato diritto alla sua meta e in faccia la vita!&nbsp;<\/em><em>Forse non realizzer\u00f2 il mio sogno, ma mai potr\u00f2 dire di avervi rinunciato, mai potr\u00f2 dire di non avere tentato.&nbsp;<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>Niente Paura \u00e8 il mio motto!<\/strong><\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\">Ecco, questo mi \u00e8 piaciuto molto perch\u00e9 mi sono ritrovata in ogni singola parola.<\/p>\n<p style=\"text-align: justify;\">Anche io non so se realizzer\u00f2 il mio sogno, ma di certo non sono disposta a rinunciarci senza tentare. Per nessuno.<\/p>\n<p style=\"text-align: justify;\">La violenza sulle donne pu\u00f2 essere una violenza fisica, una violenza sessuale o una violenza psicologica. Cos&#8217;\u00e8 la violenza psicologica? La violenza psicologica avviene quando il partner controlla la propria compagna allontanandola dalle relazioni sociali di amicizia e lavoro con una gelosia ossessiva e la insulta, la umilia, la minaccia di abbandono o di porre fine alla relazione, le dice che \u00e8 pazza per farla sentire colpevole e manipolarla. La violenza psicologica \u00e8 ancora pi\u00f9 subdola perch\u00e9 non porta i segni evidenti della violenza fisica ma ferisce ancora di pi\u00f9 nell&#8217;animo e nel cuore. Sulla violenza sessuale invece non mi esprimo, tanto la reputo bestiale e schifosa.<\/p>\n<p style=\"text-align: justify;\">Personalmente avere lo Spray al Peperoncino della Tat\u00f9 a portata di mano nella borsa mi fa uscire senza paura, quando giro sola in metropolitana, in treno o per strada la sera tardi per difendermi dalla violenza finisca e dalla violenza sessuale. Per quella psicologica lo spray non serve, bisogna lavorare su s\u00e9 stesse per uscirne.<\/p>\n<p style=\"text-align: justify;\">Quindi, a tutte le donne, dico &#8220;Niente Paura!&#8221;. Proteggete con cura maniacale la vostra indipendenza economica perch\u00e9 questa \u00e8 il primo passo dell&#8217;indipendenza affettiva. Donne, Niente Paura!&nbsp;Gli unici limiti che abbiamo sono quelli che ci costruiamo intorno. Possiamo fare o essere tutto,&nbsp;osate sognare e credete nei vostri sogni. La frase che amo di pi\u00f9?<\/p>\n\n<h4 style=\"text-align: justify;\">&#8220;Sono convinto che circa la met\u00e0 di ci\u00f2 che separa gli imprenditori di successo da quelli che non l&#8217;hanno \u00e8 la perseveranza.&#8221; Steve Jobs<\/h4>\n<p style=\"text-align: justify;\">A presto e grazie di cuore alla cara Alessia Berlusconi per avermi dato l&#8217;opportunit\u00e0 di conoscere questi due ragazzi straordinari.<\/p>\n<p style=\"text-align: justify;\">Chiara<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4970\" src=\"http:\/\/perlagesuite.com\/wp-content\/uploads\/2016\/11\/tatu-bracciale-niente-paura-spray-peperoncino.jpg\" alt=\"spray al peperoncino tat\u00f9\" width=\"1200\" height=\"800\" srcset=\"https:\/\/perlagesuite.com\/wp-content\/uploads\/2016\/11\/tatu-bracciale-niente-paura-spray-peperoncino.jpg 1080w, https:\/\/perlagesuite.com\/wp-content\/uploads\/2016\/11\/tatu-bracciale-niente-paura-spray-peperoncino-600x400.jpg 600w, https:\/\/perlagesuite.com\/wp-content\/uploads\/2016\/11\/tatu-bracciale-niente-paura-spray-peperoncino-300x200.jpg 300w, https:\/\/perlagesuite.com\/wp-content\/uploads\/2016\/11\/tatu-bracciale-niente-paura-spray-peperoncino-768x512.jpg 768w, https:\/\/perlagesuite.com\/wp-content\/uploads\/2016\/11\/tatu-bracciale-niente-paura-spray-peperoncino-1024x683.jpg 1024w, https:\/\/perlagesuite.com\/wp-content\/uploads\/2016\/11\/tatu-bracciale-niente-paura-spray-peperoncino-610x407.jpg 610w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<p style=\"text-align: justify;\">Ah, ho indossato il bracciale Niente Paura di Tat\u00f9 ed \u00e8 davvero bellissimo&#8230; ma anche quello blu unisex \u00e8 molto carino! Ma hai visto che bello il &#8220;vestito&#8221; dello spray al peperoncino?!! Grazie degli omaggi!&nbsp;?&nbsp;?<\/p>\n<p style=\"text-align: justify;\">P.S. E un grazie anche al Dott. Felice Filizzola per avermi fatto scoprire questa pizza al trancio (Spontini 1953) dietro la Galleria Vittorio Emanuele che ho trovato davvero squisita! All&#8217;evento sono stata troppo impegnata a parlare con la gente e fare foto per mangiare, ma mi sono resa conto all&#8217;ingresso della metro che avevo famissima!&nbsp;?\u2060 E&nbsp;anche per aver scattato la bellissima foto di copertina, con Alessia Berlusconi e Luca Zafarana! E anche per la bellissima definizione di Alessia come &#8220;Angelo Custode&#8221;!<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4971\" src=\"http:\/\/perlagesuite.com\/wp-content\/uploads\/2016\/11\/spontini-1953-milano-pizza.jpg\" alt=\"spontini milano pizza\" width=\"1200\" height=\"1200\" srcset=\"https:\/\/perlagesuite.com\/wp-content\/uploads\/2016\/11\/spontini-1953-milano-pizza.jpg 1080w, https:\/\/perlagesuite.com\/wp-content\/uploads\/2016\/11\/spontini-1953-milano-pizza-400x400.jpg 400w, https:\/\/perlagesuite.com\/wp-content\/uploads\/2016\/11\/spontini-1953-milano-pizza-100x100.jpg 100w, https:\/\/perlagesuite.com\/wp-content\/uploads\/2016\/11\/spontini-1953-milano-pizza-600x600.jpg 600w, https:\/\/perlagesuite.com\/wp-content\/uploads\/2016\/11\/spontini-1953-milano-pizza-150x150.jpg 150w, https:\/\/perlagesuite.com\/wp-content\/uploads\/2016\/11\/spontini-1953-milano-pizza-300x300.jpg 300w, https:\/\/perlagesuite.com\/wp-content\/uploads\/2016\/11\/spontini-1953-milano-pizza-768x768.jpg 768w, https:\/\/perlagesuite.com\/wp-content\/uploads\/2016\/11\/spontini-1953-milano-pizza-1024x1024.jpg 1024w, https:\/\/perlagesuite.com\/wp-content\/uploads\/2016\/11\/spontini-1953-milano-pizza-610x610.jpg 610w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<p style=\"text-align: justify;\">P.P.S. Ovviamente sempre un grazie a <a href=\"https:\/\/www.sony.it\/electronics\/fotocamere-cyber-shot-compatte\/dsc-rx100m4\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Sony per avermi fornito la RX100M4<\/strong><\/a> con cui \u00e8 stata scattata&nbsp;la&nbsp;foto di copertina della serata! Per chi fosse interessato all&#8217;acquisto segnalo che attualmente su Amazon \u00e8 in vendita con 200 \u20ac di sconto rispetto al prezzo di listino&nbsp;<a href=\"http:\/\/amzn.to\/2fCjkkO\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"text-decoration: underline;\">a questo link<\/span><\/a>.<\/p>[\/et_pb_text][et_pb_divider _builder_version=&#8221;4.13.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{%22gcid-65af285e-4bd3-4ea9-81b6-b2c2b9f89915%22:%91%22color%22%93}&#8221; color=&#8221;gcid-65af285e-4bd3-4ea9-81b6-b2c2b9f89915&#8243; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.0.6&#8243; global_colors_info=&#8221;{}&#8221; global_module=&#8221;21425&#8243; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.0.6&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_wc_images product=&#8221;10582&#8243; show_product_gallery=&#8221;off&#8221; _builder_version=&#8221;4.9.4&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_wc_images][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.0.6&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_wc_title product=&#8221;10582&#8243; _builder_version=&#8221;4.0.6&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_wc_title][et_pb_text _builder_version=&#8221;4.9.4&#8243; text_font=&#8221;Delius Unicase||||||||&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<p style=\"text-align: justify;\"><span style=\"color: #ff0000;\"><span style=\"caret-color: #ff0000;\"><b>Tutti i miei appunti sul vino e sul cibo in un solo libro.<\/b><\/span><\/span><\/p>[\/et_pb_text][et_pb_wc_rating product=&#8221;10582&#8243; _builder_version=&#8221;4.0.6&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_wc_rating][et_pb_wc_price product=&#8221;10582&#8243; _builder_version=&#8221;4.0.6&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_wc_price][et_pb_wc_add_to_cart product=&#8221;10582&#8243; _builder_version=&#8221;4.0.6&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_wc_add_to_cart][et_pb_text _builder_version=&#8221;4.9.4&#8243; text_font=&#8221;Delius Unicase||||||||&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<p style=\"text-align: justify;\"><span style=\"color: #ff0000;\"><strong>IN OMAGGIO<\/strong><\/span>, solo per chi compra il mio libro su questo blog, una copia della <strong>Prima Edizione da Collezione della mia Guida Vini Spumanti &#8220;500 Bolle in 500&#8221;<\/strong>, prezzo di copertina 25,30 \u20ac. [Fino ad esaurimento scorte]<\/p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]\n","protected":false},"excerpt":{"rendered":"<p>Sono appena rientrata da Milano, dove sono stata alla presentazione del nuovissimo Spray al Peperoncino per autodifesa di Tat\u00f9, la start up piemontese che in poco pi\u00f9&nbsp;2 anni ha sfornato oggetti fashion di grande gusto e dall&#8217;animo solidale. Niente Paura S.r.l. \u00e8 l&#8217;azienda di Manuel Giannini e Luca Zafarana, un nuovo modo di fare impresa [&hellip;]<\/p>\n","protected":false},"author":49,"featured_media":4967,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<p style=\"text-align: justify;\">Sono appena rientrata da Milano, dove sono stata alla presentazione del nuovissimo <strong>Spray al Peperoncino<\/strong> per autodifesa di <strong>Tat\u00f9<\/strong>, la start up piemontese che in poco pi\u00f9&nbsp;2 anni ha sfornato oggetti fashion di grande gusto e dall'animo solidale. <strong>Niente Paura<\/strong> S.r.l. \u00e8 l'azienda di <strong>Manuel Giannini<\/strong> e <strong>Luca Zafarana<\/strong>, un nuovo modo di fare impresa che ha come obiettivo di rendere pi\u00f9 umano il capitalismo destinando parte dell'utile netto per migliorare le condizioni di vita di chi si trova in difficolt\u00e0.<\/p>\n<p style=\"text-align: justify;\"><strong>Alessia Berlusconi \u00e8 stata un po' l'Angelo Custode dell'evento, e&nbsp;il suo 9.9 e la sua Rosa Mistica sono stati i vini con cui abbiamo brindato alla presentazione dello Spray al peperoncino per Autodifesa by Tat\u00f9<\/strong>. Che adoro il 9.9 ormai \u00e8 dichiarato (se ti va approfondisci <a href=\"http:\/\/perlagesuite.com\/la-contessa-alessia-berlusconi-sposa-la-riccafana-di-riccardo-fratus-a-milano\/\"><span style=\"text-decoration: underline;\"><strong>QUI il mio primo assaggio<\/strong><\/span><\/a>), quindi stasera voglio concentrarmi sulla bellezza di queste #donnechedifendonoledonne.<\/p>\n<p style=\"text-align: justify;\"><img class=\"aligncenter size-full wp-image-4973\" src=\"http:\/\/perlagesuite.com\/wp-content\/uploads\/2016\/11\/tatu-amore-scatenato-terrazza-duomo-milano.jpg\" alt=\"tatu terrazza duomo 21 milano\" width=\"1200\" height=\"1200\"><\/p>\n<p style=\"text-align: justify;\">L'evento di presentazione si \u00e8 tenuto alla <strong>Terrazza Duomo 21<\/strong>,&nbsp;uno splendido salotto affacciato sul Duomo di Milano. Mi piace sempre molto venire qui, \u00e8 un luogo esclusivo e perfetto per un&nbsp;incontro di lavoro (ma non solo). Tutto&nbsp;\u00e8 stato perfettamente organizzato, dal guardaroba alla galleria espositiva, dall'aperitivo alla presentazione vera e propria. I due titolari di Tat\u00f9, Manuel Giannini e Luca Zafarana, mi sono sembrati due ragazzi davvero in gamba, con&nbsp;un buon piglio imprenditoriale e un'etica fuori dal comune, ed \u00e8 stato bello ascoltarli.<\/p>\n<p style=\"text-align: justify;\">All'evento sono intervenute molte persone,&nbsp;volti del mondo dell'imprenditoria, tra cui&nbsp;il padre di Alessia, l'imprenditore Paolo Berlusconi e sua sorella, la produttrice televisiva Luna (Due-B Produzioni), e volti del mondo&nbsp;dello spettacolo tra cui l'attore Paolo Ruffini e il calciatore\/tronista Oscar Branzani, il web&nbsp;influencer Marco Ferrero (Iconize), la fashion influencer&nbsp;Rama Lila Giustina.<\/p>\n<p style=\"text-align: justify;\">Fin dalla nascita dell'azienda Niente Paura e del suo marchio Tat\u00f9, i due soci Manuel Giannini e Luca Zafarana avevano nella testa di creare uno strumento tecnologico per autodifesa. Quando hanno capito che produrre uno strumento tecnologico di questo tipo non era in linea con le esigenze di una fashion start up, hanno pensato di creare una partnership con la Defence Systems Srl di Modena, azienda leader nel settore della distribuzione di strumenti di protezione e difesa personale. Nasce cos\u00ec lo spray al peperoncino Tat\u00f9, con un vestito completamente ridisegnato dai due giovani imprenditori che l'hanno reso un vero e proprio oggetto del desiderio femminile e gli&nbsp;hashtag <strong>#NientePaura<\/strong> <strong>#PerLeDonneCheDifendonoLeDonne<\/strong>&nbsp;<strong>#FashionNoVictim<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Credo che sensibilizzare tutte le donne a reagire alla violenza e a camminare per strada pi\u00f9 sicure sia un qualcosa di bellissimo, che da donna non posso che accogliere a braccia aperte.<\/p>\n<p style=\"text-align: justify;\">Cito&nbsp;i ragazzi Tat\u00f9:<\/p>\n\n<blockquote>\n<p style=\"text-align: justify;\"><em>Non mi fermo dietro la montagna temendo di non essere in grado di superarla, non aspetto che dall\u2019altra parte qualcuno decida per me che cosa sono e che cosa devo volere, non immagino solo distruzione dall\u2019altra parte, o un mondo pi\u00f9 cupo del mio, n\u00e9 strade tortuose e piene di tranelli che \u00e8 meglio abbandonare.&nbsp;<\/em><strong>Non ci sono catene che io non possa spezzare!<\/strong><em>&nbsp;<\/em><em>Immagino invece una possibilit\u00e0 di potercela fare, perch\u00e9 se \u00e8 vero che \u201csolo uno su mille ce la fa\u201d, \u00e8 certo che \u00e8 colui che ha saputo osare, che non si \u00e8 fermato a piangersi addosso, che si \u00e8 rialzato dalla peggiore caduta, che ha guardato diritto alla sua meta e in faccia la vita!&nbsp;<\/em><em>Forse non realizzer\u00f2 il mio sogno, ma mai potr\u00f2 dire di avervi rinunciato, mai potr\u00f2 dire di non avere tentato.&nbsp;<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>Niente Paura \u00e8 il mio motto!<\/strong><\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\">Ecco, questo mi \u00e8 piaciuto molto perch\u00e9 mi sono ritrovata in ogni singola parola.<\/p>\n<p style=\"text-align: justify;\">Anche io non so se realizzer\u00f2 il mio sogno, ma di certo non sono disposta a rinunciarci senza tentare. Per nessuno.<\/p>\n<p style=\"text-align: justify;\">La violenza sulle donne pu\u00f2 essere una violenza fisica, una violenza sessuale o una violenza psicologica. Cos'\u00e8 la violenza psicologica? La violenza psicologica avviene quando il partner controlla la propria compagna allontanandola dalle relazioni sociali di amicizia e lavoro con una gelosia ossessiva e la insulta, la umilia, la minaccia di abbandono o di porre fine alla relazione, le dice che \u00e8 pazza per farla sentire colpevole e manipolarla. La violenza psicologica \u00e8 ancora pi\u00f9 subdola perch\u00e9 non porta i segni evidenti della violenza fisica ma ferisce ancora di pi\u00f9 nell'animo e nel cuore. Sulla violenza sessuale invece non mi esprimo, tanto la reputo bestiale e schifosa.<\/p>\n<p style=\"text-align: justify;\">Personalmente avere lo Spray al Peperoncino della Tat\u00f9 a portata di mano nella borsa mi fa uscire senza paura, quando giro sola in metropolitana, in treno o per strada la sera tardi per difendermi dalla violenza finisca e dalla violenza sessuale. Per quella psicologica lo spray non serve, bisogna lavorare su s\u00e9 stesse per uscirne.<\/p>\n<p style=\"text-align: justify;\">Quindi, a tutte le donne, dico \"Niente Paura!\". Proteggete con cura maniacale la vostra indipendenza economica perch\u00e9 questa \u00e8 il primo passo dell'indipendenza affettiva. Donne, Niente Paura!&nbsp;Gli unici limiti che abbiamo sono quelli che ci costruiamo intorno. Possiamo fare o essere tutto,&nbsp;osate sognare e credete nei vostri sogni. La frase che amo di pi\u00f9?<\/p>\n\n<h4 style=\"text-align: justify;\">\"Sono convinto che circa la met\u00e0 di ci\u00f2 che separa gli imprenditori di successo da quelli che non l'hanno \u00e8 la perseveranza.\" Steve Jobs<\/h4>\n<p style=\"text-align: justify;\">A presto e grazie di cuore alla cara Alessia Berlusconi per avermi dato l'opportunit\u00e0 di conoscere questi due ragazzi straordinari.<\/p>\n<p style=\"text-align: justify;\">Chiara<\/p>\n<p style=\"text-align: justify;\"><img class=\"aligncenter size-full wp-image-4970\" src=\"http:\/\/perlagesuite.com\/wp-content\/uploads\/2016\/11\/tatu-bracciale-niente-paura-spray-peperoncino.jpg\" alt=\"spray al peperoncino tat\u00f9\" width=\"1200\" height=\"800\"><\/p>\n<p style=\"text-align: justify;\">Ah, ho indossato il bracciale Niente Paura di Tat\u00f9 ed \u00e8 davvero bellissimo... ma anche quello blu unisex \u00e8 molto carino! Ma hai visto che bello il \"vestito\" dello spray al peperoncino?!! Grazie degli omaggi!&nbsp;?&nbsp;?<\/p>\n<p style=\"text-align: justify;\">P.S. E un grazie anche al Dott. Felice Filizzola per avermi fatto scoprire questa pizza al trancio (Spontini 1953) dietro la Galleria Vittorio Emanuele che ho trovato davvero squisita! All'evento sono stata troppo impegnata a parlare con la gente e fare foto per mangiare, ma mi sono resa conto all'ingresso della metro che avevo famissima!&nbsp;?\u2060 E&nbsp;anche per aver scattato la bellissima foto di copertina, con Alessia Berlusconi e Luca Zafarana! E anche per la bellissima definizione di Alessia come \"Angelo Custode\"!<\/p>\n<p style=\"text-align: justify;\"><img class=\"aligncenter size-full wp-image-4971\" src=\"http:\/\/perlagesuite.com\/wp-content\/uploads\/2016\/11\/spontini-1953-milano-pizza.jpg\" alt=\"spontini milano pizza\" width=\"1200\" height=\"1200\"><\/p>\n<p style=\"text-align: justify;\">P.P.S. Ovviamente sempre un grazie a <a href=\"https:\/\/www.sony.it\/electronics\/fotocamere-cyber-shot-compatte\/dsc-rx100m4\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Sony per avermi fornito la RX100M4<\/strong><\/a> con cui \u00e8 stata scattata&nbsp;la&nbsp;foto di copertina della serata! Per chi fosse interessato all'acquisto segnalo che attualmente su Amazon \u00e8 in vendita con 200 \u20ac di sconto rispetto al prezzo di listino&nbsp;<a href=\"http:\/\/amzn.to\/2fCjkkO\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"text-decoration: underline;\">a questo link<\/span><\/a>.<\/p>","_et_gb_content_width":"2880","footnotes":""},"categories":[298],"tags":[],"class_list":["post-4966","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-degustazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.0 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Tat\u00f9 e Alessia Berlusconi per le donne - Perlage Suite<\/title>\n<meta name=\"description\" content=\"Tat\u00f9 e Alessia Berlusconi presentano il nuovissimo spray al peperoncino &quot;Fashion no victim&quot; a Milano in un evento da sogno di fronte al Duomo. Bella iniziativa!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/perlagesuite.com\/en\/tatu-alessia-berlusconi-fashion-no-victim\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tat\u00f9 e Alessia Berlusconi presentano il nuovissimo Spray al Peperoncino #FashionNoVictim a Milano\" \/>\n<meta property=\"og:description\" content=\"Tat\u00f9 e Alessia Berlusconi presentano il nuovissimo spray al peperoncino &quot;Fashion no victim&quot; a Milano in un evento da sogno di fronte al Duomo. Bella iniziativa!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/perlagesuite.com\/en\/tatu-alessia-berlusconi-fashion-no-victim\/\" \/>\n<meta property=\"og:site_name\" content=\"Perlage Suite\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/chiarabassiperlagesuite\" \/>\n<meta property=\"article:published_time\" content=\"2016-11-08T10:06:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-18T14:39:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/perlagesuite.com\/wp-content\/uploads\/2016\/11\/tatu-alessia-berlusconi-chiara-bassi.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Chiara Bassi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@perlagesuite\" \/>\n<meta name=\"twitter:site\" content=\"@perlagesuite\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Chiara Bassi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/tatu-alessia-berlusconi-fashion-no-victim\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/tatu-alessia-berlusconi-fashion-no-victim\\\/\"},\"author\":{\"name\":\"Chiara Bassi\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/person\\\/81b257517a1007c1a823318ac86c6013\"},\"headline\":\"Tat\u00f9 e Alessia Berlusconi presentano il nuovissimo Spray al Peperoncino #FashionNoVictim a Milano\",\"datePublished\":\"2016-11-08T10:06:17+00:00\",\"dateModified\":\"2021-11-18T14:39:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/tatu-alessia-berlusconi-fashion-no-victim\\\/\"},\"wordCount\":1449,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/tatu-alessia-berlusconi-fashion-no-victim\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/tatu-alessia-berlusconi-chiara-bassi.jpg\",\"articleSection\":[\"Degustazioni\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/perlagesuite.com\\\/tatu-alessia-berlusconi-fashion-no-victim\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/tatu-alessia-berlusconi-fashion-no-victim\\\/\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/tatu-alessia-berlusconi-fashion-no-victim\\\/\",\"name\":\"Tat\u00f9 e Alessia Berlusconi per le donne - Perlage Suite\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/tatu-alessia-berlusconi-fashion-no-victim\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/tatu-alessia-berlusconi-fashion-no-victim\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/tatu-alessia-berlusconi-chiara-bassi.jpg\",\"datePublished\":\"2016-11-08T10:06:17+00:00\",\"dateModified\":\"2021-11-18T14:39:42+00:00\",\"description\":\"Tat\u00f9 e Alessia Berlusconi presentano il nuovissimo spray al peperoncino \\\"Fashion no victim\\\" a Milano in un evento da sogno di fronte al Duomo. Bella iniziativa!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/tatu-alessia-berlusconi-fashion-no-victim\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/perlagesuite.com\\\/tatu-alessia-berlusconi-fashion-no-victim\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/tatu-alessia-berlusconi-fashion-no-victim\\\/#primaryimage\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/tatu-alessia-berlusconi-chiara-bassi.jpg\",\"contentUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/tatu-alessia-berlusconi-chiara-bassi.jpg\",\"width\":1080,\"height\":720,\"caption\":\"tat\u00f9\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/tatu-alessia-berlusconi-fashion-no-victim\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/perlagesuite.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tat\u00f9 e Alessia Berlusconi presentano il nuovissimo Spray al Peperoncino #FashionNoVictim a Milano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#website\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/\",\"name\":\"Perlage Suite\",\"description\":\"Il Wine Blog di Chiara Bassi\",\"publisher\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/perlagesuite.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#organization\",\"name\":\"Chiara Bassi\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Chiara-Bassi-sommelier-wine-blogger-logo.png\",\"contentUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Chiara-Bassi-sommelier-wine-blogger-logo.png\",\"width\":512,\"height\":512,\"caption\":\"Chiara Bassi\"},\"image\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/chiarabassiperlagesuite\",\"https:\\\/\\\/x.com\\\/perlagesuite\",\"https:\\\/\\\/www.instagram.com\\\/perlagesuite\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/person\\\/81b257517a1007c1a823318ac86c6013\",\"name\":\"Chiara Bassi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g\",\"caption\":\"Chiara Bassi\"},\"sameAs\":[\"https:\\\/\\\/perlagesuite.com\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tat\u00f9 and Alessia Berlusconi for women - Perlage Suite","description":"Tat\u00f9 and Alessia Berlusconi present the brand new 'Fashion no victim' pepper spray in Milan at a dream event in front of the Duomo. Nice initiative!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/perlagesuite.com\/en\/tatu-alessia-berlusconi-fashion-no-victim\/","og_locale":"en_GB","og_type":"article","og_title":"Tat\u00f9 e Alessia Berlusconi presentano il nuovissimo Spray al Peperoncino #FashionNoVictim a Milano","og_description":"Tat\u00f9 e Alessia Berlusconi presentano il nuovissimo spray al peperoncino \"Fashion no victim\" a Milano in un evento da sogno di fronte al Duomo. Bella iniziativa!","og_url":"https:\/\/perlagesuite.com\/en\/tatu-alessia-berlusconi-fashion-no-victim\/","og_site_name":"Perlage Suite","article_publisher":"https:\/\/www.facebook.com\/chiarabassiperlagesuite","article_published_time":"2016-11-08T10:06:17+00:00","article_modified_time":"2021-11-18T14:39:42+00:00","og_image":[{"width":1080,"height":720,"url":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2016\/11\/tatu-alessia-berlusconi-chiara-bassi.jpg","type":"image\/jpeg"}],"author":"Chiara Bassi","twitter_card":"summary_large_image","twitter_creator":"@perlagesuite","twitter_site":"@perlagesuite","twitter_misc":{"Written by":"Chiara Bassi","Estimated reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/perlagesuite.com\/tatu-alessia-berlusconi-fashion-no-victim\/#article","isPartOf":{"@id":"https:\/\/perlagesuite.com\/tatu-alessia-berlusconi-fashion-no-victim\/"},"author":{"name":"Chiara Bassi","@id":"https:\/\/perlagesuite.com\/#\/schema\/person\/81b257517a1007c1a823318ac86c6013"},"headline":"Tat\u00f9 e Alessia Berlusconi presentano il nuovissimo Spray al Peperoncino #FashionNoVictim a Milano","datePublished":"2016-11-08T10:06:17+00:00","dateModified":"2021-11-18T14:39:42+00:00","mainEntityOfPage":{"@id":"https:\/\/perlagesuite.com\/tatu-alessia-berlusconi-fashion-no-victim\/"},"wordCount":1449,"commentCount":0,"publisher":{"@id":"https:\/\/perlagesuite.com\/#organization"},"image":{"@id":"https:\/\/perlagesuite.com\/tatu-alessia-berlusconi-fashion-no-victim\/#primaryimage"},"thumbnailUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2016\/11\/tatu-alessia-berlusconi-chiara-bassi.jpg","articleSection":["Degustazioni"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/perlagesuite.com\/tatu-alessia-berlusconi-fashion-no-victim\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/perlagesuite.com\/tatu-alessia-berlusconi-fashion-no-victim\/","url":"https:\/\/perlagesuite.com\/tatu-alessia-berlusconi-fashion-no-victim\/","name":"Tat\u00f9 and Alessia Berlusconi for women - Perlage Suite","isPartOf":{"@id":"https:\/\/perlagesuite.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/perlagesuite.com\/tatu-alessia-berlusconi-fashion-no-victim\/#primaryimage"},"image":{"@id":"https:\/\/perlagesuite.com\/tatu-alessia-berlusconi-fashion-no-victim\/#primaryimage"},"thumbnailUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2016\/11\/tatu-alessia-berlusconi-chiara-bassi.jpg","datePublished":"2016-11-08T10:06:17+00:00","dateModified":"2021-11-18T14:39:42+00:00","description":"Tat\u00f9 and Alessia Berlusconi present the brand new 'Fashion no victim' pepper spray in Milan at a dream event in front of the Duomo. Nice initiative!","breadcrumb":{"@id":"https:\/\/perlagesuite.com\/tatu-alessia-berlusconi-fashion-no-victim\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/perlagesuite.com\/tatu-alessia-berlusconi-fashion-no-victim\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/perlagesuite.com\/tatu-alessia-berlusconi-fashion-no-victim\/#primaryimage","url":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2016\/11\/tatu-alessia-berlusconi-chiara-bassi.jpg","contentUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2016\/11\/tatu-alessia-berlusconi-chiara-bassi.jpg","width":1080,"height":720,"caption":"tat\u00f9"},{"@type":"BreadcrumbList","@id":"https:\/\/perlagesuite.com\/tatu-alessia-berlusconi-fashion-no-victim\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/perlagesuite.com\/"},{"@type":"ListItem","position":2,"name":"Tat\u00f9 e Alessia Berlusconi presentano il nuovissimo Spray al Peperoncino #FashionNoVictim a Milano"}]},{"@type":"WebSite","@id":"https:\/\/perlagesuite.com\/#website","url":"https:\/\/perlagesuite.com\/","name":"Perlage Suite","description":"Chiara Bassi's Wine Blog","publisher":{"@id":"https:\/\/perlagesuite.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/perlagesuite.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/perlagesuite.com\/#organization","name":"Chiara Bassi","url":"https:\/\/perlagesuite.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/perlagesuite.com\/#\/schema\/logo\/image\/","url":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2022\/03\/Chiara-Bassi-sommelier-wine-blogger-logo.png","contentUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2022\/03\/Chiara-Bassi-sommelier-wine-blogger-logo.png","width":512,"height":512,"caption":"Chiara Bassi"},"image":{"@id":"https:\/\/perlagesuite.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/chiarabassiperlagesuite","https:\/\/x.com\/perlagesuite","https:\/\/www.instagram.com\/perlagesuite\/"]},{"@type":"Person","@id":"https:\/\/perlagesuite.com\/#\/schema\/person\/81b257517a1007c1a823318ac86c6013","name":"Chiara Bassi","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g","caption":"Chiara Bassi"},"sameAs":["https:\/\/perlagesuite.com"]}]}},"_links":{"self":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/posts\/4966","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/comments?post=4966"}],"version-history":[{"count":0,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/posts\/4966\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/media\/4967"}],"wp:attachment":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/media?parent=4966"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/categories?post=4966"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/tags?post=4966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}