{"id":6282,"date":"2017-10-21T10:20:05","date_gmt":"2017-10-21T09:20:05","guid":{"rendered":"http:\/\/perlagesuite.com\/?p=6282"},"modified":"2021-07-26T13:28:36","modified_gmt":"2021-07-26T12:28:36","slug":"prosecco-valdobbiadene-superiore-cartizze-docg-5-differenze","status":"publish","type":"post","link":"https:\/\/perlagesuite.com\/en\/prosecco-valdobbiadene-superiore-cartizze-docg-5-differenze\/","title":{"rendered":"Prosecco Valdobbiadene Superiore Cartizze DOCG: 5 differences"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;3.22&#8243;][et_pb_row _builder_version=&#8221;3.25&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.9.10&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p style=\"text-align: justify;\">Agli sgoccioli dell&#8217;uscita al pubblico della mia <strong>Guida Vini Spumanti 500 bolle in 500<\/strong>, voglio spendere qualche parola su una delle bolle pi\u00f9 bistrattate d&#8217;Italia: il Prosecco e, in particolare, un suo piccolo Cru, il <strong>Prosecco di Valdobbiadene Superiore di Cartizze DOCG<\/strong>. Ti anticipo che nella mia Guida ho dato pochissimo spazio a questa denominazione, ma non perch\u00e8 in mezzo non ci siano bollicine di assoluta qualit\u00e0, ma perch\u00e9 il Veneto, cos\u00ec come la Lombardia e il Trentino, sono da sempre le regioni pi\u00f9 trattate quando si parla di bollicine&#8230; e io ci tengo molto a farti scoprire anche qualche vino spumante fuori dai &#8220;soliti itinerari&#8221;. Il Prosecco Valdobbiadene Superiore Cartizze, tuttavia, \u00e8 a tutti gli effetti una bolla che pu\u00f2 dare grandissime soddisfazioni, soprattutto se stai facendo un aperitivo con i tuoi amici, per la sua capacit\u00e0 di accompagnare con gusto e freschezza le tue conversazioni senza interromperle!<\/p>\n<p>\n<script async=\"\" src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<ins class=\"adsbygoogle\" style=\"display: block;\" data-ad-format=\"fluid\" data-ad-layout-key=\"-8h+1r-ds+ef+h2\" data-ad-client=\"ca-pub-2294603368235139\" data-ad-slot=\"9273538802\"><\/ins><br \/>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script>\n<\/p>\n<h3 style=\"text-align: center;\">Prosecco Valdobbiadene Superiore Cartizze: Zone di Produzione<\/h3>\n<p style=\"text-align: justify;\">Il Prosecco Valdobbiadene Superiore Cartizze \u00e8 prodotto in un piccolo Cru di soli 107 ettari di vigneto suddivisi tra 117 produttori, nel comune di Valdobbiadene e, pi\u00f9 precisamente, nelle localit\u00e0 di San Pietro di Barbozza, Santo Stefano e Saccol.<\/p>\n<h3 style=\"text-align: center;\">Prosecco Valdobbiadene Superiore Cartizze: storia e origini del nome<\/h3>\n<p style=\"text-align: justify;\">Il nome &#8220;Cartizze&#8221; sembra essere una derivazione di &#8220;gardiz o gardizze&#8221;, cos\u00ec come vengono chiamati i graticci usati per l&#8217;appassimento delle uve. Nel cru del Cartizze infatti, grazie anche all&#8217;ambiente pedoclimatico caratteristico, l&#8217;uva viene vendemmiata tardi, solo dopo aver mostrato i primi segni di appassimento naturale. Questa scelta sicuramente fa s\u00ec che, grazie al minor contenuto d&#8217;acqua negli acini, si concentrino profumi e sapori che rendono il vino prodotto di qualit\u00e0 organolettica superiore.<\/p>\n<p style=\"text-align: justify;\">Un tempo l&#8217;uva, quando era pronta per la vendemmia, veniva avvolta grappolo per grappolo nelle gardizze, anzi nelle Cartize. Il risultato di questo meticoloso procedimento era un vino dolce, quasi un passito. Se questa tipologia di vino era molto apprezzata agli inizi del secolo scorso, intorno agli anni &#8217;50 l&#8217;indice di gradimento dei vini dolci sub\u00ec un arresto colossale e nacque la necessit\u00e0 di cercare una nuova strada per valorizzare queste zone cos\u00ec generose di uve profumate.<\/p>\n<p style=\"text-align: justify;\">L&#8217;idea di trasformare il Cru di Cartizze ed avvicinarlo al pi\u00f9 tradizionale prosecco in realt\u00e0 \u00e8 un&#8217;ottima trovata commerciale che ha anche interessanti risvolti gusto-olfattivi: l&#8217;anidride carbonica infatti ha il pregio di aumentare non solo le sensazioni dure che bilanciano perfettamente queste uve naturalmente morbide e dolci, ma accresce notevolmente la percezione dei profumi.<\/p>\n<p style=\"text-align: justify;\">L&#8217;uva, pronta per la vendemmia, veniva avvolta grappolo per grappolo nelle &#8220;cartize&#8221;, per aumentare il tasso zuccherino dell&#8217;uva. Il vino cos\u00ec ottenuto, il Cartizze appunto, era quindi un vino da dessert, pi\u00f9 vicino al Picolit o ai Passiti. Questa tipologia era molto apprezzata agli inizi del secolo. Con l&#8217;ultimo dopoguerra il gradimento per i vini dolci ebbe un crollo, fino ai giorni nostri, dove allo spumante viene richiesto pochissimo zucchero e un colore &#8220;scarico&#8221;. Cos\u00ec la lavorazione del cru di S.Stefano si uniform\u00f2 a quella del prosecco comune, mantenendo unicamente l&#8217;uso della vendemmia tardiva. Il Cartizze di oggi divide quindi quasi tutte le qualit\u00e0 con i Prosecchi, sottolineandone per\u00f2 la profumazione, decisamente pi\u00f9 ricca ed intensa.<\/p>\n<p style=\"text-align: justify;\">Ora puoi iscriverti alla mia newsletter o scorrere la pagina per proseguire la lettura dell&#8217;articolo! <span>\ud83d\ude09<\/span><\/p>\n<p>\n<script async=\"\" src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<ins class=\"adsbygoogle\" style=\"display: block;\" data-ad-format=\"fluid\" data-ad-layout-key=\"-8h+1r-ds+ef+h2\" data-ad-client=\"ca-pub-2294603368235139\" data-ad-slot=\"9273538802\"><\/ins><br \/>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script>\n<\/p>\n<p>[\/et_pb_text][et_pb_signup provider=&#8221;mailpoet&#8221; mailpoet_list=&#8221;PEPEblu|49&#8243; success_message=&#8221;Controlla la tua e-mail: hai appena ricevuto un mio messaggio per confermare la tua iscrizione! Se non lo visualizzi controlla in spam o nella cartella %22promozioni%22 di Gmail. Grazie e a presto!&#8221; title=&#8221;Ti piace questo contenuto?&#8221; button_text=&#8221;Iscriviti subito!&#8221; description=&#8221;<\/p>\n<p style=%22text-align: justify;%22>Iscriviti alla mia newsletter per non perderti nessun nuovo articolo del mio blog!<\/p>\n<p style=%22text-align: justify;%22>Non ti invier\u00f2 SPAM, ma solo la notifica dei nuovi articoli! Di tanto in tanto potrai ricevere anche qualche coupon per acquistare vino o partecipare ad eventi con condizioni speciali riservate ai lettori del mio blog!<\/p>\n<p style=%22text-align: justify;%22>Cheers \ud83e\udd29\ud83e\udd42<\/p>\n<p>&#8221; footer_content=&#8221;Iscrivendoti accetti le condizioni della <a href=%22https:\/\/perlagesuite.com\/privacy-2\/%22 data-et-target-link=%22_blank%22 rel=%22noopener noreferrer%22><span style=%22text-decoration: underline;%22><strong>Privacy<\/strong><\/span><\/a> di Perlage Suite.&#8221; _builder_version=&#8221;4.7.7&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Delius Unicase|700|||||||&#8221; header_font_size=&#8221;22px&#8221; body_font=&#8221;Delius||||||||&#8221; background_color=&#8221;#008c96&#8243; box_shadow_style=&#8221;preset3&#8243; box_shadow_color=&#8221;rgba(0,140,150,0.6)&#8221; global_module=&#8221;27234&#8243;][\/et_pb_signup][et_pb_text _builder_version=&#8221;4.9.10&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p>\n<script async=\"\" src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<ins class=\"adsbygoogle\" style=\"display: block;\" data-ad-format=\"fluid\" data-ad-layout-key=\"-8h+1r-ds+ef+h2\" data-ad-client=\"ca-pub-2294603368235139\" data-ad-slot=\"9273538802\"><\/ins><br \/>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script>\n<\/p>\n<h3 style=\"text-align: center;\">Prosecco Valdobbiadene Superiore Cartizze: caratteristiche organolettiche<\/h3>\n<p style=\"text-align: justify;\">Pur essendo a tutti gli effetti un prosecco, ha un colore pi\u00f9 intenso, un bouquet di profumi pi\u00f9 ampio e al gusto si presenta pi\u00f9 deciso e strutturato. Questo \u00e8 dovuto sia al particolare terroir, ma anche al metodo di vinificazione! Se da un lato il prosecco \u00e8 per lo pi\u00f9 vinificato con il Metodo Charmat, il Cartizze \u00e8 ottenuto con il Metodo Charmat Lungo o, addirittura, con il Metodo Classico!\u00a0Devo anche dirti che il Cartizze per\u00f2 ha un prezzo nettamente pi\u00f9 elevato del Prosecco di Conegliano o Valdobbiadene classici. Tuttavia, se scegli un buon prodotto e ti piacciono i vini di questa tipologia, sono certa che sarai felice di stapparti una bottiglia in compagnia! Poi certo, Cartizze a un degustatore suona un po&#8217; come una leggenda, ma a volte anche le leggende sono dotate di grande fascino&#8230; non trovi?<\/p>\n<p>Cheers \ud83d\ude42<\/p>\n<p>Chiara<\/p>\n<p style=\"text-align: justify;\">A proposito di Prosecco, che ne dici di leggere <a href=\"http:\/\/perlagesuite.com\/spumanti-integrali-cosa-sono-bellenda-le-vigne-di-alice-prosecco\/\"><span style=\"text-decoration: underline;\"><strong>questo articolo sui Prosecco Integrali di Le Vigne di Alice e Bellenda<\/strong><\/span><\/a>?<\/p>\n<p>[\/et_pb_text][et_pb_divider _builder_version=&#8221;4.9.10&#8243; _module_preset=&#8221;default&#8221; color=&#8221;#da413d&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.0.6&#8243; global_module=&#8221;21425&#8243;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.0.6&#8243;][et_pb_wc_images product=&#8221;10582&#8243; show_product_gallery=&#8221;off&#8221; _builder_version=&#8221;4.9.4&#8243;][\/et_pb_wc_images][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.0.6&#8243;][et_pb_wc_title product=&#8221;10582&#8243; _builder_version=&#8221;4.0.6&#8243;][\/et_pb_wc_title][et_pb_text _builder_version=&#8221;4.9.4&#8243; text_font=&#8221;Delius Unicase||||||||&#8221;]<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ff0000;\"><span style=\"caret-color: #ff0000;\"><b>Tutti i miei appunti sul vino e sul cibo in un solo libro.<\/b><\/span><\/span><\/p>\n<p>[\/et_pb_text][et_pb_wc_rating product=&#8221;10582&#8243; _builder_version=&#8221;4.0.6&#8243;][\/et_pb_wc_rating][et_pb_wc_price product=&#8221;10582&#8243; _builder_version=&#8221;4.0.6&#8243;][\/et_pb_wc_price][et_pb_wc_add_to_cart product=&#8221;10582&#8243; _builder_version=&#8221;4.0.6&#8243;][\/et_pb_wc_add_to_cart][et_pb_text _builder_version=&#8221;4.9.4&#8243; text_font=&#8221;Delius Unicase||||||||&#8221;]<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ff0000;\"><strong>IN OMAGGIO<\/strong><\/span>, solo per chi compra il mio libro su questo blog, una copia della <strong>Prima Edizione da Collezione della mia Guida Vini Spumanti &#8220;500 Bolle in 500&#8221;<\/strong>, prezzo di copertina 25,30 \u20ac. [Fino ad esaurimento scorte]<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A few words on one of Italy's most mistreated bubbles: Prosecco and, in particular, one of its small crus, Prosecco di Valdobbiadene Superiore di Cartizze DOCG.<\/p>","protected":false},"author":49,"featured_media":6287,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<p style=\"text-align: justify;\">Agli sgoccioli dell'uscita al pubblico della mia <strong>Guida Vini Spumanti 500 bolle in 500<\/strong>, voglio spendere qualche parola su una delle bolle pi\u00f9 bistrattate d'Italia: il Prosecco e, in particolare, un suo piccolo Cru, il <strong>Prosecco di Valdobbiadene Superiore di Cartizze DOCG<\/strong>. Ti anticipo che nella mia Guida ho dato pochissimo spazio a questa denominazione, ma non perch\u00e8 in mezzo non ci siano bollicine di assoluta qualit\u00e0, ma perch\u00e9 il Veneto, cos\u00ec come la Lombardia e il Trentino, sono da sempre le regioni pi\u00f9 trattate quando si parla di bollicine... e io ci tengo molto a farti scoprire anche qualche vino spumante fuori dai \"soliti itinerari\". Il Prosecco Valdobbiadene Superiore Cartizze, tuttavia, \u00e8 a tutti gli effetti una bolla che pu\u00f2 dare grandissime soddisfazioni, soprattutto se stai facendo un aperitivo con i tuoi amici, per la sua capacit\u00e0 di accompagnare con gusto e freschezza le tue conversazioni senza interromperle!<\/p>\n<script async=\"\" src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display: block;\" data-ad-format=\"fluid\" data-ad-layout-key=\"-8h+1r-ds+ef+h2\" data-ad-client=\"ca-pub-2294603368235139\" data-ad-slot=\"9273538802\"><\/ins>\n<script><br \/>\n     (adsbygoogle = window.adsbygoogle || []).push({});<br \/>\n<\/script>\n<h3 style=\"text-align: center;\">Prosecco Valdobbiadene Superiore Cartizze: Zone di Produzione<\/h3>\n<p style=\"text-align: justify;\">Il Prosecco Valdobbiadene Superiore Cartizze \u00e8 prodotto in un piccolo Cru di soli 107 ettari di vigneto suddivisi tra 117 produttori, nel comune di Valdobbiadene e, pi\u00f9 precisamente, nelle localit\u00e0 di San Pietro di Barbozza, Santo Stefano e Saccol.<\/p>\n\n<h3 style=\"text-align: center;\">Prosecco Valdobbiadene Superiore Cartizze: storia e origini del nome<\/h3>\n<p style=\"text-align: justify;\">Il nome \"Cartizze\" sembra essere una derivazione di \"gardiz o gardizze\", cos\u00ec come vengono chiamati i graticci usati per l'appassimento delle uve. Nel cru del Cartizze infatti, grazie anche all'ambiente pedoclimatico caratteristico, l'uva viene vendemmiata tardi, solo dopo aver mostrato i primi segni di appassimento naturale. Questa scelta sicuramente fa s\u00ec che, grazie al minor contenuto d'acqua negli acini, si concentrino profumi e sapori che rendono il vino prodotto di qualit\u00e0 organolettica superiore.<\/p>\n<p style=\"text-align: justify;\">Un tempo l'uva, quando era pronta per la vendemmia, veniva avvolta grappolo per grappolo nelle gardizze, anzi nelle Cartize. Il risultato di questo meticoloso procedimento era un vino dolce, quasi un passito. Se questa tipologia di vino era molto apprezzata agli inizi del secolo scorso, intorno agli anni '50 l'indice di gradimento dei vini dolci sub\u00ec un arresto colossale e nacque la necessit\u00e0 di cercare una nuova strada per valorizzare queste zone cos\u00ec generose di uve profumate.<\/p>\n<p style=\"text-align: justify;\">L'idea di trasformare il Cru di Cartizze ed avvicinarlo al pi\u00f9 tradizionale prosecco in realt\u00e0 \u00e8 un'ottima trovata commerciale che ha anche interessanti risvolti gusto-olfattivi: l'anidride carbonica infatti ha il pregio di aumentare non solo le sensazioni dure che bilanciano perfettamente queste uve naturalmente morbide e dolci, ma accresce notevolmente la percezione dei profumi.<\/p>\n<p style=\"text-align: justify;\">L'uva, pronta per la vendemmia, veniva avvolta grappolo per grappolo nelle \"cartize\", per aumentare il tasso zuccherino dell'uva. Il vino cos\u00ec ottenuto, il Cartizze appunto, era quindi un vino da dessert, pi\u00f9 vicino al Picolit o ai Passiti. Questa tipologia era molto apprezzata agli inizi del secolo. Con l'ultimo dopoguerra il gradimento per i vini dolci ebbe un crollo, fino ai giorni nostri, dove allo spumante viene richiesto pochissimo zucchero e un colore \"scarico\". Cos\u00ec la lavorazione del cru di S.Stefano si uniform\u00f2 a quella del prosecco comune, mantenendo unicamente l'uso della vendemmia tardiva. Il Cartizze di oggi divide quindi quasi tutte le qualit\u00e0 con i Prosecchi, sottolineandone per\u00f2 la profumazione, decisamente pi\u00f9 ricca ed intensa.<\/p>\n<script async=\"\" src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display: block;\" data-ad-format=\"fluid\" data-ad-layout-key=\"-8h+1r-ds+ef+h2\" data-ad-client=\"ca-pub-2294603368235139\" data-ad-slot=\"9273538802\"><\/ins>\n<script><br \/>\n     (adsbygoogle = window.adsbygoogle || []).push({});<br \/>\n<\/script>\n<h3 style=\"text-align: center;\">Prosecco Valdobbiadene Superiore Cartizze: caratteristiche organolettiche<\/h3>\n<p style=\"text-align: justify;\">Pur essendo a tutti gli effetti un prosecco, ha un colore pi\u00f9 intenso, un bouquet di profumi pi\u00f9 ampio e al gusto si presenta pi\u00f9 deciso e strutturato. Questo \u00e8 dovuto sia al particolare terroir, ma anche al metodo di vinificazione! Se da un lato il prosecco \u00e8 per lo pi\u00f9 vinificato con il Metodo Charmat, il Cartizze \u00e8 ottenuto con il Metodo Charmat Lungo o, addirittura, con il Metodo Classico!\u00a0Devo anche dirti che il Cartizze per\u00f2 ha un prezzo nettamente pi\u00f9 elevato del Prosecco di Conegliano o Valdobbiadene classici. Tuttavia, se scegli un buon prodotto e ti piacciono i vini di questa tipologia, sono certa che sarai felice di stapparti una bottiglia in compagnia! Poi certo, Cartizze a un degustatore suona un po' come una leggenda, ma a volte anche le leggende sono dotate di grande fascino... non trovi?<\/p>\nCheers :-)\n\nChiara\n<p style=\"text-align: justify;\">A proposito di Prosecco, che ne dici di leggere <a href=\"http:\/\/perlagesuite.com\/spumanti-integrali-cosa-sono-bellenda-le-vigne-di-alice-prosecco\/\"><span style=\"text-decoration: underline;\"><strong>questo articolo sui Prosecco Integrali di Le Vigne di Alice e Bellenda<\/strong><\/span><\/a>?<\/p>","_et_gb_content_width":"2880","footnotes":""},"categories":[428],"tags":[388,387,389],"class_list":["post-6282","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-champagne-vini-spumanti","tag-cartizze","tag-prosecco","tag-valdobbiadene"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.0 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Cartizze Prosecco Valdobbiadene Superiore DOCG: 5 differenze<\/title>\n<meta name=\"description\" content=\"Qualche parola su una delle bolle pi\u00f9 bistrattate d&#039;Italia: il Prosecco e sul suo piccolo Cru, il Prosecco di Valdobbiadene Superiore di Cartizze DOCG.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/perlagesuite.com\/en\/prosecco-valdobbiadene-superiore-cartizze-docg-5-differenze\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prosecco Valdobbiadene Superiore Cartizze DOCG: 5 differenze\" \/>\n<meta property=\"og:description\" content=\"Qualche parola su una delle bolle pi\u00f9 bistrattate d&#039;Italia: il Prosecco e sul suo piccolo Cru, il Prosecco di Valdobbiadene Superiore di Cartizze DOCG.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/perlagesuite.com\/en\/prosecco-valdobbiadene-superiore-cartizze-docg-5-differenze\/\" \/>\n<meta property=\"og:site_name\" content=\"Perlage Suite\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/chiarabassiperlagesuite\" \/>\n<meta property=\"article:published_time\" content=\"2017-10-21T09:20:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-26T12:28:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/perlagesuite.com\/wp-content\/uploads\/2017\/10\/prosecco-valdobbiadene-cartizze.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Chiara Bassi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@perlagesuite\" \/>\n<meta name=\"twitter:site\" content=\"@perlagesuite\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Chiara Bassi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/prosecco-valdobbiadene-superiore-cartizze-docg-5-differenze\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/prosecco-valdobbiadene-superiore-cartizze-docg-5-differenze\\\/\"},\"author\":{\"name\":\"Chiara Bassi\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/person\\\/81b257517a1007c1a823318ac86c6013\"},\"headline\":\"Prosecco Valdobbiadene Superiore Cartizze DOCG: 5 differenze\",\"datePublished\":\"2017-10-21T09:20:05+00:00\",\"dateModified\":\"2021-07-26T12:28:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/prosecco-valdobbiadene-superiore-cartizze-docg-5-differenze\\\/\"},\"wordCount\":1134,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/prosecco-valdobbiadene-superiore-cartizze-docg-5-differenze\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/prosecco-valdobbiadene-cartizze.jpg\",\"keywords\":[\"cartizze\",\"prosecco\",\"valdobbiadene\"],\"articleSection\":[\"Champagne &amp; Spumanti\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/perlagesuite.com\\\/prosecco-valdobbiadene-superiore-cartizze-docg-5-differenze\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/prosecco-valdobbiadene-superiore-cartizze-docg-5-differenze\\\/\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/prosecco-valdobbiadene-superiore-cartizze-docg-5-differenze\\\/\",\"name\":\"Cartizze Prosecco Valdobbiadene Superiore DOCG: 5 differenze\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/prosecco-valdobbiadene-superiore-cartizze-docg-5-differenze\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/prosecco-valdobbiadene-superiore-cartizze-docg-5-differenze\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/prosecco-valdobbiadene-cartizze.jpg\",\"datePublished\":\"2017-10-21T09:20:05+00:00\",\"dateModified\":\"2021-07-26T12:28:36+00:00\",\"description\":\"Qualche parola su una delle bolle pi\u00f9 bistrattate d'Italia: il Prosecco e sul suo piccolo Cru, il Prosecco di Valdobbiadene Superiore di Cartizze DOCG.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/prosecco-valdobbiadene-superiore-cartizze-docg-5-differenze\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/perlagesuite.com\\\/prosecco-valdobbiadene-superiore-cartizze-docg-5-differenze\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/prosecco-valdobbiadene-superiore-cartizze-docg-5-differenze\\\/#primaryimage\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/prosecco-valdobbiadene-cartizze.jpg\",\"contentUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/prosecco-valdobbiadene-cartizze.jpg\",\"width\":1080,\"height\":720,\"caption\":\"cartizze\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/prosecco-valdobbiadene-superiore-cartizze-docg-5-differenze\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/perlagesuite.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prosecco Valdobbiadene Superiore Cartizze DOCG: 5 differenze\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#website\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/\",\"name\":\"Perlage Suite\",\"description\":\"Il Wine Blog di Chiara Bassi\",\"publisher\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/perlagesuite.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#organization\",\"name\":\"Chiara Bassi\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Chiara-Bassi-sommelier-wine-blogger-logo.png\",\"contentUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Chiara-Bassi-sommelier-wine-blogger-logo.png\",\"width\":512,\"height\":512,\"caption\":\"Chiara Bassi\"},\"image\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/chiarabassiperlagesuite\",\"https:\\\/\\\/x.com\\\/perlagesuite\",\"https:\\\/\\\/www.instagram.com\\\/perlagesuite\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/person\\\/81b257517a1007c1a823318ac86c6013\",\"name\":\"Chiara Bassi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g\",\"caption\":\"Chiara Bassi\"},\"sameAs\":[\"https:\\\/\\\/perlagesuite.com\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cartizze Prosecco Valdobbiadene Superiore DOCG: 5 differences","description":"A few words on one of Italy's most mistreated bubbles: Prosecco and its little Cru, Prosecco di Valdobbiadene Superiore di Cartizze DOCG.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/perlagesuite.com\/en\/prosecco-valdobbiadene-superiore-cartizze-docg-5-differenze\/","og_locale":"en_GB","og_type":"article","og_title":"Prosecco Valdobbiadene Superiore Cartizze DOCG: 5 differenze","og_description":"Qualche parola su una delle bolle pi\u00f9 bistrattate d'Italia: il Prosecco e sul suo piccolo Cru, il Prosecco di Valdobbiadene Superiore di Cartizze DOCG.","og_url":"https:\/\/perlagesuite.com\/en\/prosecco-valdobbiadene-superiore-cartizze-docg-5-differenze\/","og_site_name":"Perlage Suite","article_publisher":"https:\/\/www.facebook.com\/chiarabassiperlagesuite","article_published_time":"2017-10-21T09:20:05+00:00","article_modified_time":"2021-07-26T12:28:36+00:00","og_image":[{"width":1080,"height":720,"url":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2017\/10\/prosecco-valdobbiadene-cartizze.jpg","type":"image\/jpeg"}],"author":"Chiara Bassi","twitter_card":"summary_large_image","twitter_creator":"@perlagesuite","twitter_site":"@perlagesuite","twitter_misc":{"Written by":"Chiara Bassi","Estimated reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/perlagesuite.com\/prosecco-valdobbiadene-superiore-cartizze-docg-5-differenze\/#article","isPartOf":{"@id":"https:\/\/perlagesuite.com\/prosecco-valdobbiadene-superiore-cartizze-docg-5-differenze\/"},"author":{"name":"Chiara Bassi","@id":"https:\/\/perlagesuite.com\/#\/schema\/person\/81b257517a1007c1a823318ac86c6013"},"headline":"Prosecco Valdobbiadene Superiore Cartizze DOCG: 5 differenze","datePublished":"2017-10-21T09:20:05+00:00","dateModified":"2021-07-26T12:28:36+00:00","mainEntityOfPage":{"@id":"https:\/\/perlagesuite.com\/prosecco-valdobbiadene-superiore-cartizze-docg-5-differenze\/"},"wordCount":1134,"commentCount":0,"publisher":{"@id":"https:\/\/perlagesuite.com\/#organization"},"image":{"@id":"https:\/\/perlagesuite.com\/prosecco-valdobbiadene-superiore-cartizze-docg-5-differenze\/#primaryimage"},"thumbnailUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2017\/10\/prosecco-valdobbiadene-cartizze.jpg","keywords":["cartizze","prosecco","valdobbiadene"],"articleSection":["Champagne &amp; Spumanti"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/perlagesuite.com\/prosecco-valdobbiadene-superiore-cartizze-docg-5-differenze\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/perlagesuite.com\/prosecco-valdobbiadene-superiore-cartizze-docg-5-differenze\/","url":"https:\/\/perlagesuite.com\/prosecco-valdobbiadene-superiore-cartizze-docg-5-differenze\/","name":"Cartizze Prosecco Valdobbiadene Superiore DOCG: 5 differences","isPartOf":{"@id":"https:\/\/perlagesuite.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/perlagesuite.com\/prosecco-valdobbiadene-superiore-cartizze-docg-5-differenze\/#primaryimage"},"image":{"@id":"https:\/\/perlagesuite.com\/prosecco-valdobbiadene-superiore-cartizze-docg-5-differenze\/#primaryimage"},"thumbnailUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2017\/10\/prosecco-valdobbiadene-cartizze.jpg","datePublished":"2017-10-21T09:20:05+00:00","dateModified":"2021-07-26T12:28:36+00:00","description":"A few words on one of Italy's most mistreated bubbles: Prosecco and its little Cru, Prosecco di Valdobbiadene Superiore di Cartizze DOCG.","breadcrumb":{"@id":"https:\/\/perlagesuite.com\/prosecco-valdobbiadene-superiore-cartizze-docg-5-differenze\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/perlagesuite.com\/prosecco-valdobbiadene-superiore-cartizze-docg-5-differenze\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/perlagesuite.com\/prosecco-valdobbiadene-superiore-cartizze-docg-5-differenze\/#primaryimage","url":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2017\/10\/prosecco-valdobbiadene-cartizze.jpg","contentUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2017\/10\/prosecco-valdobbiadene-cartizze.jpg","width":1080,"height":720,"caption":"cartizze"},{"@type":"BreadcrumbList","@id":"https:\/\/perlagesuite.com\/prosecco-valdobbiadene-superiore-cartizze-docg-5-differenze\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/perlagesuite.com\/"},{"@type":"ListItem","position":2,"name":"Prosecco Valdobbiadene Superiore Cartizze DOCG: 5 differenze"}]},{"@type":"WebSite","@id":"https:\/\/perlagesuite.com\/#website","url":"https:\/\/perlagesuite.com\/","name":"Perlage Suite","description":"Chiara Bassi's Wine Blog","publisher":{"@id":"https:\/\/perlagesuite.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/perlagesuite.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/perlagesuite.com\/#organization","name":"Chiara Bassi","url":"https:\/\/perlagesuite.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/perlagesuite.com\/#\/schema\/logo\/image\/","url":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2022\/03\/Chiara-Bassi-sommelier-wine-blogger-logo.png","contentUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2022\/03\/Chiara-Bassi-sommelier-wine-blogger-logo.png","width":512,"height":512,"caption":"Chiara Bassi"},"image":{"@id":"https:\/\/perlagesuite.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/chiarabassiperlagesuite","https:\/\/x.com\/perlagesuite","https:\/\/www.instagram.com\/perlagesuite\/"]},{"@type":"Person","@id":"https:\/\/perlagesuite.com\/#\/schema\/person\/81b257517a1007c1a823318ac86c6013","name":"Chiara Bassi","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g","caption":"Chiara Bassi"},"sameAs":["https:\/\/perlagesuite.com"]}]}},"_links":{"self":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/posts\/6282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/comments?post=6282"}],"version-history":[{"count":0,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/posts\/6282\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/media\/6287"}],"wp:attachment":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/media?parent=6282"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/categories?post=6282"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/tags?post=6282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}