{"id":6522,"date":"2017-12-16T13:14:17","date_gmt":"2017-12-16T12:14:17","guid":{"rendered":"http:\/\/perlagesuite.com\/?p=6522"},"modified":"2022-11-16T15:14:46","modified_gmt":"2022-11-16T14:14:46","slug":"spumanti-integrali-cosa-sono-bellenda-le-vigne-di-alice-prosecco","status":"publish","type":"post","link":"https:\/\/perlagesuite.com\/en\/spumanti-integrali-cosa-sono-bellenda-le-vigne-di-alice-prosecco\/","title":{"rendered":"Whole sparkling wines: notes &amp; tastings of my greatest love \u2764"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.19.0&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p style=\"text-align: left;\">Ognuno ha il sacrosanto diritto di avere un debole. E no, non sono super partes: gli <strong>spumanti integrali<\/strong>, insieme ai <a href=\"https:\/\/perlagesuite.com\/sauternes-barsac-degustazioni-primeurs-2016-bordeaux-wine\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"text-decoration: underline;\"><strong>Sauternes<\/strong><\/span><\/a>, ai <a href=\"https:\/\/perlagesuite.com\/vino-fortificato-porto\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"text-decoration: underline;\"><strong>Porto<\/strong><\/span><\/a> e a certi rossi speziati terribilmente vecchi, hanno un posto speciale nel mio cuore.\u00a0Era il Vinitaly 2016 e, come al solito, attraversavo il padiglione del Veneto solo per andare da qualche altra parte. All&#8217;epoca questa regione era di mio interesse solo quando si parlava di certi Amarone. Beata ignoranza! Quando sono arrivata per la prima volta nella loro &#8220;tana&#8221; sono rimasta totalmente affascinata dalla sua bellezza. Per questo, anche se ero molto stanca, mi sono fermata: volevo assolutamente scoprire se era opera del bianconiglio in persona!<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-6524 size-full\" src=\"https:\/\/perlagesuite.com\/wp-content\/uploads\/2017\/12\/spumanti-integrali-le-vigne-di-alice-vinitaly.jpg\" alt=\"spumanti integrali le vigne di alice\" width=\"1080\" height=\"540\" srcset=\"https:\/\/perlagesuite.com\/wp-content\/uploads\/2017\/12\/spumanti-integrali-le-vigne-di-alice-vinitaly.jpg 1080w, https:\/\/perlagesuite.com\/wp-content\/uploads\/2017\/12\/spumanti-integrali-le-vigne-di-alice-vinitaly-600x300.jpg 600w, https:\/\/perlagesuite.com\/wp-content\/uploads\/2017\/12\/spumanti-integrali-le-vigne-di-alice-vinitaly-300x150.jpg 300w, https:\/\/perlagesuite.com\/wp-content\/uploads\/2017\/12\/spumanti-integrali-le-vigne-di-alice-vinitaly-768x384.jpg 768w, https:\/\/perlagesuite.com\/wp-content\/uploads\/2017\/12\/spumanti-integrali-le-vigne-di-alice-vinitaly-1024x512.jpg 1024w, https:\/\/perlagesuite.com\/wp-content\/uploads\/2017\/12\/spumanti-integrali-le-vigne-di-alice-vinitaly-610x305.jpg 610w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/p>\n<p style=\"text-align: justify;\">Mi fermo e mi accoglie Cinzia, gentile e innamorata del suo lavoro. Assaggio tutto. Sono allibita. Ma siamo sicuri sicuri che \u00e8 Prosecco? Lo ammetto, all&#8217;epoca ero davvero ignorante su questa denominazione. Colpa che ne avevo bevuti tanti, uno peggio dell&#8217;altro. Ma come ho capito che c&#8217;era un mondo da scoprire, ho bevuto cos\u00ec tanti prosecco che mi sono assolutamente messa in pari&#8230;<\/p>\n<p style=\"text-align: justify;\">Ho notato ora che lo stand di Bellenda era nella stessa posizione di quest&#8217;anno. Pensa te che non lo avevo visto&#8230; troppo distratta a rincorrere il bianconiglio\u00a0? Stand ancora pi\u00f9 bello dell&#8217;anno precedente! Quest&#8217;anno per\u00f2 grazie a Agnese Ceschi ho scoperto anche Bellenda&#8230; e ha avuto la capacit\u00e0 di sorprendermi ed emozionarmi con un SC 1931 del 2006 con delle note di idrocarburi che non avrei mai sospettato nella Glera!<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6535\" src=\"https:\/\/perlagesuite.com\/wp-content\/uploads\/2017\/12\/500bollein500_LeVigneDiAlice-Spumanti-integrali.jpg\" alt=\"spumanti integrali le vigne di alice vinitaly 2017\" width=\"1080\" height=\"540\" srcset=\"https:\/\/perlagesuite.com\/wp-content\/uploads\/2017\/12\/500bollein500_LeVigneDiAlice-Spumanti-integrali.jpg 1080w, https:\/\/perlagesuite.com\/wp-content\/uploads\/2017\/12\/500bollein500_LeVigneDiAlice-Spumanti-integrali-600x300.jpg 600w, https:\/\/perlagesuite.com\/wp-content\/uploads\/2017\/12\/500bollein500_LeVigneDiAlice-Spumanti-integrali-300x150.jpg 300w, https:\/\/perlagesuite.com\/wp-content\/uploads\/2017\/12\/500bollein500_LeVigneDiAlice-Spumanti-integrali-768x384.jpg 768w, https:\/\/perlagesuite.com\/wp-content\/uploads\/2017\/12\/500bollein500_LeVigneDiAlice-Spumanti-integrali-1024x512.jpg 1024w, https:\/\/perlagesuite.com\/wp-content\/uploads\/2017\/12\/500bollein500_LeVigneDiAlice-Spumanti-integrali-610x305.jpg 610w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/p>\n<h3 style=\"text-align: center;\">Spumanti Integrali: cosa sono?<\/h3>\n<p style=\"text-align: left;\">Gli spumanti integrali si ottiengono dalla fermentazione in bottiglia di vini che seguono il &#8220;normale procedimento&#8221; metodo classico per poi saltare la fase della sboccatura. In pratica i lieviti rimangono dentro la bottiglia e arricchiscono il vino di particolari aromi e conferiscono a questi vini la caratteristica &#8220;velatura&#8221;, che si fa pi\u00f9 intensa se agitati (come piace a me). Facendo un passo indietro, durante la presa di spuma, i<span class=\"s2\">\u00a0lieviti trasformano lo zucchero in anidride carbonica e alcol etilico e formano una serie di sostanze secondarie che arricchiscono il vino spumante di profumi e sapori caratteristici. La curiosit\u00e0 \u00e8 che i lieviti trasformano nell\u2019arco di 6 mesi tutto lo zucchero disponibile, e impoveriscono il vino rubandogli sali minerali, proteine e amminoacidi. Trascorsi i 6 mesi comincia l\u2019autolisi, un processo biologico durante il quale i lieviti si autodistruggeranno e restituiranno al vino, con gli interessi, tutte le sostanze che gli avevano sottratto. Gli spumanti integrali quindi subiscono questo processo finch\u00e9 non li apri. Per questo evolvono continuamente in bottiglia e sono sempre diversi! I sentori tipici di cui si arricchiscono sono note citrine, note vegetali e di frutta secca.<\/span><\/p>\n<h3 style=\"text-align: center;\">Spumanti Integrali: degustazione del P.S. 2013 di Le Vigne di Alice<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6539\" src=\"https:\/\/perlagesuite.com\/wp-content\/uploads\/2017\/12\/spumanti-integrali-le-vigne-di-alice.jpg\" alt=\"spumanti integrali\" width=\"1080\" height=\"720\" srcset=\"https:\/\/perlagesuite.com\/wp-content\/uploads\/2017\/12\/spumanti-integrali-le-vigne-di-alice.jpg 1080w, https:\/\/perlagesuite.com\/wp-content\/uploads\/2017\/12\/spumanti-integrali-le-vigne-di-alice-600x400.jpg 600w, https:\/\/perlagesuite.com\/wp-content\/uploads\/2017\/12\/spumanti-integrali-le-vigne-di-alice-300x200.jpg 300w, https:\/\/perlagesuite.com\/wp-content\/uploads\/2017\/12\/spumanti-integrali-le-vigne-di-alice-768x512.jpg 768w, https:\/\/perlagesuite.com\/wp-content\/uploads\/2017\/12\/spumanti-integrali-le-vigne-di-alice-1024x683.jpg 1024w, https:\/\/perlagesuite.com\/wp-content\/uploads\/2017\/12\/spumanti-integrali-le-vigne-di-alice-610x407.jpg 610w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/p>\n<p style=\"text-align: left;\">Io sar\u00f2 sempre di parte quando si parla del P.S. di Le Vigne di Alice. Mi ha fatto rivoluzionare ogni credo sulle bollicine venete, soprattutto della zona di Conegliano Valdobbiadene e sulla Glera! Si presenta di un bel giallo paglierino &#8220;fieno&#8221; intenso e velato, con un perlage finissimo che forma prima una spuma abbondante, poi una corona persistente. Al naso la prima nota che ti sfiora \u00e8 la liquirizia, intensissima. Poi arriva la lavanda, e se chiudo gli occhi mi sento ancora in Provenza, davanti all&#8217;abbazia di Senanque in piena stagione di fioritura. Poi mandarino candito di Apt, mandorle fresche, fieno bruciato dal sole, fiori d&#8217;acacia e un finale di confetto. In bocca \u00e8 coerente, si arricchisce di una nota che mi ricorda il profumo del dulce de leche appena fatto. A proposito&#8230; oggi lo faccio\u00a0? che bella idea!!\u00a0? Lungo finale tra l&#8217;avena e il caramello. A me piace berlo da solo prima di mangiare, ma sicuramente \u00e8 intrigante anche in abbinamento a certi primi piatti farciti&#8230; tipo oggi, se Davide resuscita dalla spesa, faccio le crespelle ripiene di ricotta e verdure con tantissima besciamella: sono certa che si sposer\u00e0 benissimo, poi ti faccio sapere!\u00a0?<\/p>\n<h3 style=\"text-align: center;\">Spumanti Integrali: degustazione del Radicale 2013 di Bellenda<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6538\" src=\"https:\/\/perlagesuite.com\/wp-content\/uploads\/2017\/12\/spumanti-integrali-bellenda.jpg\" alt=\"spumanti integrali\" width=\"1080\" height=\"720\" srcset=\"https:\/\/perlagesuite.com\/wp-content\/uploads\/2017\/12\/spumanti-integrali-bellenda.jpg 1080w, https:\/\/perlagesuite.com\/wp-content\/uploads\/2017\/12\/spumanti-integrali-bellenda-600x400.jpg 600w, https:\/\/perlagesuite.com\/wp-content\/uploads\/2017\/12\/spumanti-integrali-bellenda-300x200.jpg 300w, https:\/\/perlagesuite.com\/wp-content\/uploads\/2017\/12\/spumanti-integrali-bellenda-768x512.jpg 768w, https:\/\/perlagesuite.com\/wp-content\/uploads\/2017\/12\/spumanti-integrali-bellenda-1024x683.jpg 1024w, https:\/\/perlagesuite.com\/wp-content\/uploads\/2017\/12\/spumanti-integrali-bellenda-610x407.jpg 610w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/p>\n<blockquote>\n<p style=\"text-align: left;\">Radicale \u00e8 fatto cos\u00ec: pigiatura, fermentazione sulle bucce, nessuna aggiunta di solforosa, lieviti indigeni. Lo produciamo in bottiglia magnum da molti anni e non vi nascondiamo che ci piace particolarmente per le sensazioni e i ricordi che ci trasmette, un vino dove pregi e difetti si bilanciano e a ogni sorso\u00a0 ci ricorda da dove veniamo. Nel 2013, un&#8217;annata che consideriamo molto interessante, abbiamo pensato ad una piccola tiratura di Radicale da rifermentare in una bottiglia tradizionale da 0,75. Un&#8217;edizione limitata di 300 bottiglie vestite con un&#8217;etichetta disegnata da Maurizio Armellin, dedicata alle persone che nanno creduto e credono nel nostro lavoro in continua evoluzione, alla ricerca delle radici pi\u00f9 profonde dei prodotti della nostra terra.<\/p>\n<p style=\"text-align: right;\">Bellenda 1986<\/p>\n<\/blockquote>\n<p style=\"text-align: left;\">Di lui non so nulla, ho solo visto un&#8217;etichetta nel suo genere davvero splendida. Scivola nel bicchiere di un bel giallo paglierino &#8220;fieno&#8221; molto intenso, velato, con un perlage finissimo che forma\u00a0 un turbinio di bolle al centro del bicchiere che si dispongono ai lati formando una corona lieve e persistente. Il naso \u00e8 sorprendente: noce, pino mugo, limone, panna montata non zuccherata, rabarbaro, genziana e pera candita sfumano in un finale mentolato. In bocca entra verticale, freschissimo, avvolgente, con una buona salinit\u00e0 e una grande coerenza al naso. Finale amaricante lungo. A me gli spumanti integrali piacciono &#8220;da soli&#8221;, per\u00f2, se proprio ci voglio mangiare qualcosa insieme, lo abbinerei sicuramente ai crostacei, magari a dei gamberoni avvolti nel lardo appena scottati su una purea di piselli&#8230; slurp! Dai che \u00e8 quasi mezzogiorno e ho gi\u00e0 fame&#8230;\u00a0?<\/p>\n<h3 style=\"text-align: center;\">Spumanti Integrali: quali sono i tuoi preferiti?<\/h3>\n<p style=\"text-align: justify;\">Se vuoi conoscere tutti <span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/perlagesuite.com\/500-bolle-500-guida-vini-spumanti\/\"><span style=\"text-decoration: underline;\"><strong>i miei spumanti integrali preferiti puoi comprare la mia guida vini spumanti 500 bolle in 500<\/strong><\/span><\/a><\/span>: ne troverai di davvero fantastici, te lo assicuro! E tu bevi abitualmente vini spumanti integrali? Quali sono i tuoi preferiti? Dimmelo in un commento!<\/p>\n<p style=\"text-align: center;\">E se vuoi leggere ancora qualcosa di queste due cantine:<\/p>\n<ul style=\"text-align: justify;\">\n<li><a href=\"https:\/\/perlagesuite.com\/bellenda-prosecco-s-c-1931-vinitaly-2017\/\" target=\"_blank\" rel=\"noopener noreferrer\">Bellenda: una verticale straordinaria di Prosecco S.C. 1931 al Vinitaly 2017<\/a><\/li>\n<li><a href=\"https:\/\/perlagesuite.com\/la-mia-piu-bella-scoperta-del-vinitaly-2016-prosecco-metodo-classico-ps\/\" target=\"_blank\" rel=\"noopener noreferrer\">La mia pi\u00f9 bella scoperta del Vinitaly 2016? Prosecco Metodo Classico Integrale P.S.<\/a><\/li>\n<\/ul>\n<p>Special Thanks a Cinzia, Pierfrancesca e Umberto che mi hanno ispirato questo articolo. Buon Natale a tutti voi! Ora vado a cucinare!!<\/p>\n<p style=\"text-align: justify;\">Cheers\u00a0\u2764<\/p>\n<p style=\"text-align: justify;\">Chiara<\/p>\n<p style=\"text-align: left;\"><strong>P.S.<\/strong> Come sempre ringrazio <a href=\"https:\/\/universofoto.it\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Universo Foto<\/strong><\/a> per la mia adorata <a href=\"http:\/\/amzn.to\/2j6WV1i\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Sony RX100M4<\/strong><\/a> di cui sono assolutamente innamorata! Provala, provala, provala!! Non c&#8217;\u00e8 iPhone che tenga&#8230; anche se sei abituato a fare le foto con il tuo smartphone! A proposito, ti segnalo che \u00e8 <a href=\"https:\/\/amzn.to\/2BrAtuv\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"text-decoration: underline;\"><strong>in offerta su Amazon a soli 699 \u20ac invece di 1.050 \u20ac<\/strong><\/span><\/a>! Se stai pensando di farti un regalo di Natale fantastico, cogli l&#8217;attimo!<\/p>\n<p><a href=\"https:\/\/universofoto.it\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-5622\" src=\"https:\/\/perlagesuite.com\/wp-content\/uploads\/2017\/04\/Universo-Foto-300x93.jpg\" alt=\"sony universo foto\" width=\"300\" height=\"93\" srcset=\"https:\/\/perlagesuite.com\/wp-content\/uploads\/2017\/04\/Universo-Foto-300x93.jpg 300w, https:\/\/perlagesuite.com\/wp-content\/uploads\/2017\/04\/Universo-Foto-600x186.jpg 600w, https:\/\/perlagesuite.com\/wp-content\/uploads\/2017\/04\/Universo-Foto-610x189.jpg 610w, https:\/\/perlagesuite.com\/wp-content\/uploads\/2017\/04\/Universo-Foto.jpg 645w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>[\/et_pb_text][et_pb_divider color=&#8221;gcid-65af285e-4bd3-4ea9-81b6-b2c2b9f89915&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{%22gcid-65af285e-4bd3-4ea9-81b6-b2c2b9f89915%22:%91%22color%22%93}&#8221;][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.0.6&#8243; global_module=&#8221;21425&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_wc_images product=&#8221;10582&#8243; show_product_gallery=&#8221;off&#8221; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_wc_images][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_wc_title product=&#8221;10582&#8243; _builder_version=&#8221;4.16&#8243; header_level=&#8221;h2&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_wc_title][et_pb_text _builder_version=&#8221;4.16&#8243; text_font=&#8221;Crushed||||||||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4 style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"caret-color: #ff0000;\"><b>Tutti i miei appunti sul vino e sul cibo in un solo libro.<\/b><\/span><\/span><\/h4>\n<p>[\/et_pb_text][et_pb_wc_rating product=&#8221;10582&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_wc_rating][et_pb_wc_price product=&#8221;10582&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_wc_price][et_pb_wc_add_to_cart product=&#8221;10582&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_wc_add_to_cart][et_pb_text _builder_version=&#8221;4.16&#8243; text_font=&#8221;Crushed||||||||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #86A293;\"><strong>IN OMAGGIO<\/strong><\/span>, solo per chi compra il mio libro su questo blog, una copia della <strong>Prima Edizione da Collezione della mia Guida Vini Spumanti &#8220;500 Bolle in 500&#8221;<\/strong>, prezzo di copertina 25,30 \u20ac. [Fino ad esaurimento scorte]<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ognuno ha il sacrosanto diritto di avere un debole. E no, non sono super partes: gli spumanti integrali, insieme ai Sauternes, ai Porto e a certi rossi speziati terribilmente vecchi, hanno un posto speciale nel mio cuore.\u00a0Era il Vinitaly 2016 e, come al solito, attraversavo il padiglione del Veneto solo per andare da qualche altra [&hellip;]<\/p>\n","protected":false},"author":49,"featured_media":6537,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<p style=\"text-align: justify;\">Ognuno ha il sacrosanto diritto di avere un debole. E no, non sono super partes: gli <strong>spumanti integrali<\/strong>, insieme ai <a href=\"http:\/\/perlagesuite.com\/sauternes-barsac-degustazioni-primeurs-2016-bordeaux-wine\/\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\"><strong>Sauternes<\/strong><\/span><\/a>, ai <a href=\"http:\/\/perlagesuite.com\/vino-fortificato-porto\/\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\"><strong>Porto<\/strong><\/span><\/a> e a certi rossi speziati terribilmente vecchi, hanno un posto speciale nel mio cuore.<\/p>\n<script async=\"\" src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block\" data-ad-format=\"fluid\" data-ad-layout-key=\"-gv-k+34-22-4z\" data-ad-client=\"ca-pub-2294603368235139\" data-ad-slot=\"9846354068\"><\/ins>\n<script><br \/>\n     (adsbygoogle = window.adsbygoogle || []).push({});<br \/>\n<\/script>\n<p style=\"text-align: justify;\">Era il Vinitaly 2016 e, come al solito, attraversavo il padiglione del Veneto solo per andare da qualche altra parte. All'epoca questa regione era di mio interesse solo quando si parlava di certi Amarone. Beata ignoranza! Quando sono arrivata per la prima volta nella loro \"tana\" sono rimasta totalmente affascinata dalla sua bellezza. Per questo, anche se ero molto stanca, mi sono fermata: volevo assolutamente scoprire se era opera del bianconiglio in persona!<\/p>\n<img class=\"aligncenter wp-image-6524 size-full\" src=\"http:\/\/perlagesuite.com\/wp-content\/uploads\/2017\/12\/spumanti-integrali-le-vigne-di-alice-vinitaly.jpg\" alt=\"spumanti integrali le vigne di alice\" width=\"1080\" height=\"540\">\n<p style=\"text-align: justify;\">Mi fermo e mi accoglie Cinzia, gentile e innamorata del suo lavoro. Assaggio tutto. Sono allibita. Ma siamo sicuri sicuri che \u00e8 Prosecco? Lo ammetto, all'epoca ero davvero ignorante su questa denominazione. Colpa che ne avevo bevuti tanti, uno peggio dell'altro. Ma come ho capito che c'era un mondo da scoprire, ho bevuto cos\u00ec tanti prosecco che mi sono assolutamente messa in pari...<\/p>\n<p style=\"text-align: justify;\">[tweetshare tweet=\"Fino al #vinitaly 2016 credevo che il #Prosecco fosse un #vino terribile. Beata ignoranza!\" username=\"HavanaVanille\"]<\/p>\n<script async=\"\" src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block\" data-ad-format=\"fluid\" data-ad-layout-key=\"-72-1h-7k+ic+5s\" data-ad-client=\"ca-pub-2294603368235139\" data-ad-slot=\"9273538802\"><\/ins>\n<script><br \/>\n     (adsbygoogle = window.adsbygoogle || []).push({});<br \/>\n<\/script>\n<p style=\"text-align: justify;\">Ho notato ora che lo stand di Bellenda era nella stessa posizione di quest'anno. Pensa te che non lo avevo visto... troppo distratta a rincorrere il bianconiglio&nbsp;? Stand ancora pi\u00f9 bello dell'anno precedente! Quest'anno per\u00f2 grazie a Agnese Ceschi ho scoperto anche Bellenda... e ha avuto la capacit\u00e0 di sorprendermi ed emozionarmi con un SC 1931 del 2006 con delle note di idrocarburi che non avrei mai sospettato nella Glera!<\/p>\n<img class=\"aligncenter size-full wp-image-6535\" src=\"http:\/\/perlagesuite.com\/wp-content\/uploads\/2017\/12\/500bollein500_LeVigneDiAlice-Spumanti-integrali.jpg\" alt=\"spumanti integrali le vigne di alice vinitaly 2017\" width=\"1080\" height=\"540\">\n<h3 style=\"text-align: center;\">Spumanti Integrali: cosa sono?<\/h3>\n<p style=\"text-align: justify;\">Gli spumanti integrali si ottiengono dalla fermentazione in bottiglia di vini che seguono il \"normale procedimento\" metodo classico per poi saltare la fase della sboccatura. In pratica i lieviti rimangono dentro la bottiglia e arricchiscono il vino di particolari aromi e conferiscono a questi vini la caratteristica \"velatura\", che si fa pi\u00f9 intensa se agitati (come piace a me). Facendo un passo indietro, durante la presa di spuma, i<span class=\"s2\">&nbsp;lieviti trasformano lo zucchero in anidride carbonica e alcol etilico e formano una serie di sostanze secondarie che arricchiscono il vino spumante di profumi e sapori caratteristici. La curiosit\u00e0 \u00e8 che i lieviti trasformano nell\u2019arco di 6 mesi tutto lo zucchero disponibile, e impoveriscono il vino rubandogli sali minerali, proteine e amminoacidi. Trascorsi i 6 mesi comincia l\u2019autolisi, un processo biologico durante il quale i lieviti si autodistruggeranno e restituiranno al vino, con gli interessi, tutte le sostanze che gli avevano sottratto. Gli spumanti integrali quindi subiscono questo processo finch\u00e9 non li apri. Per questo evolvono continuamente in bottiglia e sono sempre diversi! I sentori tipici di cui si arricchiscono sono note citrine, note vegetali e di frutta secca.<\/span><\/p>\n<script async=\"\" src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block\" data-ad-format=\"fluid\" data-ad-layout-key=\"-72-1h-7k+ic+5s\" data-ad-client=\"ca-pub-2294603368235139\" data-ad-slot=\"9273538802\"><\/ins>\n<script><br \/>\n     (adsbygoogle = window.adsbygoogle || []).push({});<br \/>\n<\/script>\n<h3 style=\"text-align: center;\">Spumanti Integrali: degustazione del P.S. 2013 di Le Vigne di Alice<\/h3>\n<img class=\"aligncenter size-full wp-image-6539\" src=\"http:\/\/perlagesuite.com\/wp-content\/uploads\/2017\/12\/spumanti-integrali-le-vigne-di-alice.jpg\" alt=\"spumanti integrali\" width=\"1080\" height=\"720\">\n<p style=\"text-align: justify;\">Io sar\u00f2 sempre di parte quando si parla del P.S. di Le Vigne di Alice. Mi ha fatto rivoluzionare ogni credo sulle bollicine venete, soprattutto della zona di Conegliano Valdobbiadene e sulla Glera! Si presenta di un bel giallo paglierino \"fieno\" intenso e velato, con un perlage finissimo che forma prima una spuma abbondante, poi una corona persistente. Al naso la prima nota che ti sfiora \u00e8 la liquirizia, intensissima. Poi arriva la lavanda, e se chiudo gli occhi mi sento ancora in Provenza, davanti all'abbazia di Senanque in piena stagione di fioritura. Poi mandarino candito di Apt, mandorle fresche, fieno bruciato dal sole, fiori d'acacia e un finale di confetto. In bocca \u00e8 coerente, si arricchisce di una nota che mi ricorda il profumo del dulce de leche appena fatto. A proposito... oggi lo faccio&nbsp;? che bella idea!!&nbsp;? Lungo finale tra l'avena e il caramello. A me piace berlo da solo prima di mangiare, ma sicuramente \u00e8 intrigante anche in abbinamento a certi primi piatti farciti... tipo oggi, se Davide resuscita dalla spesa, faccio le crespelle ripiene di ricotta e verdure con tantissima besciamella: sono certa che si sposer\u00e0 benissimo, poi ti faccio sapere!&nbsp;?<\/p>\n\n<h3 style=\"text-align: center;\">Spumanti Integrali: degustazione del Radicale 2013 di Bellenda<\/h3>\n<img class=\"aligncenter size-full wp-image-6538\" src=\"http:\/\/perlagesuite.com\/wp-content\/uploads\/2017\/12\/spumanti-integrali-bellenda.jpg\" alt=\"spumanti integrali\" width=\"1080\" height=\"720\">\n<blockquote>\n<p style=\"text-align: justify;\">Radicale \u00e8 fatto cos\u00ec: pigiatura, fermentazione sulle bucce, nessuna aggiunta di solforosa, lieviti indigeni. Lo produciamo in bottiglia magnum da molti anni e non vi nascondiamo che ci piace particolarmente per le sensazioni e i ricordi che ci trasmette, un vino dove pregi e difetti si bilanciano e a ogni sorso&nbsp; ci ricorda da dove veniamo. Nel 2013, un'annata che consideriamo molto interessante, abbiamo pensato ad una piccola tiratura di Radicale da rifermentare in una bottiglia tradizionale da 0,75. Un'edizione limitata di 300 bottiglie vestite con un'etichetta disegnata da Maurizio Armellin, dedicata alle persone che nanno creduto e credono nel nostro lavoro in continua evoluzione, alla ricerca delle radici pi\u00f9 profonde dei prodotti della nostra terra.<\/p>\n<p style=\"text-align: right;\">Bellenda 1986<\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\">Di lui non so nulla, ho solo visto un'etichetta nel suo genere davvero splendida. Scivola nel bicchiere di un bel giallo paglierino \"fieno\" molto intenso, velato, con un perlage finissimo che forma&nbsp; un turbinio di bolle al centro del bicchiere che si dispongono ai lati formando una corona lieve e persistente. Il naso \u00e8 sorprendente: noce, pino mugo, limone, panna montata non zuccherata, rabarbaro, genziana e pera candita sfumano in un finale mentolato. In bocca entra verticale, freschissimo, avvolgente, con una buona salinit\u00e0 e una grande coerenza al naso. Finale amaricante lungo. A me gli spumanti integrali piacciono \"da soli\", per\u00f2, se proprio ci voglio mangiare qualcosa insieme, lo abbinerei sicuramente ai crostacei, magari a dei gamberoni avvolti nel lardo appena scottati su una purea di piselli... slurp! Dai che \u00e8 quasi mezzogiorno e ho gi\u00e0 fame...&nbsp;?<\/p>\n\n<h3 style=\"text-align: center;\">Spumanti Integrali: quali sono i tuoi preferiti?<\/h3>\n<p style=\"text-align: justify;\">Se vuoi conoscere tutti <span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"http:\/\/perlagesuite.com\/500-bolle-500-guida-vini-spumanti\/\"><span style=\"text-decoration: underline;\"><strong>i miei spumanti integrali preferiti puoi comprare la mia guida vini spumanti 500 bolle in 500<\/strong><\/span><\/a><\/span>: ne troverai di davvero fantastici, te lo assicuro! E tu bevi abitualmente vini spumanti integrali? Quali sono i tuoi preferiti? Dimmelo in un commento!<\/p>\n<p style=\"text-align: center;\">E se vuoi leggere ancora qualcosa di queste due cantine:<\/p>\n\n<ul style=\"text-align: justify;\">\n \t<li><a href=\"http:\/\/perlagesuite.com\/bellenda-prosecco-s-c-1931-vinitaly-2017\/\" target=\"_blank\" rel=\"noopener\">Bellenda: una verticale straordinaria di Prosecco S.C. 1931 al Vinitaly 2017<\/a><\/li>\n \t<li><a href=\"http:\/\/perlagesuite.com\/la-mia-piu-bella-scoperta-del-vinitaly-2016-prosecco-metodo-classico-ps\/\" target=\"_blank\" rel=\"noopener\">La mia pi\u00f9 bella scoperta del Vinitaly 2016? Prosecco Metodo Classico Integrale P.S.<\/a><\/li>\n<\/ul>\nSpecial Thanks a Cinzia, Pierfrancesca e Umberto che mi hanno ispirato questo articolo. Buon Natale a tutti voi! Ora vado a cucinare!!\n<p style=\"text-align: justify;\">Cheers&nbsp;\u2764<\/p>\n<p style=\"text-align: justify;\">Chiara<\/p>\n<p style=\"text-align: justify;\"><strong>P.S.<\/strong> Come sempre ringrazio <a href=\"http:\/\/universofoto.it\" target=\"_blank\" rel=\"noopener\"><strong>Universo Foto<\/strong><\/a> per la mia adorata <a href=\"http:\/\/amzn.to\/2j6WV1i\" target=\"_blank\" rel=\"noopener\"><strong>Sony RX100M4<\/strong><\/a> di cui sono assolutamente innamorata! Provala, provala, provala!! Non c'\u00e8 iPhone che tenga... anche se sei abituato a fare le foto con il tuo smartphone! A proposito, ti segnalo che \u00e8 <a href=\"http:\/\/amzn.to\/2BrAtuv\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\"><strong>in offerta su Amazon a soli 699 \u20ac invece di 1.050 \u20ac<\/strong><\/span><\/a>! Se stai pensando di farti un regalo di Natale fantastico, cogli l'attimo!<\/p>\n<a href=\"http:\/\/universofoto.it\"><img class=\"aligncenter size-medium wp-image-5622\" src=\"http:\/\/perlagesuite.com\/wp-content\/uploads\/2017\/04\/Universo-Foto-300x93.jpg\" alt=\"sony universo foto\" width=\"300\" height=\"93\"><\/a>","_et_gb_content_width":"2880","footnotes":""},"categories":[428],"tags":[],"class_list":["post-6522","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-champagne-vini-spumanti"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.0 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Spumanti integrali: appunti &amp; degustazioni del mio pi\u00f9 grande amore \u2764<\/title>\n<meta name=\"description\" content=\"Quando si parla di spumanti integrali sono di parte: ne sono innamorata! Dal P.S. di Le Vigne di Alice al Radicale di Bellenda, appunti &amp; degustazioni \u2764\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/perlagesuite.com\/en\/spumanti-integrali-cosa-sono-bellenda-le-vigne-di-alice-prosecco\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Spumanti integrali: appunti &amp; degustazioni del mio pi\u00f9 grande amore \u2764\" \/>\n<meta property=\"og:description\" content=\"Quando si parla di spumanti integrali sono di parte: ne sono innamorata! Dal P.S. di Le Vigne di Alice al Radicale di Bellenda, appunti &amp; degustazioni \u2764\" \/>\n<meta property=\"og:url\" content=\"https:\/\/perlagesuite.com\/en\/spumanti-integrali-cosa-sono-bellenda-le-vigne-di-alice-prosecco\/\" \/>\n<meta property=\"og:site_name\" content=\"Perlage Suite\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/chiarabassiperlagesuite\" \/>\n<meta property=\"article:published_time\" content=\"2017-12-16T12:14:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-16T14:14:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/perlagesuite.com\/wp-content\/uploads\/2017\/12\/spumanti-integrali-bellenda-le-vigne-di-alice.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Chiara Bassi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@perlagesuite\" \/>\n<meta name=\"twitter:site\" content=\"@perlagesuite\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Chiara Bassi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/spumanti-integrali-cosa-sono-bellenda-le-vigne-di-alice-prosecco\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/spumanti-integrali-cosa-sono-bellenda-le-vigne-di-alice-prosecco\\\/\"},\"author\":{\"name\":\"Chiara Bassi\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/person\\\/81b257517a1007c1a823318ac86c6013\"},\"headline\":\"Spumanti integrali: appunti &#038; degustazioni del mio pi\u00f9 grande amore \u2764\",\"datePublished\":\"2017-12-16T12:14:17+00:00\",\"dateModified\":\"2022-11-16T14:14:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/spumanti-integrali-cosa-sono-bellenda-le-vigne-di-alice-prosecco\\\/\"},\"wordCount\":1393,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/spumanti-integrali-cosa-sono-bellenda-le-vigne-di-alice-prosecco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/spumanti-integrali-bellenda-le-vigne-di-alice.jpg\",\"articleSection\":[\"Champagne &amp; Spumanti\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/perlagesuite.com\\\/spumanti-integrali-cosa-sono-bellenda-le-vigne-di-alice-prosecco\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/spumanti-integrali-cosa-sono-bellenda-le-vigne-di-alice-prosecco\\\/\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/spumanti-integrali-cosa-sono-bellenda-le-vigne-di-alice-prosecco\\\/\",\"name\":\"Spumanti integrali: appunti & degustazioni del mio pi\u00f9 grande amore \u2764\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/spumanti-integrali-cosa-sono-bellenda-le-vigne-di-alice-prosecco\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/spumanti-integrali-cosa-sono-bellenda-le-vigne-di-alice-prosecco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/spumanti-integrali-bellenda-le-vigne-di-alice.jpg\",\"datePublished\":\"2017-12-16T12:14:17+00:00\",\"dateModified\":\"2022-11-16T14:14:46+00:00\",\"description\":\"Quando si parla di spumanti integrali sono di parte: ne sono innamorata! Dal P.S. di Le Vigne di Alice al Radicale di Bellenda, appunti & degustazioni \u2764\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/spumanti-integrali-cosa-sono-bellenda-le-vigne-di-alice-prosecco\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/perlagesuite.com\\\/spumanti-integrali-cosa-sono-bellenda-le-vigne-di-alice-prosecco\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/spumanti-integrali-cosa-sono-bellenda-le-vigne-di-alice-prosecco\\\/#primaryimage\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/spumanti-integrali-bellenda-le-vigne-di-alice.jpg\",\"contentUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/spumanti-integrali-bellenda-le-vigne-di-alice.jpg\",\"width\":1080,\"height\":720,\"caption\":\"spumanti integrali\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/spumanti-integrali-cosa-sono-bellenda-le-vigne-di-alice-prosecco\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/perlagesuite.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Spumanti integrali: appunti &#038; degustazioni del mio pi\u00f9 grande amore \u2764\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#website\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/\",\"name\":\"Perlage Suite\",\"description\":\"Il Wine Blog di Chiara Bassi\",\"publisher\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/perlagesuite.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#organization\",\"name\":\"Chiara Bassi\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Chiara-Bassi-sommelier-wine-blogger-logo.png\",\"contentUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Chiara-Bassi-sommelier-wine-blogger-logo.png\",\"width\":512,\"height\":512,\"caption\":\"Chiara Bassi\"},\"image\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/chiarabassiperlagesuite\",\"https:\\\/\\\/x.com\\\/perlagesuite\",\"https:\\\/\\\/www.instagram.com\\\/perlagesuite\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/person\\\/81b257517a1007c1a823318ac86c6013\",\"name\":\"Chiara Bassi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g\",\"caption\":\"Chiara Bassi\"},\"sameAs\":[\"https:\\\/\\\/perlagesuite.com\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Whole sparkling wines: notes &amp; tastings of my greatest love \u2764","description":"When it comes to full-bodied sparkling wines, I'm biased: I'm in love with them! From Le Vigne di Alice's P.S. to Bellenda's Radicale, notes &amp; tastings \u2764","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/perlagesuite.com\/en\/spumanti-integrali-cosa-sono-bellenda-le-vigne-di-alice-prosecco\/","og_locale":"en_GB","og_type":"article","og_title":"Spumanti integrali: appunti & degustazioni del mio pi\u00f9 grande amore \u2764","og_description":"Quando si parla di spumanti integrali sono di parte: ne sono innamorata! Dal P.S. di Le Vigne di Alice al Radicale di Bellenda, appunti & degustazioni \u2764","og_url":"https:\/\/perlagesuite.com\/en\/spumanti-integrali-cosa-sono-bellenda-le-vigne-di-alice-prosecco\/","og_site_name":"Perlage Suite","article_publisher":"https:\/\/www.facebook.com\/chiarabassiperlagesuite","article_published_time":"2017-12-16T12:14:17+00:00","article_modified_time":"2022-11-16T14:14:46+00:00","og_image":[{"width":1080,"height":720,"url":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2017\/12\/spumanti-integrali-bellenda-le-vigne-di-alice.jpg","type":"image\/jpeg"}],"author":"Chiara Bassi","twitter_card":"summary_large_image","twitter_creator":"@perlagesuite","twitter_site":"@perlagesuite","twitter_misc":{"Written by":"Chiara Bassi","Estimated reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/perlagesuite.com\/spumanti-integrali-cosa-sono-bellenda-le-vigne-di-alice-prosecco\/#article","isPartOf":{"@id":"https:\/\/perlagesuite.com\/spumanti-integrali-cosa-sono-bellenda-le-vigne-di-alice-prosecco\/"},"author":{"name":"Chiara Bassi","@id":"https:\/\/perlagesuite.com\/#\/schema\/person\/81b257517a1007c1a823318ac86c6013"},"headline":"Spumanti integrali: appunti &#038; degustazioni del mio pi\u00f9 grande amore \u2764","datePublished":"2017-12-16T12:14:17+00:00","dateModified":"2022-11-16T14:14:46+00:00","mainEntityOfPage":{"@id":"https:\/\/perlagesuite.com\/spumanti-integrali-cosa-sono-bellenda-le-vigne-di-alice-prosecco\/"},"wordCount":1393,"commentCount":1,"publisher":{"@id":"https:\/\/perlagesuite.com\/#organization"},"image":{"@id":"https:\/\/perlagesuite.com\/spumanti-integrali-cosa-sono-bellenda-le-vigne-di-alice-prosecco\/#primaryimage"},"thumbnailUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2017\/12\/spumanti-integrali-bellenda-le-vigne-di-alice.jpg","articleSection":["Champagne &amp; Spumanti"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/perlagesuite.com\/spumanti-integrali-cosa-sono-bellenda-le-vigne-di-alice-prosecco\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/perlagesuite.com\/spumanti-integrali-cosa-sono-bellenda-le-vigne-di-alice-prosecco\/","url":"https:\/\/perlagesuite.com\/spumanti-integrali-cosa-sono-bellenda-le-vigne-di-alice-prosecco\/","name":"Whole sparkling wines: notes &amp; tastings of my greatest love \u2764","isPartOf":{"@id":"https:\/\/perlagesuite.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/perlagesuite.com\/spumanti-integrali-cosa-sono-bellenda-le-vigne-di-alice-prosecco\/#primaryimage"},"image":{"@id":"https:\/\/perlagesuite.com\/spumanti-integrali-cosa-sono-bellenda-le-vigne-di-alice-prosecco\/#primaryimage"},"thumbnailUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2017\/12\/spumanti-integrali-bellenda-le-vigne-di-alice.jpg","datePublished":"2017-12-16T12:14:17+00:00","dateModified":"2022-11-16T14:14:46+00:00","description":"When it comes to full-bodied sparkling wines, I'm biased: I'm in love with them! From Le Vigne di Alice's P.S. to Bellenda's Radicale, notes &amp; tastings \u2764","breadcrumb":{"@id":"https:\/\/perlagesuite.com\/spumanti-integrali-cosa-sono-bellenda-le-vigne-di-alice-prosecco\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/perlagesuite.com\/spumanti-integrali-cosa-sono-bellenda-le-vigne-di-alice-prosecco\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/perlagesuite.com\/spumanti-integrali-cosa-sono-bellenda-le-vigne-di-alice-prosecco\/#primaryimage","url":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2017\/12\/spumanti-integrali-bellenda-le-vigne-di-alice.jpg","contentUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2017\/12\/spumanti-integrali-bellenda-le-vigne-di-alice.jpg","width":1080,"height":720,"caption":"spumanti integrali"},{"@type":"BreadcrumbList","@id":"https:\/\/perlagesuite.com\/spumanti-integrali-cosa-sono-bellenda-le-vigne-di-alice-prosecco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/perlagesuite.com\/"},{"@type":"ListItem","position":2,"name":"Spumanti integrali: appunti &#038; degustazioni del mio pi\u00f9 grande amore \u2764"}]},{"@type":"WebSite","@id":"https:\/\/perlagesuite.com\/#website","url":"https:\/\/perlagesuite.com\/","name":"Perlage Suite","description":"Chiara Bassi's Wine Blog","publisher":{"@id":"https:\/\/perlagesuite.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/perlagesuite.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/perlagesuite.com\/#organization","name":"Chiara Bassi","url":"https:\/\/perlagesuite.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/perlagesuite.com\/#\/schema\/logo\/image\/","url":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2022\/03\/Chiara-Bassi-sommelier-wine-blogger-logo.png","contentUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2022\/03\/Chiara-Bassi-sommelier-wine-blogger-logo.png","width":512,"height":512,"caption":"Chiara Bassi"},"image":{"@id":"https:\/\/perlagesuite.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/chiarabassiperlagesuite","https:\/\/x.com\/perlagesuite","https:\/\/www.instagram.com\/perlagesuite\/"]},{"@type":"Person","@id":"https:\/\/perlagesuite.com\/#\/schema\/person\/81b257517a1007c1a823318ac86c6013","name":"Chiara Bassi","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g","caption":"Chiara Bassi"},"sameAs":["https:\/\/perlagesuite.com"]}]}},"_links":{"self":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/posts\/6522","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/comments?post=6522"}],"version-history":[{"count":0,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/posts\/6522\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/media\/6537"}],"wp:attachment":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/media?parent=6522"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/categories?post=6522"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/tags?post=6522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}