{"id":7468,"date":"2018-07-02T09:41:45","date_gmt":"2018-07-02T08:41:45","guid":{"rendered":"http:\/\/perlagesuite.com\/?p=7468"},"modified":"2020-10-15T11:05:41","modified_gmt":"2020-10-15T10:05:41","slug":"monte-isola-vini-fratelli-mazzucchelli","status":"publish","type":"post","link":"https:\/\/perlagesuite.com\/en\/monte-isola-vini-fratelli-mazzucchelli\/","title":{"rendered":"Monte Isola: wines suspended between past and future for the Mazzucchelli brothers"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;3.22&#8243;][et_pb_row _builder_version=&#8221;3.25&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;3.27.4&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221;]<\/p>\n<p style=\"text-align: justify;\">Mercoled\u00ec scorso ero da <strong>Daniel Pennacchio a Cascina Lorenzo per tenere una piccola lezione con degustazione sui risultati dell&#8217;affinamento in legno dei vini rossi<\/strong> (e non solo). Anche se non \u00e8 di Daniel che voglio parlare, devo dire che il <strong>Marzemino (Foppello) 2013 si \u00e8 evoluto in un vino straordinario<\/strong>. Comunque \u00e8 stato un vero piacere conoscere tra i presenti <strong>i fratelli Mario e Luigi Mazzucchelli che nella mia adorata Monte Isola producono due vini davvero davvero buoni<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Mario mi ha prima portata a casa sua, dove ho avuto modo di conoscere i suoi genitori e sua sorella. La sua mamma ha sfettolato il salame prodotto dallo zio, e come si pu\u00f2 vedere da questa foto ho avuto il piacere di abbinarlo alla mia cara piadina romagnola proprio stasera. Con grande successo devo aggiungere! Come? <strong>Vuoi sapere la ricetta della piadina romagnola?<\/strong> Ma \u00e8 facilissimo!! 60 g di strutto (io ho usato il burro delle Ardenne perch\u00e9 non ho trovato lo strutto sull&#8217;isola, bisogna che diciamo a Fabio di provvedere!!), 80 g di acqua calda, 240 g di farina 00, sale e la punta di un cucchiaino di bicarbonato. Impasta, lascia riposare almeno mezz&#8217;ora sotto una scodella, stendi col mattarello e via a cuocere sulla padella antiaderente 4 minuti per lato a fuoco medio!<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-7471\" src=\"http:\/\/perlagesuite.com\/wp-content\/uploads\/2018\/07\/salame-monte-isola-ricetta-piadina-romagnola.jpg\" alt=\"salame monte isola vini monte isola ricetta piadina\" width=\"1080\" height=\"720\" srcset=\"https:\/\/perlagesuite.com\/wp-content\/uploads\/2018\/07\/salame-monte-isola-ricetta-piadina-romagnola.jpg 1080w, https:\/\/perlagesuite.com\/wp-content\/uploads\/2018\/07\/salame-monte-isola-ricetta-piadina-romagnola-300x200.jpg 300w, https:\/\/perlagesuite.com\/wp-content\/uploads\/2018\/07\/salame-monte-isola-ricetta-piadina-romagnola-768x512.jpg 768w, https:\/\/perlagesuite.com\/wp-content\/uploads\/2018\/07\/salame-monte-isola-ricetta-piadina-romagnola-1024x683.jpg 1024w, https:\/\/perlagesuite.com\/wp-content\/uploads\/2018\/07\/salame-monte-isola-ricetta-piadina-romagnola-610x407.jpg 610w, https:\/\/perlagesuite.com\/wp-content\/uploads\/2018\/07\/salame-monte-isola-ricetta-piadina-romagnola-600x400.jpg 600w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/p>\n<p style=\"text-align: justify;\">Comunque torniamo ai vini della famiglia Mazzucchelli! Devo dire che appena ho assaggiato il <strong>vino rosso<\/strong>, che nasce da uve prodotte con vitigni di <strong>Merlot e Barbera<\/strong> che hanno ormai compiuto mezzo secolo, mi ha subito stupito per il <strong>bouquet particolarmente speziato<\/strong> e un&#8217;insolita <strong>morbidezza<\/strong> per un Merlot relativamente giovane. La prima cosa che ho pensato \u00e8 che gli aromi sono un dono della <strong>barrique<\/strong> dato che Mario mi ha detto che affina in botti di rovere. Invece Mario mi ha confermato che \u00e8 proprio l&#8217;uva a custodire questo particolare profumo e ho avuto modo di verificarlo quando abbiamo &#8220;rubato&#8221; col ladro (mi ha insegnato proprio lui questo sinonimo&#8230; io l&#8217;ho sempre chiamato pipetta o alzavino!) dalla botte un campione di vino dell&#8217;annata 2017. Speziatissimo, forse ancora pi\u00f9 della 2015, e la botte \u00e8 al quarto passaggio! No, davvero non \u00e8 lei la responsabile di questo bouquet cos\u00ec particolare. <strong>L&#8217;annata 2017 si preannuncia davvero straordinaria<\/strong>&#8230; peccato che ce ne sia solo una botte disponibile!&nbsp;\ud83d\ude0b<\/p>\n<p>&nbsp;<\/p>\n<blockquote class=\"instagram-media\" style=\"background: #FFF; border: 0; border-radius: 3px; box-shadow: 0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width: 658px; padding: 0; width: calc(100% - 2px);\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/BkriqNghbLI\/\" data-instgrm-version=\"8\">\n<div style=\"padding: 8px;\">\n<div style=\"background: #F8F8F8; line-height: 0; margin-top: 40px; padding: 50.0% 0; text-align: center; width: 100%;\">\n<div style=\"background: url(data:image\/png; base64,ivborw0kggoaaaansuheugaaacwaaaascamaaaapwqozaaaabgdbtueaalgpc\/xhbqaaaafzukdcak7ohokaaaamuexurczmzpf399fx1+bm5mzy9amaaadisurbvdjlvzxbesmgces5\/p8\/t9furvcrmu73jwlzosgsiizurcjo\/ad+eqjjb4hv8bft+idpqocx1wjosbfhh2xssxeiyn3uli\/6mnree07uiwjev8ueowds88ly97kqytlijkktuybbruayvh5wohixmpi5we58ek028czwyuqdlkpg1bkb4nnm+veanfhqn1k4+gpt6ugqcvu2h2ovuif\/gwufyy8owepdyzsa3avcqpvovvzzz2vtnn2wu8qzvjddeto90gsy9mvlqtgysy231mxry6i2ggqjrty0l8fxcxfcbbhwrsyyaaaaaelftksuqmcc); display: block; height: 44px; margin: 0 auto -44px; position: relative; top: -22px; width: 44px;\"><\/div>\n<\/div>\n<p style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; line-height: 17px; margin-bottom: 0; margin-top: 8px; overflow: hidden; padding: 8px 0 7px; text-align: center; text-overflow: ellipsis; white-space: nowrap;\"><a style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: normal; line-height: 17px; text-decoration: none;\" href=\"https:\/\/www.instagram.com\/p\/BkriqNghbLI\/\" target=\"_blank\" rel=\"noopener noreferrer\">Un post condiviso da Chiara Bassi &#8211; PerlageSuite (@perlagesuite)<\/a> in data: <time style=\"font-family: Arial,sans-serif; font-size: 14px; line-height: 17px;\" datetime=\"2018-07-01T07:16:38+00:00\">Lug 1, 2018 at 12:16 PDT<\/time><\/p>\n<\/div>\n<\/blockquote>\n<p><script async=\"\" defer=\"\" src=\"\/\/www.instagram.com\/embed.js\"><\/script><\/p>\n<p style=\"text-align: justify;\">Ho assaggiato anche l&#8217;<strong>annata 2016<\/strong>, questa riposava nella botte d&#8217;acciaio, ma devo dire che non mi ha convinta del tutto. Il naso l&#8217;ho trovato piacevolissimo, con note quasi di vin brul\u00e9: mela, scorze d&#8217;arancia, cannella, chiodi di garofano e marasca sotto spirito di grande intensit\u00e0 mi avevano piacevolmente attratta, ma purtroppo in bocca rivela un tannino verde che credo difficilmente si armonizzer\u00e0. Si pu\u00f2 provare qualche mese in bottiglia per vedere cosa succede!<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-7475\" src=\"http:\/\/perlagesuite.com\/wp-content\/uploads\/2018\/07\/mario-mazzucchelli-vini-monte-isola-cosa-vedere-1.jpg\" alt=\"vini monte isola\" width=\"1080\" height=\"720\" srcset=\"https:\/\/perlagesuite.com\/wp-content\/uploads\/2018\/07\/mario-mazzucchelli-vini-monte-isola-cosa-vedere-1.jpg 1080w, https:\/\/perlagesuite.com\/wp-content\/uploads\/2018\/07\/mario-mazzucchelli-vini-monte-isola-cosa-vedere-1-300x200.jpg 300w, https:\/\/perlagesuite.com\/wp-content\/uploads\/2018\/07\/mario-mazzucchelli-vini-monte-isola-cosa-vedere-1-768x512.jpg 768w, https:\/\/perlagesuite.com\/wp-content\/uploads\/2018\/07\/mario-mazzucchelli-vini-monte-isola-cosa-vedere-1-1024x683.jpg 1024w, https:\/\/perlagesuite.com\/wp-content\/uploads\/2018\/07\/mario-mazzucchelli-vini-monte-isola-cosa-vedere-1-610x407.jpg 610w, https:\/\/perlagesuite.com\/wp-content\/uploads\/2018\/07\/mario-mazzucchelli-vini-monte-isola-cosa-vedere-1-600x400.jpg 600w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/p>\n<p style=\"text-align: justify;\"><strong>I vigneti di Massimo e Luigi Mazzucchelli sono molto curati e denotano preparazione e amore.<\/strong> La cantina \u00e8 piccolina, ma in progetto di spostarla in un ambiente che ho visto in anteprima e sarebbe davvero ottimale, sia per le caratteristiche architettoniche sia per la posizione. Nell&#8217;attuale cantina c&#8217;\u00e8 l&#8217;essenziale, il torchio che usa il pap\u00e0, una botte in acciaio sulla quale il pap\u00e0 ha una licenza speciale nello spillare il vino che beve a pranzo, la botte in legno di cui ho gi\u00e0 parlato, qualche altra botte storica non pi\u00f9 utilizzata&#8230; e qualche vecchia annata di moscato passito.<\/p>\n<p style=\"text-align: justify;\">Pensa, <strong>solo 10 litri all&#8217;anno<\/strong> per un vino davvero interessante. Con Mario abbiamo degustato l&#8217;<strong>annata 2003 di Moscato Bianco Passito<\/strong>, e mi sono anche portata a casa la bottiglia: ero curiosa di vedere come evolveva nei giorni successivi. Il colore \u00e8 giallo oro carico, pecca leggermente di limpidezza rispetto alla brillantezza che ci ha abituato la tecnologia e il mercato attuale. Da degustare assolutamente in un bicchiere Napoleon, per esaltarne al meglio le caratteristiche organolettiche e stemperare un po&#8217; quell&#8217;alcolicit\u00e0 che fa capolino anche dagli archetti cos\u00ec ravvicinati mentre si ruota il bicchiere. Al naso mi ricorda certi vin santi che bevevo anni fa, quando con nonna passavo l&#8217;estate dalla zia in Toscana&#8230; mi ricorda certi panorami del Casentino a cui sono tanto affezionata e di cui custodisco gelosamente i ricordi. Il tempo gli ha regalato note quasi eteree, ma la frutta candita, in particolare la pera e il cedro, resta il sentore principale. Quando ho chiuso gli occhi mi sono persa per un istante, e mi sono immaginata nella fabbrica di canditi di Apt, in Provenza, quando sceglievo i canditi da portare al mio pap\u00e0 per fare la mia adorata cassata siciliana. In bocca ha un&#8217;ottima rispondenza al naso, \u00e8 morbidissimo, e conferma quell&#8217;alcolicit\u00e0 che si era intuita alla vista. Gode ancora di buona freschezza, e questo mi lascia intuire che <strong>qualche bottiglia Mario Mazzucchelli potrebbe ancora dimenticarsela in quella piccola cassettina dei tesori<\/strong>.<\/p>\n<blockquote class=\"instagram-media\" style=\"background: #FFF; border: 0; border-radius: 3px; box-shadow: 0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width: 658px; padding: 0; width: calc(100% - 2px);\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/BkuVPhnhKFw\/\" data-instgrm-version=\"8\">\n<div style=\"padding: 8px;\">\n<div style=\"background: #F8F8F8; line-height: 0; margin-top: 40px; padding: 50.0% 0; text-align: center; width: 100%;\">\n<div style=\"background: url(data:image\/png; base64,ivborw0kggoaaaansuheugaaacwaaaascamaaaapwqozaaaabgdbtueaalgpc\/xhbqaaaafzukdcak7ohokaaaamuexurczmzpf399fx1+bm5mzy9amaaadisurbvdjlvzxbesmgces5\/p8\/t9furvcrmu73jwlzosgsiizurcjo\/ad+eqjjb4hv8bft+idpqocx1wjosbfhh2xssxeiyn3uli\/6mnree07uiwjev8ueowds88ly97kqytlijkktuybbruayvh5wohixmpi5we58ek028czwyuqdlkpg1bkb4nnm+veanfhqn1k4+gpt6ugqcvu2h2ovuif\/gwufyy8owepdyzsa3avcqpvovvzzz2vtnn2wu8qzvjddeto90gsy9mvlqtgysy231mxry6i2ggqjrty0l8fxcxfcbbhwrsyyaaaaaelftksuqmcc); display: block; height: 44px; margin: 0 auto -44px; position: relative; top: -22px; width: 44px;\"><\/div>\n<\/div>\n<p style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; line-height: 17px; margin-bottom: 0; margin-top: 8px; overflow: hidden; padding: 8px 0 7px; text-align: center; text-overflow: ellipsis; white-space: nowrap;\"><a style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: normal; line-height: 17px; text-decoration: none;\" href=\"https:\/\/www.instagram.com\/p\/BkuVPhnhKFw\/\" target=\"_blank\" rel=\"noopener noreferrer\">Un post condiviso da Chiara Bassi &#8211; PerlageSuite (@perlagesuite)<\/a> in data: <time style=\"font-family: Arial,sans-serif; font-size: 14px; line-height: 17px;\" datetime=\"2018-07-02T09:17:07+00:00\">Lug 2, 2018 at 2:17 PDT<\/time><\/p>\n<\/div>\n<\/blockquote>\n<p><script async=\"\" defer=\"\" src=\"\/\/www.instagram.com\/embed.js\"><\/script><\/p>\n<p style=\"text-align: justify;\">Per me c&#8217;\u00e8 davvero tanta potenzialit\u00e0 qui, bisogna solo raccoglierla. Non so se quello di Mario rester\u00e0 sempre un hobby o diventer\u00e0 una vera professione, ma quando c&#8217;\u00e8 la passione io credo che tutto \u00e8 possibile. Del resto io ne sono la prova vivente, no?<\/p>\n<p style=\"text-align: justify;\">Complimenti al pap\u00e0 e alla mamma, in formissima. Chiudo questo articolo proprio con una battuta del <strong>pap\u00e0, che mi ha raccontato che quando era giovane era ben felice quando da una sola pianta ci riempiva una cesta d&#8217;uva, e oggi ha lasciato spazio ai figli che fanno diradamento per concentrarsi sulla qualit\u00e0<\/strong>. I tempi cambiano, lo studio e le vicissitudini della vita cambiano le prospettive&#8230; noi inevitabilmente cambiamo con esse, ci modelliamo come neve al sole sciogliendoci fin quasi a scomparire per poi ripresentarci puntualmente ogni anno davanti a noi stessi e dicendoci: supereremo anche questa. Ma quando c&#8217;\u00e8 la passione, quando si fa squadra, quando c&#8217;\u00e8 l&#8217;amore&#8230; i risultati ci sono sempre, \u00e8 solo questione di saper aspettare.<\/p>\n<p>Un abbraccio,<\/p>\n<p>Chiara<\/p>\n<p style=\"text-align: justify;\">PS Come sempre <strong><a href=\"https:\/\/amzn.to\/2Kzai9N\" target=\"_blank\" rel=\"noopener noreferrer\">ringrazio Sony e Universo Foto per la splendida macchina fotografica RX100M4 <span style=\"text-decoration: underline;\">(che puoi comprare su Amazon cliccando QUI a soli 729 \u20ac invece di 1.050 \u20ac)<\/span><\/a><\/strong>&#8230; che \u00e8 davvero una manna dal cielo per le foto in cantina e al tramonto senza flash! Credo che ogni vignaiolo e ogni winelovers dovrebbe averne una! Altro che iPhone!!!&nbsp;\ud83d\ude04<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/universofoto.it\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-5622\" src=\"http:\/\/perlagesuite.com\/wp-content\/uploads\/2017\/04\/Universo-Foto-300x93.jpg\" alt=\"sony universo foto\" width=\"300\" height=\"93\" srcset=\"https:\/\/perlagesuite.com\/wp-content\/uploads\/2017\/04\/Universo-Foto-300x93.jpg 300w, https:\/\/perlagesuite.com\/wp-content\/uploads\/2017\/04\/Universo-Foto-600x186.jpg 600w, https:\/\/perlagesuite.com\/wp-content\/uploads\/2017\/04\/Universo-Foto-610x189.jpg 610w, https:\/\/perlagesuite.com\/wp-content\/uploads\/2017\/04\/Universo-Foto.jpg 645w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.0.6&#8243; global_module=&#8221;21425&#8243;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.0.6&#8243;][et_pb_wc_images product=&#8221;10582&#8243; _builder_version=&#8221;4.0.6&#8243;][\/et_pb_wc_images][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.0.6&#8243;][et_pb_wc_title product=&#8221;10582&#8243; _builder_version=&#8221;4.0.6&#8243;][\/et_pb_wc_title][et_pb_wc_rating product=&#8221;10582&#8243; _builder_version=&#8221;4.0.6&#8243;][\/et_pb_wc_rating][et_pb_wc_description product=&#8221;10582&#8243; _builder_version=&#8221;4.0.6&#8243;][\/et_pb_wc_description][et_pb_wc_price product=&#8221;10582&#8243; _builder_version=&#8221;4.0.6&#8243;][\/et_pb_wc_price][et_pb_wc_add_to_cart product=&#8221;10582&#8243; _builder_version=&#8221;4.0.6&#8243;][\/et_pb_wc_add_to_cart][et_pb_text _builder_version=&#8221;4.0.6&#8243; text_font=&#8221;Delius Unicase||||||||&#8221;]<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ff0000;\"><strong>IN OMAGGIO<\/strong><\/span>, solo per chi compra il mio libro su Perlage Suite, una copia della <strong>Prima Edizione da Collezione della mia Guida Vini Spumanti &#8220;500 Bolle in 500&#8221;<\/strong>, prezzo di copertina 25,30 \u20ac.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mercoled\u00ec scorso ero da Daniel Pennacchio a Cascina Lorenzo per tenere una piccola lezione con degustazione sui risultati dell&#8217;affinamento in legno dei vini rossi (e non solo). Anche se non \u00e8 di Daniel che voglio parlare, devo dire che il Marzemino (Foppello) 2013 si \u00e8 evoluto in un vino straordinario. Comunque \u00e8 stato un vero [&hellip;]<\/p>\n","protected":false},"author":49,"featured_media":7477,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<p style=\"text-align: justify;\">Mercoled\u00ec scorso ero da <strong>Daniel Pennacchio a Cascina Lorenzo per tenere una piccola lezione con degustazione sui risultati dell'affinamento in legno dei vini rossi<\/strong> (e non solo). Anche se non \u00e8 di Daniel che voglio parlare, devo dire che il <strong>Marzemino (Foppello) 2013 si \u00e8 evoluto in un vino straordinario<\/strong>. Comunque \u00e8 stato un vero piacere conoscere tra i presenti <strong>i fratelli Mario e Luigi Mazzucchelli che nella mia adorata Monte Isola producono due vini davvero davvero buoni<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Mario mi ha prima portata a casa sua, dove ho avuto modo di conoscere i suoi genitori e sua sorella. La sua mamma ha sfettolato il salame prodotto dallo zio, e come si pu\u00f2 vedere da questa foto ho avuto il piacere di abbinarlo alla mia cara piadina romagnola proprio stasera. Con grande successo devo aggiungere! Come? <strong>Vuoi sapere la ricetta della piadina romagnola?<\/strong> Ma \u00e8 facilissimo!! 60 g di strutto (io ho usato il burro delle Ardenne perch\u00e9 non ho trovato lo strutto sull'isola, bisogna che diciamo a Fabio di provvedere!!), 80 g di acqua calda, 240 g di farina 00, sale e la punta di un cucchiaino di bicarbonato. Impasta, lascia riposare almeno mezz'ora sotto una scodella, stendi col mattarello e via a cuocere sulla padella antiaderente 4 minuti per lato a fuoco medio!<\/p>\n<img class=\"alignnone size-full wp-image-7471\" src=\"http:\/\/perlagesuite.com\/wp-content\/uploads\/2018\/07\/salame-monte-isola-ricetta-piadina-romagnola.jpg\" alt=\"salame monte isola vini monte isola ricetta piadina\" width=\"1080\" height=\"720\">\n<p style=\"text-align: justify;\">Comunque torniamo ai vini della famiglia Mazzucchelli! Devo dire che appena ho assaggiato il <strong>vino rosso<\/strong>, che nasce da uve prodotte con vitigni di <strong>Merlot e Barbera<\/strong> che hanno ormai compiuto mezzo secolo, mi ha subito stupito per il <strong>bouquet particolarmente speziato<\/strong> e un'insolita <strong>morbidezza<\/strong> per un Merlot relativamente giovane. La prima cosa che ho pensato \u00e8 che gli aromi sono un dono della <strong>barrique<\/strong> dato che Mario mi ha detto che affina in botti di rovere. Invece Mario mi ha confermato che \u00e8 proprio l'uva a custodire questo particolare profumo e ho avuto modo di verificarlo quando abbiamo \"rubato\" col ladro (mi ha insegnato proprio lui questo sinonimo... io l'ho sempre chiamato pipetta o alzavino!) dalla botte un campione di vino dell'annata 2017. Speziatissimo, forse ancora pi\u00f9 della 2015, e la botte \u00e8 al quarto passaggio! No, davvero non \u00e8 lei la responsabile di questo bouquet cos\u00ec particolare. <strong>L'annata 2017 si preannuncia davvero straordinaria<\/strong>... peccato che ce ne sia solo una botte disponibile!&nbsp;\ud83d\ude0b<\/p>\n&nbsp;\n<blockquote class=\"instagram-media\" style=\"background: #FFF; border: 0; border-radius: 3px; box-shadow: 0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width: 658px; padding: 0; width: calc(100% - 2px);\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/BkriqNghbLI\/\" data-instgrm-version=\"8\">\n<div style=\"padding: 8px;\">\n<div style=\"background: #F8F8F8; line-height: 0; margin-top: 40px; padding: 50.0% 0; text-align: center; width: 100%;\">\n<div style=\"background: url(data:image\/png; base64,ivborw0kggoaaaansuheugaaacwaaaascamaaaapwqozaaaabgdbtueaalgpc\/xhbqaaaafzukdcak7ohokaaaamuexurczmzpf399fx1+bm5mzy9amaaadisurbvdjlvzxbesmgces5\/p8\/t9furvcrmu73jwlzosgsiizurcjo\/ad+eqjjb4hv8bft+idpqocx1wjosbfhh2xssxeiyn3uli\/6mnree07uiwjev8ueowds88ly97kqytlijkktuybbruayvh5wohixmpi5we58ek028czwyuqdlkpg1bkb4nnm+veanfhqn1k4+gpt6ugqcvu2h2ovuif\/gwufyy8owepdyzsa3avcqpvovvzzz2vtnn2wu8qzvjddeto90gsy9mvlqtgysy231mxry6i2ggqjrty0l8fxcxfcbbhwrsyyaaaaaelftksuqmcc); display: block; height: 44px; margin: 0 auto -44px; position: relative; top: -22px; width: 44px;\"><\/div>\n<\/div>\n<p style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; line-height: 17px; margin-bottom: 0; margin-top: 8px; overflow: hidden; padding: 8px 0 7px; text-align: center; text-overflow: ellipsis; white-space: nowrap;\"><a style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: normal; line-height: 17px; text-decoration: none;\" href=\"https:\/\/www.instagram.com\/p\/BkriqNghbLI\/\" target=\"_blank\" rel=\"noopener noreferrer\">Un post condiviso da Chiara Bassi - PerlageSuite (@perlagesuite)<\/a> in data: <time style=\"font-family: Arial,sans-serif; font-size: 14px; line-height: 17px;\" datetime=\"2018-07-01T07:16:38+00:00\">Lug 1, 2018 at 12:16 PDT<\/time><\/p>\n\n<\/div><\/blockquote>\n<script async=\"\" defer=\"\" src=\"\/\/www.instagram.com\/embed.js\"><\/script>\n<p style=\"text-align: justify;\">Ho assaggiato anche l'<strong>annata 2016<\/strong>, questa riposava nella botte d'acciaio, ma devo dire che non mi ha convinta del tutto. Il naso l'ho trovato piacevolissimo, con note quasi di vin brul\u00e9: mela, scorze d'arancia, cannella, chiodi di garofano e marasca sotto spirito di grande intensit\u00e0 mi avevano piacevolmente attratta, ma purtroppo in bocca rivela un tannino verde che credo difficilmente si armonizzer\u00e0. Si pu\u00f2 provare qualche mese in bottiglia per vedere cosa succede!<\/p>\n<img class=\"alignnone size-full wp-image-7475\" src=\"http:\/\/perlagesuite.com\/wp-content\/uploads\/2018\/07\/mario-mazzucchelli-vini-monte-isola-cosa-vedere-1.jpg\" alt=\"vini monte isola\" width=\"1080\" height=\"720\">\n<p style=\"text-align: justify;\"><strong>I vigneti di Massimo e Luigi Mazzucchelli sono molto curati e denotano preparazione e amore.<\/strong> La cantina \u00e8 piccolina, ma in progetto di spostarla in un ambiente che ho visto in anteprima e sarebbe davvero ottimale, sia per le caratteristiche architettoniche sia per la posizione. Nell'attuale cantina c'\u00e8 l'essenziale, il torchio che usa il pap\u00e0, una botte in acciaio sulla quale il pap\u00e0 ha una licenza speciale nello spillare il vino che beve a pranzo, la botte in legno di cui ho gi\u00e0 parlato, qualche altra botte storica non pi\u00f9 utilizzata... e qualche vecchia annata di moscato passito.<\/p>\n<p style=\"text-align: justify;\">Pensa, <strong>solo 10 litri all'anno<\/strong> per un vino davvero interessante. Con Mario abbiamo degustato l'<strong>annata 2003 di Moscato Bianco Passito<\/strong>, e mi sono anche portata a casa la bottiglia: ero curiosa di vedere come evolveva nei giorni successivi. Il colore \u00e8 giallo oro carico, pecca leggermente di limpidezza rispetto alla brillantezza che ci ha abituato la tecnologia e il mercato attuale. Da degustare assolutamente in un bicchiere Napoleon, per esaltarne al meglio le caratteristiche organolettiche e stemperare un po' quell'alcolicit\u00e0 che fa capolino anche dagli archetti cos\u00ec ravvicinati mentre si ruota il bicchiere. Al naso mi ricorda certi vin santi che bevevo anni fa, quando con nonna passavo l'estate dalla zia in Toscana... mi ricorda certi panorami del Casentino a cui sono tanto affezionata e di cui custodisco gelosamente i ricordi. Il tempo gli ha regalato note quasi eteree, ma la frutta candita, in particolare la pera e il cedro, resta il sentore principale. Quando ho chiuso gli occhi mi sono persa per un istante, e mi sono immaginata nella fabbrica di canditi di Apt, in Provenza, quando sceglievo i canditi da portare al mio pap\u00e0 per fare la mia adorata cassata siciliana. In bocca ha un'ottima rispondenza al naso, \u00e8 morbidissimo, e conferma quell'alcolicit\u00e0 che si era intuita alla vista. Gode ancora di buona freschezza, e questo mi lascia intuire che <strong>qualche bottiglia Mario Mazzucchelli potrebbe ancora dimenticarsela in quella piccola cassettina dei tesori<\/strong>.<\/p>\n\n<blockquote class=\"instagram-media\" style=\"background: #FFF; border: 0; border-radius: 3px; box-shadow: 0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width: 658px; padding: 0; width: calc(100% - 2px);\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/BkuVPhnhKFw\/\" data-instgrm-version=\"8\">\n<div style=\"padding: 8px;\">\n<div style=\"background: #F8F8F8; line-height: 0; margin-top: 40px; padding: 50.0% 0; text-align: center; width: 100%;\">\n<div style=\"background: url(data:image\/png; base64,ivborw0kggoaaaansuheugaaacwaaaascamaaaapwqozaaaabgdbtueaalgpc\/xhbqaaaafzukdcak7ohokaaaamuexurczmzpf399fx1+bm5mzy9amaaadisurbvdjlvzxbesmgces5\/p8\/t9furvcrmu73jwlzosgsiizurcjo\/ad+eqjjb4hv8bft+idpqocx1wjosbfhh2xssxeiyn3uli\/6mnree07uiwjev8ueowds88ly97kqytlijkktuybbruayvh5wohixmpi5we58ek028czwyuqdlkpg1bkb4nnm+veanfhqn1k4+gpt6ugqcvu2h2ovuif\/gwufyy8owepdyzsa3avcqpvovvzzz2vtnn2wu8qzvjddeto90gsy9mvlqtgysy231mxry6i2ggqjrty0l8fxcxfcbbhwrsyyaaaaaelftksuqmcc); display: block; height: 44px; margin: 0 auto -44px; position: relative; top: -22px; width: 44px;\"><\/div>\n<\/div>\n<p style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; line-height: 17px; margin-bottom: 0; margin-top: 8px; overflow: hidden; padding: 8px 0 7px; text-align: center; text-overflow: ellipsis; white-space: nowrap;\"><a style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: normal; line-height: 17px; text-decoration: none;\" href=\"https:\/\/www.instagram.com\/p\/BkuVPhnhKFw\/\" target=\"_blank\" rel=\"noopener noreferrer\">Un post condiviso da Chiara Bassi - PerlageSuite (@perlagesuite)<\/a> in data: <time style=\"font-family: Arial,sans-serif; font-size: 14px; line-height: 17px;\" datetime=\"2018-07-02T09:17:07+00:00\">Lug 2, 2018 at 2:17 PDT<\/time><\/p>\n\n<\/div><\/blockquote>\n<script async=\"\" defer=\"\" src=\"\/\/www.instagram.com\/embed.js\"><\/script>\n<p style=\"text-align: justify;\">Per me c'\u00e8 davvero tanta potenzialit\u00e0 qui, bisogna solo raccoglierla. Non so se quello di Mario rester\u00e0 sempre un hobby o diventer\u00e0 una vera professione, ma quando c'\u00e8 la passione io credo che tutto \u00e8 possibile. Del resto io ne sono la prova vivente, no?<\/p>\n<p style=\"text-align: justify;\">Complimenti al pap\u00e0 e alla mamma, in formissima. Chiudo questo articolo proprio con una battuta del <strong>pap\u00e0, che mi ha raccontato che quando era giovane era ben felice quando da una sola pianta ci riempiva una cesta d'uva, e oggi ha lasciato spazio ai figli che fanno diradamento per concentrarsi sulla qualit\u00e0<\/strong>. I tempi cambiano, lo studio e le vicissitudini della vita cambiano le prospettive... noi inevitabilmente cambiamo con esse, ci modelliamo come neve al sole sciogliendoci fin quasi a scomparire per poi ripresentarci puntualmente ogni anno davanti a noi stessi e dicendoci: supereremo anche questa. Ma quando c'\u00e8 la passione, quando si fa squadra, quando c'\u00e8 l'amore... i risultati ci sono sempre, \u00e8 solo questione di saper aspettare.<\/p>\nUn abbraccio,\n\nChiara\n<p style=\"text-align: justify;\">PS Come sempre <strong><a href=\"https:\/\/amzn.to\/2Kzai9N\" target=\"_blank\" rel=\"noopener noreferrer\">ringrazio Sony e Universo Foto per la splendida macchina fotografica RX100M4 <span style=\"text-decoration: underline;\">(che puoi comprare su Amazon cliccando QUI a soli 729 \u20ac invece di 1.050 \u20ac)<\/span><\/a><\/strong>... che \u00e8 davvero una manna dal cielo per le foto in cantina e al tramonto senza flash! Credo che ogni vignaiolo e ogni winelovers dovrebbe averne una! Altro che iPhone!!!&nbsp;\ud83d\ude04<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/universofoto.it\"><img class=\"alignnone size-medium wp-image-5622\" src=\"http:\/\/perlagesuite.com\/wp-content\/uploads\/2017\/04\/Universo-Foto-300x93.jpg\" alt=\"sony universo foto\" width=\"300\" height=\"93\"><\/a><\/p>","_et_gb_content_width":"2880","footnotes":""},"categories":[501],"tags":[],"class_list":["post-7468","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ristoranti"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.0 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Monte Isola: vini sospesi tra passato e futuro per i fratelli Mazzucchelli - Perlage Suite<\/title>\n<meta name=\"description\" content=\"Una bellissima visita tra i vigneti dei fratelli Mazzucchelli nel cuore di Monte Isola per custodire pochissime bottiglie preziose come tesori perduti.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/perlagesuite.com\/en\/monte-isola-vini-fratelli-mazzucchelli\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Monte Isola: vini sospesi tra passato e futuro per i fratelli Mazzucchelli\" \/>\n<meta property=\"og:description\" content=\"Una bellissima visita tra i vigneti dei fratelli Mazzucchelli nel cuore di Monte Isola per custodire pochissime bottiglie preziose come tesori perduti.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/perlagesuite.com\/en\/monte-isola-vini-fratelli-mazzucchelli\/\" \/>\n<meta property=\"og:site_name\" content=\"Perlage Suite\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/chiarabassiperlagesuite\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-02T08:41:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-15T10:05:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/perlagesuite.com\/wp-content\/uploads\/2018\/07\/mario-mazzucchelli-vini-monte-isola.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Chiara Bassi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@perlagesuite\" \/>\n<meta name=\"twitter:site\" content=\"@perlagesuite\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Chiara Bassi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/monte-isola-vini-fratelli-mazzucchelli\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/monte-isola-vini-fratelli-mazzucchelli\\\/\"},\"author\":{\"name\":\"Chiara Bassi\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/person\\\/81b257517a1007c1a823318ac86c6013\"},\"headline\":\"Monte Isola: vini sospesi tra passato e futuro per i fratelli Mazzucchelli\",\"datePublished\":\"2018-07-02T08:41:45+00:00\",\"dateModified\":\"2020-10-15T10:05:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/monte-isola-vini-fratelli-mazzucchelli\\\/\"},\"wordCount\":1247,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/monte-isola-vini-fratelli-mazzucchelli\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/mario-mazzucchelli-vini-monte-isola.jpg\",\"articleSection\":[\"Ristoranti\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/perlagesuite.com\\\/monte-isola-vini-fratelli-mazzucchelli\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/monte-isola-vini-fratelli-mazzucchelli\\\/\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/monte-isola-vini-fratelli-mazzucchelli\\\/\",\"name\":\"Monte Isola: vini sospesi tra passato e futuro per i fratelli Mazzucchelli - Perlage Suite\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/monte-isola-vini-fratelli-mazzucchelli\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/monte-isola-vini-fratelli-mazzucchelli\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/mario-mazzucchelli-vini-monte-isola.jpg\",\"datePublished\":\"2018-07-02T08:41:45+00:00\",\"dateModified\":\"2020-10-15T10:05:41+00:00\",\"description\":\"Una bellissima visita tra i vigneti dei fratelli Mazzucchelli nel cuore di Monte Isola per custodire pochissime bottiglie preziose come tesori perduti.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/monte-isola-vini-fratelli-mazzucchelli\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/perlagesuite.com\\\/monte-isola-vini-fratelli-mazzucchelli\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/monte-isola-vini-fratelli-mazzucchelli\\\/#primaryimage\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/mario-mazzucchelli-vini-monte-isola.jpg\",\"contentUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/mario-mazzucchelli-vini-monte-isola.jpg\",\"width\":1080,\"height\":720,\"caption\":\"vini monte isola\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/monte-isola-vini-fratelli-mazzucchelli\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/perlagesuite.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Monte Isola: vini sospesi tra passato e futuro per i fratelli Mazzucchelli\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#website\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/\",\"name\":\"Perlage Suite\",\"description\":\"Il Wine Blog di Chiara Bassi\",\"publisher\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/perlagesuite.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#organization\",\"name\":\"Chiara Bassi\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Chiara-Bassi-sommelier-wine-blogger-logo.png\",\"contentUrl\":\"https:\\\/\\\/perlagesuite.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Chiara-Bassi-sommelier-wine-blogger-logo.png\",\"width\":512,\"height\":512,\"caption\":\"Chiara Bassi\"},\"image\":{\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/chiarabassiperlagesuite\",\"https:\\\/\\\/x.com\\\/perlagesuite\",\"https:\\\/\\\/www.instagram.com\\\/perlagesuite\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/perlagesuite.com\\\/#\\\/schema\\\/person\\\/81b257517a1007c1a823318ac86c6013\",\"name\":\"Chiara Bassi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g\",\"caption\":\"Chiara Bassi\"},\"sameAs\":[\"https:\\\/\\\/perlagesuite.com\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Monte Isola: wines suspended between past and future for the Mazzucchelli brothers - Perlage Suite","description":"A beautiful visit to the Mazzucchelli brothers' vineyards in the heart of Monte Isola to guard a few precious bottles like lost treasures.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/perlagesuite.com\/en\/monte-isola-vini-fratelli-mazzucchelli\/","og_locale":"en_GB","og_type":"article","og_title":"Monte Isola: vini sospesi tra passato e futuro per i fratelli Mazzucchelli","og_description":"Una bellissima visita tra i vigneti dei fratelli Mazzucchelli nel cuore di Monte Isola per custodire pochissime bottiglie preziose come tesori perduti.","og_url":"https:\/\/perlagesuite.com\/en\/monte-isola-vini-fratelli-mazzucchelli\/","og_site_name":"Perlage Suite","article_publisher":"https:\/\/www.facebook.com\/chiarabassiperlagesuite","article_published_time":"2018-07-02T08:41:45+00:00","article_modified_time":"2020-10-15T10:05:41+00:00","og_image":[{"width":1080,"height":720,"url":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2018\/07\/mario-mazzucchelli-vini-monte-isola.jpg","type":"image\/jpeg"}],"author":"Chiara Bassi","twitter_card":"summary_large_image","twitter_creator":"@perlagesuite","twitter_site":"@perlagesuite","twitter_misc":{"Written by":"Chiara Bassi","Estimated reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/perlagesuite.com\/monte-isola-vini-fratelli-mazzucchelli\/#article","isPartOf":{"@id":"https:\/\/perlagesuite.com\/monte-isola-vini-fratelli-mazzucchelli\/"},"author":{"name":"Chiara Bassi","@id":"https:\/\/perlagesuite.com\/#\/schema\/person\/81b257517a1007c1a823318ac86c6013"},"headline":"Monte Isola: vini sospesi tra passato e futuro per i fratelli Mazzucchelli","datePublished":"2018-07-02T08:41:45+00:00","dateModified":"2020-10-15T10:05:41+00:00","mainEntityOfPage":{"@id":"https:\/\/perlagesuite.com\/monte-isola-vini-fratelli-mazzucchelli\/"},"wordCount":1247,"commentCount":0,"publisher":{"@id":"https:\/\/perlagesuite.com\/#organization"},"image":{"@id":"https:\/\/perlagesuite.com\/monte-isola-vini-fratelli-mazzucchelli\/#primaryimage"},"thumbnailUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2018\/07\/mario-mazzucchelli-vini-monte-isola.jpg","articleSection":["Ristoranti"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/perlagesuite.com\/monte-isola-vini-fratelli-mazzucchelli\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/perlagesuite.com\/monte-isola-vini-fratelli-mazzucchelli\/","url":"https:\/\/perlagesuite.com\/monte-isola-vini-fratelli-mazzucchelli\/","name":"Monte Isola: wines suspended between past and future for the Mazzucchelli brothers - Perlage Suite","isPartOf":{"@id":"https:\/\/perlagesuite.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/perlagesuite.com\/monte-isola-vini-fratelli-mazzucchelli\/#primaryimage"},"image":{"@id":"https:\/\/perlagesuite.com\/monte-isola-vini-fratelli-mazzucchelli\/#primaryimage"},"thumbnailUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2018\/07\/mario-mazzucchelli-vini-monte-isola.jpg","datePublished":"2018-07-02T08:41:45+00:00","dateModified":"2020-10-15T10:05:41+00:00","description":"A beautiful visit to the Mazzucchelli brothers' vineyards in the heart of Monte Isola to guard a few precious bottles like lost treasures.","breadcrumb":{"@id":"https:\/\/perlagesuite.com\/monte-isola-vini-fratelli-mazzucchelli\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/perlagesuite.com\/monte-isola-vini-fratelli-mazzucchelli\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/perlagesuite.com\/monte-isola-vini-fratelli-mazzucchelli\/#primaryimage","url":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2018\/07\/mario-mazzucchelli-vini-monte-isola.jpg","contentUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2018\/07\/mario-mazzucchelli-vini-monte-isola.jpg","width":1080,"height":720,"caption":"vini monte isola"},{"@type":"BreadcrumbList","@id":"https:\/\/perlagesuite.com\/monte-isola-vini-fratelli-mazzucchelli\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/perlagesuite.com\/"},{"@type":"ListItem","position":2,"name":"Monte Isola: vini sospesi tra passato e futuro per i fratelli Mazzucchelli"}]},{"@type":"WebSite","@id":"https:\/\/perlagesuite.com\/#website","url":"https:\/\/perlagesuite.com\/","name":"Perlage Suite","description":"Chiara Bassi's Wine Blog","publisher":{"@id":"https:\/\/perlagesuite.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/perlagesuite.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/perlagesuite.com\/#organization","name":"Chiara Bassi","url":"https:\/\/perlagesuite.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/perlagesuite.com\/#\/schema\/logo\/image\/","url":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2022\/03\/Chiara-Bassi-sommelier-wine-blogger-logo.png","contentUrl":"https:\/\/perlagesuite.com\/wp-content\/uploads\/2022\/03\/Chiara-Bassi-sommelier-wine-blogger-logo.png","width":512,"height":512,"caption":"Chiara Bassi"},"image":{"@id":"https:\/\/perlagesuite.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/chiarabassiperlagesuite","https:\/\/x.com\/perlagesuite","https:\/\/www.instagram.com\/perlagesuite\/"]},{"@type":"Person","@id":"https:\/\/perlagesuite.com\/#\/schema\/person\/81b257517a1007c1a823318ac86c6013","name":"Chiara Bassi","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2d79bd9bb4582f8af9b4c76c8e21c46c1d0c1cde8dc9dc57cf739c0d296754d2?s=96&d=mm&r=g","caption":"Chiara Bassi"},"sameAs":["https:\/\/perlagesuite.com"]}]}},"_links":{"self":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/posts\/7468","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/comments?post=7468"}],"version-history":[{"count":0,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/posts\/7468\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/media\/7477"}],"wp:attachment":[{"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/media?parent=7468"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/categories?post=7468"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/perlagesuite.com\/en\/wp-json\/wp\/v2\/tags?post=7468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}